{"id":26761,"date":"2025-04-09T14:28:50","date_gmt":"2025-04-09T14:28:50","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=26761"},"modified":"2025-06-09T08:32:50","modified_gmt":"2025-06-09T08:32:50","slug":"8-37","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/th\/archives\/26761","title":{"rendered":"\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e04\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e08\u0e30\u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e2b\u0e19\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e21\u0e32\u0e23\u0e23\u0e49\u0e32\u0e22\u0e41\u0e25\u0e30\u0e08\u0e30\u0e01\u0e25\u0e48\u0e32\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e02\u0e32\u0e27\u0e48\u0e32 \u201c\u0e40\u0e08\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e32\u0e23\u0e23\u0e49\u0e32\u0e22\u201d"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"26761\" class=\"elementor elementor-26761\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-72245772 e-flex e-con-boxed e-con e-parent\" data-id=\"72245772\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6991c9ed elementor-widget elementor-widget-text-editor\" data-id=\"6991c9ed\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><h1 class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">7 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2561<\/span><\/span><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"xzpqnlu xjm9jq1 x6ikm8r x10wlt62 x10l6tqk x1i1rx1s\">\u00a0<\/span><\/span><\/h1><\/div><\/div><\/div><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e19\u0e35\u0e49\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e2a\u0e2b\u0e32\u0e22\u0e1c\u0e39\u0e49\u0e28\u0e23\u0e31\u0e17\u0e18\u0e32\u0e22\u0e34\u0e48\u0e07\u0e01\u0e27\u0e48\u0e32\u0e1e\u0e27\u0e01\u0e40\u0e23\u0e32 \u0e44\u0e14\u0e49\u0e17\u0e39\u0e25\u0e16\u0e32\u0e21\u0e17\u0e48\u0e32\u0e19\u0e28\u0e32\u0e2a\u0e14\u0e32\u0e27\u0e48\u0e32 \u0e02\u0e2d\u0e1e\u0e23\u0e30\u0e1c\u0e39\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e17\u0e23\u0e07\u0e2d\u0e27\u0e22\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2a\u0e31\u0e19\u0e15\u0e34\u0e2a\u0e38\u0e02\u0e41\u0e01\u0e48\u0e17\u0e48\u0e32\u0e19 \u0e1e\u0e27\u0e01\u0e17\u0e48\u0e32\u0e19\u0e08\u0e07\u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e2b\u0e19\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e21\u0e32\u0e23\u0e23\u0e49\u0e32\u0e22\u0e41\u0e25\u0e30\u0e1b\u0e0f\u0e34\u0e40\u0e2a\u0e18\u0e17\u0e48\u0e32\u0e19\u0e2b\u0e32\u0e01\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e08\u0e31\u0e1a\u0e17\u0e48\u0e32\u0e19\u0e44\u0e14\u0e49 \u0e17\u0e48\u0e32\u0e19\u0e28\u0e32\u0e2a\u0e14\u0e32 \u0e02\u0e2d\u0e1e\u0e23\u0e30\u0e1c\u0e39\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e17\u0e23\u0e07\u0e2d\u0e27\u0e22\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2a\u0e31\u0e19\u0e15\u0e34\u0e2a\u0e38\u0e02\u0e41\u0e01\u0e48\u0e17\u0e48\u0e32\u0e19 \u0e1a\u0e2d\u0e01\u0e01\u0e31\u0e1a\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e27\u0e48\u0e32 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e17\u0e23\u0e2b\u0e14\u0e2d\u0e14\u0e17\u0e19\u0e02\u0e2d\u0e07\u0e17\u0e48\u0e32\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e1e\u0e1a\u0e17\u0e48\u0e32\u0e19 \u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e08\u0e30\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e17\u0e48\u0e32\u0e19\u0e41\u0e25\u0e30\u0e28\u0e23\u0e31\u0e17\u0e18\u0e32\u0e43\u0e19\u0e17\u0e48\u0e32\u0e19<br class=\"html-br\" \/><br class=\"html-br\" \/>\u0e04\u0e38\u0e13\u0e25\u0e2d\u0e07\u0e08\u0e34\u0e19\u0e15\u0e19\u0e32\u0e01\u0e32\u0e23\u0e14\u0e39\u0e2a\u0e34\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e22\u0e31\u0e07\u0e44\u0e07?<br class=\"html-br\" \/>\u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e23\u0e48\u0e27\u0e21\u0e17\u0e32\u0e07 \u0e41\u0e25\u0e49\u0e27\u0e40\u0e23\u0e32\u0e25\u0e48\u0e30?<br class=\"html-br\" \/>\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e28\u0e23\u0e31\u0e17\u0e18\u0e32\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e2b\u0e19\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e21\u0e32\u0e23\u0e23\u0e49\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e30\u0e01\u0e25\u0e48\u0e32\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e02\u0e32\u0e27\u0e48\u0e32 \u201c\u0e40\u0e08\u0e49\u0e32\u0e04\u0e37\u0e2d\u0e21\u0e32\u0e23\u0e23\u0e49\u0e32\u0e22\u201d \u0e17\u0e48\u0e32\u0e19\u0e28\u0e32\u0e2a\u0e14\u0e32 \u0e02\u0e2d\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e17\u0e23\u0e07\u0e2d\u0e27\u0e22\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2a\u0e31\u0e19\u0e15\u0e34\u0e2a\u0e38\u0e02\u0e41\u0e01\u0e48\u0e17\u0e48\u0e32\u0e19 \u0e44\u0e14\u0e49\u0e01\u0e25\u0e48\u0e32\u0e27\u0e16\u0e36\u0e07\u0e17\u0e48\u0e32\u0e19\u0e43\u0e19\u0e2b\u0e30\u0e14\u0e35\u0e29\u0e2d\u0e31\u0e19\u0e2a\u0e39\u0e07\u0e2a\u0e48\u0e07 \u0e02\u0e49\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e27\u0e34\u0e07\u0e27\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e1e\u0e23\u0e30\u0e1c\u0e39\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e02\u0e49\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e48\u0e32\u0e19<br class=\"html-br\" \/><br class=\"html-br\" \/>\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e40\u0e28\u0e32\u0e30\u0e2e\u0e32\u0e1a\u0e30\u0e2e\u0e3a (\u0e02\u0e2d\u0e2d\u0e31\u0e25\u0e25\u0e2d\u0e2e\u0e3a\u0e17\u0e23\u0e07\u0e1e\u0e2d\u0e1e\u0e23\u0e30\u0e17\u0e31\u0e22\u0e43\u0e19\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32) \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32: \u0e42\u0e2d\u0e49 \u0e17\u0e48\u0e32\u0e19\u0e28\u0e32\u0e2a\u0e14\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e2d\u0e31\u0e25\u0e25\u0e2d\u0e2e\u0e3a \u0e40\u0e23\u0e32\u0e04\u0e27\u0e23\u0e42\u0e15\u0e49\u0e40\u0e16\u0e35\u0e22\u0e07\u0e41\u0e25\u0e30\u0e01\u0e25\u0e48\u0e32\u0e27\u0e2b\u0e32\u0e40\u0e02\u0e32\u0e27\u0e48\u0e32\u0e42\u0e01\u0e2b\u0e01\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48? \u0e17\u0e48\u0e32\u0e19\u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32: \u0e2d\u0e22\u0e48\u0e32\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e43\u0e14\u0e43\u0e19\u0e2b\u0e21\u0e39\u0e48\u0e1e\u0e27\u0e01\u0e17\u0e48\u0e32\u0e19\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e40\u0e02\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e35\u0e48\u0e08\u0e30\u0e17\u0e33\u0e40\u0e0a\u0e48\u0e19\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2b\u0e32\u0e01\u0e40\u0e02\u0e32\u0e44\u0e1b\u0e2b\u0e32\u0e40\u0e02\u0e32 \u0e40\u0e02\u0e32\u0e08\u0e30\u0e16\u0e39\u0e01\u0e25\u0e48\u0e2d\u0e25\u0e27\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e40\u0e02\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e30\u0e2b\u0e25\u0e07\u0e1c\u0e34\u0e14\u0e41\u0e25\u0e30\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e0f\u0e34\u0e40\u0e2a\u0e18\u0e28\u0e23\u0e31\u0e17\u0e18\u0e32<br class=\"html-br\" \/><br class=\"html-br\" \/>\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u201c\u0e43\u0e04\u0e23\u0e40\u0e25\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e22\u0e32\u0e19\u0e17\u0e35\u0e48\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e15\u0e48\u0e2d\u0e2b\u0e19\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e2a\u0e32\u0e01\u0e25\u0e42\u0e25\u0e01\u0e43\u0e19\u0e40\u0e27\u0e25\u0e32\u0e19\u0e31\u0e49\u0e19?\u201d \u0e17\u0e48\u0e32\u0e19\u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u201c\u0e1c\u0e39\u0e49\u0e28\u0e23\u0e31\u0e17\u0e18\u0e32\u0e04\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e08\u0e30\u0e21\u0e38\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e44\u0e1b\u0e2b\u0e32\u0e40\u0e02\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e30\u0e16\u0e39\u0e01\u0e01\u0e2d\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e17\u0e2b\u0e32\u0e23\u0e14\u0e31\u0e08\u0e0d\u0e32\u0e25\u0e21\u0e32\u0e1e\u0e1a \u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e08\u0e30\u0e01\u0e25\u0e48\u0e32\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e02\u0e32\u0e27\u0e48\u0e32 \u2018\u0e42\u0e2d\u0e49 \u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c\u0e40\u0e2d\u0e4b\u0e22 \u0e40\u0e08\u0e49\u0e32\u0e08\u0e30\u0e44\u0e1b\u0e44\u0e2b\u0e19\u2019 \u0e40\u0e02\u0e32\u0e08\u0e30\u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u2018\u0e09\u0e31\u0e19\u0e08\u0e30\u0e44\u0e1b\u0e2b\u0e32\u0e0a\u0e32\u0e22\u0e1c\u0e39\u0e49\u0e19\u0e35\u0e49\u0e17\u0e35\u0e48\u0e2d\u0e49\u0e32\u0e07\u0e15\u0e31\u0e27\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u2019 \u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e08\u0e30\u0e1b\u0e23\u0e30\u0e2b\u0e25\u0e32\u0e14\u0e43\u0e08\u0e43\u0e19\u0e04\u0e33\u0e15\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32\u0e41\u0e25\u0e30\u0e16\u0e32\u0e21\u0e40\u0e02\u0e32\u0e27\u0e48\u0e32 \u2018\u0e17\u0e48\u0e32\u0e19\u0e44\u0e21\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e43\u0e19\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e2b\u0e23\u0e37\u0e2d?\u2019 \u0e40\u0e02\u0e32\u0e08\u0e30\u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u2018\u0e19\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32 \u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e17\u0e48\u0e32\u0e19\u0e04\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e0a\u0e31\u0e49\u0e19\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19 \u0e40\u0e02\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e04\u0e48\u0e04\u0e19\u0e19\u0e2d\u0e01\u0e23\u0e35\u0e15\u0e17\u0e35\u0e48\u0e1b\u0e0f\u0e34\u0e40\u0e2a\u0e18\u0e28\u0e23\u0e31\u0e17\u0e18\u0e32\u2019 \u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e08\u0e30\u0e01\u0e48\u0e2d\u0e01\u0e1a\u0e0f\u0e15\u0e48\u0e2d\u0e40\u0e02\u0e32\u0e41\u0e25\u0e30\u0e15\u0e30\u0e42\u0e01\u0e19\u0e40\u0e23\u0e35\u0e22\u0e01\u0e43\u0e2b\u0e49\u0e06\u0e48\u0e32\u0e40\u0e02\u0e32 \u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07\u0e08\u0e30\u0e17\u0e33\u0e40\u0e0a\u0e48\u0e19\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e08\u0e30\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e27\u0e48\u0e32\u0e14\u0e31\u0e08\u0e0d\u0e32\u0e25\u0e2a\u0e31\u0e48\u0e07\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e06\u0e48\u0e32\u0e43\u0e04\u0e23\u0e08\u0e19\u0e01\u0e27\u0e48\u0e32\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e08\u0e30\u0e41\u0e08\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e32\u0e17\u0e23\u0e32\u0e1a \u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e08\u0e30\u0e25\u0e48\u0e32\u0e21\u0e42\u0e0b\u0e48\u0e40\u0e02\u0e32\u0e41\u0e25\u0e30\u0e19\u0e33\u0e15\u0e31\u0e27\u0e40\u0e02\u0e32\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e14\u0e31\u0e08\u0e0d\u0e32\u0e25 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e28\u0e23\u0e31\u0e17\u0e18\u0e32\u0e40\u0e2b\u0e47\u0e19\u0e40\u0e02\u0e32 \u0e40\u0e02\u0e32\u0e08\u0e30\u0e15\u0e30\u0e42\u0e01\u0e19\u0e2a\u0e38\u0e14\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e27\u0e48\u0e32 \u2018\u0e42\u0e2d\u0e49 \u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e25\u0e32\u0e22 \u0e2d\u0e22\u0e48\u0e32\u0e2b\u0e25\u0e07\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e0a\u0e31\u0e22\u0e0f\u0e2d\u0e19\u0e19\u0e35\u0e49 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e02\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e19\u0e42\u0e01\u0e2b\u0e01\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e2d\u0e01\u0e25\u0e27\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e49\u0e32\u0e07\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e43\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e40\u0e02\u0e32\u0e44\u0e21\u0e48\u0e21\u0e35 \u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e17\u0e48\u0e32\u0e19\u0e28\u0e32\u0e2a\u0e19\u0e17\u0e39\u0e15\u0e02\u0e2d\u0e07\u0e2d\u0e31\u0e25\u0e25\u0e2d\u0e2e\u0e3a\u0e01\u0e25\u0e48\u0e32\u0e27 (\u0e02\u0e2d\u0e2a\u0e31\u0e19\u0e15\u0e34\u0e2a\u0e38\u0e02\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33\u0e40\u0e23\u0e34\u0e0d\u0e08\u0e32\u0e01\u0e2d\u0e31\u0e25\u0e25\u0e2d\u0e2e\u0e4c\u0e08\u0e07\u0e21\u0e35\u0e41\u0e14\u0e48\u0e17\u0e48\u0e32\u0e19) \u0e44\u0e14\u0e49\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e17\u0e48\u0e32\u0e19\u0e41\u0e25\u0e49\u0e27\u201d \u0e04\u0e27\u0e32\u0e21\u0e42\u0e01\u0e23\u0e18\u0e02\u0e2d\u0e07\u0e21\u0e32\u0e23\u0e23\u0e49\u0e32\u0e22\u0e08\u0e30\u0e17\u0e27\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e02\u0e32\u0e08\u0e30\u0e2a\u0e31\u0e48\u0e07\u0e25\u0e39\u0e01\u0e19\u0e49\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e21\u0e31\u0e14\u0e40\u0e02\u0e32 \u0e16\u0e25\u0e01\u0e2b\u0e19\u0e31\u0e07\u0e40\u0e02\u0e32 \u0e41\u0e25\u0e30\u0e15\u0e35\u0e2b\u0e25\u0e31\u0e07\u0e41\u0e25\u0e30\u0e17\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32 \u0e21\u0e32\u0e23\u0e23\u0e49\u0e32\u0e22\u0e08\u0e30\u0e1e\u0e39\u0e14\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e42\u0e01\u0e23\u0e18\u0e08\u0e31\u0e14 \u0e2a\u0e31\u0e48\u0e07\u0e25\u0e39\u0e01\u0e19\u0e49\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e17\u0e33\u0e23\u0e49\u0e32\u0e22\u0e41\u0e25\u0e30\u0e17\u0e33\u0e23\u0e49\u0e32\u0e22\u0e40\u0e02\u0e32 \u0e41\u0e25\u0e30\u0e28\u0e23\u0e31\u0e17\u0e18\u0e32\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e08\u0e30\u0e17\u0e27\u0e35\u0e04\u0e39\u0e13 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e21\u0e32\u0e23\u0e23\u0e49\u0e32\u0e22\u0e08\u0e30\u0e2a\u0e31\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e25\u0e39\u0e01\u0e19\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e22\u0e1c\u0e48\u0e32\u0e40\u0e02\u0e32\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e28\u0e35\u0e23\u0e29\u0e30\u0e08\u0e23\u0e14\u0e02\u0e32 \u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e08\u0e30\u0e17\u0e33\u0e40\u0e0a\u0e48\u0e19\u0e19\u0e31\u0e49\u0e19 \u0e42\u0e14\u0e22\u0e41\u0e22\u0e01\u0e2a\u0e2d\u0e07\u0e0b\u0e35\u0e01\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e01\u0e31\u0e19 \u0e21\u0e32\u0e23\u0e23\u0e49\u0e32\u0e22\u0e08\u0e30\u0e40\u0e14\u0e34\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e15\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e04\u0e19\u0e08\u0e30\u0e01\u0e23\u0e32\u0e1a\u0e25\u0e07\u0e15\u0e48\u0e2d\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e02\u0e32\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e48\u0e2d\u0e2b\u0e22\u0e34\u0e48\u0e07\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e42\u0e2d\u0e2b\u0e31\u0e07 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e40\u0e02\u0e32\u0e08\u0e30\u0e1e\u0e39\u0e14\u0e01\u0e31\u0e1a\u0e40\u0e02\u0e32\u0e27\u0e48\u0e32 \u201c\u0e25\u0e38\u0e01\u0e02\u0e36\u0e49\u0e19\u201d \u0e2a\u0e2d\u0e07\u0e0b\u0e35\u0e01\u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e01\u0e25\u0e49\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e2d\u0e21\u0e23\u0e27\u0e21\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e0a\u0e32\u0e22\u0e04\u0e19\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e01\u0e25\u0e31\u0e1a\u0e04\u0e37\u0e19\u0e0a\u0e35\u0e1e \u0e21\u0e32\u0e23\u0e23\u0e49\u0e32\u0e22\u0e08\u0e30\u0e16\u0e32\u0e21\u0e40\u0e02\u0e32\u0e27\u0e48\u0e32 \u201c\u0e40\u0e08\u0e49\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e43\u0e19\u0e40\u0e23\u0e32\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d?\u201d \u0e43\u0e1a\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e28\u0e23\u0e31\u0e17\u0e18\u0e32\u0e08\u0e30\u0e2a\u0e27\u0e48\u0e32\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u201c\u0e17\u0e48\u0e32\u0e19\u0e44\u0e14\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e17\u0e48\u0e32\u0e19\u0e28\u0e32\u0e2a\u0e14\u0e32 (\u0e02\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e19\u0e15\u0e34\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33\u0e40\u0e23\u0e34\u0e0d\u0e08\u0e32\u0e01\u0e2d\u0e31\u0e25\u0e25\u0e2d\u0e2e\u0e4c\u0e08\u0e07\u0e21\u0e35\u0e41\u0e14\u0e48\u0e17\u0e48\u0e32\u0e19) \u0e44\u0e14\u0e49\u0e1a\u0e2d\u0e01\u0e40\u0e23\u0e32\u0e27\u0e48\u0e32\u0e17\u0e48\u0e32\u0e19\u0e08\u0e30\u0e17\u0e33\u0e40\u0e0a\u0e48\u0e19\u0e19\u0e31\u0e49\u0e19\u0e01\u0e31\u0e1a\u0e09\u0e31\u0e19\u201d \u0e0a\u0e32\u0e22\u0e04\u0e19\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e15\u0e30\u0e42\u0e01\u0e19\u0e2a\u0e38\u0e14\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e27\u0e48\u0e32 \u201c\u0e08\u0e07\u0e23\u0e30\u0e27\u0e31\u0e07\u0e40\u0e16\u0e34\u0e14 \u0e42\u0e2d\u0e49\u0e1c\u0e39\u0e49\u0e04\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e25\u0e32\u0e22 \u0e40\u0e02\u0e32\u0e08\u0e30\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e2d\u0e30\u0e44\u0e23\u0e01\u0e31\u0e1a\u0e43\u0e04\u0e23\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e09\u0e31\u0e19 \u0e40\u0e27\u0e17\u0e21\u0e19\u0e15\u0e23\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32\u0e16\u0e39\u0e01\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e44\u0e23\u0e49\u0e1c\u0e25 \u0e41\u0e25\u0e30\u0e40\u0e02\u0e32\u0e08\u0e30\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e1b\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e19\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e1b\u0e25\u0e49\u0e19\u0e40\u0e08\u0e15\u0e08\u0e33\u0e19\u0e07\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e34\u0e21\u201d \u0e40\u0e2b\u0e25\u0e48\u0e32\u0e21\u0e32\u0e23\u0e23\u0e49\u0e32\u0e22\u0e08\u0e30\u0e1e\u0e32\u0e40\u0e02\u0e32\u0e44\u0e1b\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23 \u0e41\u0e15\u0e48\u0e40\u0e02\u0e32\u0e08\u0e30\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e2d\u0e37\u0e49\u0e2d\u0e21\u0e16\u0e36\u0e07\u0e40\u0e02\u0e32\u0e44\u0e14\u0e49 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2d\u0e31\u0e25\u0e25\u0e2d\u0e2e\u0e4c\u0e1c\u0e39\u0e49\u0e17\u0e23\u0e07\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e44\u0e14\u0e49\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e0a\u0e48\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e07\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e04\u0e2d\u0e41\u0e25\u0e30\u0e44\u0e2b\u0e1b\u0e25\u0e32\u0e23\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e2b\u0e25\u0e48\u0e32\u0e21\u0e32\u0e23\u0e23\u0e49\u0e32\u0e22\u0e08\u0e30\u0e08\u0e31\u0e1a\u0e40\u0e02\u0e32\u0e14\u0e49\u0e27\u0e22\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e17\u0e49\u0e32\u0e41\u0e25\u0e49\u0e27\u0e42\u0e22\u0e19\u0e40\u0e02\u0e32\u0e25\u0e07\u0e44\u0e1b \u0e1c\u0e39\u0e49\u0e04\u0e19\u0e08\u0e30\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e40\u0e02\u0e32\u0e42\u0e22\u0e19\u0e40\u0e02\u0e32\u0e25\u0e07\u0e43\u0e19\u0e44\u0e1f\u0e19\u0e23\u0e01 \u0e41\u0e15\u0e48\u0e17\u0e35\u0e48\u0e08\u0e23\u0e34\u0e07\u0e41\u0e25\u0e49\u0e27\u0e40\u0e02\u0e32\u0e16\u0e39\u0e01\u0e42\u0e22\u0e19\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e43\u0e19\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e04\u0e33\u0e1e\u0e22\u0e32\u0e19\u0e17\u0e35\u0e48\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e15\u0e48\u0e2d\u0e2b\u0e19\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e2a\u0e32\u0e01\u0e25\u0e42\u0e25\u0e01<br class=\"html-br\" \/><br class=\"html-br\" \/>\u0e42\u0e2d\u0e49\u0e1e\u0e23\u0e30\u0e1c\u0e39\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32 \u0e42\u0e1b\u0e23\u0e14\u0e17\u0e23\u0e07\u0e43\u0e2b\u0e49\u0e02\u0e49\u0e32\u0e1e\u0e40\u0e08\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e22\u0e32\u0e19\u0e17\u0e35\u0e48\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e15\u0e48\u0e2d\u0e1e\u0e23\u0e30\u0e2d\u0e07\u0e04\u0e4c \u0e42\u0e2d\u0e49\u0e1e\u0e23\u0e30\u0e1c\u0e39\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>7 \u0623\u0643\u062a\u0648\u0628\u0631 2018 \u0627\u0644\u0635\u062d\u0627\u0628\u0629 \u0648\u0647\u0645 \u0643\u0627\u0646\u0648\u0627 \u0627\u0641\u0636\u0644 \u0627\u064a\u0645\u0627\u0646\u0627 \u0645\u0646\u0627 \u0639\u0646\u062f\u0645\u0627 \u0633\u0623\u0644\u0648\u0627 \u0627\u0644\u0646\u0628\u064a \u0635\u0644 \u0627\u0644\u0644\u0647 \u0639\u0644\u064a\u0647 \u0648\u0633\u0644\u0645 \u0627\u0646 \u064a\u0648\u0627\u062c\u0647\u0648\u0627 \u0627\u0644\u062f\u062c\u0627\u0644 \u0648\u064a\u0643\u0630\u0628\u0648\u0647 \u0627\u0630\u0627 \u0627\u062f\u0631\u0643\u0648\u0647 \u0641\u0642\u0627\u0644 \u0644\u0647\u0645 \u0627\u0644\u0646\u0628\u064a \u0635\u0644 \u0627\u0644\u0644\u0647 \u0639\u0644\u064a\u0647 \u0648\u0633\u0644\u0645 \u0644\u0647\u0645 \u0627\u0646 \u0645\u0646 \u0634\u062f\u0647 \u0641\u062a\u0646\u062a\u0647 \u0645\u0645\u0643\u0646 \u0644\u0645\u0627 \u064a\u0634\u0648\u0641\u0648\u0647 \u064a\u062a\u0628\u0639\u0648\u0647 \u0648\u064a\u0624\u0645\u0646\u0648\u0627 \u0628\u0647 \u0647\u0644 \u0645\u0645\u0643\u0646 \u062a\u062a\u062e\u064a\u0644\u0648\u0627 \u0630\u0644\u0643 \u0647\u0624\u0644\u0627\u0621 \u0647\u0645 \u0627\u0644\u0635\u062d\u0627\u0628\u0647 \u0641\u0645\u0627 \u0628\u0644\u0643\u0645 \u0628\u0646\u0627 \u0646\u062d\u0646 \u0644\u0627 \u064a\u0648\u062c\u062f \u0633\u0648\u0649 \u0645\u0624\u0645\u0646 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":36258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[114],"tags":[],"class_list":{"0":"post-26761","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-114"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/th\/wp-json\/wp\/v2\/posts\/26761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/th\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/th\/wp-json\/wp\/v2\/comments?post=26761"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/th\/wp-json\/wp\/v2\/posts\/26761\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/th\/wp-json\/wp\/v2\/media\/36258"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/th\/wp-json\/wp\/v2\/media?parent=26761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/th\/wp-json\/wp\/v2\/categories?post=26761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/th\/wp-json\/wp\/v2\/tags?post=26761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}