{"id":26440,"date":"2025-04-09T09:50:22","date_gmt":"2025-04-09T09:50:22","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=26440"},"modified":"2025-06-09T11:11:39","modified_gmt":"2025-06-09T11:11:39","slug":"5-161","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/pt\/archives\/26440","title":{"rendered":"Muitas pessoas se surpreendem que algu\u00e9m como eu, com a cren\u00e7a na jihad e essa forma de pensar, tenha continuado no ex\u00e9rcito at\u00e9 atingir o posto de major. A essas pessoas, eu digo:"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"26440\" class=\"elementor elementor-26440\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-45abd85e e-flex e-con-boxed e-con e-parent\" data-id=\"45abd85e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d49bf2c elementor-widget elementor-widget-text-editor\" data-id=\"3d49bf2c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><h1 class=\"x1gslohp\">\u00a0<\/h1><\/div><div class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">4 \u0623\u0628\u0631\u064a\u0644 2016<\/span><\/span><\/div><\/div><\/div><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Ac\u00e7\u00f5es que podem ser tomadas para este posto\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">Muitas pessoas se surpreendem que algu\u00e9m como eu, com a cren\u00e7a na jihad e essa forma de pensar, tenha continuado no ex\u00e9rcito at\u00e9 atingir o posto de major. A essas pessoas, eu digo:<br class=\"html-br\" \/>1- Eu n\u00e3o fui est\u00fapido o suficiente para dizer \u00e0 lideran\u00e7a do ex\u00e9rcito antes de entrar para o ex\u00e9rcito ou depois de me tornar oficial que estava tentando travar a jihad na Chech\u00eania, B\u00f3snia ou outros pa\u00edses isl\u00e2micos, mas essa cren\u00e7a permaneceu dentro de mim e n\u00e3o a revelei a ningu\u00e9m para n\u00e3o ser acusado de extremismo.<br class=\"html-br\" \/>2- Os livros sobre conquistas isl\u00e2micas que escrevi antes da revolu\u00e7\u00e3o n\u00e3o eram do conhecimento do ex\u00e9rcito, e sua escrita e publica\u00e7\u00e3o eram secretas, sem que eu mencionasse em meus livros que eu era um oficial. Tamb\u00e9m encurtei meu nome de Tamer Mohamed Samir Mohamed Badr para Tamer Badr apenas, para que eles n\u00e3o pudessem me alcan\u00e7ar.<br class=\"html-br\" \/>3- \u00c9 poss\u00edvel que eu tenha sido inclu\u00eddo na lista negra da intelig\u00eancia porque costumava rezar as ora\u00e7\u00f5es obrigat\u00f3rias na mesquita ou porque minha esposa e eu nos recusamos a tirar o hijab para que pud\u00e9ssemos viajar como adido militar. Portanto, eu esperava que o ex\u00e9rcito n\u00e3o me deixasse em paz at\u00e9 que eu alcan\u00e7asse o posto de general de brigada. Minha dispensa antecipada do ex\u00e9rcito era esperada para mim quando eu alcan\u00e7asse o posto de capit\u00e3o, quer eu a pedisse ou n\u00e3o.<br class=\"html-br\" \/>4- Quando entrei para o ex\u00e9rcito, alistei-me ainda jovem e tinha um objetivo: ser martirizado em uma guerra que eu considerava pr\u00f3xima entre n\u00f3s e a entidade sionista. Portanto, escolhi a infantaria para estar na vanguarda dessa guerra. Quando permaneci no ex\u00e9rcito e vi o estado em que hav\u00edamos chegado, acrescentei a esse objetivo: alcan\u00e7ar uma patente que me permitisse mudar a situa\u00e7\u00e3o atual, caso n\u00e3o fosse martirizado na guerra.<br class=\"html-br\" \/>5- Durante a revolu\u00e7\u00e3o de 25 de janeiro, eu tinha esperan\u00e7a de mudan\u00e7a, mas ela rapidamente se dissipou. Por isso, sempre participei secretamente das marchas de um milh\u00e3o de pessoas. S\u00f3 Deus sabe se eu estava sendo vigiado ou n\u00e3o, at\u00e9 anunciar minha ades\u00e3o \u00e0 revolu\u00e7\u00e3o durante os eventos de Mohamed Mahmoud. Ent\u00e3o, me tornei como um livro aberto para os servi\u00e7os de intelig\u00eancia, e eles sabiam tudo sobre mim desde a inf\u00e2ncia at\u00e9 os dias atuais.<br class=\"html-br\" \/>6- Depois de 30 de junho, n\u00e3o tive d\u00favidas de que n\u00e3o poderia continuar no ex\u00e9rcito, ent\u00e3o solicitei a aposentadoria antecipada. Apesar do meu amor pelo ex\u00e9rcito, n\u00e3o pude continuar nessas circunst\u00e2ncias.<br class=\"html-br\" \/>7- Algumas pessoas costumam perguntar: &quot;Existem oficiais como eu no ex\u00e9rcito?&quot; Eu lhes digo: &quot;Conhe\u00e7o muitos oficiais que s\u00e3o muito melhores do que eu, que s\u00e3o bem-educados e religiosamente comprometidos. Alguns deles foram tentados e mudaram, enquanto outros permanecem firmes em seus princ\u00edpios. Certamente, aqueles que permanecem firmes em seus princ\u00edpios s\u00e3o incapazes de expressar isso pelas raz\u00f5es que mencionei anteriormente.&quot;<br class=\"html-br\" \/>8- Quando algu\u00e9m me pergunta se me arrependo de ter entrado para o Col\u00e9gio Militar desde o in\u00edcio, digo que n\u00e3o. Aprendi no Ex\u00e9rcito coisas que n\u00e3o teria aprendido em nenhum outro lugar.<br class=\"html-br\" \/>9- Quando algu\u00e9m me pergunta se me arrependo de ter pedido para deixar o ex\u00e9rcito, digo que n\u00e3o. Entrei para o ex\u00e9rcito com um prop\u00f3sito espec\u00edfico. Se esse prop\u00f3sito for explorado para ganho ou prop\u00f3sitos pessoais, ent\u00e3o n\u00e3o tenho necessidade de continuar no ex\u00e9rcito.<br class=\"html-br\" \/>10- No final das contas, n\u00e3o odeio o ex\u00e9rcito, mas odeio us\u00e1-lo e explor\u00e1-lo para interesses e objetivos pessoais.<br class=\"html-br\" \/><br class=\"html-br\" \/>Tamer Badr<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>4 \u0623\u0628\u0631\u064a\u0644 2016 \u0641\u064a \u0646\u0627\u0633 \u0643\u062a\u064a\u0631\u0647 \u0628\u062a\u062a\u0639\u062c\u0628 \u0625\u0646 \u0648\u0627\u062d\u062f \u0632\u064a\u064a \u0628\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u062c\u0647\u0627\u062f \u0648\u0628\u0647\u0630\u0627 \u0627\u0644\u0641\u0643\u0631 \u0625\u0633\u062a\u0645\u0631 \u0641\u064a \u0627\u0644\u062c\u064a\u0634 \u062d\u062a\u0649 \u0648\u0635\u0644 \u0644\u0631\u062a\u0628\u0629 \u0631\u0627\u0626\u062f \u0648\u0625\u0644\u0649 \u0647\u0624\u0644\u0627\u0621 \u0623\u0642\u0648\u0644 1- \u0627\u0646\u0627 \u0644\u0645 \u0623\u0643\u0646 \u063a\u0628\u064a\u0627\u064b \u062d\u062a\u0649 \u0623\u0642\u0648\u0644 \u0644\u0642\u064a\u0627\u062f\u0627\u062a \u0627\u0644\u062c\u064a\u0634 \u0642\u0628\u0644 \u062f\u062e\u0648\u0644\u064a \u0627\u0644\u062d\u0631\u0628\u064a\u0629 \u0623\u0648 \u0628\u0639\u062f \u0623\u0646 \u0623\u0635\u0628\u062d\u062a \u0636\u0627\u0628\u0637 \u0628\u0623\u0646\u0646\u064a \u0643\u0646\u062a \u0623\u062d\u0627\u0648\u0644 \u0627\u0644\u062c\u0647\u0627\u062f \u0641\u064a \u0627\u0644\u0634\u064a\u0634\u0627\u0646 \u0623\u0648 \u0627\u0644\u0628\u0648\u0633\u0646\u0647 \u0623\u0648 \u063a\u064a\u0631\u0647\u0627 \u0645\u0646 \u0627\u0644\u0628\u0644\u0627\u062f \u0627\u0644\u0627\u0633\u0644\u0627\u0645\u064a\u0629 \u0648\u0644\u0643\u0646 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":36331,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[183,117,118],"tags":[],"class_list":{"0":"post-26440","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-183","8":"category-117","9":"category-118"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/posts\/26440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/comments?post=26440"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/posts\/26440\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/media\/36331"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/media?parent=26440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/categories?post=26440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/tags?post=26440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}