{"id":26240,"date":"2025-04-08T10:48:26","date_gmt":"2025-04-08T10:48:26","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=26240"},"modified":"2025-07-04T16:00:54","modified_gmt":"2025-07-04T16:00:54","slug":"g-132","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/pt\/archives\/26240","title":{"rendered":"Hoje, 8 de abril, marca o quarto anivers\u00e1rio da ida de alguns oficiais \u00e0 Pra\u00e7a Tahrir para protestar contra as pol\u00edticas do conselho militar."},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"26240\" class=\"elementor elementor-26240\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-139b6eaf e-flex e-con-boxed e-con e-parent\" data-id=\"139b6eaf\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4462b1de elementor-widget elementor-widget-text-editor\" data-id=\"4462b1de\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><h1 class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">8 de abril de 2015<\/span><\/span><\/h1><\/div><\/div><\/div><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Ac\u00e7\u00f5es que podem ser tomadas para este posto\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">Hoje, 8 de abril, marca o quarto anivers\u00e1rio da ida de alguns oficiais \u00e0 Pra\u00e7a Tahrir para protestar contra as pol\u00edticas do conselho militar.<br class=\"html-br\" \/>Eu deveria ter ido ao campo naquele dia, se n\u00e3o fosse pela doen\u00e7a da minha esposa e por eu t\u00ea-la levado ao hospital.<br class=\"html-br\" \/>H\u00e1 muitos rumores sobre os oficiais que participaram da revolu\u00e7\u00e3o, e o n\u00famero de c\u00e9ticos \u00e9 grande, e eu os desculpo pelo que acharam do comportamento de alguns dos oficiais que participaram da revolu\u00e7\u00e3o. Muitas pessoas come\u00e7aram a considerar a queda dos oficiais neste dia um jogo de intelig\u00eancia, e eu, \u00e9 claro, estou esperando por essas acusa\u00e7\u00f5es.<br class=\"html-br\" \/>Embora eu n\u00e3o conhe\u00e7a os oficiais que participaram da revolu\u00e7\u00e3o, exceto alguns com quem lidei depois de entrar na pris\u00e3o, mas, pelo meu acompanhamento, n\u00e3o acredito que sua descida inicial tenha sido arranjada pela intelig\u00eancia. Eu teria descido com eles naquele dia sem qualquer arranjo da intelig\u00eancia. \u00c9 certo que nenhum deles desceu \u00e0 pra\u00e7a com um arranjo da intelig\u00eancia. No entanto, vejo que eles s\u00e3o como o resto dos revolucion\u00e1rios que participaram da revolu\u00e7\u00e3o, e n\u00e3o s\u00e3o anjos. Entre os revolucion\u00e1rios que participaram da revolu\u00e7\u00e3o est\u00e3o aqueles que foram enganados, aqueles que tra\u00edram a revolu\u00e7\u00e3o, aqueles que continuaram nela, aqueles que se aposentaram da pol\u00edtica, aqueles que foram recrutados e aqueles que n\u00e3o entendem os truques da pol\u00edtica suja. Em outras palavras, os oficiais da revolu\u00e7\u00e3o s\u00e3o seres humanos como o resto dos revolucion\u00e1rios, e n\u00e3o devemos basear julgamentos sobre todos os oficiais da revolu\u00e7\u00e3o com base nas a\u00e7\u00f5es de alguns deles.<br class=\"html-br\" \/>Esperamos n\u00e3o generalizar o julgamento negativo sobre todos os oficiais da revolu\u00e7\u00e3o, para n\u00e3o prejudicar muitos deles.<br class=\"html-br\" \/><br class=\"html-br\" \/>Tamer Badr (dos oficiais de 20 de novembro)<br \/><\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>8 \u0623\u0628\u0631\u064a\u0644 2015 \u0627\u0644\u064a\u0648\u0645 8 \u0627\u0628\u0631\u064a\u0644 \u0648\u0647\u0648 \u0627\u0644\u0630\u0643\u0631\u064a \u0627\u0644\u0631\u0627\u0628\u0639\u0629 \u0644\u0646\u0632\u0648\u0644 \u0628\u0639\u0636 \u0627\u0644\u0636\u0628\u0627\u0637 \u0625\u0644\u064a \u0645\u064a\u062f\u0627\u0646 \u0627\u0644\u062a\u062d\u0631\u064a\u0631 \u0644\u0644\u0627\u0639\u062a\u0631\u0627\u0636 \u0639\u0644\u0649 \u0633\u064a\u0627\u0633\u0629 \u0627\u0644\u0645\u062c\u0644\u0633 \u0627\u0644\u0639\u0633\u0643\u0631\u064a \u0648\u0642\u062f \u0643\u0627\u0646 \u0645\u0646 \u0627\u0644\u0645\u0641\u062a\u0631\u0636 \u0646\u0632\u0648\u0644\u064a \u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u064a\u0648\u0645 \u0625\u0644\u064a \u0627\u0644\u0645\u064a\u062f\u0627\u0646 \u0644\u0648\u0644\u0627 \u0638\u0631\u0648\u0641 \u0645\u0631\u0636 \u0632\u0648\u062c\u062a\u064a \u0648\u0630\u0647\u0627\u0628\u064a \u0628\u0647\u0627 \u0625\u0644\u0649 \u0627\u0644\u0645\u0633\u062a\u0634\u0641\u064a \u0648\u0627\u0644\u0623\u0642\u0627\u0648\u064a\u0644 \u0623\u0635\u0628\u062d\u062a \u0643\u062b\u064a\u0631\u0629 \u0639\u0646 \u0627\u0644\u0636\u0628\u0627\u0637 \u0627\u0644\u0645\u0634\u0627\u0631\u0643\u064a\u0646 \u0641\u064a \u0627\u0644\u062b\u0648\u0631\u0629 \u0648\u0623\u0635\u0628\u062d \u0639\u062f\u062f \u0627\u0644\u0645\u0634\u0643\u0643\u064a\u0646 \u0643\u062b\u064a\u0631\u0648\u0646 \u0648\u0623\u0646\u0627 \u0623\u0639\u0630\u0631\u0647\u0645 \u0644\u0645\u0627 \u0648\u062c\u062f\u0648\u0647 \u0645\u0646 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":37371,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[117],"tags":[],"class_list":{"0":"post-26240","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-117"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/posts\/26240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/comments?post=26240"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/posts\/26240\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/media\/37371"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/media?parent=26240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/categories?post=26240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/tags?post=26240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}