{"id":22357,"date":"2025-03-28T20:30:43","date_gmt":"2025-03-28T20:30:43","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=22357"},"modified":"2025-04-20T08:34:17","modified_gmt":"2025-04-20T08:34:17","slug":"fdghgsfh","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/pt\/archives\/22357","title":{"rendered":"Introdu\u00e7\u00e3o do Dr. Ragheb al-Sarjani a Dias Inesquec\u00edveis"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"22357\" class=\"elementor elementor-22357\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4adb6a2 e-flex e-con-boxed e-con e-parent\" data-id=\"4adb6a2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1149a2c2 elementor-widget elementor-widget-text-editor\" data-id=\"1149a2c2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><h1 class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">13 de mar\u00e7o de 2025<\/span><\/span><\/h1><\/div><\/div><\/div><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Ac\u00e7\u00f5es que podem ser tomadas para este posto\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">Escrevi e publiquei meu segundo livro em segredo antes da revolu\u00e7\u00e3o, quando era oficial das For\u00e7as Armadas. \u00c9 o livro &quot;Dias Inesquec\u00edveis&quot;. Conheci o Professor Dr. Ragheb El-Sergany em 2010, que concordou em escrever uma introdu\u00e7\u00e3o para este livro. Era a seguinte:<\/span><\/h1><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><br class=\"html-br\" \/><strong>Introdu\u00e7\u00e3o do Dr. Ragheb al-Sarjani a Dias Inesquec\u00edveis<\/strong><\/span><\/h1><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><br class=\"html-br\" \/>A hist\u00f3ria isl\u00e2mica sofreu muita neglig\u00eancia ao longo dos anos e dos s\u00e9culos e, como resultado, muitos orientalistas e ocidentais adulteraram esta hist\u00f3ria; assim, a hist\u00f3ria emergiu de uma forma muito diferente da verdade, e as li\u00e7\u00f5es e ensinamentos perderam-se no meio destas distor\u00e7\u00f5es, tornando a hist\u00f3ria um estudo acad\u00e9mico sem sentido para os leitores.<br class=\"html-br\" \/>Perante esta situa\u00e7\u00e3o infeliz, algumas pessoas zelosas tiveram de se levantar para salvar esta longa hist\u00f3ria; de facto, para salvar a juventude mu\u00e7ulmana que n\u00e3o conseguiu encontrar uma fonte adequada e segura para ler a hist\u00f3ria da Ummah. N\u00e3o exagero se disser que o mundo inteiro - mu\u00e7ulmano ou n\u00e3o mu\u00e7ulmano - precisa desta gloriosa hist\u00f3ria isl\u00e2mica, pois o mundo nunca conheceu tal esplendor e esplendor como o que encontr\u00e1mos na nossa grande hist\u00f3ria.<br class=\"html-br\" \/>Este livro \u00e9 uma dessas novidades!<br class=\"html-br\" \/>\u00c9 um livro valioso que recolhe magistralmente um grande n\u00famero de dias decisivos na hist\u00f3ria da na\u00e7\u00e3o isl\u00e2mica e, no entanto, esta enorme cole\u00e7\u00e3o n\u00e3o provocou uma enormidade semelhante no n\u00famero de p\u00e1ginas! Isto indica a extraordin\u00e1ria mestria do autor em selecionar o \u00fatil de cada batalha e o importante de cada encontro. Esta \u00e9 talvez uma das coisas mais proeminentes que distingue este livro dos outros, pois o autor tem uma capacidade magistral de ser conciso e concentrado, de modo a que se sinta que, ao ler quatro ou cinco p\u00e1ginas sobre uma enorme batalha, se aprendeu tudo e n\u00e3o se precisa de outra informa\u00e7\u00e3o, enquanto os especialistas sabem que um historiador pode escrever volumes inteiros sobre tais batalhas!<br class=\"html-br\" \/>Come\u00e7a na \u00e9poca do Profeta, depois salta a uma velocidade adequada entre as diferentes \u00e9pocas hist\u00f3ricas, como as eras Rashidi, Om\u00edada, Ab\u00e1ssida, Ayyubid, Mameluca e Otomana, e n\u00e3o deixa de viajar geograficamente para diferentes partes do mundo; chega ao Oriente e fala das batalhas da \u00cdndia, e deixa o Oriente para o Ocidente para descrever as batalhas da Andaluzia!<br class=\"html-br\" \/>Este livro tamb\u00e9m se distingue pelo facto de falar de muitas batalhas sobre as quais muitos mu\u00e7ulmanos n\u00e3o conhecem quaisquer pormenores, e n\u00e3o exagero se disser que os mu\u00e7ulmanos n\u00e3o sabem o nome das batalhas! Basta mencionar, por exemplo, as batalhas de Ain al-Tamr, a conquista de Dibel, a batalha de Talas, a conquista de Sumnat, a batalha de Nicopolis, a batalha de Mohawks, e outras batalhas cuja men\u00e7\u00e3o foi esquecida e cujas p\u00e1ginas est\u00e3o empoeiradas, at\u00e9 que este autor veio honesta e cuidadosamente desvendar esses dias interm\u00e9dios.<br class=\"html-br\" \/>Acima de tudo, este valioso livro caracteriza-se por dois aspectos que o distinguem de muitas das obras que enchiam a biblioteca isl\u00e2mica, tornando-o \u00fanico no seu g\u00e9nero.<br class=\"html-br\" \/>Quanto \u00e0 primeira coisa: A primeira coisa \u00e9 que ele n\u00e3o se limitou \u00e0s vit\u00f3rias dos mu\u00e7ulmanos, mas mencionou com grande imparcialidade e exatid\u00e3o as grandes batalhas em que os mu\u00e7ulmanos foram derrotados! Como a Batalha de Uhud, a Batalha do Tribunal dos M\u00e1rtires, a Batalha de Aqab, e outras derrotas, e isto \u00e9, de facto, uma clara intelig\u00eancia do autor; destaca para o leitor a sua honestidade na apresenta\u00e7\u00e3o dos acontecimentos, e sublinha que os dias s\u00e3o estados entre na\u00e7\u00f5es, e n\u00e3o priva os leitores de beneficiarem das importantes li\u00e7\u00f5es destas batalhas.<br class=\"html-br\" \/>A segunda coisa \u00e9 que o autor n\u00e3o se limitou a contar os acontecimentos, como fazem muitos autores, mas aprofundou os assuntos e procurou os factores de vit\u00f3ria e as causas de derrota, de modo a que o leitor saia do livro com um conhecimento abundante das raz\u00f5es da ascens\u00e3o e queda das na\u00e7\u00f5es, atingindo assim o objetivo de contar a hist\u00f3ria; como o nosso Senhor nos mostrou quando disse: \"Havia nas suas hist\u00f3rias uma li\u00e7\u00e3o para os s\u00e1bios\" [Joseph: 111]. De facto, o autor formulou tudo isto com grande profissionalismo.<br class=\"html-br\" \/>Finalmente:<br class=\"html-br\" \/>O literalismo do autor n\u00e3o impediu que o seu estilo fosse delicado e belo, pelo que as frases do livro s\u00e3o graciosas, as suas palavras s\u00e3o requintadas e a sua apresenta\u00e7\u00e3o \u00e9 suave e agrad\u00e1vel, o que conferiu ao livro um esplendor e um esplendor.<br class=\"html-br\" \/>Embora saiba que esta \u00e9 a primeira tentativa do autor de escrever sobre assuntos militares, tenho a certeza de que nunca ser\u00e1 a \u00faltima, pois as batalhas da hist\u00f3ria isl\u00e2mica e os seus pormenores precisam de centenas de volumes e milhares de explica\u00e7\u00f5es e an\u00e1lises.<br class=\"html-br\" \/>O meu conselho para o Sr. Tamer Badr \u00e9 que renove sempre a sua inten\u00e7\u00e3o com cada livro, para que Deus Todo-Poderoso escreva os seus livros para que se espalhem e lhe d\u00ea uma grande recompensa.<br class=\"html-br\" \/>Pe\u00e7o a Al\u00e1 que fortale\u00e7a o Isl\u00e3o e os mu\u00e7ulmanos<br class=\"html-br\" \/>Dr. Ragheb Al-Sarjani<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>13 \u0645\u0627\u0631\u0633 2025 \u00a0 \u0643\u062a\u0628\u062a \u0648\u0646\u0634\u0631\u062a \u062b\u0627\u0646\u064a \u0643\u062a\u0628\u064a \u0641\u064a \u0627\u0644\u0633\u0631 \u0642\u0628\u0644 \u0627\u0644\u062b\u0648\u0631\u0629 \u0639\u0646\u062f\u0645\u0627 \u0643\u0646\u062a \u0636\u0627\u0628\u0637 \u0641\u064a \u0627\u0644\u0642\u0648\u0627\u062a \u0627\u0644\u0645\u0633\u0644\u062d\u0629 \u0648\u0647\u0648 \u0643\u062a\u0627\u0628 \u0641\u0636\u0644 \u0623\u064a\u0627\u0645 \u0644\u0627 \u062a\u0646\u0633\u0649 \u062d\u064a\u062b \u0642\u0627\u0628\u0644\u062a \u0627\u0644\u0623\u0633\u062a\u0627\u0630 \u0627\u0644\u062f\u0643\u062a\u0648\u0631 \u0631\u0627\u063a\u0628 \u0627\u0644\u0633\u0631\u062c\u0627\u0646\u064a \u0641\u064a \u0639\u0627\u0645 2010 \u0627\u0644\u0630\u064a \u0648\u0627\u0641\u0642 \u0639\u0644\u0649 \u0643\u062a\u0627\u0628\u0629 \u0645\u0642\u062f\u0645\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0643\u062a\u0627\u0628 \u0648\u0643\u0627\u0646\u062a \u0645\u0627 \u064a\u0644\u064a \u0645\u0642\u062f\u0645\u0629 \u0627\u0644\u0627\u0633\u062a\u0627\u0630 \u0627\u0644\u062f\u0643\u062a\u0648\u0631 \u0631\u0627\u063a\u0628 \u0627\u0644\u0633\u0631\u062c\u0627\u0646\u064a \u0644\u0643\u062a\u0627\u0628 \u0623\u064a\u0627\u0645 \u0644\u0627 \u062a\u0646\u0633\u0649 \u0639\u0627\u0646\u064a \u0627\u0644\u062a\u0627\u0631\u064a\u062e \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a [&hellip;]<\/p>","protected":false},"author":2,"featured_media":22358,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[115],"tags":[],"class_list":{"0":"post-22357","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-115"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/posts\/22357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/comments?post=22357"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/posts\/22357\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/media\/22358"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/media?parent=22357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/categories?post=22357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/tags?post=22357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}