{"id":21450,"date":"2025-03-26T11:16:53","date_gmt":"2025-03-26T11:16:53","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=21450"},"modified":"2025-04-17T12:26:50","modified_gmt":"2025-04-17T12:26:50","slug":"sdfgrt","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/pt\/archives\/21450","title":{"rendered":"O livro de Isa\u00edas fala com muita precis\u00e3o da grande tribula\u00e7\u00e3o que ter\u00e1 lugar no Egito"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"21450\" class=\"elementor elementor-21450\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17bf0ddd e-flex e-con-boxed e-con e-parent\" data-id=\"17bf0ddd\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5e2f04 elementor-widget elementor-widget-text-editor\" data-id=\"c5e2f04\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><h1 class=\"x1gslohp\">\u00a0<\/h1><\/div><div class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">15 de junho de 2014<\/span><\/span><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"xzpqnlu xjm9jq1 x6ikm8r x10wlt62 x10l6tqk x1i1rx1s\">\u00a0<\/span><span aria-hidden=\"true\">\u00a0<\/span><\/span><\/div><\/div><\/div><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Ac\u00e7\u00f5es que podem ser tomadas para este posto\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><strong> O livro de Isa\u00edas fala com muita precis\u00e3o da grande tribula\u00e7\u00e3o que ter\u00e1 lugar no Egito<\/strong> <\/span><\/div><\/div><\/div><\/div><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">Os livros do Antigo Testamento cont\u00eam verdade e falsidade, e n\u00e3o acreditamos neles nem desacreditamos, exceto no que \u00e9 mencionado no Alcor\u00e3o e na Sunnah a respeito de sua descren\u00e7a ou cren\u00e7a. O Mensageiro, que Deus o aben\u00e7oe e lhe d\u00ea paz, disse: &quot;Se o Povo do Livro vos disser algo, n\u00e3o acrediteis neles nem desacrediteis neles, e dizei: Cremos no que nos foi revelado e no que vos foi revelado.&quot; Narrado por Al-Bukhari e Ahmad. E at\u00e9 agora, existem textos na B\u00edblia que trazem boas novas do nosso Mestre Muhammad, que Deus o aben\u00e7oe e lhe d\u00ea paz, e eles n\u00e3o mudaram.<br class=\"html-br\" \/>O cap\u00edtulo 19 do Livro de Isa\u00edas fala detalhadamente sobre uma grande tribula\u00e7\u00e3o que ocorrer\u00e1 no Egito, mencionando suas fases, que come\u00e7am com conflitos internos, uma guerra quase civil, ou conflitos entre o povo eg\u00edpcio, a perda da ordem e a eclos\u00e3o do caos. Em seguida, menciona o colapso econ\u00f4mico e suas consequ\u00eancias, que resultar\u00e3o desse caos e conflitos. Em seguida, menciona como as figuras proeminentes das tribos eg\u00edpcias (a m\u00eddia eg\u00edpcia) ser\u00e3o enganadas naquele momento. Em seguida, menciona o Egito caindo sob um governante cruel durante esse per\u00edodo, ou como resultado disso. Essa fase dif\u00edcil, que \u00e9 a grande calamidade para o Egito, e que vemos como nada mais que uma terr\u00edvel tribula\u00e7\u00e3o, terminar\u00e1 ap\u00f3s o retorno dos eg\u00edpcios a Deus Todo-Poderoso (Deus n\u00e3o muda a condi\u00e7\u00e3o de um povo at\u00e9 que ele mude o que h\u00e1 em si mesmo). Deus lhes prover\u00e1 um governante justo que os livrar\u00e1 de suas afli\u00e7\u00f5es. Acreditamos que ele ser\u00e1 um governante de acordo com o m\u00e9todo prof\u00e9tico, se Deus quiser (o Mahdi). Depois disso, haver\u00e1 algum tipo de unidade entre o Egito e o Iraque, ap\u00f3s a qual a Palestina ser\u00e1 libertada, se Deus quiser, como mencionado no final da profecia.<br class=\"html-br\" \/>Aqui est\u00e1 o cap\u00edtulo 19 do Livro de Isa\u00edas<br class=\"html-br\" \/>1 O fardo acerca do Egito. Eis que o Senhor cavalga numa nuvem veloz e vem ao Egito. Os \u00eddolos do Egito tremer\u00e3o diante dele, e o cora\u00e7\u00e3o do Egito se derreter\u00e1 dentro deles.<br class=\"html-br\" \/>2 E incitarei eg\u00edpcios contra eg\u00edpcios, e pelejar\u00e3o cada um contra o seu irm\u00e3o, e cada um contra o seu pr\u00f3ximo, cidade contra cidade, e reino contra reino.<br class=\"html-br\" \/>3 E o esp\u00edrito do Egito se derramar\u00e1 dentro dela, e o seu conselho ser\u00e1 consumido; e consultar\u00e3o \u00eddolos, e m\u00fasicos, e adivinhos, e feiticeiros.<br class=\"html-br\" \/>4 E entregarei os eg\u00edpcios nas m\u00e3os de um senhor cruel, e um rei poderoso governar\u00e1 sobre eles, diz o Senhor Deus dos Ex\u00e9rcitos.<br class=\"html-br\" \/>5 E as \u00e1guas do mar secar\u00e3o, e o rio ficar\u00e1 seco.<br class=\"html-br\" \/>6 E os rios cheirar\u00e3o mal, e os ribeiros do Egito diminuir\u00e3o e secar\u00e3o; e os canaviais e os juncos perecer\u00e3o.<br class=\"html-br\" \/>7 E os jardins do Nilo, na margem do Nilo, e todas as fazendas do Nilo, secar\u00e3o e ser\u00e3o espalhadas, e n\u00e3o existir\u00e3o.<br class=\"html-br\" \/>8 E os pescadores gemem, e todos os que lan\u00e7am a linha no Nilo lamentam, e os que estendem a rede sobre a superf\u00edcie das \u00e1guas est\u00e3o tristes.<br class=\"html-br\" \/>9 E os que trabalham com linho penteado e os que tecem tecidos brancos ser\u00e3o envergonhados.<br class=\"html-br\" \/>10 E as suas colunas ser\u00e3o quebradas, e todos os trabalhadores ficar\u00e3o deprimidos em esp\u00edrito.<br class=\"html-br\" \/>11 Os pr\u00edncipes de Zo\u00e3 s\u00e3o tolos, e os s\u00e1bios conselheiros do fara\u00f3 s\u00e3o t\u00e3o s\u00e1bios quanto os animais. Como voc\u00eas podem dizer ao fara\u00f3: &quot;Sou filho de s\u00e1bios, filho de reis antigos?&quot;<br class=\"html-br\" \/>12 Onde est\u00e3o os teus s\u00e1bios? Que eles te digam o que o Senhor dos Ex\u00e9rcitos planejou para o Egito.<br class=\"html-br\" \/>13 Os pr\u00edncipes de Zo\u00e3 tornaram-se loucos, os pr\u00edncipes de M\u00eanfis foram enganados; ele fez o Egito se desviar, bem como os l\u00edderes das suas tribos.<br class=\"html-br\" \/>14 O Senhor misturou um esp\u00edrito perverso no meio dela; e fizeram o Egito cambalear em todas as suas obras, como o b\u00eabado cambaleia no seu v\u00f4mito.<br class=\"html-br\" \/>15 Assim, n\u00e3o haver\u00e1 no Egito obra alguma que possa ser feita pela cabe\u00e7a, pela cauda ou pelo caule da palmeira.<br class=\"html-br\" \/>16 Naquele dia o Egito ser\u00e1 como mulheres; tremer\u00e1 e tremer\u00e1 ao sacudir a m\u00e3o do Senhor dos Ex\u00e9rcitos, que ele agitar\u00e1 sobre ele.<br class=\"html-br\" \/>17 E a terra de Jud\u00e1 ser\u00e1 um terror para o Egito; todo aquele que se lembrar dela ficar\u00e1 aterrorizado por causa do ju\u00edzo que o Senhor dos Ex\u00e9rcitos executar\u00e1 contra ela.<br class=\"html-br\" \/>18 Naquele dia, haver\u00e1 cinco cidades na terra do Egito que falar\u00e3o a l\u00edngua de Cana\u00e3 e jurar\u00e3o fidelidade ao Senhor dos Ex\u00e9rcitos. Uma delas ser\u00e1 chamada Cidade do Sol.<br class=\"html-br\" \/>19 Naquele dia haver\u00e1 um altar ao Senhor no meio da terra do Egito, e uma coluna ao Senhor na sua fronteira.<br class=\"html-br\" \/>20 E ser\u00e1 um sinal e uma testemunha ao Senhor dos Ex\u00e9rcitos na terra do Egito, pois clamar\u00e3o ao Senhor por causa dos seus opressores, e ele lhes enviar\u00e1 um salvador e um defensor, e os livrar\u00e1.<br class=\"html-br\" \/>21 E o Senhor ser\u00e1 conhecido no Egito, e os eg\u00edpcios conhecer\u00e3o o Senhor naquele dia; e oferecer\u00e3o sacrif\u00edcios e ofertas, e far\u00e3o votos ao Senhor, e os cumprir\u00e3o.<br class=\"html-br\" \/>22 E o Senhor ferir\u00e1 o Egito, ferindo-o e curando-o. Ent\u00e3o eles se converter\u00e3o ao Senhor, e ele os ouvir\u00e1 e os curar\u00e1.<br class=\"html-br\" \/>23 Naquele dia haver\u00e1 uma estrada do Egito para a Ass\u00edria, e os ass\u00edrios ir\u00e3o para o Egito e os eg\u00edpcios para a Ass\u00edria, e os eg\u00edpcios adorar\u00e3o com os ass\u00edrios.<br class=\"html-br\" \/>24 Naquele dia, Israel ser\u00e1 o terceiro com o Egito e com a Ass\u00edria, uma b\u00ean\u00e7\u00e3o na terra, que o Senhor dos Ex\u00e9rcitos aben\u00e7oar\u00e1, dizendo: Bendito seja o Egito, meu povo, e a Ass\u00edria, obra das minhas m\u00e3os, e Israel, minha heran\u00e7a.\u00a0<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u00a0 15 \u064a\u0648\u0646\u064a\u0648 2014\u00a0\u00a0 \u0633\u0641\u0631 \u0623\u0634\u0639\u064a\u0627\u0621 \u064a\u062a\u0643\u0644\u0645 \u0628\u062f\u0642\u0647 \u0634\u062f\u064a\u062f\u0629 \u0639\u0646 \u0641\u062a\u0646\u0629 \u0639\u0638\u064a\u0645\u0647 \u0633\u062a\u062d\u062f\u062b \u0628\u0645\u0635\u0631 \u0623\u0633\u0641\u0627\u0631 \u0627\u0644\u0639\u0647\u062f \u0627\u0644\u0642\u062f\u064a\u0645 \u0641\u064a\u0647\u0627 \u0627\u0644\u0635\u062f\u0642 \u0648\u0627\u0644\u0643\u0630\u0628 \u0648\u0646\u062d\u0646 \u0644\u0627 \u0646\u0635\u062f\u0642\u0647\u0645 \u0648\u0644\u0627 \u0646\u0643\u0630\u0628\u0647\u0645 \u0625\u0644\u0627 \u0641\u064a\u0645\u0627 \u0648\u0631\u062f \u0641\u064a\u0647 \u062a\u0643\u0630\u064a\u0628\u0647\u0645 \u0623\u0648 \u062a\u0635\u062f\u064a\u0642\u0647\u0645 \u0645\u0646 \u0627\u0644\u0643\u062a\u0627\u0628 \u0648\u0627\u0644\u0633\u0646\u0629, \u0641\u0642\u062f \u0642\u0627\u0644\u064e \u0627\u0644\u0631\u0633\u0648\u0644 \u0639\u0644\u064a\u0647 \u0627\u0644\u0635\u0644\u0627\u0629 \u0648\u0627\u0644\u0633\u0644\u0627\u0645: (( \u0625\u0630\u0627 \u062d\u062f\u062b\u0643\u0645 \u0623\u0647\u0644 \u0627\u0644\u0643\u062a\u0627\u0628\u061b \u0641\u0644\u0627 \u062a\u0635\u062f\u0642\u0648\u0647\u0645 \u0648\u0644\u0627 \u062a\u0643\u0630\u0628\u0648\u0647\u0645\u060c \u0648\u0642\u0648\u0644\u0648\u0627: \u0622\u0645\u0646\u0627 \u0628\u0645\u0627 \u0623\u0646\u0632\u0644 \u0625\u0644\u064a\u0646\u0627 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":21451,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[114],"tags":[],"class_list":{"0":"post-21450","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-114"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/posts\/21450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/comments?post=21450"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/posts\/21450\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/media\/21451"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/media?parent=21450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/categories?post=21450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/tags?post=21450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}