{"id":21177,"date":"2025-03-25T12:49:06","date_gmt":"2025-03-25T12:49:06","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=21177"},"modified":"2025-04-26T19:01:36","modified_gmt":"2025-04-26T19:01:36","slug":"hfgffg","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/pt\/archives\/21177","title":{"rendered":"per\u00edodo recorrente de distra\u00e7\u00e3o e fadiga devido a vis\u00f5es"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"21177\" class=\"elementor elementor-21177\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-328d6c5b e-flex e-con-boxed e-con e-parent\" data-id=\"328d6c5b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6379822a elementor-widget elementor-widget-text-editor\" data-id=\"6379822a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Somente amigos que entendem do assunto de vis\u00f5es devem ler isto, mas n\u00e3o o resto, porque n\u00e3o h\u00e1 necessidade de zombaria.<br class=\"html-br\" \/>Para mim, h\u00e1 momentos em que tenho certeza de que as vis\u00f5es que tenho s\u00e3o verdadeiras.<br class=\"html-br\" \/>E \u00e0s vezes sinto que \u00e9 obra do diabo.<br class=\"html-br\" \/>Cada vez que tenho f\u00e9 que essas vis\u00f5es s\u00e3o verdadeiras, elas aumentam.<br class=\"html-br\" \/>Quando nego essas vis\u00f5es e digo que elas s\u00e3o obra de Satan\u00e1s, elas param de vir a mim.<br class=\"html-br\" \/>Passei por esses per\u00edodos mais de uma vez nos anos anteriores.<br class=\"html-br\" \/>A \u00faltima foi h\u00e1 cerca de um m\u00eas, e em um estado de desespero, onde eu sentia que nenhuma vis\u00e3o estava se realizando, ent\u00e3o eu disse a mim mesmo que essas vis\u00f5es eram obra de Satan\u00e1s para me enganar, ent\u00e3o eu n\u00e3o acreditei mais nelas, embora algumas das minhas vis\u00f5es realmente se tornassem realidade recentemente. Mas durante um per\u00edodo de desespero, tive vis\u00f5es em v\u00e1rios dias consecutivos nos quais eu estava cantando &quot;Deus \u00e9 Grande&quot;, ent\u00e3o eu me convenci de que elas eram obra de Satan\u00e1s, e como voc\u00ea disse, eu rejeitei a b\u00ean\u00e7\u00e3o e deliberadamente a esqueci e n\u00e3o a escrevi em p\u00fablico, ent\u00e3o eu realmente a esqueci, e depois disso as vis\u00f5es pararam de vir a mim desde ent\u00e3o, e j\u00e1 faz mais de um m\u00eas desde que tive vis\u00f5es, e eu fiz o mesmo h\u00e1 v\u00e1rios meses, ent\u00e3o as vis\u00f5es pararam de vir a mim por um longo tempo.<br class=\"html-br\" \/>Devo ignorar as vis\u00f5es e neg\u00e1-las para que elas parem de vir at\u00e9 mim, ou devo acreditar que elas s\u00e3o vis\u00f5es verdadeiras para que elas voltem at\u00e9 mim?<br class=\"html-br\" \/>Mas o problema de acreditar que as vis\u00f5es que tenho s\u00e3o verdadeiras \u00e9 que temo que, por causa delas, eu me desvie e um dia me encontre no meu leito de morte sem que essas vis\u00f5es se realizem. Ent\u00e3o, sentirei que Satan\u00e1s estava me enganando.<br class=\"html-br\" \/>Nos \u00faltimos anos, eu costumava ter esses sentimentos. Por um tempo, eu negava as vis\u00f5es, e ent\u00e3o elas paravam de vir at\u00e9 mim. Por um tempo, eu acreditava nessas vis\u00f5es, e ent\u00e3o elas voltavam com frequ\u00eancia. Eu tinha muitas vis\u00f5es que inclu\u00edam profetas e eventos futuros.<br class=\"html-br\" \/>Estou agora numa fase de resist\u00eancia a mim mesmo e de arrependimento pelo per\u00edodo em que neguei as vis\u00f5es que me vieram. Anseio por ver o Profeta, que Deus o aben\u00e7oe e lhe conceda paz, e sinto que a cessa\u00e7\u00e3o das minhas vis\u00f5es foi resultado da minha nega\u00e7\u00e3o dessas vis\u00f5es e da rejei\u00e7\u00e3o da b\u00ean\u00e7\u00e3o que Deus me concedeu.<br class=\"html-br\" \/>Qual \u00e9 a explica\u00e7\u00e3o para o que est\u00e1 acontecendo comigo? Isso \u00e9 normal? Qual \u00e9 o conselho?<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0627\u0644\u0623\u0635\u062f\u0642\u0627\u0621 \u0627\u0644\u0644\u064a \u0628\u064a\u0641\u0647\u0645\u0648\u0627 \u0641\u0649 \u0645\u0648\u0636\u0648\u0639 \u0627\u0644\u0631\u0624\u0649 \u0641\u0642\u0637 \u064a\u0642\u0631\u0623\u0648\u0627 \u0647\u0630\u0627 \u0627\u0644\u0643\u0644\u0627\u0645 \u0627\u0645\u0627 \u0627\u0644\u0628\u0627\u0642\u0649 \u0641\u0644\u0627 \u0639\u0644\u0634\u0627\u0646 \u0645\u0641\u064a\u0634 \u062f\u0627\u0639\u0649 \u0644\u0644\u0633\u062e\u0631\u064a\u0629\u0628\u0627\u0644\u0646\u0633\u0628\u0629 \u0644\u064a \u0647\u0646\u0627\u0643 \u0641\u062a\u0631\u0627\u062a \u064a\u0643\u0648\u0646 \u0639\u0646\u062f\u064a \u064a\u0642\u064a\u0646 \u0628\u0627\u0646 \u0627\u0644\u0631\u0624\u0649 \u0627\u0644\u0644\u0649 \u0628\u062a\u0623\u062a\u064a\u0646\u064a \u0647\u064a \u0631\u0624\u0649 \u062d\u0642\u0648\u0641\u062a\u0631\u0627\u062a \u0628\u0634\u0639\u0631 \u0627\u0646\u0647\u0627 \u0645\u0646 \u0639\u0645\u0644 \u0627\u0644\u0634\u064a\u0637\u0627\u0646\u0643\u0644 \u0644\u0645\u0627 \u064a\u0643\u0648\u0646 \u0639\u0646\u062f\u0649 \u0627\u064a\u0645\u0627\u0646 \u0627\u0646\u0647\u0627 \u0628\u062a\u0643\u0648\u0646 \u0631\u0624\u0649 \u062d\u0642 \u0628\u062a\u0632\u064a\u062f \u0647\u0630\u0647 \u0627\u0644\u0631\u0624\u0649\u0648\u0644\u0645\u0627 \u0628\u0643\u0630\u0628 \u0647\u0630\u0647 \u0627\u0644\u0631\u0624\u0649 \u0648\u0628\u0642\u0648\u0644 \u0627\u0646\u0647\u0627 \u0645\u0646 \u0639\u0645\u0644 \u0627\u0644\u0634\u064a\u0637\u0627\u0646 \u0628\u062a\u0646\u0642\u0637\u0639 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":21178,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-21177","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-1"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/posts\/21177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/comments?post=21177"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/posts\/21177\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/media\/21178"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/media?parent=21177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/categories?post=21177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/tags?post=21177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}