{"id":21138,"date":"2025-03-25T12:08:04","date_gmt":"2025-03-25T12:08:04","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=21138"},"modified":"2025-05-02T17:14:11","modified_gmt":"2025-05-02T17:14:11","slug":"ghkgh","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/pt\/archives\/21138","title":{"rendered":"Vis\u00e3o do Mahdi sendo sitiado durante a ora\u00e7\u00e3o, 2 de julho de 2023"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"21138\" class=\"elementor elementor-21138\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ac7451e e-flex e-con-boxed e-con e-parent\" data-id=\"5ac7451e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4bf6c04d elementor-widget elementor-widget-text-editor\" data-id=\"4bf6c04d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Vi o Mahdi e um grupo de pessoas sob uma das novas pontes. N\u00e3o conseguia dizer exatamente onde ficava. Era uma pra\u00e7a vazia sob a ponte, sem mesquita. Quando a ora\u00e7\u00e3o foi chamada sob a ponte, o Mahdi hesitou em ser o im\u00e3, mas deu um passo \u00e0 frente e se tornou o im\u00e3. Ele sabia que era o Mahdi, mas n\u00e3o contou a ningu\u00e9m que o acompanhava e guardou esse segredo para si.<br class=\"html-br\" \/>Na primeira rak&#039;ah, Al-Mahdi recitou Al-Fatihah, depois os dois \u00faltimos versos da Surata Al-Baqarah: \u201cO Mensageiro acreditou no que lhe foi revelado por seu Senhor, e [assim tamb\u00e9m] os crentes. Todos eles acreditaram em Allah, em Seus anjos, em Seus livros e em Seus mensageiros. N\u00e3o fazemos distin\u00e7\u00e3o entre nenhum de Seus mensageiros, e eles dizem: \u2018Ouvimos e obedecemos. Teu perd\u00e3o, nosso Senhor, e a Ti \u00e9 o destino final.\u2019 (285) Allah n\u00e3o cobra de uma alma exceto [com o que est\u00e1 dentro] de sua capacidade. Ela ter\u00e1 tudo o que ganhou e incorrer\u00e1 em tudo o que cometeu. Nosso Senhor, nenhuma alma ser\u00e1 punida por seus pecados. Repreende-nos se esquecermos ou cometermos um erro, nosso Senhor, e n\u00e3o coloques sobre n\u00f3s um fardo como o que colocaste sobre aqueles que nos antecederam. Nosso Senhor, e n\u00e3o nos sobrecarregues com aquilo que n\u00e3o temos capacidade de suportar. Perdoa-nos, perdoa-nos e tem miseric\u00f3rdia de n\u00f3s. Tu \u00e9s nosso Protetor, ent\u00e3o nos d\u00e1 a vit\u00f3ria sobre o povo descrente. (286)<br class=\"html-br\" \/>Durante a ora\u00e7\u00e3o do Mahdi, muitos soldados apareceram e cercaram o Mahdi e os fi\u00e9is que o acompanhavam. Eles sabiam que o Mahdi estava entre os que oravam, mas n\u00e3o sabiam exatamente quem era o Mahdi. Queriam saber quem era o Mahdi, e o Mahdi n\u00e3o queria se revelar, nem para os fi\u00e9is que o acompanhavam, nem para os soldados que o cercavam e para aqueles que o acompanhavam.<br class=\"html-br\" \/>Os soldados revistaram os fi\u00e9is e os aterrorizaram. Um grupo de fi\u00e9is ficou com medo das a\u00e7\u00f5es dos soldados, ent\u00e3o eles deixaram o local durante a ora\u00e7\u00e3o. Cerca de metade dos fi\u00e9is, ou menos, permaneceu com o Mahdi na ora\u00e7\u00e3o. Enquanto o Mahdi estava sentado no primeiro tashahhud, um oficial estendeu a m\u00e3o para apertar a m\u00e3o da primeira fileira de fi\u00e9is, ent\u00e3o eles apertaram as m\u00e3os. Ele fez isso para que eles soubessem quem era o Mahdi. Ent\u00e3o, ele se aproximou do Mahdi e estendeu a m\u00e3o para cumpriment\u00e1-lo durante o primeiro tashahhud. O Mahdi estendeu a m\u00e3o e a apertou, hesitante em apertar a m\u00e3o de algu\u00e9m durante a ora\u00e7\u00e3o. No entanto, o oficial n\u00e3o o reconheceu, e o Mahdi completou sua ora\u00e7\u00e3o. Ent\u00e3o, o oficial disse aos soldados que o acompanhavam: &quot;Quero os nomes de todos esses fi\u00e9is depois que terminarem de orar&quot;. O Mahdi temeu que eles o reconhecessem.<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0631\u0623\u064a\u062a \u0627\u0644\u0645\u0647\u062f\u064a \u0648\u0645\u062c\u0645\u0648\u0639\u0629 \u0645\u0646 \u0627\u0644\u0646\u0627\u0633 \u062a\u062d\u062a \u0625\u062d\u062f\u0649 \u0627\u0644\u0643\u0628\u0627\u0631\u064a \u0627\u0644\u062c\u062f\u064a\u062f\u0629 \u0648\u0644\u0645 \u0623\u0645\u064a\u0632 \u0645\u0643\u0627\u0646\u0647\u0627 \u0628\u0627\u0644\u0636\u0628\u0637 \u0648\u0642\u062f \u0643\u0627\u0646\u062a \u0633\u0627\u062d\u0629 \u062e\u0627\u0644\u064a\u0629 \u062a\u062d\u062a \u0627\u0644\u0643\u0648\u0628\u0631\u064a \u0644\u0627 \u064a\u0648\u062c\u062f \u0628\u0647\u0627 \u0645\u0633\u062c\u062f \u0648\u0639\u0646\u062f \u0625\u0642\u0627\u0645\u0629 \u0627\u0644\u0635\u0644\u0627\u0629 \u062a\u062d\u062a \u0627\u0644\u0643\u0648\u0628\u0631\u064a \u062a\u0631\u062f\u062f \u0627\u0644\u0645\u0647\u062f\u064a \u0641\u064a \u0623\u0646 \u064a\u0643\u0648\u0646 \u0627\u0644\u0625\u0645\u0627\u0645 \u0641\u064a \u062a\u0644\u0643 \u0627\u0644\u0635\u0644\u0627\u0629 \u0648\u0644\u0643\u0646\u0647 \u062a\u0642\u062f\u0645 \u0648\u0623\u0635\u0628\u062d \u0627\u0644\u0625\u0645\u0627\u0645 \u0648\u0642\u062f \u0643\u0627\u0646 \u064a\u0639\u0631\u0641 \u0623\u0646\u0647 \u0647\u0648 \u0627\u0644\u0645\u0647\u062f\u064a \u0648\u0644\u0643\u0646\u0647 \u0644\u0645 \u064a\u062e\u0628\u0631 \u0623\u062d\u062f \u0645\u0645\u0646 \u0645\u0639\u0647 \u0648\u0643\u062a\u0645 \u0647\u0630\u0627 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":21139,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[112],"tags":[],"class_list":{"0":"post-21138","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category--2021-"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/posts\/21138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/comments?post=21138"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/posts\/21138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/media\/21139"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/media?parent=21138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/categories?post=21138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/tags?post=21138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}