{"id":20487,"date":"2025-03-23T11:33:54","date_gmt":"2025-03-23T11:33:54","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=20487"},"modified":"2025-04-28T15:18:54","modified_gmt":"2025-04-28T15:18:54","slug":"gebrel","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/pt\/archives\/20487","title":{"rendered":"Vis\u00e3o do nosso Mestre Gabriel, que a paz esteja com ele, em 22 de mar\u00e7o de 2019, ap\u00f3s a ora\u00e7\u00e3o da madrugada"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"20487\" class=\"elementor elementor-20487\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2004af28 e-flex e-con-boxed e-con e-parent\" data-id=\"2004af28\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70433359 elementor-widget elementor-widget-text-editor\" data-id=\"70433359\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Eu vi que estava em um casamento popular e o irm\u00e3o da noiva veio at\u00e9 a irm\u00e3, brandiu uma adaga e a atingiu no rosto. Ent\u00e3o, o casamento se transformou em dan\u00e7a com facas e os presentes estavam brincando com facas e batendo uns nos outros. Alguns deles se divertiram batendo uns nos outros com as facas e outros estavam brincando com as facas contra a vontade. Havia um grupo de convidados que estava com medo dessa situa\u00e7\u00e3o, ent\u00e3o eles come\u00e7aram a evitar a brincadeira e ficaram em um canto do sal\u00e3o de casamento enquanto ele observava com expectativa, e ele n\u00e3o gostou da situa\u00e7\u00e3o.<br class=\"html-br\" \/>Eu estava observando o que estava acontecendo e estava de p\u00e9 entre um grupo de pessoas brincando com facas e o grupo que estava de p\u00e9 assistindo com expectativa em um canto do sal\u00e3o de casamento.<br class=\"html-br\" \/>Ent\u00e3o, um dos anjos apareceu na forma de um homem com duas pequenas asas atr\u00e1s das costas. Todo o seu corpo e roupas eram brancos com um tom bege.<br class=\"html-br\" \/>O irm\u00e3o da noiva, segurando a faca, zombou do anjo e torceu seu bra\u00e7o. Mas o anjo lhe disse: &quot;Esta \u00e9 a \u00faltima coisa que voc\u00ea far\u00e1 sem sentir dor?&quot; O irm\u00e3o da noiva ficou surpreso. Ent\u00e3o o anjo, com a maior simplicidade, levantou o irm\u00e3o da noiva e o jogou no ch\u00e3o com a m\u00e3o que o irm\u00e3o da noiva segurava. Depois disso, o sal\u00e3o ficou em sil\u00eancio.<br class=\"html-br\" \/>Ent\u00e3o o anjo e eu nos sentamos lado a lado no corredor. Perguntei quem ele era. Ele respondeu: &quot;Sou Gabriel&quot;. Fiquei surpreso e perguntei: &quot;Tudo bem se voc\u00ea vier at\u00e9 mim assim para que eu possa te ver?&quot;. Ele respondeu: &quot;Sim&quot;. Tivemos uma breve conversa da qual n\u00e3o me lembro. Ent\u00e3o Gabriel, que a paz esteja com ele, desapareceu de cena.<br class=\"html-br\" \/>Ent\u00e3o o irm\u00e3o da noiva fez exatamente o que fez comigo, e eu o joguei no ch\u00e3o, assim como Gabriel, que a paz esteja com ele, fez com ele.<br class=\"html-br\" \/>A cena ent\u00e3o me levou ao Col\u00e9gio Militar Eg\u00edpcio, onde eu havia estudado anteriormente. Eu estava praticando queda de bra\u00e7o com meus colegas oficiais e, sempre que jogava com um deles, eu o derrotava facilmente, e fazia o mesmo com todos os colegas, sem descanso, e at\u00e9 mesmo derrotava aqueles que eram maiores do que eu.<br class=\"html-br\" \/>Ent\u00e3o, levei um grupo de meus colegas oficiais para visitar uma base militar americana em Alexandria. Encontrei um desfile militar de soldados americanos no p\u00e1tio de desfile. Ent\u00e3o, um grupo de soldados mu\u00e7ulmanos americanos apareceu para mim, incluindo uma mulher mu\u00e7ulmana americana. Havia algu\u00e9m nesse grupo lendo o Alcor\u00e3o.<\/h1><p><strong>Interpreta\u00e7\u00e3o da vis\u00e3o neste v\u00eddeo<\/strong><\/p><p><iframe title=\"Vis\u00e3o do nosso Mestre Gabriel, que a paz esteja com ele, em 22 de mar\u00e7o de 2019\" width=\"800\" height=\"600\" src=\"https:\/\/www.youtube.com\/embed\/QAE9qMjltDc?list=PLGSQ8bPhLqKvbIK2NxQ1CoUA-dKyGIGlP\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0631\u0623\u064a\u062a \u0628\u0627\u0646\u0646\u0649 \u0641\u0649 \u0641\u0631\u062d \u0634\u0639\u0628\u0649 \u0648\u062c\u0627\u0621 \u0627\u062e\u0648 \u0627\u0644\u0639\u0631\u0648\u0633\u0647 \u0627\u0644\u0649 \u0623\u062e\u062a\u0647 \u0648\u0642\u0627\u0645 \u0628\u0627\u0634\u0647\u0627\u0631 \u062e\u0646\u062c\u0631 \u0648\u0636\u0631\u0628 \u0627\u062e\u062a\u0647 \u0639\u0644\u0649 \u0648\u062c\u0647\u0647\u0627 \u0628\u0627\u0644\u062e\u0646\u062c\u0631 \u062b\u0645 \u062a\u062d\u0648\u0644 \u0627\u0644\u0641\u0631\u062d \u0627\u0644\u0649 \u0631\u0642\u0635 \u0628\u0627\u0644\u0633\u0643\u0627\u0643\u064a\u0646 \u0648\u0627\u0644\u0646\u0627\u0633 \u0641\u0649 \u0627\u0644\u0641\u0631\u062d \u064a\u0644\u0639\u0628\u0648\u0646 \u0628\u0627\u0644\u0633\u0643\u0627\u0643\u064a\u0646 \u0648\u0628\u064a\u0636\u0631\u0628\u0648\u0627 \u0628\u0639\u0636\u0647\u0645 \u0627\u0644\u0628\u0639\u0636 \u0628\u0627\u0644\u0633\u0643\u0627\u0643\u064a\u0646 \u0645\u0646\u0647\u0645 \u0645\u0646 \u0643\u0627\u0646 \u0645\u0633\u062a\u0645\u062a\u0639 \u0628\u0636\u0631\u0628 \u0628\u0639\u0636\u0647\u0645 \u0627\u0644\u0628\u0639\u0636 \u0628\u0627\u0644\u0633\u0643\u0627\u0643\u064a\u0646 \u0648\u0645\u0646\u0647\u0645 \u0645\u0646 \u0643\u0627\u0646 \u064a\u0644\u0639\u0628 \u0628\u0627\u0644\u0633\u0643\u0627\u0643\u064a\u0646 \u0628\u063a\u064a\u0631 \u0631\u063a\u0628\u062a\u0647 \u0648\u0643\u0627\u0646 \u064a\u0648\u062c\u062f \u062c\u0632\u0621 \u0645\u0646 \u0627\u0644\u0645\u0639\u0632\u0648\u0645\u064a\u0646 \u0643\u0627\u0646 \u062e\u0627\u064a\u0641 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":20488,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[111],"tags":[],"class_list":{"0":"post-20487","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category--2016-2020"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/posts\/20487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/comments?post=20487"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/posts\/20487\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/media\/20488"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/media?parent=20487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/categories?post=20487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/tags?post=20487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}