{"id":20320,"date":"2025-03-21T17:44:59","date_gmt":"2025-03-21T17:44:59","guid":{"rendered":"https:\/\/white-ant-267257.hostingersite.com\/?page_id=20320"},"modified":"2025-07-31T13:33:43","modified_gmt":"2025-07-31T13:33:43","slug":"visions-2016-2020","status":"publish","type":"page","link":"https:\/\/tamerbadr.com\/pt\/visions-2016-2020","title":{"rendered":"Vis\u00f5es 2016-2020"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"20320\" class=\"elementor elementor-20320\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-325f7dc elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"325f7dc\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a5ff8d0\" data-id=\"a5ff8d0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dce55a7 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dce55a7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-07e74d4\" data-id=\"07e74d4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e7894d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"9e7894d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Roya Tamer Badr<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f5a13a elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3f5a13a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2016-2020\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a748cf0\" data-id=\"a748cf0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fbd21a elementor-widget__width-auto elementor-widget-laptop__width-initial elementor-widget-tablet__width-auto elementor-invisible elementor-widget elementor-widget-image\" data-id=\"6fbd21a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" fetchpriority=\"high\" decoding=\"async\" width=\"330\" height=\"250\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/463441143_8625855717500959_1120569030532963356_n-1.jpg\" class=\"elementor-animation-float attachment-full size-full wp-image-20368\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-0626ec7 elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-image\" data-id=\"0626ec7\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" decoding=\"async\" width=\"956\" height=\"825\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2022\/10\/about-dot-vector.png\" class=\"attachment-full size-full wp-image-883\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b661bd3 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b661bd3\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e5c672a\" data-id=\"e5c672a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1053d6 elementor-widget__width-auto elementor-absolute elementor-invisible elementor-widget elementor-widget-image\" data-id=\"e1053d6\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" decoding=\"async\" width=\"305\" height=\"227\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2022\/10\/opening-quote-icon.png\" class=\"attachment-full size-full wp-image-1947\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-1dcdb37 e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"1dcdb37\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-019de4b elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"019de4b\" data-element_type=\"widget\" data-settings=\"{&quot;pagination_type&quot;:&quot;numbers_and_prev_next&quot;,&quot;classic_columns&quot;:&quot;3&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-22321 post type-post status-publish format-standard has-post-thumbnail category-113 category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/22321\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"285\" height=\"300\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/95738856_3068743629878890_230145307160084480_n.jpg\" class=\"attachment-medium size-medium wp-image-22322\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/22321\" >\n\t\t\t\tMazdan em Malta\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t28\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>9 maio 2020Um prov\u00e9rbio antigo \u00e9 utilizado para descrever uma pessoa que fala, aconselha ou sugere mas n\u00e3o \u00e9 ouvida, e a origem do prov\u00e9rbio remonta a v\u00e1rios romances.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/22321\" aria-label=\"Read more about \u064a\u0624\u0630\u0646 \u0641\u064a \u0645\u0627\u0644\u0637\u0627\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-22299 post type-post status-publish format-standard has-post-thumbnail category-113 category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/22299\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"278\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/92948244_3010366592383261_6647614999084662784_n.jpg\" class=\"attachment-medium size-medium wp-image-22300\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/22299\" >\n\t\t\t\tA vis\u00e3o da rejei\u00e7\u00e3o do meu livro por Al-Azhar As cartas esperadas em 22 de fevereiro de 2020 tornaram-se quase todas realidade em 23 de mar\u00e7o de 2020, depois de Al-Azhar ter rejeitado o meu livro, quase um m\u00eas depois desta vis\u00e3o\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t28\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>14 de abril de 2020 A vis\u00e3o da rejei\u00e7\u00e3o do meu livro por Al-Azhar As mensagens esperadas em 22 de fevereiro de 2020 tornaram-se quase todas realidade em 23 de mar\u00e7o de 2020, depois de Al-Azhar ter rejeitado o meu livro<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/22299\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u0631\u0641\u0636 \u0627\u0644\u0623\u0632\u0647\u0631 \u0644\u0643\u062a\u0627\u0628\u064a \u0627\u0644\u0631\u0633\u0627\u0626\u0644 \u0627\u0644\u0645\u0646\u062a\u0638\u0631\u0629 \u064a\u0648\u0645 22 \u0641\u0628\u0631\u0627\u064a\u0631 2020 \u062a\u0642\u0631\u064a\u0628\u0627 \u0643\u0644\u0647\u0627 \u062a\u062d\u0642\u0642\u062a \u064a\u0648\u0645 23 \u0645\u0627\u0631\u0633 2020 \u0628\u0639\u062f \u0623\u0646 \u0631\u0641\u0636 \u0627\u0644\u0623\u0632\u0647\u0631 \u0643\u062a\u0627\u0628\u064a \u0623\u064a \u0628\u0639\u062f \u0647\u0630\u0647 \u0627\u0644\u0631\u0624\u064a\u0627 \u0628\u0634\u0647\u0631 \u062a\u0642\u0631\u064a\u0628\u0627\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-22267 post type-post status-publish format-standard has-post-thumbnail category-113 category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/22267\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"270\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/91158302_2974630042623583_339038692507123712_n.jpg\" class=\"attachment-medium size-medium wp-image-22268\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/22267\" >\n\t\t\t\tEsta \u00e9 a interpreta\u00e7\u00e3o das minhas vis\u00f5es sobre manter o livro fora de cat\u00e1logo e do\u00e1-lo\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t28\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>29 de mar\u00e7o de 2020 Esta \u00e9 a interpreta\u00e7\u00e3o das minhas vis\u00f5es relativamente \u00e0 proibi\u00e7\u00e3o de impress\u00e3o e doa\u00e7\u00e3o do livro.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/22267\" aria-label=\"Read more about \u0647\u0630\u0627 \u062a\u0623\u0648\u064a\u0644 \u0631\u0624\u064a\u0627\u064a \u0628\u062e\u0635\u0648\u0635 \u0645\u0646\u0639 \u0627\u0644\u0643\u062a\u0627\u0628 \u0645\u0646 \u0627\u0644\u0637\u0628\u0639 \u0648\u0627\u0644\u062a\u0635\u062f\u0642 \u0628\u0647\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-22222 post type-post status-publish format-standard has-post-thumbnail category-121 category-113 category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/22222\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"70\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/84964379_2860574907362431_1650564225434648576_n.jpg\" class=\"attachment-medium size-medium wp-image-22223\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/22222\" >\n\t\t\t\tA rela\u00e7\u00e3o entre o livro das cartas esperadas e as vis\u00f5es que tive\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t28\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>5 de fevereiro de 2020 A rela\u00e7\u00e3o entre o livro As Mensagens Esperadas e as vis\u00f5es que tive Muitos pensaram que meu livro As Mensagens Esperadas era uma interpreta\u00e7\u00e3o das vis\u00f5es dos sinais da Hora e que eu usava vis\u00f5es<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/22222\" aria-label=\"Read more about \u0627\u0644\u0639\u0644\u0627\u0642\u0629 \u0628\u064a\u0646 \u0643\u062a\u0627\u0628 \u0627\u0644\u0631\u0633\u0627\u0626\u0644 \u0627\u0644\u0645\u0646\u062a\u0638\u0631\u0629 \u0648\u0627\u0644\u0631\u0624\u0649 \u0627\u0644\u062a\u064a \u0631\u0623\u064a\u062a\u0647\u0627\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-21103 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/21103\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"126\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/472528301_9086252944794565_5732122463549045896_n.jpg\" class=\"attachment-medium size-medium wp-image-21104\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/21103\" >\n\t\t\t\tVis\u00e3o de Takbir, Adhan e do Ex\u00e9rcito de Liberta\u00e7\u00e3o da Palestina em 21 de agosto de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t25\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Vi o ex\u00e9rcito mu\u00e7ulmano se preparando para libertar a Palestina, e de frente para ele estava o ex\u00e9rcito de ocupa\u00e7\u00e3o sionista. Ent\u00e3o, gritei &quot;Deus \u00e9 Grande&quot; pela primeira vez, mas o ex\u00e9rcito mu\u00e7ulmano n\u00e3o respondeu. Ent\u00e3o, gritei mais uma vez:<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/21103\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u0627\u0644\u062a\u0643\u0628\u064a\u0631 \u0648\u0627\u0644\u0623\u0630\u0627\u0646 \u0648\u062c\u064a\u0634 \u062a\u062d\u0631\u064a\u0631 \u0641\u0644\u0633\u0637\u064a\u0646 \u064a\u0648\u0645 21 \u0623\u063a\u0633\u0637\u0633 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-21100 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/21100\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"197\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/124978955_3590805384339376_3265339189722945119_n.jpg\" class=\"attachment-medium size-medium wp-image-21101\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/21100\" >\n\t\t\t\tUma vis\u00e3o da luta do Profeta \ufdfa e do Mahdi antes da ora\u00e7\u00e3o do amanhecer em 11 de novembro de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t25\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Vi o Profeta, que Deus o aben\u00e7oe e lhe d\u00ea paz, lutando com sua espada na Batalha de Uhud, e com ele estavam nosso mestre Abu Bakr e nosso mestre Umar, que Deus esteja satisfeito com ambos. E quando o Profeta, que Deus o aben\u00e7oe e lhe d\u00ea paz, estava exausto da batalha, sentou-se.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/21100\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u062c\u0647\u0627\u062f \u0627\u0644\u0646\u0628\u064a \ufdfa \u0648\u0627\u0644\u0645\u0647\u062f\u064a \u0642\u0628\u0644 \u0635\u0644\u0627\u0629 \u0641\u062c\u0631 \u064a\u0648\u0645 11 \u0646\u0648\u0641\u0645\u0628\u0631 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-21097 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/21097\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"223\" height=\"300\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/122450204_3536061599813755_7886048940607229532_n.jpg\" class=\"attachment-medium size-medium wp-image-21098\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/21097\" >\n\t\t\t\tVis\u00e3o de uvas vermelhas e um anjo rei em 22 de outubro de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t25\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Eu vi que estava fazendo um serm\u00e3o religioso para as pessoas e estava dizendo a elas que o Profeta, que Deus o aben\u00e7oe e lhe d\u00ea paz, costumava dizer: Eu sou o caminho para Deus, ent\u00e3o quem quiser alcan\u00e7\u00e1-lo\u2026<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/21097\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u0627\u0644\u0639\u0646\u0628 \u0627\u0644\u0623\u062d\u0645\u0631 \u0648\u0645\u0644\u0643 \u0645\u0646 \u0627\u0644\u0645\u0644\u0627\u0626\u0643\u0629 \u064a\u0648\u0645 22 \u0623\u0643\u062a\u0648\u0628\u0631 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-21094 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/21094\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"244\" height=\"300\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/118958197_3396225233797393_6298300285887472210_n.jpg\" class=\"attachment-medium size-medium wp-image-21095\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/21094\" >\n\t\t\t\tUma vis\u00e3o de soldados eg\u00edpcios recitando a Surat Al-Qamar em 5 de setembro de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t25\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Vi duas fileiras de soldados eg\u00edpcios vestindo macac\u00f5es camuflados, dispostos em duas fileiras regulares, cerca de dez em n\u00famero, divididos em duas fileiras, uma atr\u00e1s da outra, e as duas fileiras, cada uma<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/21094\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u062a\u0644\u0627\u0648\u0629 \u0627\u0644\u0639\u0633\u0643\u0631\u064a\u064a\u0646 \u0627\u0644\u0645\u0635\u0631\u064a\u064a\u0646 \u0644\u0633\u0648\u0631\u0629 \u0627\u0644\u0642\u0645\u0631 \u064a\u0648\u0645 5 \u0633\u0628\u062a\u0645\u0628\u0631 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20895 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20895\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"198\" height=\"300\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/117035044_3288035644616353_5306596156081396040_n.jpg\" class=\"attachment-medium size-medium wp-image-20896\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/20895\" >\n\t\t\t\tUma vis\u00e3o das dez esposas na manh\u00e3 do Dia de Arafah, 30 de julho de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Tive um sonho estranho. N\u00e3o sei se foi uma vis\u00e3o ou um sonho real. Sonhei que um jovem elefante me casou com sete lindas garotas somalis. Depois que as casei, ele me casou com mais tr\u00eas.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20895\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u0627\u0644\u0632\u0648\u062c\u0627\u062a \u0627\u0644\u0639\u0634\u0631 \u0635\u0628\u0627\u062d \u064a\u0648\u0645 \u0639\u0631\u0641\u0629 \u064a\u0648\u0645 30 \u064a\u0648\u0644\u064a\u0648 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20892 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20892\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/100702203_3125459810873938_9211415698306236416_n.jpg\" class=\"attachment-medium size-medium wp-image-20893\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/20892\" >\n\t\t\t\tVis\u00e3o do c\u00edrculo religioso com os judeus no final de maio de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Eu vi que estava convidando pessoas para assistir a uma aula de religi\u00e3o isl\u00e2mica ou algo assim, e um judeu veio at\u00e9 mim e sentou-se na minha frente enquanto ouvia minha palestra sobre religi\u00e3o isl\u00e2mica.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20892\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u0627\u0644\u062d\u0644\u0642\u0629 \u0627\u0644\u062f\u064a\u0646\u064a\u0629 \u0645\u0639 \u0627\u0644\u064a\u0647\u0648\u062f \u0641\u064a \u0646\u0647\u0627\u064a\u0629 \u0645\u0627\u064a\u0648 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20889 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20889\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/98071103_3092324924187427_3230106540950159360_n.jpg\" class=\"attachment-medium size-medium wp-image-20890\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/20889\" >\n\t\t\t\tVis\u00e3o de trai\u00e7\u00e3o e tempestade de areia em 18 de maio de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Percebi que estava em um ve\u00edculo de transporte militar com cerca de cinco soldados. O ve\u00edculo n\u00e3o tinha motorista, mas estava avan\u00e7ando, e um oficial que eu conhecia estava sentado ao meu lado.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20889\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u0627\u0644\u062e\u064a\u0627\u0646\u0629 \u0648\u0627\u0644\u0639\u0627\u0635\u0641\u0629 \u0627\u0644\u0631\u0645\u0644\u064a\u0629 \u064a\u0648\u0645 18 \u0645\u0627\u064a\u0648 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20886 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20886\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"300\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/96808926_3080453128707940_3986101809604198400_n.jpg\" class=\"attachment-medium size-medium wp-image-20887\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/20886\" >\n\t\t\t\tVis\u00e3o do ex\u00e9rcito do afundamento da terra no dia 21 do Ramad\u00e3, correspondente a 14 de maio de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Eu vi que estava em frente \u00e0 Caaba no momento do juramento de fidelidade ao Mahdi, e as pessoas no santu\u00e1rio estavam repetindo muito: &quot;Deus \u00e9 Grande, Deus \u00e9 Grande&quot;. Ent\u00e3o a cena me levou para ver a entidade sionista.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20886\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u062c\u064a\u0634 \u0627\u0644\u062e\u0633\u0641 \u064a\u0648\u0645 21 \u0631\u0645\u0636\u0627\u0646 \u0627\u0644\u0645\u0648\u0627\u0641\u0642 14 \u0645\u0627\u064a\u0648 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20883 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20883\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/94377535_3038284656258121_633257043343441920_n.jpg\" class=\"attachment-medium size-medium wp-image-20884\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/20883\" >\n\t\t\t\tUma vis\u00e3o do momento da grande erup\u00e7\u00e3o vulc\u00e2nica e da fuma\u00e7a vis\u00edvel em 26 de abril de 2020.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Percebi que estava em uma das cidades americanas perto do local do enorme vulc\u00e3o Yulston antes de sua explos\u00e3o, e isso foi nas primeiras horas da manh\u00e3, depois do amanhecer e antes do nascer do sol.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20883\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u0644\u062d\u0638\u0629 \u0627\u0646\u0641\u062c\u0627\u0631 \u0627\u0644\u0628\u0631\u0643\u0627\u0646 \u0627\u0644\u0647\u0627\u0626\u0644 \u0648\u0627\u0644\u062f\u062e\u0627\u0646 \u0627\u0644\u0645\u0628\u064a\u0646 \u0628\u0648\u0645 26 \u0627\u0628\u0631\u064a\u0644 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20880 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20880\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/93848012_3028783417208245_8616528548460494848_n.jpg\" class=\"attachment-medium size-medium wp-image-20881\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/20880\" >\n\t\t\t\tVis\u00e3o da can\u00e7\u00e3o f\u00fanebre na Palestine TV em 22 de abril de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Eu vi que estava sentado com meu irm\u00e3o Tariq e na nossa frente estava a televis\u00e3o, assistindo a uma m\u00fasica palestina chamada &quot;Al-Jana&#039;iz&quot; no Canal Palestina, e as cenas da m\u00fasica eram sobre a resist\u00eancia palestina \u00e0 ocupa\u00e7\u00e3o sionista.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20880\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u0623\u063a\u0646\u064a\u0629 \u0627\u0644\u062c\u0646\u0627\u0626\u0632 \u0639\u0644\u0649 \u0642\u0646\u0627\u0629 \u0641\u0644\u0633\u0637\u064a\u0646 \u064a\u0648\u0645 22 \u0627\u0628\u0631\u064a\u0644 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20877 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20877\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/93837108_3026914860728434_5644094503099826176_n.jpg\" class=\"attachment-medium size-medium wp-image-20878\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/20877\" >\n\t\t\t\tA vis\u00e3o de Tamer Badr e o furac\u00e3o em 21 de abril de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>A Irm\u00e3 Mooka Ahmed teve uma vis\u00e3o na qual disse: \u201cVi meu bom irm\u00e3o, Tamer Badr, entrando no meu quarto, e eu estava sentada em uma cama. A cama era t\u00e3o alta que Tamer Badr\u2026\u201d<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20877\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u062a\u0627\u0645\u0631 \u0628\u062f\u0631 \u0648\u0627\u0644\u0627\u0639\u0635\u0627\u0631 \u064a\u0648\u0645 21 \u0627\u0628\u0631\u064a\u0644 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20874 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20874\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"294\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/92543308_3003569559729631_3350026653534257152_n.jpg\" class=\"attachment-medium size-medium wp-image-20875\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/20874\" >\n\t\t\t\tVis\u00e3o do C\u00e9u e as Tr\u00eas Mulheres Veladas em 11 de abril de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Eu vi que estava visitando o Para\u00edso e estava olhando de cima para uma pequena parte do Para\u00edso onde vi uma praia com \u00e1gua azul clara e areia muito branca e l\u00e1<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20874\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u0627\u0644\u062c\u0646\u0629 \u0648\u0627\u0644\u0645\u0646\u062a\u0642\u0628\u0627\u062a \u0627\u0644\u062b\u0644\u0627\u062b\u0629 \u064a\u0648\u0645 11 \u0625\u0628\u0631\u064a\u0644 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20871 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20871\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"198\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/92951810_2994710573948863_5394538387598213120_n.jpg\" class=\"attachment-medium size-medium wp-image-20872\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/20871\" >\n\t\t\t\tVis\u00e3o de receber a unidade m\u00e9dica e Surat Ad-Dukhan em 7 de abril de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Vi minha irm\u00e3 Amal me ligando para me dizer que o estado havia fornecido apoio m\u00e9dico como resultado da epidemia de Corona e ela me pediu para ir \u00e0 unidade m\u00e9dica para marcar uma consulta<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20871\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u0627\u0633\u062a\u0642\u0628\u0627\u0644 \u0627\u0644\u0648\u062d\u062f\u0629 \u0627\u0644\u0637\u0628\u064a\u0629 \u0648\u0633\u0648\u0631\u0629 \u0627\u0644\u062f\u062e\u0627\u0646 \u064a\u0648\u0645 7 \u0627\u0628\u0631\u064a\u0644 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20868 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20868\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"156\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/91512675_2988292977923956_1603186591516327936_n.jpg\" class=\"attachment-medium size-medium wp-image-20869\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/20868\" >\n\t\t\t\tVis\u00e3o de Jesus, que a paz esteja com ele, e as palavras de suas caracter\u00edsticas em 4 de abril de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Eu vi que nosso mestre Jesus, que a paz esteja com ele, saiu de um t\u00famulo desconhecido e estava deitado em uma cama e as pessoas estavam reunidas ao redor dele e perguntavam sobre sua vida passada e ele estava acordado e disse:<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20868\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u0633\u064a\u062f\u0646\u0627 \u0639\u064a\u0633\u0649 \u0639\u0644\u064a\u0647 \u0627\u0644\u0633\u0644\u0627\u0645 \u0648\u0643\u0644\u0645\u0629 \u0634\u064e\u0645\u064e\u0627\u0626\u0650\u0644\u0650\u0647\u0650\u0645\u0652 \u064a\u0648\u0645 4 \u0627\u0628\u0631\u064a\u0644 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20865 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20865\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/91976994_2990195177733736_1490257268350910464_n.jpg\" class=\"attachment-medium size-medium wp-image-20866\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/20865\" >\n\t\t\t\tVis\u00e3o da epidemia de Corona e o vers\u00edculo (Ent\u00e3o, quando removemos o castigo deles, eles imediatamente quebraram sua promessa) 5 de abril de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Tive uma vis\u00e3o de um telefone me dizendo que a epidemia de Corona \u00e9 um sinal de alerta que ser\u00e1 revelado por Deus Todo-Poderoso quando as pessoas se arrependerem e que isso<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20865\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u0648\u0628\u0627\u0621 \u0643\u0648\u0631\u0648\u0646\u0627 \u0648\u0622\u064a\u0629 ( \u0641\u064e\u0644\u064e\u0645\u0651\u064e\u0627 \u0643\u064e\u0634\u064e\u0641\u0652\u0646\u064e\u0627 \u0639\u064e\u0646\u0652\u0647\u064f\u0645\u064f \u0627\u0644\u0652\u0639\u064e\u0630\u064e\u0627\u0628\u064e \u0625\u0650\u0630\u064e\u0627 \u0647\u064f\u0645\u0652 \u064a\u064e\u0646\u0643\u064f\u062b\u064f\u0648\u0646\u064e ) \u064a\u0648\u0645 5 \u0627\u0628\u0631\u064a\u0644 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20860 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20860\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/90174931_2958617134224874_2416002864452206592_n.jpg\" class=\"attachment-medium size-medium wp-image-20861\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/20860\" >\n\t\t\t\tVis\u00f5es de Jesus, que a paz esteja com ele, e a palestra de treinamento de combate em 22 de mar\u00e7o de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Percebi que estava em uma sala fechada, de tamanho m\u00e9dio, com v\u00e1rios combatentes, como se estiv\u00e9ssemos em uma reuni\u00e3o de guerra. Ent\u00e3o, nosso Mestre Jesus, que a paz esteja com ele, entrou, ent\u00e3o o recebi e o aconselhei.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20860\" aria-label=\"Read more about \u0631\u0624\u064a \u0633\u064a\u062f\u0646\u0627 \u0639\u064a\u0633\u0649 \u0639\u0644\u064a\u0647 \u0627\u0644\u0633\u0644\u0627\u0645 \u0648\u0645\u062d\u0627\u0636\u0631\u0629 \u0627\u0644\u062a\u062f\u0631\u064a\u0628 \u0639\u0644\u0649 \u0627\u0644\u0642\u062a\u0627\u0644 \u064a\u0648\u0645 22 \u0645\u0627\u0631\u0633 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20857 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20857\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"230\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/88396001_2925557327530855_5567178132819017728_n.jpg\" class=\"attachment-medium size-medium wp-image-20858\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/20857\" >\n\t\t\t\tUma vis\u00e3o de vender peixe cru e depois do\u00e1-lo como caridade em 7 de mar\u00e7o de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Em uma vis\u00e3o que tive hoje, acredito que esteja relacionada ao meu livro. Espero que voc\u00ea consiga interpret\u00e1-la. Vi que havia mercadorias compostas de peixes crus de todos os tipos sendo vendidas no supermercado. Observe que...<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20857\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u0628\u064a\u0639 \u0627\u0644\u0623\u0633\u0645\u0627\u0643 \u0627\u0644\u0646\u064a\u0629 \u062b\u0645 \u0627\u0644\u062a\u0635\u062f\u0642 \u0628\u0647\u0627 \u064a\u0648\u0645 7 \u0645\u0627\u0631\u0633 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20854 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20854\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/87469361_2924124681007453_8360292728021450752_n.jpg\" class=\"attachment-medium size-medium wp-image-20855\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/20854\" >\n\t\t\t\tUma vis\u00e3o de algumas pessoas rezando com roupas do Ihram na Mesquita Al-Hussein em 6 de mar\u00e7o de 2020.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Eu vi que entrei na Mesquita Al-Hussein no Cairo com minhas roupas normais e estava rezando, mas vi algumas pessoas entrando na mesquita com roupas do Ihram, ent\u00e3o fiquei surpreso com a forma como as pessoas entram<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20854\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u0635\u0644\u0627\u0629 \u0628\u0639\u0636 \u0627\u0644\u0646\u0627\u0633 \u0628\u0645\u0644\u0627\u0628\u0633 \u0627\u0644\u0625\u062d\u0631\u0627\u0645 \u0628\u0645\u0633\u062c\u062f \u0627\u0644\u062d\u0633\u064a\u0646 \u064a\u0648\u0645 6 \u0645\u0627\u0631\u0633 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20851 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20851\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"175\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/90147575_2959767010776553_2212034674291638272_n.jpg\" class=\"attachment-medium size-medium wp-image-20852\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/20851\" >\n\t\t\t\tA Vis\u00e3o da Terra est\u00e1 se preparando para o aparecimento do Mahdi em 1\u00ba de mar\u00e7o de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Esta \u00e9 uma vis\u00e3o que hesitei em publicar quando a vi. Duvidei que fosse uma vis\u00e3o, pois pensava que era apenas um pensamento, mas a acelera\u00e7\u00e3o dos eventos que estamos vivendo agora me faz sentir que \u00e9...<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20851\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u0627\u0644\u0623\u0631\u0636 \u062a\u062a\u062c\u0647\u0632 \u0644\u0638\u0647\u0648\u0631 \u0627\u0644\u0645\u0647\u062f\u0649 \u0641\u0649 \u0627\u0648\u0644 \u0645\u0627\u0631\u0633 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20848 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20848\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/ScreenShot001-5.jpg\" class=\"attachment-medium size-medium wp-image-20849\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/20848\" >\n\t\t\t\tUma vis\u00e3o de Gabriel, que a paz esteja com ele, ensinando ao Mahdi o Alcor\u00e3o e sua interpreta\u00e7\u00e3o em meados de janeiro de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Eu vi o Mahdi em p\u00e9 e na frente dele estava nosso mestre Gabriel, que a paz esteja com ele, mas nosso mestre Gabriel, que a paz esteja com ele, n\u00e3o estava vis\u00edvel para mim, mas eu podia senti-lo e nosso mestre<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20848\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u062a\u0644\u0642\u064a\u0646 \u0633\u064a\u062f\u0646\u0627 \u062c\u0628\u0631\u064a\u0644 \u0639\u0644\u064a\u0647 \u0627\u0644\u0633\u0644\u0627\u0645 \u0644\u0644\u0645\u0647\u062f\u0649 \u0627\u0644\u0642\u0631\u0622\u0646 \u0648\u062a\u0641\u0633\u064a\u0631\u0647 \u0645\u0646\u062a\u0635\u0641 \u064a\u0646\u0627\u064a\u0631 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20840 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20840\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/87118841_2896121823807739_5388127208311095296_n-1.jpg\" class=\"attachment-medium size-medium wp-image-20841\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/20840\" >\n\t\t\t\tVis\u00e3o da rejei\u00e7\u00e3o do meu livro, The Expected Letters, pela Al-Azhar, em 22 de fevereiro de 2020.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Eu me vi navegando pelas p\u00e1ginas do Facebook no meu celular at\u00e9 que parei em um videoclipe do programa de Omar Adeeb mostrando uma foto da capa do meu livro.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20840\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u0631\u0641\u0636 \u0627\u0644\u0623\u0632\u0647\u0631 \u0644\u0643\u062a\u0627\u0628\u064a \u0627\u0644\u0631\u0633\u0627\u0626\u0644 \u0627\u0644\u0645\u0646\u062a\u0638\u0631\u0629 \u064a\u0648\u0645 22 \u0641\u0628\u0631\u0627\u064a\u0631 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20837 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20837\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/86290959_2883603071726281_4600321165594984448_n-1.jpg\" class=\"attachment-medium size-medium wp-image-20838\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/20837\" >\n\t\t\t\tA vis\u00e3o do islamismo sobre as pessoas ap\u00f3s verem a lua se abrindo antes da ora\u00e7\u00e3o do Fajr em 16 de fevereiro de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Acredito que essa vis\u00e3o tenha uma conex\u00e3o direta com a vis\u00e3o que tive anteontem sobre a divis\u00e3o da lua em 14 de fevereiro de 2020. A vis\u00e3o que tive foi que os cidad\u00e3os da Austr\u00e1lia se converteram ao islamismo depois...<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20837\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u0625\u0633\u0644\u0627\u0645 \u0646\u0627\u0633 \u0628\u0639\u062f \u0631\u0624\u064a\u0629 \u0627\u0646\u0634\u0642\u0627\u0642 \u0627\u0644\u0642\u0645\u0631 \u0642\u0628\u0644 \u0635\u0644\u0627\u0629 \u0641\u062c\u0631 \u064a\u0648\u0645 16 \u0641\u0628\u0631\u0627\u064a\u0631 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20834 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20834\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"298\" height=\"169\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/89654650_2927529100667011_3750886048738050048_n.jpg\" class=\"attachment-medium size-medium wp-image-20835\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/20834\" >\n\t\t\t\tUma vis\u00e3o de mim indo para a pris\u00e3o por causa do livro &quot;Cartas&quot; previsto para fevereiro de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Vi que fui para a pris\u00e3o e havia outra pessoa na cela, ent\u00e3o perguntei a um deles por que ele tinha ido para a pris\u00e3o. Ele me disse que era por causa da minha participa\u00e7\u00e3o na Revolu\u00e7\u00e3o de Janeiro. Ele me perguntou o que<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20834\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u062f\u062e\u0648\u0644\u064a \u0627\u0644\u0633\u062c\u0646 \u0628\u0633\u0628\u0628 \u0643\u062a\u0627\u0628 \u0627\u0644\u0631\u0633\u0627\u0626\u0644 \u0627\u0644\u0645\u0646\u062a\u0638\u0631\u0629 \u0641\u064a \u0641\u0628\u0631\u0627\u064a\u0631 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20831 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20831\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"198\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/86171734_2879642612122327_2589489869281558528_n.jpg\" class=\"attachment-medium size-medium wp-image-20832\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/20831\" >\n\t\t\t\tVis\u00e3o da lua se partindo em 14 de fevereiro de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Eu vi a lua e ela tinha uma rachadura no sentido do comprimento de cima para baixo e eu estava dizendo Deus \u00e9 Grande Deus \u00e9 Grande e eu recitei Surat Al-Qamar na \u00edntegra enquanto eu estava chorando e ent\u00e3o eu olhei<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20831\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u0627\u0646\u0634\u0642\u0627\u0642 \u0627\u0644\u0642\u0645\u0631 \u064a\u0648\u0645 14 \u0641\u0628\u0631\u0627\u064a\u0631 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20828 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20828\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"160\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/85023820_2873237266096195_4987656383093538816_n.jpg\" class=\"attachment-medium size-medium wp-image-20829\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/20828\" >\n\t\t\t\tUma vis\u00e3o do mart\u00edrio de Ikrimah ibn Abi Jahl em 11 de fevereiro de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Vi Ikrimah ibn Abi Jahl lutando pela causa de Deus em batalha at\u00e9 ser apunhalado no est\u00f4mago com uma espada. A interpreta\u00e7\u00e3o da vis\u00e3o est\u00e1 neste v\u00eddeo.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20828\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u0627\u0633\u062a\u0634\u0647\u0627\u062f \u0639\u0643\u0631\u0645\u0629 \u0628\u0646 \u0627\u0628\u064a \u062c\u0647\u0644 \u064a\u0648\u0645 11 \u0641\u0628\u0631\u0627\u064a\u0631 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20822 post type-post status-publish format-standard has-post-thumbnail category--2016-2020\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20822\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"300\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/03\/84586769_2868832279870027_7526324952333549568_n.jpg\" class=\"attachment-medium size-medium wp-image-20823\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/20822\" >\n\t\t\t\tUma vis\u00e3o do Alcor\u00e3o dividido em partes e o nome Tamer antes do amanhecer de 9 de fevereiro de 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24\/03\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Eu vi que estava em frente a uma pequena biblioteca e entre os livros \u00e0 minha frente estava o Alcor\u00e3o dividido em cerca de dez volumes (mais ou menos um pouco) e os volumes do Alcor\u00e3o estavam<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/20822\" aria-label=\"Read more about \u0631\u0624\u064a\u0627 \u0627\u0644\u0645\u0635\u062d\u0641 \u0627\u0644\u0645\u0642\u0633\u0645 \u0625\u0644\u0649 \u0623\u062c\u0632\u0627\u0621 \u0648\u0627\u0633\u0645 \u062a\u0627\u0645\u0631 \u0642\u0628\u0644 \u0641\u062c\u0631 \u064a\u0648\u0645 9 \u0641\u0628\u0631\u0627\u064a\u0631 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"e-load-more-anchor\" data-page=\"1\" data-max-page=\"3\" data-next-page=\"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/pages\/20320\/page\/2\"><\/div>\n\t\t\t\t<nav class=\"elementor-pagination\" aria-label=\"Pagination\">\n\t\t\t<span class=\"page-numbers prev\">\" Anterior<\/span>\n<span aria-current=\"page\" class=\"page-numbers current\"><span class=\"elementor-screen-only\">Page<\/span>1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/pages\/20320\/page\/2\"><span class=\"elementor-screen-only\">Page<\/span>2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/pages\/20320\/page\/3\"><span class=\"elementor-screen-only\">Page<\/span>3<\/a>\n<a class=\"page-numbers next\" href=\"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/pages\/20320\/page\/2\">Seguinte \"<\/a>\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f0c0ab6 elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"f0c0ab6\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ada810\" data-id=\"4ada810\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bde9d00 elementor-widget__width-auto elementor-absolute elementor-invisible elementor-widget elementor-widget-image\" data-id=\"bde9d00\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" decoding=\"async\" width=\"305\" height=\"227\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2022\/10\/opening-quote-icon.png\" class=\"attachment-full size-full wp-image-1947\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Vis\u00f5es de Tamer Badr 2016-2020<\/p>","protected":false},"author":1,"featured_media":4468,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-20320","page","type-page","status-publish","has-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/pages\/20320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/comments?post=20320"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/pages\/20320\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/media\/4468"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/media?parent=20320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}