{"id":20291,"date":"2025-03-21T17:33:10","date_gmt":"2025-03-21T17:33:10","guid":{"rendered":"https:\/\/white-ant-267257.hostingersite.com\/?page_id=20291"},"modified":"2025-07-31T13:29:10","modified_gmt":"2025-07-31T13:29:10","slug":"individual","status":"publish","type":"page","link":"https:\/\/tamerbadr.com\/pt\/individual","title":{"rendered":"Pessoal"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"20291\" class=\"elementor elementor-20291\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-325f7dc elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"325f7dc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a5ff8d0\" data-id=\"a5ff8d0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dce55a7 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dce55a7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-07e74d4\" data-id=\"07e74d4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f5ba851 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"f5ba851\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Tamer Badr<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f5a13a elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3f5a13a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pessoal<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80f5872 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"80f5872\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>H\u00e1 quem se surpreenda que uma pessoa como eu, com a cren\u00e7a na jihad e esse pensamento, tenha continuado no ex\u00e9rcito at\u00e9 atingir o posto de major. A esses eu digo:<\/h4><h1>1- Eu n\u00e3o fui est\u00fapido o suficiente para dizer \u00e0 lideran\u00e7a do ex\u00e9rcito antes de entrar para o ex\u00e9rcito ou depois de me tornar oficial que estava tentando travar a jihad na Chech\u00eania, B\u00f3snia ou outros pa\u00edses isl\u00e2micos, mas essa cren\u00e7a permaneceu dentro de mim e n\u00e3o a revelei a ningu\u00e9m para n\u00e3o ser acusado de extremismo.<br \/>2- Os livros sobre conquistas isl\u00e2micas que escrevi antes da revolu\u00e7\u00e3o n\u00e3o eram do conhecimento do ex\u00e9rcito, e sua escrita e publica\u00e7\u00e3o eram secretas, sem que eu mencionasse em meus livros que eu era um oficial. Tamb\u00e9m encurtei meu nome de Tamer Mohamed Samir Mohamed Badr para Tamer Badr apenas, para que eles n\u00e3o pudessem me alcan\u00e7ar.<br \/>3- \u00c9 poss\u00edvel que eu tenha sido inclu\u00eddo na lista negra da intelig\u00eancia porque costumava rezar as ora\u00e7\u00f5es obrigat\u00f3rias na mesquita ou porque minha esposa e eu nos recusamos a tirar o hijab para que pud\u00e9ssemos viajar como adido militar. Portanto, eu esperava que o ex\u00e9rcito n\u00e3o me deixasse em paz at\u00e9 que eu alcan\u00e7asse o posto de general de brigada. Minha dispensa antecipada do ex\u00e9rcito era esperada para mim quando eu alcan\u00e7asse o posto de capit\u00e3o, quer eu a pedisse ou n\u00e3o.<br \/>4- Quando entrei para o ex\u00e9rcito, alistei-me ainda jovem e tinha um objetivo: ser martirizado em uma guerra que eu considerava pr\u00f3xima entre n\u00f3s e a entidade sionista. Portanto, escolhi a infantaria para estar na vanguarda dessa guerra. Quando permaneci no ex\u00e9rcito e vi o estado em que hav\u00edamos chegado, acrescentei a esse objetivo: alcan\u00e7ar uma patente que me permitisse mudar a situa\u00e7\u00e3o atual, caso n\u00e3o fosse martirizado na guerra.<br \/>5- Durante a revolu\u00e7\u00e3o de 25 de janeiro, eu tinha esperan\u00e7a de mudan\u00e7a, mas ela rapidamente se dissipou. Por isso, sempre participei secretamente das marchas de um milh\u00e3o de pessoas. S\u00f3 Deus sabe se eu estava sendo vigiado ou n\u00e3o, at\u00e9 anunciar minha ades\u00e3o \u00e0 revolu\u00e7\u00e3o durante os eventos de Mohamed Mahmoud. Ent\u00e3o, me tornei como um livro aberto para os servi\u00e7os de intelig\u00eancia, e eles sabiam tudo sobre mim desde a inf\u00e2ncia at\u00e9 os dias atuais.<br \/>6- Depois de 30 de junho, n\u00e3o tive d\u00favidas de que n\u00e3o poderia continuar no ex\u00e9rcito, ent\u00e3o solicitei a aposentadoria antecipada. Apesar do meu amor pelo ex\u00e9rcito, n\u00e3o pude continuar nessas circunst\u00e2ncias.<br \/>7- Algumas pessoas costumam perguntar: &quot;Existem oficiais como eu no ex\u00e9rcito?&quot; Eu lhes digo: &quot;Conhe\u00e7o muitos oficiais que s\u00e3o muito melhores do que eu, que s\u00e3o bem-educados e religiosamente comprometidos. Alguns deles foram tentados e mudaram, enquanto outros permanecem firmes em seus princ\u00edpios. Certamente, aqueles que permanecem firmes em seus princ\u00edpios s\u00e3o incapazes de expressar isso pelas raz\u00f5es que mencionei anteriormente.&quot;<br \/>8- Quando algu\u00e9m me pergunta se me arrependo de ter entrado para o Col\u00e9gio Militar desde o in\u00edcio, digo que n\u00e3o. Aprendi no Ex\u00e9rcito coisas que n\u00e3o teria aprendido em nenhum outro lugar.<br \/>9- Quando algu\u00e9m me pergunta se me arrependo de ter pedido para deixar o ex\u00e9rcito, digo que n\u00e3o. Entrei para o ex\u00e9rcito com um prop\u00f3sito espec\u00edfico. Se esse prop\u00f3sito for explorado para ganho ou prop\u00f3sitos pessoais, ent\u00e3o n\u00e3o tenho necessidade de continuar no ex\u00e9rcito.<br \/>10- No final das contas, n\u00e3o odeio o ex\u00e9rcito, mas odeio us\u00e1-lo e explor\u00e1-lo para interesses e objetivos pessoais.<\/h1><h6>Tamer Badr<\/h6>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a748cf0\" data-id=\"a748cf0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2693d2c elementor-widget__width-auto elementor-widget-laptop__width-initial elementor-widget-tablet__width-auto elementor-invisible elementor-widget elementor-widget-image\" data-id=\"2693d2c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/5410520.jpg\" class=\"elementor-animation-float attachment-full size-full wp-image-36331\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a356fd elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-image\" data-id=\"2a356fd\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" decoding=\"async\" width=\"956\" height=\"825\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2022\/10\/about-dot-vector.png\" class=\"attachment-full size-full wp-image-883\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ffeb2d1 elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"ffeb2d1\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8d6efff\" data-id=\"8d6efff\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f8f605 elementor-widget__width-auto elementor-absolute elementor-invisible elementor-widget elementor-widget-image\" data-id=\"5f8f605\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" decoding=\"async\" width=\"305\" height=\"227\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2022\/10\/opening-quote-icon.png\" class=\"attachment-full size-full wp-image-1947\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-10c58c4 e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"10c58c4\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-88b4d05 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"88b4d05\" data-element_type=\"widget\" data-settings=\"{&quot;pagination_type&quot;:&quot;numbers_and_prev_next&quot;,&quot;classic_columns&quot;:&quot;3&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-36894 post type-post status-publish format-standard has-post-thumbnail category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/36894\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"106\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/07\/4566.jpg\" class=\"attachment-medium size-medium wp-image-36895\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/36894\" >\n\t\t\t\tSignificado do nome Tamer\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t03\/07\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>19 de novembro de 2018. Esta \u00e9 a primeira vez que tenho conhecimento desta informa\u00e7\u00e3o. O significado do nome Tamer. O nome Tamer \u00e9 originalmente um nome turco e significa o soldado ideal. Em hebraico, significa rico.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/36894\" aria-label=\"Read more about \u0645\u0639\u0646\u0649 \u0625\u0633\u0645 \u062a\u0627\u0645\u0631\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-27015 post type-post status-publish format-standard has-post-thumbnail category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/27015\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"199\" height=\"300\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/6-9.jpg\" class=\"attachment-medium size-medium wp-image-36735\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/27015\" >\n\t\t\t\tEles exclu\u00edram minha conta e rejeitaram minha foto por me considerarem uma pessoa perigosa. Deus nos basta e \u00e9 o melhor Dispensador de todos os nossos problemas.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t10\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\t1 coment\u00e1rio\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>31 de janeiro de 2024. Eles exclu\u00edram minha conta e rejeitaram minha foto por me considerarem uma pessoa perigosa. Deus nos basta e \u00e9 o melhor Dispensador de todos os nossos problemas.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/27015\" aria-label=\"Read more about \u062d\u0630\u0641\u0648\u0627 \u062d\u0633\u0627\u0628\u064a \u0648\u0631\u0641\u0636\u0648\u0627 \u0635\u0648\u0631\u062a\u064a \u0644\u0623\u0646\u0647\u0645 \u0628\u064a\u0639\u062a\u0628\u0631\u0648\u0646\u064a \u0645\u0646 \u0627\u0644\u0623\u0641\u0631\u0627\u062f \u0627\u0644\u062e\u0637\u0631\u064a\u0646 \u0648\u062d\u0633\u0628\u0646\u0627 \u0627\u0644\u0644\u0647 \u0648\u0646\u0639\u0645 \u0627\u0644\u0648\u0643\u064a\u0644\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-27012 post type-post status-publish format-standard has-post-thumbnail category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/27012\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"187\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/55-2.jpg\" class=\"attachment-medium size-medium wp-image-36737\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/27012\" >\n\t\t\t\tInfelizmente, todas as minhas tentativas de recuperar minha conta principal do Facebook, que criei em 2011, falharam.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t10\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>31 de janeiro de 2024 Infelizmente, todas as minhas tentativas de recuperar minha conta principal do Facebook, que criei em 2011, falharam. Al\u00e9m disso, toda vez que publico minha foto normal, eles me amea\u00e7am.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/27012\" aria-label=\"Read more about \u0644\u0644\u0623\u0633\u0641 \u0643\u0644 \u0645\u062d\u0627\u0648\u0644\u0627\u062a\u064a \u0641\u0634\u0644\u062a \u0641\u064a \u0627\u0633\u062a\u0639\u0627\u062f\u0629 \u062d\u0633\u0627\u0628\u064a \u0627\u0644\u0631\u0626\u064a\u0633\u064a \u0639\u0644\u0649 \u0627\u0644\u0641\u064a\u0633 \u0627\u0644\u0630\u064a \u0623\u0646\u0634\u0623\u062a\u0647 \u0645\u0646\u0630 \u0639\u0627\u0645 2011\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26987 post type-post status-publish format-standard has-post-thumbnail category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26987\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/6546-2.jpg\" class=\"attachment-medium size-medium wp-image-36849\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26987\" >\n\t\t\t\tSe eu pudesse voltar no tempo para aqueles eventos, eu anunciaria minha ades\u00e3o \u00e0 revolu\u00e7\u00e3o.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t10\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>19 de novembro de 2020 Os eventos de Mohamed Mahmoud 2011 permanecer\u00e3o o ponto de virada mais importante em toda a minha vida, de um oficial das for\u00e7as armadas a um civil protestando na pra\u00e7a, ent\u00e3o<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26987\" aria-label=\"Read more about \u0648\u0644\u0648 \u0639\u0627\u062f \u0628\u064a \u0627\u0644\u0632\u0645\u0646 \u0645\u0631\u0629 \u0623\u062e\u0631\u0649 \u0623\u062b\u0646\u0627\u0621 \u062a\u0644\u0643 \u0627\u0644\u0623\u062d\u062f\u0627\u062b \u0641\u0633\u0623\u0639\u0644\u0646 \u0627\u0646\u0636\u0645\u0627\u0645\u064a \u0627\u0644\u0649 \u0627\u0644\u062b\u0648\u0631\u0629\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26959 post type-post status-publish format-standard has-post-thumbnail category-121 category-117 category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26959\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/8567.jpg\" class=\"attachment-medium size-medium wp-image-36851\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26959\" >\n\t\t\t\tA lista de acusa\u00e7\u00f5es dirigidas a mim pela maioria das pessoas de 2011 a 2020\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t10\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>2 de junho de 2020 A lista de acusa\u00e7\u00f5es dirigidas a mim pela maioria das pessoas de 2011 a 2020. A maioria de voc\u00eas pensou em todas as seguintes acusa\u00e7\u00f5es contra mim, quer voc\u00ea as tenha declarado<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26959\" aria-label=\"Read more about \u0644\u0627\u0626\u062d\u0629 \u0627\u0644\u0627\u062a\u0647\u0627\u0645\u0627\u062a \u0627\u0644\u062a\u064a \u0648\u062c\u0647\u062a \u0644\u064a \u0645\u0646 \u0623\u063a\u0644\u0628 \u0627\u0644\u0646\u0627\u0633 \u0645\u0646\u0630 2011 \u0648\u062d\u062a\u0649 2020\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26956 post type-post status-publish format-standard has-post-thumbnail category-121 category-117 category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26956\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"280\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/7865.jpg\" class=\"attachment-medium size-medium wp-image-36853\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26956\" >\n\t\t\t\tNa vida de cada um de n\u00f3s existe um Brutus\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t10\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>25 de abril de 2020 Na vida de cada um de n\u00f3s existe um Brutus, mas a diferen\u00e7a entre mim e voc\u00ea \u00e9 que conheci muitas pessoas a quem Brutus se aplica, um n\u00famero que perdi a conta, especialmente<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26956\" aria-label=\"Read more about \u0641\u064a \u062d\u064a\u0627\u0629 \u0643\u0644 \u0645\u0646\u0627 \u0628\u0631\u0648\u062a\u0633\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26946 post type-post status-publish format-standard has-post-thumbnail category-117 category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26946\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"138\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/8-3.jpg\" class=\"attachment-medium size-medium wp-image-36856\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26946\" >\n\t\t\t\tEles fecharam a Umrah por tempo indeterminado.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>5 de mar\u00e7o de 2020. No ano passado, n\u00e3o consegui realizar a Umrah durante o Ramad\u00e3 por causa das taxas para repeti-la. Este ano, depois de reservar a Umrah inteira durante o Ramad\u00e3 e pagar o valor, encontrei-os...<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26946\" aria-label=\"Read more about \u0642\u0641\u0644\u0648\u0627 \u0627\u0644\u0639\u0645\u0631\u0629 \u0627\u0644\u0649 \u0627\u062c\u0644 \u063a\u064a\u0631 \u0645\u0633\u0645\u0649\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26921 post type-post status-publish format-standard has-post-thumbnail category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26921\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"189\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/678.jpg\" class=\"attachment-medium size-medium wp-image-36858\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26921\" >\n\t\t\t\tFiquei em segundo lugar no n\u00edvel do Uber Egito em termos de avalia\u00e7\u00e3o dos capit\u00e3es pelos clientes do Uber com uma classifica\u00e7\u00e3o de 5 estrelas, gra\u00e7as a Deus.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Em 8 de agosto de 2019, fiquei em segundo lugar no ranking da Uber Egito em termos de avalia\u00e7\u00e3o dos clientes da Uber com 5 estrelas, gra\u00e7as a Deus. Observa\u00e7\u00e3o: a Uber n\u00e3o...<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26921\" aria-label=\"Read more about \u062d\u0635\u0644\u062a \u0639\u0644\u0649 \u0627\u0644\u0645\u0631\u0643\u0632 \u0627\u0644\u062b\u0627\u0646\u064a \u0639\u0644\u0649 \u0645\u0633\u062a\u0648\u0649 \u0627\u0648\u0628\u0631 \u0645\u0635\u0631 \u0645\u0646 \u062d\u064a\u062b \u062a\u0642\u064a\u064a\u0645 \u0639\u0645\u0644\u0627\u0621 \u0627\u0648\u0628\u0631 \u0644\u0644\u0643\u0628\u0627\u062a\u0646 \u0628\u062a\u0642\u064a\u064a\u0645 \u0665 \u0646\u062c\u0648\u0645 \u0648\u0644\u0644\u0647 \u0627\u0644\u062d\u0645\u062f\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26918 post type-post status-publish format-standard has-post-thumbnail category-117 category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26918\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"209\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/9-4.jpg\" class=\"attachment-medium size-medium wp-image-36860\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26918\" >\n\t\t\t\tComo eg\u00edpcio, vou torcer pela Arg\u00e9lia e esperar que eles ven\u00e7am e conquistem o t\u00edtulo africano.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>18 de julho de 2019 Infelizmente, o esporte est\u00e1 sendo usado para criar uma divis\u00e3o entre os povos \u00e1rabes com prop\u00f3sitos pol\u00edticos sujos. Rejeito a tentativa de criar uma divis\u00e3o entre os povos eg\u00edpcio e argelino. O Egito ajudou a Arg\u00e9lia em...<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26918\" aria-label=\"Read more about \u0623\u0646\u0627 \u0643\u0645\u0635\u0631\u064a \u0633\u0623\u0634\u062c\u0639 \u0627\u0644\u062c\u0632\u0627\u0626\u0631 \u0648\u0627\u062a\u0645\u0646\u0649 \u0644\u0647\u0627 \u0627\u0644\u0641\u0648\u0632 \u0648\u0627\u0644\u062d\u0635\u0648\u0644 \u0639\u0644\u0649 \u0627\u0644\u0644\u0642\u0628 \u0627\u0644\u0623\u0641\u0631\u064a\u0642\u0649\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26909 post type-post status-publish format-standard has-post-thumbnail category-121 category-117 category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26909\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"129\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/87658.jpg\" class=\"attachment-medium size-medium wp-image-36865\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26909\" >\n\t\t\t\tAs piores facadas que j\u00e1 recebi na vida foram aquelas que me foram dadas nas costas por aqueles que estavam comigo no campo.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>1 de julho de 2019 Osama Abbas, o dono da famosa foto durante a revolu\u00e7\u00e3o, na qual ele enxugava as l\u00e1grimas do oficial do ex\u00e9rcito que protegia a pra\u00e7a durante a revolu\u00e7\u00e3o, e que um dia foi<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26909\" aria-label=\"Read more about \u0627\u0633\u0648\u0621 \u0627\u0644\u0637\u0639\u0646\u0627\u062a \u0627\u0644\u062a\u0649 \u062a\u0639\u0631\u0636\u062a \u0644\u0647\u0627 \u0641\u0649 \u062d\u064a\u0627\u062a\u0649 \u0647\u0649 \u0627\u0644\u062a\u0649 \u0637\u0639\u0646\u062a\u0649 \u0641\u0649 \u0638\u0647\u0631\u0649 \u0645\u0645\u0646 \u0643\u0646\u062a \u0645\u0639\u0647\u0645 \u0641\u0649 \u0627\u0644\u0645\u064a\u062f\u0627\u0646\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26902 post type-post status-publish format-standard has-post-thumbnail category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26902\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"285\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/546345.jpg\" class=\"attachment-medium size-medium wp-image-36867\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26902\" >\n\t\t\t\tFiz 5.000 viagens de Uber em mais de dois anos e meio.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>27 de maio de 2019: Completei 5.000 viagens com a Uber em mais de dois anos e meio, per\u00edodo em que aprendi muito lidando com milhares de personalidades e nacionalidades. Atualiza\u00e7\u00e3o<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26902\" aria-label=\"Read more about \u0648\u0635\u0644\u062a \u0644\u062e\u0645\u0633\u0629 \u0622\u0644\u0627\u0641 \u0631\u062d\u0644\u0629 \u0645\u0639 \u0627\u0648\u0628\u0631 \u0641\u0649 \u0627\u0643\u062a\u0631 \u0645\u0646 \u0633\u0646\u062a\u064a\u0646 \u0648\u0646\u0635\u0641\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26880 post type-post status-publish format-standard has-post-thumbnail category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26880\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/654757.jpg\" class=\"attachment-medium size-medium wp-image-36871\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26880\" >\n\t\t\t\tA quest\u00e3o n\u00e3o \u00e9 o n\u00famero de anos em que voc\u00ea foi mu\u00e7ulmano, mas sim o seu servi\u00e7o ao islamismo, mesmo que esse per\u00edodo tenha sido curto.\u00a0\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>9 de mar\u00e7o de 2019, enquanto eu trabalhava na Uber hoje, o grupo de brasileiros que est\u00e1 comigo nesta foto viajou comigo. Eles s\u00e3o do Rio de Janeiro. Fiquei surpreso que um deles fosse...<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26880\" aria-label=\"Read more about \u0627\u0644\u0639\u0628\u0631\u0629 \u0645\u0634 \u0628\u0639\u062f\u062f \u0627\u0644\u0633\u0646\u064a\u0646 \u0627\u0644\u0644\u0649 \u0643\u0646\u062a\u0645 \u0641\u064a\u0647\u0627 \u0645\u0633\u0644\u0645\u064a\u0646 \u0628\u0644 \u0627\u0644\u0639\u0628\u0631\u0629 \u0628\u062e\u062f\u0645\u062a\u0643 \u0644\u0644\u0627\u0633\u0644\u0627\u0645 \u062d\u062a\u0649 \u0648\u0644\u0648 \u0643\u0627\u0646\u062a \u0647\u0630\u0647 \u0627\u0644\u0645\u062f\u0647 \u0642\u0635\u064a\u0631\u0629\u00a0\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26868 post type-post status-publish format-standard has-post-thumbnail category-183 category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26868\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"174\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/05105.png\" class=\"attachment-medium size-medium wp-image-36293\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26868\" >\n\t\t\t\tCaxemira\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>27 de fevereiro de 2019 Por ocasi\u00e3o da tens\u00e3o que atualmente ocorre entre a \u00cdndia e o Paquist\u00e3o devido \u00e0 Caxemira, que \u00e9 uma regi\u00e3o mu\u00e7ulmana sob controle indiano, esta regi\u00e3o traz lembran\u00e7as comigo quando<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26868\" aria-label=\"Read more about \u0643\u0634\u0645\u064a\u0631\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26865 post type-post status-publish format-standard has-post-thumbnail category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26865\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"272\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/2346.jpg\" class=\"attachment-medium size-medium wp-image-36873\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26865\" >\n\t\t\t\tInven\u00e7\u00e3o da m\u00e1quina do tempo\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>25 de fevereiro de 2019 A \u00fanica inven\u00e7\u00e3o que vejo em filmes de fic\u00e7\u00e3o cient\u00edfica que gostaria de ver na realidade \u00e9 a inven\u00e7\u00e3o de uma m\u00e1quina do tempo, onde eu possa entrar nessa m\u00e1quina<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26865\" aria-label=\"Read more about \u0625\u062e\u062a\u0631\u0627\u0639 \u0622\u0644\u0629 \u0627\u0644\u0632\u0645\u0646\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26843 post type-post status-publish format-standard has-post-thumbnail category-117 category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26843\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"292\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/080.jpg\" class=\"attachment-medium size-medium wp-image-36875\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26843\" >\n\t\t\t\tN\u00e3o ficarei na fila e direi n\u00e3o, a menos que haja garantias de que meu voto ser\u00e1 contado.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>10 de fevereiro de 2019 N\u00e3o estou disposto a ficar na fila para tirar fotos para que o mundo inteiro possa me ver e ent\u00e3o no final eu entro em uma sala fechada e escrevo nela e ningu\u00e9m pode me ver escrevendo<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26843\" aria-label=\"Read more about \u0645\u0634 \u0647\u0646\u0632\u0644 \u0648\u0627\u0642\u0641 \u0637\u0627\u0628\u0648\u0631 \u0648\u0627\u0642\u0648\u0644 \u0644\u0627 \u0627\u0644\u0627 \u0644\u0645\u0627 \u064a\u0643\u0648\u0646 \u0641\u0649 \u0636\u0645\u0627\u0646\u0627\u062a \u0627\u0646 \u0635\u0648\u062a\u0649 \u0647\u064a\u062a\u062d\u0633\u0628\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26826 post type-post status-publish format-standard has-post-thumbnail category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26826\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"178\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/76587.jpg\" class=\"attachment-medium size-medium wp-image-36877\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26826\" >\n\t\t\t\tDeus \u00e9 suficiente para n\u00f3s, e Ele \u00e9 o melhor Dispositor de assuntos, em rela\u00e7\u00e3o \u00e0queles que cobram taxas pelas visitas \u00e0 Grande Mesquita.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>14 de janeiro de 2019 Deus nos basta e \u00e9 o melhor Dispensador de todos os assuntos. Aqueles que imp\u00f5em multas, impostos ou qualquer outro nome \u00e0queles que visitam a Sagrada Casa de Deus s\u00e3o...<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26826\" aria-label=\"Read more about \u062d\u0633\u0628\u0646\u0627 \u0627\u0644\u0644\u0647 \u0648\u0646\u0639\u0645 \u0627\u0644\u0648\u0643\u064a\u0644 \u0641\u0649 \u0627\u0644\u0644\u0649 \u0628\u064a\u0641\u0631\u0636 \u0631\u0633\u0648\u0645 \u0639\u0644\u0649 \u0632\u064a\u0627\u0631\u0629 \u0627\u0644\u0645\u0633\u062c\u062f \u0627\u0644\u062d\u0631\u0627\u0645\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26823 post type-post status-publish format-standard has-post-thumbnail category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26823\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"264\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/65865.jpg\" class=\"attachment-medium size-medium wp-image-36882\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26823\" >\n\t\t\t\t\u00d3 Deus, que transformas os cora\u00e7\u00f5es, firma meu cora\u00e7\u00e3o em Tua religi\u00e3o.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>20 de janeiro de 2019 H\u00e1 algum tempo tenho medo de ser um daqueles sobre quem o Mensageiro de Deus, que Deus o aben\u00e7oe e lhe d\u00ea paz, disse: \u201cO trabalhador far\u00e1 o trabalho do povo de\u2026\u201d<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26823\" aria-label=\"Read more about \u0627\u0644\u0644\u0647\u0645 \u064a\u0627 \u0645\u0642\u0644\u0628 \u0627\u0644\u0642\u0644\u0648\u0628 \u062b\u0628\u062a \u0642\u0644\u0628\u064a \u0639\u0644\u0649 \u062f\u064a\u0646\u0643\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26792 post type-post status-publish format-standard has-post-thumbnail category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26792\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/687967.jpg\" class=\"attachment-medium size-medium wp-image-36884\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26792\" >\n\t\t\t\tPreciso que eles orem de cora\u00e7\u00e3o por mim para que Deus expanda meu peito, facilite minhas coisas e me guie pelo caminho certo.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>18 de dezembro de 2018 Tenho milhares de amigos no Facebook e preciso que eles orem de cora\u00e7\u00e3o por mim para que Deus expanda meu peito, facilite minhas coisas e que meu Senhor me guie<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26792\" aria-label=\"Read more about \u0648\u0625\u0646\u0646\u064a \u0645\u062d\u062a\u0627\u062c \u0645\u0646\u0647\u0645 \u062f\u0639\u0648\u0629 \u0645\u0646 \u0627\u0644\u0642\u0644\u0628 \u0644\u0649 \u0628\u0623\u0646 \u064a\u0634\u0631\u062d \u0627\u0644\u0644\u0647 \u0635\u062f\u0631\u064a \u0648\u0623\u0646 \u064a\u064a\u0633\u0631 \u0623\u0645\u0631\u064a \u0648\u0627\u0646 \u064a\u0647\u062f\u064a\u0646\u0649 \u0631\u0628\u064a \u0627\u0644\u0649 \u0627\u0644\u0637\u0631\u064a\u0642 \u0627\u0644\u0635\u062d\u064a\u062d\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26786 post type-post status-publish format-standard has-post-thumbnail category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26786\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/7798.jpg\" class=\"attachment-medium size-medium wp-image-36886\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26786\" >\n\t\t\t\tMeu av\u00f4 Abdullah Al-Kamil Al-Mahd bin Al-Hassan Al-Muthanna bin Al-Hassan Al-Sabt bin Imam Ali, que Deus esteja satisfeito com ele\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>28 de novembro de 2018 Meu av\u00f4 \u00e9 Abdullah Al-Kamil Al-Muhdh bin Al-Hassan Al-Muthanna bin Al-Hassan Al-Sabt bin Imam Ali, que Deus esteja satisfeito com ele, e Fatima Al-Zahra, que Deus esteja satisfeito com ela.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26786\" aria-label=\"Read more about \u062c\u062f\u064a \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0627\u0644\u0643\u0627\u0645\u0644 \u0627\u0644\u0645\u062d\u0636 \u0628\u0646 \u0627\u0644\u062d\u0633\u0646 \u0627\u0644\u0645\u062b\u0646\u0649 \u0628\u0646 \u0627\u0644\u062d\u0633\u0646 \u0627\u0644\u0633\u0628\u0637 \u0628\u0646 \u0627\u0644\u0625\u0645\u0627\u0645 \u0639\u0644\u064a \u0643\u0631\u0645 \u0627\u0644\u0644\u0647 \u0648\u062c\u0647\u0647\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26783 post type-post status-publish format-standard has-post-thumbnail category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26783\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/0099.jpg\" class=\"attachment-medium size-medium wp-image-36888\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26783\" >\n\t\t\t\t\u00d3 Deus, perdoa-nos, tem miseric\u00f3rdia de n\u00f3s e purifica os nossos cora\u00e7\u00f5es, \u00f3 Senhor do mundo.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>27 de novembro de 2018 \u00d3 Deus, perdoa-nos, tem miseric\u00f3rdia de n\u00f3s e purifica os nossos cora\u00e7\u00f5es, \u00f3 Senhor do Mundo.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26783\" aria-label=\"Read more about \u0627\u0644\u0644\u0647\u0645 \u0627\u063a\u0641\u0631 \u0644\u0646\u0627 \u0648\u0627\u0631\u062d\u0645\u0646\u0627 \u0648\u0637\u0647\u0631 \u0642\u0644\u0648\u0628\u0646\u0627 \u064a\u0627 \u0631\u0628 \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u0646\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26780 post type-post status-publish format-standard has-post-thumbnail category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26780\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/0990.jpg\" class=\"attachment-medium size-medium wp-image-36890\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26780\" >\n\t\t\t\tMeu av\u00f4, Imam Hassan bin Ali, que Deus esteja satisfeito com ambos\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>26 de novembro de 2018 Meu av\u00f4, Imam Hassan bin Ali, que Deus esteja satisfeito com ambos<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26780\" aria-label=\"Read more about \u062c\u062f\u064a \u0627\u0644\u0625\u0645\u0627\u0645 \u0627\u0644\u062d\u0633\u0646 \u0628\u0646 \u0639\u0644\u064a \u0631\u0636\u064a \u0627\u0644\u0644\u0647 \u0639\u0646\u0647\u0645\u0627\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26777 post type-post status-publish format-standard has-post-thumbnail category-117 category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26777\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"192\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/6546-3.jpg\" class=\"attachment-medium size-medium wp-image-36892\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26777\" >\n\t\t\t\tOs eventos de Mohamed Mahmoud permanecer\u00e3o sempre em minha mem\u00f3ria com todos os seus detalhes.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>19 de novembro de 2018. Ainda n\u00e3o esqueci aqueles que foram feridos e martirizados ao meu lado nos eventos de Mohamed Mahmoud, e n\u00e3o esqueci meus companheiros nesses eventos. Os eventos de Mohamed Mahmoud permanecer\u00e3o<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26777\" aria-label=\"Read more about \u0633\u062a\u0638\u0644 \u0623\u062d\u062f\u0627\u062b \u0645\u062d\u0645\u062f \u0645\u062d\u0645\u0648\u062f \u0641\u0649 \u0630\u0627\u0643\u0631\u062a\u064a \u062f\u0627\u0626\u0645\u0627 \u0628\u0643\u0644 \u062a\u0641\u0627\u0635\u064a\u0644\u0647\u0627\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26768 post type-post status-publish format-standard has-post-thumbnail category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26768\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"241\" height=\"300\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/878.jpg\" class=\"attachment-medium size-medium wp-image-36900\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26768\" >\n\t\t\t\tFico muito feliz quando encontro soldados que estiveram comigo h\u00e1 muito tempo e ainda me lembram deles.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>19 de outubro de 2018. Fico muito feliz quando encontro soldados que estiveram comigo h\u00e1 muito tempo e que ainda me lembram. Que Deus os aben\u00e7oe e me perdoe por n\u00e3o me lembrar dos soldados que estiveram comigo.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26768\" aria-label=\"Read more about \u0628\u0643\u0648\u0646 \u0633\u0639\u064a\u062f \u062c\u062f\u0627 \u0644\u0645\u0627 \u0627\u0644\u0627\u0642\u0649 \u0639\u0633\u0627\u0643\u0631 \u0643\u0627\u0646\u0648\u0627 \u0645\u0639\u0627\u064a\u0627 \u0645\u0646 \u0632\u0645\u0627\u0646 \u0648\u0644\u0633\u0647 \u0641\u0643\u0631\u0646\u0649\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26757 post type-post status-publish format-standard has-post-thumbnail category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26757\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/\u0634\u0647\u0627\u062f\u0629-\u0627\u0644\u0646\u0633\u0628-1917-1-scaled.jpg\" class=\"attachment-medium size-medium wp-image-36902\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26757\" >\n\t\t\t\tUm certificado de linhagem do Sindicato dos Nobres Cavalheiros do Egito para um membro da fam\u00edlia Asal.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>28 de setembro de 2018 Um certificado de linhagem do Sindicato dos Nobres do Egito para um membro da minha fam\u00edlia, a fam\u00edlia Asal, da nobreza Idrisid, descendentes do Imam Hassan.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26757\" aria-label=\"Read more about \u0634\u0647\u0627\u062f\u0629 \u0646\u0633\u0628 \u0645\u0646 \u0646\u0642\u0627\u0628\u0629 \u0627\u0644\u0633\u0627\u062f\u0629 \u0627\u0644\u0623\u0634\u0631\u0627\u0641 \u0628\u0627\u0644\u062f\u064a\u0627\u0631 \u0627\u0644\u0645\u0635\u0631\u064a\u0629 \u062a\u062e\u0635 \u0627\u062d\u062f \u0623\u0641\u0631\u0627\u062f \u0645\u0646 \u0639\u0627\u0626\u0644\u062a\u064a \u0639\u0627\u0626\u0644\u0629 \u0639\u0633\u0644\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26754 post type-post status-publish format-standard has-post-thumbnail category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26754\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/5464.jpg\" class=\"attachment-medium size-medium wp-image-36904\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26754\" >\n\t\t\t\tSe algum de voc\u00eas puder me dar uma oportunidade de emprego em Meca, Medina ou at\u00e9 mesmo Jid\u00e1, por favor me avise.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>3 de setembro de 2018. Ap\u00f3s retornar ao Egito, anseio por visitar a Casa Sagrada de Deus e a Mesquita do Profeta. Realizei a Umrah duas vezes e o Hajj uma vez, e espero visit\u00e1-la muitas outras vezes.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26754\" aria-label=\"Read more about \u0644\u0648 \u0641\u064a \u062d\u062f \u0645\u0646\u0643\u0645 \u064a\u0642\u062f\u0631 \u064a\u0648\u0641\u0631 \u0644\u0649 \u0641\u0631\u0635\u0629 \u0639\u0645\u0644 \u0641\u0649 \u0645\u0643\u0647 \u0627\u0648 \u0627\u0644\u0645\u062f\u064a\u0646\u0647 \u0623\u0648 \u062d\u062a\u0649 \u062c\u062f\u0647 \u064a\u0642\u0648\u0644 \u0644\u0649\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26751 post type-post status-publish format-standard has-post-thumbnail category-116 category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26751\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"245\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/867867-1.jpg\" class=\"attachment-medium size-medium wp-image-36589\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26751\" >\n\t\t\t\tLouvado seja Deus, completei a pr\u00e1tica do quinto pilar do islamismo.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>25 de agosto de 2018. Gra\u00e7as a Deus, conclu\u00ed a pr\u00e1tica do quinto pilar do Isl\u00e3. Percebi que a maioria da delega\u00e7\u00e3o eg\u00edpcia para o Hajj era idosa. Tenho alguns conselhos.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26751\" aria-label=\"Read more about \u0627\u0644\u062d\u0645\u062f \u0644\u0644\u0647 \u0627\u0646\u062a\u0647\u064a\u062a \u0645\u0646 \u0623\u062f\u0627\u0621 \u0627\u0644\u0631\u0643\u0646 \u0627\u0644\u062e\u0627\u0645\u0633 \u0645\u0646 \u0623\u0631\u0643\u0627\u0646 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26748 post type-post status-publish format-standard has-post-thumbnail category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26748\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/465.jpg\" class=\"attachment-medium size-medium wp-image-36906\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26748\" >\n\t\t\t\tNo Hajj\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>11 de agosto de 2018. De agora at\u00e9 o Dia de Arafah, se algum dos meus amigos quiser que eu ore por ele, por favor, escreva aqui em um breve coment\u00e1rio. N\u00e3o hesite em perguntar.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26748\" aria-label=\"Read more about \u0641\u064a \u0627\u0644\u062d\u062c\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26727 post type-post status-publish format-standard has-post-thumbnail category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26727\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"143\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/7878.jpg\" class=\"attachment-medium size-medium wp-image-36908\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26727\" >\n\t\t\t\tA cidade marroquina de Fez\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>19 de junho de 2018 A cidade marroquina de Fez foi fundada por meu av\u00f4 Idris II, filho de Idris, o Grande, filho de Abdullah al-Muhadh, filho do Imam al-Hasan al-Muthanna, filho do Imam al-Hasan al-Sabt.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26727\" aria-label=\"Read more about \u0645\u062f\u064a\u0646\u0629 \u0641\u0627\u0633 \u0627\u0644\u0645\u063a\u0631\u0628\u064a\u0629\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26723 post type-post status-publish format-standard has-post-thumbnail category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26723\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"292\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/4536.png\" class=\"attachment-medium size-medium wp-image-36915\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26723\" >\n\t\t\t\tTrechos de uma carta do meu av\u00f4 Idris, o Grande, ao povo de Marrocos\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>18 de junho de 2018 Trechos da carta do meu av\u00f4, o fundador do estado Idrisid, Idris, o Grande, filho de Abdullah al-Mahd, filho do Imam al-Hasan al-Muthanna, filho do Imam al-Hasan al-Sabt, filho de<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26723\" aria-label=\"Read more about \u0645\u0642\u062a\u0637\u0641\u0627\u062a \u0645\u0646 \u0631\u0633\u0627\u0644\u0629 \u062c\u062f\u064a \u0625\u062f\u0631\u064a\u0633 \u0627\u0644\u0623\u0643\u0628\u0631 \u0625\u0644\u0649 \u0623\u0647\u0644 \u0627\u0644\u0645\u063a\u0631\u0628\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26719 post type-post status-publish format-standard has-post-thumbnail category-118\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26719\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"194\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/04\/6543.jpg\" class=\"attachment-medium size-medium wp-image-36917\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tamerbadr.com\/pt\/archives\/26719\" >\n\t\t\t\tO santu\u00e1rio do meu av\u00f4 Idris, o Jovem, filho de Idris, o Velho\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t09\/04\/2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>14 de junho de 2018 Uma foto do santu\u00e1rio do meu av\u00f4 Idris, o Jovem, filho de Idris, o Velho, filho de Abdullah al-Mahd, filho do Imam al-Hasan al-Muthanna, filho do Imam al-Hasan al-Sabt, filho de<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/tamerbadr.com\/pt\/archives\/26719\" aria-label=\"Read more about \u0636\u0631\u064a\u062d \u062c\u062f\u064a \u0625\u062f\u0631\u064a\u0633 \u0627\u0644\u0623\u0635\u063a\u0631 \u0628\u0646 \u0625\u062f\u0631\u064a\u0633 \u0627\u0644\u0623\u0643\u0628\u0631\" tabindex=\"-1\" >\n\t\t\tLer mais \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"e-load-more-anchor\" data-page=\"1\" data-max-page=\"6\" data-next-page=\"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/pages\/20291\/page\/2\"><\/div>\n\t\t\t\t<nav class=\"elementor-pagination\" aria-label=\"Pagination\">\n\t\t\t<span class=\"page-numbers prev\">\" Anterior<\/span>\n<span aria-current=\"page\" class=\"page-numbers current\"><span class=\"elementor-screen-only\">Page<\/span>1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/pages\/20291\/page\/2\"><span class=\"elementor-screen-only\">Page<\/span>2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/pages\/20291\/page\/3\"><span class=\"elementor-screen-only\">Page<\/span>3<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/pages\/20291\/page\/4\"><span class=\"elementor-screen-only\">Page<\/span>4<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/pages\/20291\/page\/5\"><span class=\"elementor-screen-only\">Page<\/span>5<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/pages\/20291\/page\/6\"><span class=\"elementor-screen-only\">Page<\/span>6<\/a>\n<a class=\"page-numbers next\" href=\"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/pages\/20291\/page\/2\">Seguinte \"<\/a>\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6955ca8 elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"6955ca8\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a6bc38f\" data-id=\"a6bc38f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-348e0df elementor-widget__width-auto elementor-absolute elementor-invisible elementor-widget elementor-widget-image\" data-id=\"348e0df\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" decoding=\"async\" width=\"305\" height=\"227\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2022\/10\/opening-quote-icon.png\" class=\"attachment-full size-full wp-image-1947\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0627\u0645\u0631 \u0628\u062f\u0631 \u0634\u062e\u0635\u064a \u0647\u0646\u0627\u0643 \u0645\u0646 \u064a\u062a\u0639\u062c\u0628 \u0645\u0646 \u0634\u062e\u0635 \u0645\u062b\u0644\u064a \u0628\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u062c\u0647\u0627\u062f \u0648\u0628\u0647\u0630\u0627 \u0627\u0644\u0641\u0643\u0631 \u0625\u0633\u062a\u0645\u0631 \u0641\u064a \u0627\u0644\u062c\u064a\u0634 \u062d\u062a\u0649 \u0648\u0635\u0644 \u0644\u0631\u062a\u0628\u0629 \u0631\u0627\u0626\u062f \u0648\u0625\u0644\u0649 \u0647\u0624\u0644\u0627\u0621 \u0623\u0642\u0648\u0644 1- \u0627\u0646\u0627 \u0644\u0645 \u0623\u0643\u0646 \u063a\u0628\u064a\u0627\u064b \u062d\u062a\u0649 \u0623\u0642\u0648\u0644 \u0644\u0642\u064a\u0627\u062f\u0627\u062a \u0627\u0644\u062c\u064a\u0634 \u0642\u0628\u0644 \u062f\u062e\u0648\u0644\u064a \u0627\u0644\u062d\u0631\u0628\u064a\u0629 \u0623\u0648 \u0628\u0639\u062f \u0623\u0646 \u0623\u0635\u0628\u062d\u062a \u0636\u0627\u0628\u0637 \u0628\u0623\u0646\u0646\u064a \u0643\u0646\u062a \u0623\u062d\u0627\u0648\u0644 \u0627\u0644\u062c\u0647\u0627\u062f \u0641\u064a \u0627\u0644\u0634\u064a\u0634\u0627\u0646 \u0623\u0648 \u0627\u0644\u0628\u0648\u0633\u0646\u0647 \u0623\u0648 \u063a\u064a\u0631\u0647\u0627 \u0645\u0646 \u0627\u0644\u0628\u0644\u0627\u062f \u0627\u0644\u0627\u0633\u0644\u0627\u0645\u064a\u0629 \u0648\u0644\u0643\u0646 \u0647\u0630\u0647 [&hellip;]<\/p>","protected":false},"author":1,"featured_media":4468,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-20291","page","type-page","status-publish","has-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/pages\/20291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/comments?post=20291"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/pages\/20291\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/media\/4468"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/pt\/wp-json\/wp\/v2\/media?parent=20291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}