{"id":25957,"date":"2025-04-06T12:48:22","date_gmt":"2025-04-06T12:48:22","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=25957"},"modified":"2025-06-09T16:44:20","modified_gmt":"2025-06-09T16:44:20","slug":"5-73","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/nl\/archives\/25957","title":{"rendered":"Generatie van de Al-Aqsa Bevrijding"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"25957\" class=\"elementor elementor-25957\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27cfc62a e-flex e-con-boxed e-con e-parent\" data-id=\"27cfc62a\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35ed9b06 elementor-widget elementor-widget-text-editor\" data-id=\"35ed9b06\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><h1 class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">2 september 2014<\/span><\/span><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"xzpqnlu xjm9jq1 x6ikm8r x10wlt62 x10l6tqk x1i1rx1s\">\u00a0<\/span><\/span><\/h1><\/div><\/div><\/div><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Acties die voor dit bericht moeten worden ondernomen\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><strong>Generatie van de Al-Aqsa Bevrijding<\/strong><br class=\"html-br\" \/><br class=\"html-br\" \/>Het gezegde dat onze generatie niet te vergelijken is met de generatie die Al-Aqsa bevrijdde ten tijde van Saladin of met de generatie die de Tataren versloeg, etc., is niet waar.<br class=\"html-br\" \/>De uitspraak dat Al-Aqsa niet bevrijd zal worden als er niet evenveel moslims zijn die het Fajr-gebed bidden als er zijn die het vrijdaggebed bidden, is eveneens onjuist.<br class=\"html-br\" \/><br class=\"html-br\" \/>Al deze beweringen zijn onjuist en hebben als doel ons te frustreren en ons ervan te weerhouden na te denken over de bevrijding van Al-Aqsa. Ik zal het je bewijzen vanuit de geschiedenis, die helaas veel mensen niet lezen. Als je het zou lezen, zou je de waarheid kennen die voor jou verborgen is.<br class=\"html-br\" \/><br class=\"html-br\" \/>1- De Boodschapper, moge God hem zegenen en vrede schenken, versloeg de ongelovigen en veroverde Mekka. Er waren huichelaars, christenen en joden in Medina. Heeft de Boodschapper, moge God hem zegenen en vrede schenken, gewacht tot alle inwoners van Medina geloofden voordat hij Mekka veroverde?<br class=\"html-br\" \/>2- Abu Bakr al-Siddiq begon zijn veroveringen in Irak en de Levant na de Ridda-oorlogen, waarin het Arabische Schiereiland zich van de islam had afgekeerd, met uitzondering van Medina, Mekka en Taif. Hij wachtte niet tot het geloof de harten van iedereen op het Arabische Schiereiland had bereikt voordat hij begon met de veroveringen van Irak en de Levant.<br class=\"html-br\" \/>3- De grootste overwinningen van de moslims in Hattin, Ain Jalut, Zallaqa en andere overwinningen en veroveringen werden niet behaald doordat alle moslims in hun landen alleen in God geloofden. Er waren goede en slechte mensen onder hen en de legers die al deze overwinningen behaalden, wachtten niet tot hun familieleden en geliefden bij zonsopgang baden om hun gevechten te voeren.<br class=\"html-br\" \/><br class=\"html-br\" \/>Wij zijn niet minder dan onze voorouders die v\u00f3\u00f3r ons kwamen. Als God de Almachtige ons een belofte heeft gedaan om Jeruzalem te veroveren, waarom zouden wij dan niet de generatie zijn die Al-Aqsa verovert?<br class=\"html-br\" \/><br class=\"html-br\" \/>Onze generatie heeft de vastberadenheid en wilskracht die haar kwalificeren voor deze grote missie. Het is de generatie die zich verzette tegen de tirannieke heersers, in opstand kwam en haar leven opofferde om een einde te maken aan onrecht. De beste jihad is een woord van waarheid tegenover een onrechtvaardige heerser. Wat deze generatie mist, is een hernieuwde intentie om de gevangengenomen Al-Aqsa-moskee te openen, zodat God haar de overwinning kan schenken in haar revolutie en de overwinning op haar vijanden.<br class=\"html-br\" \/><br class=\"html-br\" \/>Als jij God steunt, zal Hij jou steunen en jouw voeten stevig maken.<br class=\"html-br\" \/><br class=\"html-br\" \/>God verandert de toestand van een volk niet, zolang het volk niet verandert wat in zichzelf is.<br class=\"html-br\" \/><br class=\"html-br\" \/>Vernieuw uw intenties, dan zal uw revolutie zegevieren en zult u over uw vijanden zegevieren.<br class=\"html-br\" \/><br class=\"html-br\" \/>Majoor Tamer Badr\u00a0<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>2 september 2014 De generatie die Al-Aqsa zal bevrijden. Het gezegde dat onze generatie niet is zoals de generatie die Al-Aqsa bevrijdde tijdens het tijdperk van Saladin, of zoals de generatie die de Tataren versloeg, etc., klopt niet. Het gezegde dat Al-Aqsa niet bevrijd zal worden tenzij het aantal moslims dat het Fajr-gebed bidt gelijk is aan het aantal moslims dat het vrijdaggebed bidt, klopt evenmin. Al deze gezegden zijn onjuist en hun doel is [\u2026]<\/p>","protected":false},"author":2,"featured_media":36400,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[183,117],"tags":[],"class_list":{"0":"post-25957","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-183","8":"category-117"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/nl\/wp-json\/wp\/v2\/posts\/25957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/nl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/nl\/wp-json\/wp\/v2\/comments?post=25957"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/nl\/wp-json\/wp\/v2\/posts\/25957\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/nl\/wp-json\/wp\/v2\/media\/36400"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/nl\/wp-json\/wp\/v2\/media?parent=25957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/nl\/wp-json\/wp\/v2\/categories?post=25957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/nl\/wp-json\/wp\/v2\/tags?post=25957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}