{"id":20724,"date":"2025-03-24T09:38:10","date_gmt":"2025-03-24T09:38:10","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=20724"},"modified":"2025-04-28T06:05:28","modified_gmt":"2025-04-28T06:05:28","slug":"hdgkjgk","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/nl\/archives\/20724","title":{"rendered":"De visie van generaal-majoor Ahmed Wasfi op 14 juli 2019"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"20724\" class=\"elementor elementor-20724\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-153720b7 e-flex e-con-boxed e-con e-parent\" data-id=\"153720b7\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23ed0bd5 elementor-widget elementor-widget-text-editor\" data-id=\"23ed0bd5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Ik zag mezelf staan in een straat in het centrum van Ca\u00efro, en voor me stond een menigte militairen die me steunden. Generaal-majoor Ahmed Wasfi kwam naar me toe als gezant van de politieke leiding om me te bedreigen met mijn woorden. Toen hij voor me stond, legde hij zijn hand op mijn schouder om me te bedreigen, maar zijn hand reikte niet tot mijn schouder omdat er een verborgen barri\u00e8re was die verhinderde dat zijn hand mijn schouder raakte. Desondanks bleef hij me adviseren om te stoppen met praten over politiek. Ik luisterde kalm naar hem, maar ik weigerde zijn advies. Hij liep van me weg en sprak op zijn mobiele telefoon met de leiding, en vertelde hen dat ik hun dreigementen had afgewezen. Daarna begon ik de militairen die me steunden aan te spreken, en ik eiste het vertrek van Sisi. Ik zei dat ik hier zou blijven tot hij vertrok, en ik riep meerdere keren &quot;God is Groot&quot; totdat het visioen eindigde.<\/h1><h1><strong>Interpretatie van het visioen in deze video<\/strong><\/h1><p><iframe title=\"De visie van generaal-majoor Ahmed Wasfi op 14 juli 2019\" width=\"800\" height=\"600\" src=\"https:\/\/www.youtube.com\/embed\/TrHlaM2s3Pg?list=PLGSQ8bPhLqKvbIK2NxQ1CoUA-dKyGIGlP\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0631\u0623\u064a\u062a \u0623\u0646\u0646\u064a \u0623\u0642\u0641 \u0641\u064a \u0623\u062d\u062f \u0634\u0648\u0627\u0631\u0639 \u0648\u0633\u0637 \u0627\u0644\u0628\u0644\u062f \u0628\u0627\u0644\u0642\u0627\u0647\u0631\u0629 \u0648\u0623\u0645\u0627\u0645\u064a \u062d\u0634\u062f \u0645\u0646 \u0627\u0644\u0639\u0633\u0643\u0631\u064a\u064a\u0646 \u0627\u0644\u0645\u0624\u064a\u062f\u064a\u0646 \u0644\u064a\u060c \u0641\u062c\u0627\u0621\u0646\u064a \u0627\u0644\u0644\u0648\u0627\u0621 \u0627\u062d\u0645\u062f \u0648\u0635\u0641\u064a\u00a0 \u0643\u0645\u0628\u0639\u0648\u062b \u0645\u0646 \u0627\u0644\u0642\u064a\u0627\u062f\u0629 \u0627\u0644\u0633\u064a\u0627\u0633\u064a\u0629 \u0644\u062a\u0647\u062f\u064a\u062f\u064a \u0628\u0627\u0644\u062a\u0648\u0642\u0641 \u0639\u0646 \u0627\u0644\u0643\u0644\u0627\u0645\u060c \u0648\u062d\u064a\u0646 \u0648\u0642\u0641 \u0623\u0645\u0627\u0645\u064a \u0648\u0636\u0639 \u064a\u062f\u0647 \u0639\u0644\u0649 \u0643\u062a\u0641\u064a \u0644\u062a\u0647\u062f\u064a\u062f\u064a \u0648\u0644\u0643\u0646 \u064a\u062f\u0647 \u0644\u0645 \u062a\u0635\u0644 \u0627\u0644\u0649 \u0643\u062a\u0641\u064a \u0644\u0648\u062c\u0648\u062f \u062d\u0627\u062c\u0632 \u062e\u0641\u0649 \u0645\u0646\u0639 \u064a\u062f\u0647 \u0645\u0646 \u0645\u0644\u0627\u0645\u0633\u0629 \u0643\u062a\u0641\u064a\u060c \u0648\u0628\u0627\u0644\u0631\u063a\u0645 \u0645\u0646 \u0630\u0644\u0643 \u0627\u0633\u062a\u0645\u0631 \u0641\u064a \u0646\u0635\u062d\u064a [&hellip;]<\/p>","protected":false},"author":2,"featured_media":20725,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[111],"tags":[],"class_list":{"0":"post-20724","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category--2016-2020"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/nl\/wp-json\/wp\/v2\/posts\/20724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/nl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/nl\/wp-json\/wp\/v2\/comments?post=20724"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/nl\/wp-json\/wp\/v2\/posts\/20724\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/nl\/wp-json\/wp\/v2\/media\/20725"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/nl\/wp-json\/wp\/v2\/media?parent=20724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/nl\/wp-json\/wp\/v2\/categories?post=20724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/nl\/wp-json\/wp\/v2\/tags?post=20724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}