{"id":22738,"date":"2025-03-30T11:43:48","date_gmt":"2025-03-30T11:43:48","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=22738"},"modified":"2025-03-30T11:43:48","modified_gmt":"2025-03-30T11:43:48","slug":"hjgfdjhfg","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/it\/archives\/22738","title":{"rendered":"Malcolm X"},"content":{"rendered":"<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\">\n<div class=\"x1iyjqo2\">\n<div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\">\n<div class=\"xu06os2 x1ok221b\">\n<div class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">24 giugno 2013<\/span><\/span><\/div>\n<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<div class=\"xqcrz7y x78zum5 x1qx5ct2 x1y1aw1k x1sxyh0 xwib8y2 xurb0ha xw4jnvo\">\n<div>\n<div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Azioni che possono essere intraprese per questo posto\">\n<div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\"><strong><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">Malcolm X<\/span><\/strong><\/div>\n<div role=\"none\" data-visualcompletion=\"ignore\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">Chi \u00e8 questa persona chiamata (Malcolm X) che la maggior parte dei giovani della nazione islamica non conosce?<br class=\"html-br\" \/><br class=\"html-br\" \/>Lui \u00e8 l&#039;uomo che \u00e8 morto in piedi.<br class=\"html-br\" \/><br class=\"html-br\" \/><br class=\"html-br\" \/>Che cosa ci importa?<br class=\"html-br\" \/><br class=\"html-br\" \/><br class=\"html-br\" \/>Questa importante figura ebbe un ruolo fondamentale \u2013 dopo Dio \u2013 nella diffusione della religione islamica tra gli afroamericani, in un&#039;epoca in cui i neri d&#039;America soffrivano profondamente a causa della discriminazione razziale tra loro e i bianchi. Furono sottoposti a ogni tipo di umiliazione e degradazione, e sopportarono il tormento della tortura e varie forme di odio da parte di questi ultimi.<br class=\"html-br\" \/><br class=\"html-br\" \/>In questo clima turbolento di oppressione e umiliazione, Malcolm X nacque da un padre pastore di una chiesa e da una madre originaria delle Indie Occidentali. Quando aveva sei anni, suo padre fu ucciso dai bianchi dopo avergli spaccato la testa e averlo messo sulla traiettoria di un autobus elettrico che lo invest\u00ec fino a farlo morire. La famiglia di Malcolm X cominci\u00f2 a deteriorarsi rapidamente. finanziariamente ed emotivamente. Vivevano di elemosine e assistenza sociale da parte dei bianchi, che erano riluttanti a concedere. In queste dure condizioni, la madre di Malcolm X sub\u00ec un trauma psicologico che si svilupp\u00f2 fino al ricovero in un ospedale psichiatrico, dove trascorse il resto della sua vita. Malcolm X e le sue otto sorelle soffrirono l'amarezza di aver perso sia il padre che la madre, e divennero bambini affidati alle cure dello Stato, che li distribu\u00ec in diverse case...<br class=\"html-br\" \/><br class=\"html-br\" \/>Nel frattempo, Malcolm X frequent\u00f2 una scuola vicina dove era l'unico studente nero. Era intelligente e brillante e superava tutti i suoi coetanei, per cui i suoi insegnanti avevano paura di lui, il che li portava a distruggerlo psicologicamente e moralmente, e a deriderlo, soprattutto quando voleva continuare i suoi studi nel campo della legge... Questo fu il punto di svolta della sua vita. Abbandon\u00f2 la scuola e si spost\u00f2 tra diversi lavori degradanti che si addicono a un negro. Da cameriere in un ristorante manovale in una ferrovia a lustrascarpe in una discoteca. Finch\u00e9 non divenne un noto ballerino, fu tentato da una vita di frivolezze e perdite e inizi\u00f2 a bere alcolici e fumare sigarette, trovando nel gioco d'azzardo la sua principale fonte di risparmio. Finch\u00e9 non fin\u00ec per fare uso di droghe e persino per spacciarle, e poi per rubare case e automobili. Tutto questo quando non aveva ancora ventuno anni. Finch\u00e9 lui e i suoi amici non furono catturati dalla polizia. Lo condannarono a una pena esagerata di dieci anni di reclusione, mentre per i bianchi la pena detentiva non superava i cinque anni.<br class=\"html-br\" \/><br class=\"html-br\" \/>In carcere, Malcolm X si astenne dal fumare o dal mangiare carne di maiale e divor\u00f2 migliaia di libri in vari campi del sapere, instaurando una cultura elevata che gli permise di completare le carenze della sua personalit\u00e0.<br class=\"html-br\" \/><br class=\"html-br\" \/>In quel periodo, tutti i fratelli di Malcolm X si convertirono all&#039;Islam per mano di un uomo di nome Muhammad Elijah, che sosteneva di essere un profeta di Dio inviato solo ai neri! Cercarono di convincere Malcolm X a convertirsi all&#039;Islam con ogni mezzo e metodo, finch\u00e9 non si convert\u00ec. La sua morale miglior\u00f2, la sua personalit\u00e0 divenne pi\u00f9 spiccata e inizi\u00f2 a partecipare a sermoni e dibattiti all&#039;interno della prigione per invocare l&#039;Islam. Finch\u00e9 non fu graziato e rilasciato, in modo che non continuasse a invocare l&#039;Islam all&#039;interno della prigione.<br class=\"html-br\" \/><br class=\"html-br\" \/>Malcolm X era affiliato al movimento Nation of Islam, che aveva idee sbagliate e fondamenti razzisti incompatibili con l'Islam, nonostante l'uso dell'Islam come slogan luminoso. Erano intolleranti nei confronti della razza nera e rendevano l'Islam esclusivo per loro e non per le altre razze, mentre avevano la morale virtuosa e gli alti valori dell'Islam... In altre parole, prendevano dall'Islam la sua apparenza e lasciavano la sua essenza ed esperienza.<br class=\"html-br\" \/><br class=\"html-br\" \/>Malcolm X continu\u00f2 a far parte dei ranghi della Nation of Islam, invitando le persone a unirsi ad essa con i suoi discorsi eloquenti e la sua forte personalit\u00e0. Fu un aiutante instancabile e un braccio instancabile di forza, vigore e aggressivit\u00e0... fino ad attirare molte persone ad unirsi a questo movimento.<br class=\"html-br\" \/><br class=\"html-br\" \/>Malcolm X voleva compiere l&#039;Hajj e, durante il suo viaggio, vide da vicino il vero Islam, ne apprese la verit\u00e0 e si rese conto dell&#039;errore della dottrina razzista che aveva abbracciato e sostenuto. Cos\u00ec, abbracci\u00f2 la vera religione islamica e si fece chiamare (Hajj Malik El-Shabazz).<br class=\"html-br\" \/><br class=\"html-br\" \/>Al suo ritorno, si dedic\u00f2 alla predicazione del vero Islam e cerc\u00f2 di correggere i concetti errati della Nation of Islam. Tuttavia, si scontr\u00f2 con l'ostilit\u00e0 e l'odio di questi ultimi, che cominciarono a molestarlo e a minacciarlo, ma lui non se ne cur\u00f2 e continu\u00f2 a camminare su un sentiero chiaro e deciso, invocando il vero Islam che elimina ogni forma di razzismo.<br class=\"html-br\" \/><br class=\"html-br\" \/>In uno dei suoi eloquenti sermoni, pronunciati per chiamare il popolo a Dio, i tiranni si rifiutarono di fare altro che mettere a tacere la voce della verit\u00e0. Le loro mani lo assassinarono mentre era in piedi sul palco a parlare al popolo, quando sedici proiettili a tradimento furono sparati verso il suo corpo alto e magro. E poi venne la fine. E che fine meravigliosa. Chiediamo a Dio di accoglierlo tra i martiri nel Giorno della Resurrezione.\u00a0<\/span><\/div>","protected":false},"excerpt":{"rendered":"<p>24 \u064a\u0648\u0646\u064a\u0648 2013 \u0645\u0627\u0644\u0643\u0648\u0645 \u0623\u0643\u0633 \u0645\u0646 \u0647\u0648 \u0647\u0630\u0627 \u0627\u0644\u0634\u062e\u0635 \u0627\u0644\u0645\u062f\u0639\u0648 (\u0645\u0627\u0644\u0643\u0648\u0645 \u0623\u0643\u0633) \u0627\u0644\u0630\u064a \u064a\u062c\u0647\u0644\u0647 \u0623\u0643\u062b\u0631 \u0634\u0628\u0627\u0628 \u0627\u0644\u0623\u0645\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\u061f\u0625\u0646\u0647 \u0627\u0644\u0631\u062c\u0644 \u0627\u0644\u0630\u064a \u0645\u0627\u062a \u0648\u0627\u0642\u0641\u0627 .\u0648\u0645\u0627 \u0627\u0644\u0630\u064a \u064a\u0647\u0645\u0646\u0627 \u0641\u064a \u0623\u0645\u0631\u0647\u061f\u0625\u0646 \u0647\u0630\u0647 \u0627\u0644\u0634\u062e\u0635\u064a\u0629 \u0627\u0644\u0647\u0627\u0645\u0629 \u0643\u0627\u0646 \u0644\u0647\u0627 \u0641\u0636\u0644 \u0643\u0628\u064a\u0631 &#8211; \u0628\u0639\u062f \u0627\u0644\u0644\u0647 &#8211; \u0641\u064a \u0646\u0634\u0631 \u0627\u0644\u062f\u064a\u0646 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a \u0628\u064a\u0646 \u0627\u0644\u0623\u0645\u0631\u064a\u0643\u0627\u0646 \u0627\u0644\u0633\u0648\u062f\u060c \u0641\u064a \u0627\u0644\u0648\u0642\u062a \u0627\u0644\u0630\u064a \u0643\u0627\u0646 \u0627\u0644\u0633\u0648\u062f \u0641\u064a \u0623\u0645\u0631\u064a\u0643\u0627 \u064a\u0639\u0627\u0646\u0648\u0646 \u0628\u0634\u062f\u0629 \u0645\u0646 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":22739,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[184],"tags":[],"class_list":{"0":"post-22738","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-184"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts\/22738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/comments?post=22738"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts\/22738\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/media\/22739"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/media?parent=22738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/categories?post=22738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/tags?post=22738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}