{"id":22299,"date":"2025-03-28T19:48:30","date_gmt":"2025-03-28T19:48:30","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=22299"},"modified":"2025-04-27T18:42:19","modified_gmt":"2025-04-27T18:42:19","slug":"gfdsghf","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/it\/archives\/22299","title":{"rendered":"La visione del rifiuto del mio libro da parte di Al-Azhar Le lettere attese il 22 febbraio 2020 si sono quasi tutte avverate il 23 marzo 2020 dopo che Al-Azhar ha rifiutato il mio libro, quasi un mese dopo questa visione."},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"22299\" class=\"elementor elementor-22299\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-40ebe5cd e-flex e-con-boxed e-con e-parent\" data-id=\"40ebe5cd\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49d6bf41 elementor-widget elementor-widget-text-editor\" data-id=\"49d6bf41\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>14 aprile 2020<\/h1><h1><br \/>La visione del rifiuto del mio libro da parte di Al-Azhar Le lettere attese il 22 febbraio 2020 si sono quasi tutte avverate il 23 marzo 2020 dopo che Al-Azhar ha rifiutato il mio libro, quasi un mese dopo questa visione.<br \/>La cosa importante \u00e8 che in questa visione mi chiedevo come l&#039;impiegato di Al-Azhar mi avrebbe informato del rifiuto del mio libro da parte di Al-Azhar senza discuterne con me, ma gloria a Dio, questa parte della visione si \u00e8 compiuta letteralmente, senza aggiunte o sottrazioni. Inoltre, come ho visto nella visione, l&#039;impiegato mi ha dato un foglio da firmare con le informazioni, e questo \u00e8 ci\u00f2 che \u00e8 realmente accaduto.<br \/>C&#039;\u00e8 una parte della visione che non ho rivelato al pubblico all&#039;epoca, ovvero la pubblicazione dell&#039;intero libro in formato PDF. Questa parte non era adatta alla pubblicazione in quel momento, quindi l&#039;ho tenuta per me finch\u00e9 il mio libro non \u00e8 stato bandito da Al-Azhar.<br \/>L&#039;intera visione si \u00e8 letteralmente avverata fin dall&#039;inizio, e persino il mio amico Hani Saeed mi ha consolato. Rimane l&#039;ultima parte della visione, che contiene strani simboli che non sono riuscito a interpretare fino ad ora. Finch\u00e9 la maggior parte della visione si \u00e8 avverata, questa parte rimane. Spero che chiunque sappia come interpretarla me lo dica.<br \/>L&#039;ultima parte della visione<br \/>C&#039;era un carretto di fagioli accanto a me, cos\u00ec ho comprato delle patatine fritte in un sacchetto di plastica trasparente. Ho iniziato a mangiarle da solo, senza il mio amico. Ho mangiato il primo sacchetto di patatine fritte nello stesso sacchetto di plastica con le patate finch\u00e9 non ho smesso di mangiare il sacchetto di plastica e ho mangiato solo le patatine fritte finch\u00e9 non mi sono sazio prima di finire met\u00e0 del primo sacchetto. Ho deciso di portare il resto a casa.<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>14 \u0623\u0628\u0631\u064a\u0644 2020 \u0631\u0624\u064a\u0627 \u0631\u0641\u0636 \u0627\u0644\u0623\u0632\u0647\u0631 \u0644\u0643\u062a\u0627\u0628\u064a \u0627\u0644\u0631\u0633\u0627\u0626\u0644 \u0627\u0644\u0645\u0646\u062a\u0638\u0631\u0629 \u064a\u0648\u0645 22 \u0641\u0628\u0631\u0627\u064a\u0631 2020 \u062a\u0642\u0631\u064a\u0628\u0627 \u0643\u0644\u0647\u0627 \u062a\u062d\u0642\u0642\u062a \u064a\u0648\u0645 23 \u0645\u0627\u0631\u0633 2020 \u0628\u0639\u062f \u0623\u0646 \u0631\u0641\u0636 \u0627\u0644\u0623\u0632\u0647\u0631 \u0643\u062a\u0627\u0628\u064a \u0623\u064a \u0628\u0639\u062f \u0647\u0630\u0647 \u0627\u0644\u0631\u0624\u064a\u0627 \u0628\u0634\u0647\u0631 \u062a\u0642\u0631\u064a\u0628\u0627\u0627\u0644\u0645\u0647\u0645 \u0623\u0646\u0627 \u0641\u064a \u0647\u0630\u0647 \u0627\u0644\u0631\u0624\u064a\u0627 \u0643\u0646\u062a \u0645\u062a\u0639\u062c\u0628 \u0627\u0632\u0627\u064a \u0645\u0648\u0638\u0641 \u0627\u0644\u0623\u0632\u0647\u0631 \u0647\u064a\u0628\u0644\u063a\u0646\u064a \u0628\u0631\u0641\u0636 \u0627\u0644\u0623\u0632\u0647\u0631 \u0644\u0643\u062a\u0627\u0628\u064a \u062f\u0648\u0646 \u0645\u0646\u0627\u0642\u0634\u062a\u0647 \u0648\u0644\u0643\u0646 \u0633\u0628\u062d\u0627\u0646 \u0627\u0644\u0644\u0647 \u0641\u0647\u0630\u0627 \u0627\u0644\u062c\u0632\u0621 \u0645\u0646 \u0627\u0644\u0631\u0624\u064a\u0627 \u062a\u062d\u0642\u0642 \u062d\u0631\u0641\u064a\u0627 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":22300,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[113,111],"tags":[],"class_list":{"0":"post-22299","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-113","8":"category--2016-2020"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts\/22299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/comments?post=22299"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts\/22299\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/media\/22300"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/media?parent=22299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/categories?post=22299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/tags?post=22299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}