{"id":22028,"date":"2025-03-27T15:26:39","date_gmt":"2025-03-27T15:26:39","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=22028"},"modified":"2025-04-17T07:55:18","modified_gmt":"2025-04-17T07:55:18","slug":"dgsafgsg","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/it\/archives\/22028","title":{"rendered":"Un messaggio atteso una settimana prima della pubblicazione del libro di lettere"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"22028\" class=\"elementor elementor-22028\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4efccfbc e-flex e-con-boxed e-con e-parent\" data-id=\"4efccfbc\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-640e1df9 elementor-widget elementor-widget-text-editor\" data-id=\"640e1df9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><h1 class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">5 dicembre 2019<\/span><\/span><\/h1><\/div><\/div><\/div><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Azioni che possono essere intraprese per questo posto\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">Senza entrare nei dettagli per il momento<br class=\"html-br\" \/>Se Dio vuole, il libro verr\u00e0 pubblicato la prossima settimana, se non ci saranno problemi che ne impediranno la pubblicazione.<br class=\"html-br\" \/>Il libro susciter\u00e0 una grande controversia religiosa. Tutti coloro che ne conoscono il contenuto mi hanno detto che mi trover\u00f2 coinvolto in una battaglia religiosa molto importante, di cui verrete a conoscenza quando verr\u00e0 pubblicato il mio libro &quot;Le lettere attese&quot;.<br class=\"html-br\" \/>Questa battaglia non \u00e8 la mia battaglia, ma piuttosto dovrebbe essere la battaglia di altre persone, poich\u00e9 avranno i propri mezzi con cui Dio le sosterr\u00e0 per vincere questa battaglia, mentre io sono solo in questa battaglia e non ho alcun mezzo per vincere questa battaglia tranne ci\u00f2 che ho menzionato nel mio libro e le prove e le dimostrazioni che ho menzionato per dimostrare il mio punto di vista, che alla fine non influenzeranno il successo di questa battaglia dal mio punto di vista, e Dio lo sa meglio, perch\u00e9 discute di una credenza religiosa che \u00e8 stata prevalente per secoli, e questa credenza non sar\u00e0 rovesciata da un libro in un breve periodo di tempo.<br class=\"html-br\" \/>Molte persone mi attaccheranno, compresi molti di voi, non appena sentiranno il contenuto del libro e senza averlo letto. Questo \u00e8 un problema di cui ho sofferto da quando ho iniziato a scrivere il libro fino ad ora.<br class=\"html-br\" \/>Il libro contiene 400 pagine, tutte collegate tra loro. I capitoli sono stati organizzati in ordine, poich\u00e9 ogni capitolo dipende da quello precedente. Ci auguriamo che leggiate il libro in ordine, in modo che sia facile da comprendere.<br class=\"html-br\" \/>Molte persone mi attaccheranno non appena annuncer\u00f2 il libro e, senza nemmeno leggerlo, mi porranno domande a cui il libro risponde. Non \u00e8 logico che io risponda a ogni domanda con una o quattro pagine di risposta e poi riassuma il tutto in poche righe su Facebook. Di conseguenza, chi mi ha posto la domanda non sar\u00e0 convinto dalla risposta breve, quindi mi attaccher\u00e0 o mi porr\u00e0 un&#039;altra domanda correlata alla prima, e io sar\u00f2 costretto a riassumergli di nuovo il contenuto del libro. Quindi, non finir\u00f2 di discutere e discutere tramite i commenti di Facebook con persone che non hanno nemmeno letto il mio libro.<br class=\"html-br\" \/>Mi scuso per non aver risposto a nessuna delle domande presenti nel libro, poich\u00e9 non potr\u00f2 riassumere la mia lettera per ogni intervistatore per non perderli. Ci auguriamo che comprendiate la mia posizione, in modo che nessuno si senta offeso da me.<br class=\"html-br\" \/>Il libro \u00e8 di 400 pagine. Credo di aver dato tutte le risposte alle domande che mi aspetto da voi. Potr\u00f2 rispondere solo alle domande di chi ha letto l&#039;intero libro e ha un dubbio su una parte del libro che non capisce e che vorrebbe capire.<br class=\"html-br\" \/>Chi sente parlare del mio libro e vuole verificare la veridicit\u00e0 di ci\u00f2 che contiene e desidera la verit\u00e0 ha due possibilit\u00e0: o cerca da solo e impiega circa sei mesi nella sua ricerca, come me, per arrivare a ci\u00f2 che ho raggiunto io nel mio libro, oppure legge il mio libro in tre giorni finch\u00e9 non arriva a ci\u00f2 che sono arrivato io, e poi completa ci\u00f2 che sono arrivato io, oppure si ferma, oppure non \u00e8 convinto da ci\u00f2 che c&#039;\u00e8 nel mio libro.<br class=\"html-br\" \/>Chiedo ai miei amici pi\u00f9 cari di non cancellarmi dalla loro lista di amici finch\u00e9 non avranno letto il mio libro, dopodich\u00e9 saranno liberi di starmi lontano.<br class=\"html-br\" \/>Il libro \u00e8 protetto da copyright perch\u00e9 desidero che venga stampato e distribuito in formato cartaceo sul territorio per uno scopo personale, e sar\u00e0 pubblicato da un ufficio che lo distribuir\u00e0 in Egitto e all&#039;estero. Pubblicher\u00f2 il nome e il numero di telefono dell&#039;ufficio quando il libro sar\u00e0 pubblicato, e non posso distribuirlo in formato PDF via Internet per evitare imbarazzi.\u00a0<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>5 \u062f\u064a\u0633\u0645\u0628\u0631 2019 \u00a0 \u062f\u0648\u0646 \u0627\u0644\u062f\u062e\u0648\u0644 \u0641\u064a \u0627\u0644\u062a\u0641\u0627\u0635\u064a\u0644 \u0641\u064a \u0627\u0644\u0648\u0642\u062a \u0627\u0644\u062d\u0627\u0644\u064a\u0627\u0646 \u0634\u0627\u0621 \u0627\u0644\u0644\u0647 \u0627\u0644\u0643\u062a\u0627\u0628 \u0633\u064a\u0638\u0647\u0631 \u0627\u0644\u0623\u0633\u0628\u0648\u0639 \u0627\u0644\u0642\u0627\u062f\u0645 \u0644\u0648 \u0644\u0645 \u062a\u062d\u062f\u062b \u0623\u064a \u0645\u0634\u0627\u0643\u0644 \u062a\u064f\u0639\u064a\u0642 \u0646\u0634\u0631\u0647\u0648\u0627\u0644\u0643\u062a\u0627\u0628 \u0633\u064a\u062b\u064a\u0631 \u062c\u062f\u0644 \u062f\u064a\u0646\u064a \u0643\u0628\u064a\u0631 \u0641\u0643\u0644 \u0645\u0646 \u0639\u0631\u0641 \u0645\u062d\u062a\u0648\u0649 \u0627\u0644\u0643\u062a\u0627\u0628 \u0642\u0627\u0644 \u0644\u0649 \u0623\u0646\u0646\u064a \u0633\u0623\u062f\u062e\u0644 \u0645\u0639\u0631\u0643\u0629 \u062f\u064a\u0646\u064a\u0629 \u0643\u0628\u064a\u0631\u0629 \u062c\u062f\u064b\u0627 \u0623\u0646\u062a\u0645 \u0633\u062a\u0639\u0631\u0641\u0648\u0646\u0647\u0627 \u0639\u0646\u062f\u0645\u0627 \u0633\u064a\u0635\u062f\u0631 \u0643\u062a\u0627\u0628\u064a &#8220;\u0627\u0644\u0631\u0633\u0627\u0626\u0644 \u0627\u0644\u0645\u0646\u062a\u0638\u0631\u0629&#8221;.\u0647\u0630\u0647 \u0627\u0644\u0645\u0639\u0631\u0643\u0629 \u0644\u064a\u0633\u062a \u0645\u0639\u0631\u0643\u062a\u064a \u0628\u0644 \u0645\u0646 \u0627\u0644\u0645\u0641\u062a\u0631\u0636 \u0623\u0646\u0647\u0627 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":22029,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[113],"tags":[],"class_list":{"0":"post-22028","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-113"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts\/22028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/comments?post=22028"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts\/22028\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/media\/22029"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/media?parent=22028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/categories?post=22028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/tags?post=22028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}