{"id":21955,"date":"2025-03-27T12:13:13","date_gmt":"2025-03-27T12:13:13","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=21955"},"modified":"2025-04-20T09:08:24","modified_gmt":"2025-04-20T09:08:24","slug":"gfhg-2","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/it\/archives\/21955","title":{"rendered":"Saif al-Din Qutuz"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"21955\" class=\"elementor elementor-21955\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d4ee056 e-flex e-con-boxed e-con e-parent\" data-id=\"6d4ee056\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67c28f8a elementor-widget elementor-widget-text-editor\" data-id=\"67c28f8a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><h1 class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">5 marzo 2019<\/span><\/span><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"xzpqnlu xjm9jq1 x6ikm8r x10wlt62 x10l6tqk x1i1rx1s\">\u00a0<\/span><\/span><\/h1><\/div><\/div><\/div><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Azioni che possono essere intraprese per questo posto\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><strong>Saif al-Din Qutuz<\/strong><br class=\"html-br\" \/><\/span><\/h1><h1>\u00a0<\/h1><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">Voglio che dimentichiate il film &quot;Wa Islamah&quot; e leggiate la vera storia di Qutuz e di come ha trasformato l&#039;Egitto da uno stato di caos a una grande vittoria sulla pi\u00f9 grande superpotenza dell&#039;epoca, in un solo anno.<br class=\"html-br\" \/>Per tua informazione, non libereremo Al-Aqsa se non seguiremo ci\u00f2 che ha fatto Qutuz, ma sei ancora in uno stato di negligenza.<br class=\"html-br\" \/><br class=\"html-br\" \/><strong>Qutuz<\/strong><br class=\"html-br\" \/><br class=\"html-br\" \/>\u00c8 re Al-Muzaffar Saif al-Din Qutuz bin Abdullah al-Mu&#039;izzi, sultano mamelucco d&#039;Egitto. \u00c8 considerato il re pi\u00f9 importante dello stato mamelucco, sebbene il suo regno sia durato solo un anno, perch\u00e9 riusc\u00ec a fermare l&#039;avanzata mongola che stava quasi per distruggere lo stato islamico. Li sconfisse con una schiacciante sconfitta nella battaglia di Ain Jalut e ne insegu\u00ec i resti fino a liberare il Levante.<br class=\"html-br\" \/><br class=\"html-br\" \/><strong>La sua origine e la sua educazione<\/strong><\/span><\/h1><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><br class=\"html-br\" \/>Qutuz nacque come principe musulmano durante l&#039;Impero Corazmio. Si chiamava Mahmud ibn Mamdud, nipote del sultano Jalal ad-Din Khwarazm Shah. Nacque nella terra di Khwarazm Shah da un padre di nome Mamdud e da una madre sorella del re Jalal ad-Din ibn Khwarazm Shah. Suo nonno fu uno dei pi\u00f9 grandi re di Khwarazm Shah e combatt\u00e9 lunghe guerre contro Gengis Khan, il re tartaro, ma fu sconfitto e Najm ad-Din prese il potere. Ebbe un brillante inizio di regno e sconfisse i tartari in numerose battaglie. Tuttavia, in seguito sub\u00ec diverse sconfitte finch\u00e9 i tartari non raggiunsero la sua capitale. Dopo il crollo dell&#039;Impero Corazmio nel 628 AH \/ 1231 d.C., fu rapito dai Mongoli. Lui e altri bambini furono portati a Damasco e venduti al mercato degli schiavi, ricevendo il nome di Qutuz. Qutuz rimase uno schiavo che venne comprato e venduto finch\u00e9 non fin\u00ec nelle mani di Izz ad-Din Aybak, uno dei principi mamelucchi della dinastia ayyubide in Egitto.<br class=\"html-br\" \/>Shams ad-Din al-Jazari narra nella sua storia di Sayf ad-Din Qutuz: &quot;Quando era schiavo di Musa ibn Ghanim al-Maqdisi a Damasco, il suo padrone lo picchi\u00f2 e lo insult\u00f2 riguardo a suo padre e suo nonno. Pianse e non mangi\u00f2 nulla per il resto della giornata. Il padrone ordin\u00f2 a Ibn al-Zaim al-Farrash di placarlo e di dargli da mangiare. Al-Farrash narr\u00f2 che gli port\u00f2 del cibo e gli disse: &#039;Tutto questo pianto per uno schiaffo?&#039; Qutuz rispose: &#039;Piango perch\u00e9 ha insultato mio padre e mio nonno, che sono migliori di lui&#039;. Dissi: &#039;Chi \u00e8 tuo padre? Uno di loro \u00e8 un infedele?&#039; Rispose: &#039;Per Dio, sono solo un musulmano, figlio di un musulmano. Sono Mahmud ibn Mamdud, nipote di Khwarazm Shah, uno dei figli dei re&#039;. Cos\u00ec rimase in silenzio e io lo placai Racconta anche che, da giovane, disse a uno dei suoi coetanei di aver visto il Messaggero di Dio (pace e benedizioni su di lui) e che questi gli diede la buona notizia che avrebbe governato l&#039;Egitto e sconfitto i Tartari. Ci\u00f2 significa che l&#039;uomo si considerava in missione e che era cos\u00ec giusto da aver visto il Messaggero di Dio e che Dio lo aveva scelto per questo. Non c&#039;\u00e8 dubbio che Qutuz, che Dio abbia misericordia di lui, fosse un messaggero della misericordia di Dio e della divina provvidenza per la nazione araba e islamica e per il mondo, al fine di liberare il mondo dal male e dal pericolo dei Tartari per sempre. Il suo arrivo per governare l&#039;Egitto fu di buon auspicio per l&#039;Egitto e per il mondo arabo e islamico.<br class=\"html-br\" \/>Qutuz fu descritto come un giovane biondo con una folta barba, un eroe coraggioso, casto nei rapporti con il Profeta, al di sopra dei peccati minori e devoto alla preghiera, al digiuno e alla recitazione delle suppliche. Spos\u00f2 una donna del suo popolo e non lasci\u00f2 figli maschi. Lasci\u00f2 invece due figlie, di cui non si seppe pi\u00f9 nulla dopo di lui.<br class=\"html-br\" \/><br class=\"html-br\" \/><strong>La sua tutela sul governo<\/strong><\/span><\/h1><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><br class=\"html-br\" \/>Re Izz ad-Din Aybak nomin\u00f2 Qutuz vice del Sultano. Dopo che il Re al-Mu&#039;izz Izz ad-Din Aybak fu ucciso dalla moglie Shajar ad-Durr, e dopo di lui, sua moglie Shajar ad-Durr fu uccisa dalle concubine della prima moglie di Aybak, il Sultano Nur ad-Din Ali ibn Aybak assunse il potere e Saif ad-Din Qutuz assunse la tutela del giovane Sultano, che aveva solo 15 anni.<br class=\"html-br\" \/>L&#039;ascesa al potere del giovane Norandino caus\u00f2 molti disordini in Egitto e nel mondo islamico. La maggior parte dei disordini proveniva da alcuni Mamelucchi Bahri che rimasero in Egitto e non fuggirono in Levante con coloro che fuggirono durante i giorni del re Al-Mu&#039;izz Izz ad-Din Aybak. Uno di questi Mamelucchi Bahri, di nome Sanjar al-Halabi, guid\u00f2 la rivolta. Voleva governare per s\u00e9 dopo l&#039;assassinio di Izz ad-Din Aybak, cos\u00ec Qutuz fu costretto ad arrestarlo e imprigionarlo. Qutuz arrest\u00f2 anche alcuni dei leader delle varie ribellioni, cos\u00ec il resto dei Mamelucchi Bahri fugg\u00ec rapidamente in Levante, per unirsi ai loro leader che vi si erano rifugiati in precedenza durante i giorni del re Al-Mu&#039;izz. Quando i Mamelucchi Bahri giunsero nel Levante, incoraggiarono i principi ayyubidi a invadere l&#039;Egitto, e alcuni di questi principi risposero loro, tra cui Mughis al-Din Omar, l&#039;emiro di Karak, che avanz\u00f2 con il suo esercito per invadere l&#039;Egitto. Mughis al-Din arriv\u00f2 effettivamente con il suo esercito in Egitto, e Qutuz gli si avvicin\u00f2 e gli imped\u00ec di entrare in Egitto, e ci\u00f2 accadde a Dhul-Qi&#039;dah nell&#039;anno 655 dell&#039;Egira \/ 1257 d.C. Poi Mughis al-Din torn\u00f2 a sognare di invadere di nuovo l&#039;Egitto, ma Qutuz glielo imped\u00ec di nuovo a Rabi&#039; al-Akhir nell&#039;anno 656 dell&#039;Egira \/ 1258 d.C.<br class=\"html-br\" \/><br class=\"html-br\" \/><strong>Ha assunto il potere<\/strong><\/span><\/h1><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><br class=\"html-br\" \/>Qutuz Mahmud ibn Mamdud ibn Khwarazm Shah governava di fatto il paese, ma sul trono sedeva un sultano bambino. Qutuz vedeva in questo un indebolimento dell&#039;autorit\u00e0 del governo in Egitto, una diminuzione della fiducia del popolo nel re e un rafforzamento della determinazione dei suoi nemici, che consideravano il sovrano un bambino. Il sultano bambino era interessato ai combattimenti di galli, ai combattimenti di arieti, all&#039;allevamento di piccioni, alle cavalcate sugli asini nella cittadella e alla socializzazione con la gente ignorante e comune, lasciando che sua madre e coloro che erano al suo seguito gestissero gli affari di stato in quei tempi difficili. Questa situazione anomala si protrasse per quasi tre anni, nonostante i crescenti pericoli e la caduta di Baghdad nelle mani dei Mongoli. Uno dei pi\u00f9 colpiti e pienamente consapevole di questi pericoli fu il principe Qutuz, profondamente rattristato da quella che considerava l&#039;incoscienza del re, il controllo esercitato dalle donne sulle risorse del paese e la tirannia dei principi, che anteponevano i propri interessi a quelli del paese e del suo popolo.<br class=\"html-br\" \/>Qui, Qutuz prese la coraggiosa decisione di deporre il sultano bambino, Nur ad-Din Ali, e di salire al trono d&#039;Egitto. Ci\u00f2 accadde il 24 di Dhu al-Qi&#039;dah del 657 AH \/ 1259 d.C., pochi giorni prima dell&#039;arrivo di Hulagu ad Aleppo. Fin da quando era salito al potere, Qutuz si era preparato ad affrontare i Tatari.<br class=\"html-br\" \/>Quando Qutuz assunse il potere, la situazione politica interna era estremamente tesa. Sei sovrani avevano governato l&#039;Egitto nel corso di circa dieci anni: il re al-Salih Najm al-Din Ayyub, suo figlio Turan Shah, Shajar al-Durr, il re al-Mu&#039;izz Izz al-Din Aybak, il sultano Nur al-Din Ali ibn Aybak e Sayf al-Din Qutuz. C&#039;erano anche molti Mamelucchi che bramavano il potere e lo contendevano.<br class=\"html-br\" \/>Il paese stava attraversando anche una grave crisi economica a causa delle ripetute crociate, delle guerre che avevano avuto luogo tra l&#039;Egitto e i suoi vicini del Levante e dei conflitti e delle lotte interne.<br class=\"html-br\" \/>Qutuz si adoper\u00f2 per migliorare la situazione in Egitto mentre si preparava ad affrontare i Tatari.<br class=\"html-br\" \/><br class=\"html-br\" \/><strong>Preparandosi all&#039;incontro con i Tartari<\/strong><\/span><\/h1><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><br class=\"html-br\" \/>Qutuz svent\u00f2 le ambizioni di potere dei Mamelucchi unendoli dietro un unico obiettivo: fermare e contrastare l&#039;avanzata tatara. Riun\u00ec principi, comandanti anziani, studiosi di spicco e opinion leader in Egitto e disse loro chiaramente: &quot;La mia unica intenzione (cio\u00e8, la mia intenzione nel prendere il potere) era che ci unissimo per combattere i Tatari, e questo non pu\u00f2 essere raggiunto senza un re. Quando usciremo e sconfiggeremo questo nemico, allora la questione sar\u00e0 vostra. Mettete al potere chi volete&quot;. La maggior parte dei presenti si calm\u00f2 e accett\u00f2 la proposta. Qutuz accett\u00f2 anche un trattato di pace con Baybars, che gli aveva inviato messaggeri chiedendogli di unirsi per affrontare gli eserciti mongoli che erano entrati a Damasco e ne avevano catturato il re, al-Nasir Yusuf. Qutuz apprezz\u00f2 molto Baybars, gli diede l&#039;incarico di ministro, gli concesse Qalub e i villaggi circostanti e lo tratt\u00f2 come uno degli emiri. Lo mise addirittura in prima linea negli eserciti durante la battaglia di Ain Jalut.<br class=\"html-br\" \/>In preparazione alla battaglia decisiva con i Tatari, Qutuz scrisse ai principi del Levante e il principe Al-Mansur, sovrano di Hama, gli rispose e part\u00ec da Hama con parte del suo esercito per unirsi all&#039;esercito di Qutuz in Egitto. Quanto ad Al-Mughith Omar, sovrano di Al-Karak, e Badr Al-Din Lu&#039;lu&#039;, sovrano di Mosul, preferirono un&#039;alleanza con i Mongoli e il tradimento. Quanto al re Al-Sa&#039;id Hassan bin Abdul Aziz, sovrano di Baniyas, anch&#039;egli si rifiut\u00f2 categoricamente di collaborare con Qutuz e si un\u00ec invece alle forze tartare con il suo esercito per aiutarle a combattere i musulmani.<br class=\"html-br\" \/>Qutuz sugger\u00ec di imporre tasse al popolo per sostenere l&#039;esercito. Questa decisione richiese un editto religioso (fatwa), poich\u00e9 i musulmani in uno stato islamico pagano solo la zakat, e solo coloro che sono in grado di pagarla lo fanno, e alle condizioni note della zakat. L&#039;imposizione di tasse oltre alla zakat pu\u00f2 essere fatta solo in circostanze molto speciali, e deve esserci una base legale che lo consenta. Qutuz consult\u00f2 lo sceicco Al-Izz ibn Abd Al-Salam, che eman\u00f2 la seguente fatwa: &quot;Se il nemico attacca il paese, \u00e8 obbligatorio per il mondo intero combatterlo. \u00c8 lecito prendere dal popolo ci\u00f2 che lo aiuter\u00e0 con il suo equipaggiamento, a condizione che nulla rimanga nel tesoro pubblico e che vendiate i vostri beni e il vostro equipaggiamento. Ognuno di voi dovrebbe limitarsi al suo cavallo e alle sue armi, e dovreste essere uguali in questo alla gente comune. Quanto al prendere il denaro del popolo comune mentre rimangono il denaro e l&#039;equipaggiamento di lusso dei comandanti dell&#039;esercito, allora ci\u00f2 non \u00e8 lecito&quot;.<br class=\"html-br\" \/>Qutuz accett\u00f2 le parole dello sceicco Al-Izz bin Abdul Salam e inizi\u00f2 da solo. Vendette tutto ci\u00f2 che possedeva e ordin\u00f2 ai ministri e ai principi di fare lo stesso. Tutti obbedirono e l&#039;intero esercito fu pronto.<br class=\"html-br\" \/><br class=\"html-br\" \/><strong>L&#039;arrivo dei messaggeri tartari<\/strong><\/span><\/h1><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><br class=\"html-br\" \/>Mentre Qutuz preparava il suo esercito e il suo popolo per affrontare i Tatari, i messaggeri di Hulagu giunsero con un messaggio minaccioso a Qutuz che diceva: &quot;Nel nome del Dio dei cieli, il cui diritto \u00e8 dovuto a Lui, che ci ha dato il possesso della Sua terra e ci ha dato autorit\u00e0 sulla Sua creazione, che il re vittorioso, che \u00e8 di razza mamelucca, il signore dell&#039;Egitto e dei suoi distretti, e tutti i suoi principi, soldati, impiegati e lavoratori, i suoi nomadi e i suoi cittadini, i suoi grandi e piccoli, conosce. Noi siamo i soldati di Dio sulla Sua terra. Siamo stati creati dalla Sua ira ed Egli ci ha dato autorit\u00e0 su chiunque la Sua ira abbia colpito. Avete una lezione in tutte le terre e un monito dalla nostra determinazione. Quindi prestate attenzione agli altri e affidateci i vostri affari prima che il velo venga rimosso e l&#039;errore ritorni a voi. Non abbiamo piet\u00e0 di coloro che piangono, n\u00e9 abbiamo piet\u00e0 di coloro che si lamentano. Abbiamo conquistato le terre e purificato la terra da corruzione. Quindi dovreste fuggire e noi dovremmo inseguirvi. Quale terra vi dar\u00e0 riparo? Quale paese vi protegger\u00e0? Cosa vedete? Abbiamo acqua e terra? Non avete scampo dalle nostre spade e nessuna via d&#039;uscita dalle nostre mani. I nostri cavalli sono veloci, le nostre spade sono fulmini, le nostre lance sono penetranti, le nostre frecce sono mortali, i nostri cuori sono come montagne e i nostri numeri sono come sabbia. Le nostre fortezze sono impotenti, i nostri eserciti sono inutili per combatterci e le vostre preghiere contro di noi non sono ascoltate, perch\u00e9 avete mangiato ci\u00f2 che \u00e8 proibito, siete stati troppo orgogliosi per ricambiare il saluto, avete tradito i vostri giuramenti e la disobbedienza e la disobbedienza si sono diffuse tra voi. Quindi aspettatevi umiliazione e disonore: &quot;Cos\u00ec oggi sarete ricompensati con la punizione dell&#039;umiliazione per ci\u00f2 che avete usato per essere arroganti sulla terra senza ragione&quot;. [Al-Ahqaf: 20], &quot;E coloro che fanno il male verranno a sapere a quale [finale] ritorno saranno restituiti&quot;. [Ash-Shu\u2019ara\u2019: 227] \u00c8 stato dimostrato che noi siamo i miscredenti e voi siete i malvagi, e abbiamo dato autorit\u00e0 su di voi a Colui nelle cui mani \u00e8 la gestione degli affari e le decisioni decretate. \u201cI vostri molti sono pochi ai nostri occhi, e i vostri nobili sono umili ai nostri occhi. I vostri re non hanno potere su di noi se non attraverso l&#039;umiliazione. Quindi non prolungare il tuo discorso e affrettati a rispondere prima che la guerra accenda il suo fuoco e accenda le sue scintille, e non trovi n\u00e9 onore n\u00e9 gloria da noi, n\u00e9 un libro n\u00e9 un amuleto, quando le nostre lance ti attaccano violentemente e sei afflitto dalla pi\u00f9 grande calamit\u00e0 da parte nostra, e le tue terre si svuotano di te e i suoi troni si svuotano. Siamo stati giusti con te, quando ti abbiamo inviato, e tu sei giusto con i nostri messaggeri su di te.\u201d<br class=\"html-br\" \/>Qutuz radun\u00f2 i capi e i consiglieri e mostr\u00f2 loro la lettera. Alcuni dei capi erano dell&#039;opinione che fosse meglio arrendersi ai Tatari ed evitare gli orrori della guerra. Qutuz disse: &quot;Incontrer\u00f2 personalmente i Tatari, o capi dei musulmani. Avete mangiato a lungo dal tesoro pubblico e siete avversi agli invasori. Io me ne vado. Chiunque scelga il jihad mi accompagner\u00e0, e chiunque non lo scelga torner\u00e0 a casa sua. Dio lo conosce, e il peccato delle donne musulmane ricade sul collo di coloro che sono in ritardo per combattere&quot;.<br class=\"html-br\" \/>I comandanti e i principi erano emozionati nel vedere il loro capo decidere di andare a combattere personalmente i Tatari, invece di inviare un esercito e rimanere indietro.<br class=\"html-br\" \/>Poi si alz\u00f2 in piedi per rivolgersi ai principi piangendo e dicendo: &quot;O principi dei musulmani, chi difender\u00e0 l&#039;Islam se non ci saremo noi?&quot;<br class=\"html-br\" \/>I principi dichiararono il loro accordo al jihad e all&#039;impegno ad affrontare i Tatari, a qualunque costo. La determinazione dei musulmani fu rafforzata dall&#039;arrivo di una lettera di Sarim al-Din al-Ashrafi, che era stato catturato dai Mongoli durante l&#039;invasione della Siria. Accett\u00f2 quindi di arruolarsi nelle loro fila, spiegando loro la loro esiguit\u00e0 numerica e incoraggiandoli a combatterli, a non temerli.<br class=\"html-br\" \/>Qutuz tagli\u00f2 la gola ai messaggeri che Hulagu gli aveva inviato con il messaggio minaccioso e ne appese le teste ad Al-Raydaniyah al Cairo. Si tenne il venticinquesimo per portare i corpi a Hulagu. Invi\u00f2 messaggeri in tutto l&#039;Egitto per invocare il jihad sulla via di Allah, i suoi obblighi e le sue virt\u00f9. Al-Izz ibn Abd al-Salam in persona chiam\u00f2 il popolo, cos\u00ec molti insorsero per formare il cuore e il fianco sinistro dell&#039;esercito musulmano. Le forze regolari mamelucche formarono il fianco destro, mentre il resto si nascose dietro le colline per decidere la battaglia.<br class=\"html-br\" \/><br class=\"html-br\" \/><strong>Sul campo di battaglia<\/strong><\/span><\/h1><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><br class=\"html-br\" \/>I due eserciti si incontrarono nel luogo noto come Ain Jalut in Palestina il 25 di Ramadan del 658 dell&#039;Egira \/ 3 settembre 1260 d.C. La guerra fu feroce e i Tatari sfruttarono tutte le loro capacit\u00e0. La superiorit\u00e0 dell&#039;ala destra tatara, che stava esercitando pressione sull&#039;ala sinistra delle forze islamiche, divenne evidente. Le forze islamiche iniziarono a ritirarsi sotto la terribile pressione dei Tatari. I Tatari iniziarono a penetrare nell&#039;ala sinistra islamica e i martiri iniziarono a cadere. Se i Tatari avessero completato la loro penetrazione nell&#039;ala sinistra, avrebbero circondato l&#039;esercito islamico.<br class=\"html-br\" \/>Qutuz si trovava in posizione elevata dietro le linee, osservando l&#039;intera situazione, ordinando alle divisioni dell&#039;esercito di colmare le lacune e pianificando ogni minima cosa. Qutuz si rese conto delle sofferenze che l&#039;ala sinistra dei musulmani stava attraversando, cos\u00ec spinse le ultime divisioni regolari verso di essa da dietro le colline, ma la pressione tartara continuava.<br class=\"html-br\" \/>Qutuz stesso scese sul campo di battaglia per sostenere i soldati e risollevarne il morale. Gett\u00f2 a terra l&#039;elmo, esprimendo il suo desiderio di martirio e la sua mancanza di paura della morte, e pronunci\u00f2 il suo famoso grido: &quot;O Islam!&quot;<br class=\"html-br\" \/>Qutuz combatt\u00e9 ferocemente con l&#039;esercito, finch\u00e9 uno dei Tatari non gli scocc\u00f2 una freccia, mancandolo ma colpendo il cavallo che stava cavalcando, che mor\u00ec all&#039;istante. Qutuz smont\u00f2 e combatt\u00e9 a piedi, non avendo un cavallo. Uno dei principi lo vide combattere a piedi, cos\u00ec si precipit\u00f2 da lui e gli consegn\u00f2 il suo cavallo. Tuttavia, Qutuz rifiut\u00f2, dicendo: &quot;Non priverei i musulmani del tuo beneficio!!&quot;. Continu\u00f2 a combattere a piedi finch\u00e9 non gli portarono un cavallo di riserva. Alcuni principi lo incolparono per questa azione e dissero: &quot;Perch\u00e9 non hai cavalcato il cavallo di Tizio? Se qualcuno del nemico ti avesse visto, ti avrebbe ucciso e l&#039;Islam sarebbe perito a causa tua&quot;.<br class=\"html-br\" \/>Qutuz disse: &quot;Quanto a me, stavo per andare in paradiso, ma l&#039;Islam ha un Signore che non lo deluder\u00e0. Furono uccisi Tizio, Tizio e Tizio... finch\u00e9 non cont\u00f2 un certo numero di re (come Omar, Othman e Ali). Poi Dio stabil\u00ec per l&#039;Islam coloro che lo avrebbero protetto, oltre a loro, e l&#039;Islam non lo deluse&quot;.<br class=\"html-br\" \/>I musulmani vinsero e Qutuz insegu\u00ec i loro superstiti. I musulmani epurarono l&#039;intero Levante nel giro di poche settimane. Il Levante torn\u00f2 sotto il dominio dell&#039;Islam e dei musulmani, e Damasco fu conquistata. Qutuz dichiar\u00f2 la riunificazione dell&#039;Egitto e del Levante in un unico stato sotto la sua guida, dopo dieci anni di divisione, dalla morte del re Al-Salih Najm al-Din Ayyub. Qutuz, che Dio abbia misericordia di lui, tenne sermoni dai pulpiti in tutte le citt\u00e0 egiziane, palestinesi e levantine, finch\u00e9 non furono pronunciati sermoni per lui nell&#039;alto Levante e nelle citt\u00e0 intorno al fiume Eufrate.<br class=\"html-br\" \/>Qutuz inizi\u00f2 a distribuire le province islamiche tra i principi musulmani. Fu parte della sua saggezza, che Dio abbia misericordia di lui, il fatto che riport\u00f2 alcuni principi ayyubidi ai loro incarichi, al fine di garantire che non scoppiassero conflitti nel Levante. Qutuz, che Dio abbia misericordia di lui, non temette il loro tradimento, soprattutto dopo che fu chiaro loro che non erano in grado di sconfiggere Qutuz e i suoi giusti soldati.<br class=\"html-br\" \/><br class=\"html-br\" \/><strong>Il suo omicidio<\/strong><\/span><\/h1><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><br class=\"html-br\" \/>Rukn al-Din Baybars uccise il sultano al-Muzaffar Qutuz a Dhu al-Qi&#039;dah, il 24 ottobre 1260 d.C., durante il ritorno dell&#039;esercito in Egitto. Il motivo era che il sultano Qutuz aveva promesso a Baybars di concedergli il governo di Aleppo dopo la fine della guerra. Dopodich\u00e9, il sultano Qutuz pens\u00f2 di rinunciare al sultanato e di continuare la sua vita nell&#039;ascetismo e nella ricerca della conoscenza, lasciando la guida del paese al comandante del suo esercito, Rukn al-Din Baybars. Di conseguenza, ritratt\u00f2 la sua decisione di concedere a Baybars il governatore di Aleppo, poich\u00e9 sarebbe diventato re dell&#039;intero paese. Baybars credeva che il sultano Qutuz lo avesse ingannato, e i suoi compagni iniziarono a raccontarglielo e a incitarlo a ribellarsi al sultano e a ucciderlo. Quando Qutuz torn\u00f2 dalla riconquista di Damasco ai Tatari, i Mamelucchi Bahri, tra cui Baybars, si radunarono per assassinarlo mentre erano in viaggio verso l&#039;Egitto. Un giorno, mentre si avvicinava all&#039;Egitto, and\u00f2 a caccia e i cammelli lo seguirono, trovandosi sulla strada. Anz al-Isfahani gli si avvicin\u00f2 per intercedere per alcuni dei suoi compagni. Questi intercedette per lui e cerc\u00f2 di baciargli la mano, ma lui gliela trattenne. Baybars lo sopraffece. Cadde con la spada, con le mani e la bocca lacerate. Gli altri gli scagliarono frecce e lo uccisero. Qutuz fu poi portato al Cairo e l\u00ec sepolto.<br class=\"html-br\" \/><br class=\"html-br\" \/>A coloro che leggono i libri di storia che hanno preservato questa vicenda, sembra che Saif ad-Din Qutuz sia venuto per compiere una specifica missione storica e, non appena l&#039;ha portata a termine, \u00e8 scomparso dalla scena storica dopo aver attirato attenzione e ammirazione che hanno reso il suo ruolo storico, nonostante il suo breve periodo di tempo, grande e duraturo.<br class=\"html-br\" \/><br class=\"html-br\" \/><strong>Perch\u00e9 siamo stati grandi<\/strong><br class=\"html-br\" \/>Dal libro Unforgettable Leaders di Tamer Badr\u00a0<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>5 \u0645\u0627\u0631\u0633 2019\u00a0 \u00a0 \u0633\u064a\u0641 \u0627\u0644\u062f\u064a\u0646 \u0642\u0637\u0632 \u00a0 \u0623\u0631\u064a\u062f \u0645\u0646\u0643\u0645 \u0623\u0646 \u062a\u0646\u0633\u0648\u0627 \u0641\u064a\u0644\u0645 \u0648\u0627 \u0627\u0633\u0644\u0627\u0645\u0627\u0647 \u0648\u062a\u0642\u0631\u0623\u0648\u0627 \u0642\u0635\u0629 \u062d\u064a\u0627\u0629 \u0642\u0637\u0632 \u0627\u0644\u062d\u0642\u064a\u0642\u064a\u0629 \u0648\u0643\u064a\u0641 \u062d\u0648\u0644 \u0645\u0635\u0631 \u0645\u0646 \u062d\u0627\u0644\u0629 \u0627\u0644\u0641\u0648\u0636\u0649 \u0625\u0644\u0649 \u0625\u0646\u062a\u0635\u0627\u0631 \u0639\u0638\u064a\u0645 \u0639\u0644\u0649 \u0623\u0643\u0628\u0631 \u0642\u0648\u0629 \u0639\u0638\u0645\u064a \u0641\u064a \u0630\u0644\u0643 \u0627\u0644\u0648\u0642\u062a \u062e\u0644\u0627\u0644 \u0639\u0627\u0645 \u0648\u0627\u062d\u062f \u0641\u0642\u0637\u0648\u0644\u0644\u0639\u0644\u0645 \u0644\u0646 \u0646\u062d\u0631\u0631 \u0627\u0644\u0627\u0642\u0635\u0649 \u0625\u0644\u0627 \u0625\u0630\u0627 \u0627\u062a\u0628\u0639\u0646\u0627 \u0645\u0627 \u0641\u0639\u0644\u0647 \u0642\u0637\u0632 \u0648\u0644\u0643\u0646\u0643\u0645 \u0644\u0627\u062a\u0632\u0627\u0644\u0648\u0646 \u0641\u064a \u062d\u0627\u0644\u0629 \u0627\u0644\u063a\u0641\u0644\u0629 \u0642\u0637\u0632 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":21956,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[115,184],"tags":[],"class_list":{"0":"post-21955","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-115","8":"category-184"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts\/21955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/comments?post=21955"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts\/21955\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/media\/21956"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/media?parent=21955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/categories?post=21955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/tags?post=21955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}