{"id":21103,"date":"2025-03-25T11:14:45","date_gmt":"2025-03-25T11:14:45","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=21103"},"modified":"2025-04-27T18:43:26","modified_gmt":"2025-04-27T18:43:26","slug":"ggg","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/it\/archives\/21103","title":{"rendered":"Visione di Takbir, Adhan e dell&#039;Esercito di Liberazione della Palestina il 21 agosto 2020"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"21103\" class=\"elementor elementor-21103\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4981f7ae e-flex e-con-boxed e-con e-parent\" data-id=\"4981f7ae\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-502680c elementor-widget elementor-widget-text-editor\" data-id=\"502680c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Vidi l&#039;esercito musulmano prepararsi a liberare la Palestina, e di fronte a loro c&#039;era l&#039;esercito di occupazione sionista. Cos\u00ec dissi &quot;Dio \u00e8 grande&quot; per la prima volta e gridai &quot;Dio \u00e8 grande&quot;, ma l&#039;esercito musulmano non ripet\u00e9 dopo di me. Poi gridai &quot;Dio \u00e8 grande&quot; una o due volte, e i musulmani ripeterono &quot;Dio \u00e8 grande&quot; dopo di me. Poi recitai l&#039;intero invito alla preghiera dall&#039;inizio alla fine, a voce alta, in modo che l&#039;intero esercito musulmano potesse sentirlo.<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Vidi l&#039;esercito musulmano prepararsi a liberare la Palestina, e di fronte a loro c&#039;era l&#039;esercito di occupazione sionista. Cos\u00ec dissi &quot;Dio \u00e8 grande&quot; per la prima volta e gridai &quot;Dio \u00e8 grande&quot;, ma l&#039;esercito musulmano non ripet\u00e9 dopo di me. Poi gridai &quot;Dio \u00e8 grande&quot; una o due volte, e i musulmani ripeterono &quot;Dio \u00e8 grande&quot; dopo di me. Poi recitai l&#039;intero invito alla preghiera dall&#039;inizio alla fine, a voce alta, in modo che l&#039;intero esercito musulmano potesse sentirlo.<\/p>","protected":false},"author":2,"featured_media":21104,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[111],"tags":[],"class_list":{"0":"post-21103","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category--2016-2020"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts\/21103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/comments?post=21103"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts\/21103\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/media\/21104"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/media?parent=21103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/categories?post=21103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/tags?post=21103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}