{"id":20784,"date":"2025-03-24T11:03:21","date_gmt":"2025-03-24T11:03:21","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=20784"},"modified":"2025-04-28T05:57:13","modified_gmt":"2025-04-28T05:57:13","slug":"sdws","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/it\/archives\/20784","title":{"rendered":"La visione di Ges\u00f9, la pace sia con lui, e la sua visita a questa vita mondana per un giorno il 4 settembre 2019"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"20784\" class=\"elementor elementor-20784\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2423278b e-flex e-con-boxed e-con e-parent\" data-id=\"2423278b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3197b484 elementor-widget elementor-widget-text-editor\" data-id=\"3197b484\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Vidi che ero tornato con la mia macchina e l&#039;avevo fermata davanti a casa mia nella Citt\u00e0 del 6 ottobre. Rimasi sorpreso che un&#039;auto accanto a me fosse arrivata nello stesso momento e si fosse fermata anch&#039;essa davanti a casa mia. Scoprii che chi la guidava era il nostro maestro Ges\u00f9, la pace sia su di lui, e che era venuto in questa vita terrena e a casa mia per farmi visita. Scesi velocemente dall&#039;auto e mi assicurai che fosse chiusa a chiave per evitare che me la rubassero e per potermi dedicare all&#039;incontro con il nostro maestro Ges\u00f9, la pace sia su di lui. Il nostro maestro Ges\u00f9, la pace sia su di lui, scese dall&#039;auto e ci dirigemmo l&#039;uno verso l&#039;altro. Lo abbracciai calorosamente e il nostro maestro Ges\u00f9, la pace sia su di lui, fece lo stesso con me, solo che mi abbracci\u00f2, mi sollev\u00f2 da terra e mi fece girare su di s\u00e9 diverse volte per darmi il benvenuto. Il nostro maestro Ges\u00f9, la pace sia con lui, aveva lineamenti chiari in questa visione, a differenza del solito, poich\u00e9 era pi\u00f9 alto di me di circa due o tre spanne, con una corporatura snella, la pelle color grano, denti bianchi e abbaglianti, capelli neri e un&#039;et\u00e0 non superiore ai trent&#039;anni. Dopo esserci salutati a vicenda e prima di salire a casa mia al secondo piano, abbiamo incontrato la figlia del nostro vicino cristiano che vive al quinto piano, e, per vostra informazione, \u00e8 una giovane donna. Cos\u00ec l&#039;ho presentata a Ges\u00f9, la pace sia con lui, e le ho confermato che era venuto in questa vita terrena per visitarmi solo per un giorno prima del suo ritorno, e che nessuna forza avrebbe potuto arrestarlo mentre era a casa mia durante quel giorno. Tuttavia, la figlia del nostro vicino cristiano rimase sorpresa dalla differenza nei lineamenti e nel colore del volto di Ges\u00f9, la pace sia su di lui, rispetto a quello raffigurato nelle sue chiese, cos\u00ec lo salut\u00f2 sorpresa, dubitando che fosse il Messia, la pace sia su di lui, e sal\u00ec a casa sua e con Ges\u00f9, la pace sia su di lui, sal\u00ec a casa mia.<br class=\"html-br\" \/>La scena cambi\u00f2 quando un certo numero di cristiani si avvicin\u00f2 a Ges\u00f9, la pace sia su di lui, e lo accolse. Egli pose la mano sopra le loro teste e poi alz\u00f2 entrambe le mani, supplicando Dio Onnipotente. Anche i cristiani accanto a lui alzarono le mani e supplicarono Dio Onnipotente, fino alla fine della visione.<\/h1><h1>Nota:<br class=\"html-br\" \/>1- Il profeta che ho visto pi\u00f9 spesso nei miei sogni finora \u00e8 il nostro maestro Ges\u00f9, la pace sia su di lui, innumerevoli volte. L&#039;ho visto per la prima volta quando ero alle medie, ed \u00e8 stato anche il primo profeta che ho visto nei sogni.<br class=\"html-br\" \/>2- La prima volta che ho esaminato i lineamenti del nostro maestro Ges\u00f9, la pace sia su di lui, \u00e8 stato nella prima visione che ho avuto di lui alle scuole medie. Il suo colore era bianco e i suoi capelli erano chiari, leggermente simili alle immagini che lo raffigurano nelle chiese. Poi l&#039;ho visto nelle altre visioni, e i suoi tratti del viso non erano chiari. Oggi, tuttavia, ho visto il suo colore marrone grano e i suoi capelli erano neri. Devo ricordarvi che il Profeta, la pace e le benedizioni su di lui, vide il nostro maestro Ges\u00f9, la pace sia su di lui, in due forme diverse, e sono state menzionate in due hadith autentici. Nella sua descrizione del nostro maestro Ges\u00f9, la pace sia su di lui, durante il viaggio di Isra, lo descrisse come rossastro e bianco, mentre nella visione in cui il Profeta era l&#039;Anticristo, lo descrisse come dalla pelle scura, ovvero molto scura. \u00c8 possibile che il cambiamento di colore del volto di un singolo profeta sia correlato allo stato del sognatore o allo stato della visione stessa. Speriamo che possiate interpretare la mia visione dei lineamenti del suo volto in questa visione.<br class=\"html-br\" \/>3- Quello che so \u00e8 che il nostro Maestro Ges\u00f9, la pace sia su di lui, torner\u00e0 in questa vita terrena e vi rimarr\u00e0 per molti anni. Qual \u00e8 l&#039;interpretazione del fatto che ho avuto conferma nella visione che rimarr\u00e0 in questa vita terrena solo per un giorno?<\/h1><h1><strong>Interpretazione della visione in questo video<\/strong><\/h1><p><iframe title=\"La visione di Ges\u00f9, la pace sia con lui, e la sua visita a questa vita mondana per un giorno il 4 settembre 2019\" width=\"800\" height=\"600\" src=\"https:\/\/www.youtube.com\/embed\/aNsRBrh-i_0?list=PLGSQ8bPhLqKvbIK2NxQ1CoUA-dKyGIGlP\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0631\u0623\u064a\u062a \u0623\u0646\u0646\u064a \u0639\u062f\u062a \u0628\u0633\u064a\u0627\u0631\u062a\u064a \u0648\u062a\u0648\u0642\u0641\u062a \u0628\u0647\u0627 \u0623\u0645\u0627\u0645 \u0628\u064a\u062a\u064a \u0628\u0645\u062f\u064a\u0646\u0629 \u0627\u0644\u0633\u0627\u062f\u0633 \u0645\u0646 \u0623\u0643\u062a\u0648\u0628\u0631 \u0641\u0641\u0648\u062c\u0626\u062a \u0628\u0623\u0646 \u0633\u064a\u0627\u0631\u0629 \u0628\u062c\u0627\u0646\u0628\u064a \u0642\u062f \u0648\u0635\u0644\u062a \u0641\u064a \u0646\u0641\u0633 \u0627\u0644\u062a\u0648\u0642\u064a\u062a \u0648\u062a\u0648\u0642\u0641\u062a \u0623\u064a\u0636\u0627\u064b \u0623\u0645\u0627\u0645 \u0628\u064a\u062a\u064a \u0641\u0625\u0630\u0627 \u0628\u064a \u0623\u062c\u062f \u0645\u0646 \u064a\u0642\u0648\u062f\u0647\u0627 \u0647\u0648 \u0633\u064a\u062f\u0646\u0627 \u0639\u064a\u0633\u0649 \u0639\u0644\u064a\u0647 \u0627\u0644\u0633\u0644\u0627\u0645 \u0648\u0623\u0646\u0647 \u0623\u062a\u0649 \u0627\u0644\u0649 \u0627\u0644\u062d\u064a\u0627\u0629 \u0627\u0644\u062f\u0646\u064a\u0627 \u0648\u0627\u0644\u0649 \u0628\u064a\u062a\u064a \u0644\u0632\u064a\u0627\u0631\u062a\u064a\u060c \u0646\u0632\u0644\u062a \u0645\u0646 \u0633\u064a\u0627\u0631\u062a\u064a \u0645\u0633\u0631\u0639\u0627\u064b \u0648\u062a\u0623\u0643\u062f\u062a \u0645\u0646 \u0623\u0646\u0647\u0627 \u0645\u063a\u0644\u0642\u0629 \u062d\u062a\u0649 \u0644\u0627 \u062a\u062a\u0645 \u0633\u0631\u0642\u062a\u0647\u0627 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":20785,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[111],"tags":[],"class_list":{"0":"post-20784","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category--2016-2020"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts\/20784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/comments?post=20784"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts\/20784\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/media\/20785"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/media?parent=20784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/categories?post=20784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/tags?post=20784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}