{"id":20766,"date":"2025-03-24T10:24:00","date_gmt":"2025-03-24T10:24:00","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=20766"},"modified":"2025-04-28T05:58:58","modified_gmt":"2025-04-28T05:58:58","slug":"asdf","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/it\/archives\/20766","title":{"rendered":"La visione della donna giusta e del pretendente al Mahdi il 19 agosto 2019, prima dell&#039;alba"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"20766\" class=\"elementor elementor-20766\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6696338c e-flex e-con-boxed e-con e-parent\" data-id=\"6696338c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a9ef723 elementor-widget elementor-widget-text-editor\" data-id=\"2a9ef723\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Prima dell&#039;alba ebbi una visione in cui mi impersonavo in una donna giusta la cui identit\u00e0 mi era sconosciuta e che non conoscevo in realt\u00e0. Non notai i lineamenti del suo volto e mi resi conto di trovarmi in una stanza con una persona nota che affermava di essere il Mahdi atteso e che aveva dei seguaci. Non c&#039;\u00e8 bisogno di menzionare il suo nome. Mi stava chiudendo a chiave nella sua stanza, ma riuscii a fuggire. Cerc\u00f2 di raggiungermi, ma non ci riusc\u00ec. Poi la scena mi commosse (ed ero ancora incarnata in quella donna giusta) mentre giravo intorno alla Kaaba e improvvisamente la persona che affermava di essere il Mahdi mi pugnal\u00f2 di nascosto allo stomaco in mezzo alla folla e poi scomparve in mezzo alla folla. Tuttavia, la pugnalata non mi fece alcun effetto e continuai a girare intorno alla Kaaba.<\/h1><h1><strong>Interpretazione della visione in questo video<\/strong><\/h1><p><iframe title=\"La visione della donna giusta e del pretendente al Mahdi del 19 agosto 2019\" width=\"800\" height=\"600\" src=\"https:\/\/www.youtube.com\/embed\/UKGY2hDzpYI?list=PLGSQ8bPhLqKvbIK2NxQ1CoUA-dKyGIGlP\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0642\u0628\u0644 \u0627\u0644\u0641\u062c\u0631 \u0631\u0623\u064a\u062a \u0631\u0624\u064a\u0627 \u0628\u0623\u0646\u0646\u064a \u062a\u062c\u0633\u062f\u062a \u0639\u0644\u0649 \u0647\u064a\u0626\u0629 \u0627\u0645\u0631\u0623\u0647 \u0635\u0627\u0644\u062d\u0647 \u0645\u062c\u0647\u0648\u0644\u0629 \u0634\u062e\u0635\u064a\u062a\u0647\u0627 \u0628\u0627\u0644\u0646\u0633\u0628\u0629 \u0644\u064a \u0648\u0644\u0627 \u0623\u0639\u0631\u0641\u0647\u0627 \u0641\u064a \u0627\u0644\u0648\u0627\u0642\u0639 \u0648\u0644\u0645 \u0623\u0644\u0627\u062d\u0638 \u0645\u0644\u0627\u0645\u062d \u0648\u062c\u0647\u0647\u0627 \u0648\u0627\u0646\u0646\u064a \u0627\u0635\u0628\u062d\u062a \u0628\u062f\u0627\u062e\u0644 \u063a\u0631\u0641\u0629 \u0645\u0639 \u0634\u062e\u0635\u064a\u0647 \u0645\u0639\u0631\u0648\u0641\u0647 \u062a\u062f\u0639\u0649 \u0627\u0646\u0647 \u0627\u0644\u0645\u0647\u062f\u0649 \u0627\u0644\u0645\u0646\u062a\u0638\u0631 \u0648\u0644\u0647 \u0627\u062a\u0628\u0627\u0639 \u0644\u0627 \u062f\u0627\u0639\u0649 \u0644\u0630\u0643\u0631 \u0627\u0633\u0645\u0647 \u0648\u0642\u062f \u0643\u0627\u0646 \u064a\u062d\u0628\u0633\u0646\u064a \u0641\u064a \u063a\u0631\u0641\u062a\u0647 \u0648\u0644\u0643\u0646\u0646\u064a \u062a\u0645\u0643\u0646\u062a \u0645\u0646 \u0627\u0644\u0641\u0631\u0627\u0631 \u0645\u0646 \u063a\u0631\u0641\u062a\u0647 \u0648\u0642\u062f \u062d\u0627\u0648\u0644 \u0627\u0644\u0644\u062d\u0627\u0642 \u0628\u064a \u0648\u0644\u0643\u0646\u0647 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":20767,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[111],"tags":[],"class_list":{"0":"post-20766","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category--2016-2020"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts\/20766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/comments?post=20766"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts\/20766\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/media\/20767"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/media?parent=20766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/categories?post=20766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/tags?post=20766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}