{"id":20737,"date":"2025-03-24T09:47:47","date_gmt":"2025-03-24T09:47:47","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=20737"},"modified":"2025-04-28T06:04:26","modified_gmt":"2025-04-28T06:04:26","slug":"5-229","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/it\/archives\/20737","title":{"rendered":"Visione di preghiera nel Sinai il 24 luglio 2019, prima della chiamata alla preghiera dell&#039;alba"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"20737\" class=\"elementor elementor-20737\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48caeba2 e-flex e-con-boxed e-con e-parent\" data-id=\"48caeba2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ce4bf6d elementor-widget elementor-widget-text-editor\" data-id=\"7ce4bf6d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Vidi che mi ero spostato dall&#039;Egitto al Sinai e trovai l&#039;esercito egiziano pronto a combattere contro l&#039;entit\u00e0 sionista, schierato in due file lungo il Sinai, da nord a sud, nell&#039;ultimo terzo del Sinai, di fronte all&#039;Egitto. Erano in fila per la preghiera, ma la loro qibla era rivolta a est, verso la Palestina. Non notai la presenza di un imam tra loro, e loro erano in piedi, tranne per il fatto che la prima fila era leggermente pi\u00f9 lunga della seconda. C&#039;erano sedie vuote accanto a queste file, attaccate a loro sulla destra, cos\u00ec entrai per pregare con loro e mi misi nella prima fila, che si estende approssimativamente fino al Sinai meridionale, ma mi misi all&#039;estrema destra della prima fila e c&#039;era una sedia vuota a separarmi dalla prima fila, sapendo che la mia posizione in questa fila era il Sinai meridionale e la visione termin\u00f2.<br class=\"html-br\" \/>Vorrei interpretare la visione, sapendo che l&#039;argomento della mia presenza nel Sinai del Sud \u00e8 stato ripetuto in molte visioni. Inoltre, sappiate che l&#039;argomento del mio ritorno nell&#039;esercito \u00e8 del tutto improbabile, e lo prender\u00f2 in considerazione solo in un caso e non in un altro, ovvero lo scoppio di una guerra con l&#039;entit\u00e0 sionista.<\/h1><h1><strong>Interpretazione della visione in questo video<\/strong><\/h1><p><iframe title=\"Visione di preghiera nel Sinai il 24 luglio 2019\" width=\"800\" height=\"600\" src=\"https:\/\/www.youtube.com\/embed\/c-2WJTrx9pU?list=PLGSQ8bPhLqKvbIK2NxQ1CoUA-dKyGIGlP\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0631\u0623\u064a\u062a \u0623\u0646\u0646\u064a \u0627\u0646\u062a\u0642\u0644\u062a \u0645\u0646 \u0645\u0635\u0631 \u0625\u0644\u0649 \u0633\u064a\u0646\u0627\u0621 \u0641\u0648\u062c\u062f\u062a \u0627\u0644\u062c\u064a\u0634 \u0627\u0644\u0645\u0635\u0631\u064a \u0639\u0644\u0649 \u0647\u064a\u0626\u0629 \u0627\u0633\u062a\u0639\u062f\u0627\u062f \u0644\u0644\u062d\u0631\u0628 \u0645\u0639 \u0627\u0644\u0643\u064a\u0627\u0646 \u0627\u0644\u0635\u0647\u064a\u0648\u0646\u064a \u0648\u0645\u0635\u0637\u0641\u064a\u0646 \u0639\u0644\u0649 \u0647\u064a\u0626\u0629 \u0635\u0641\u064a\u0646 \u0641\u0642\u0637 \u0644\u0627 \u063a\u064a\u0631 \u0628\u0637\u0648\u0644 \u0633\u064a\u0646\u0627\u0621 \u0645\u0646 \u0627\u0644\u0634\u0645\u0627\u0644 \u0648\u062d\u062a\u0649 \u062c\u0646\u0648\u0628 \u0633\u064a\u0646\u0627\u0621 \u0641\u064a \u0627\u0644\u062b\u0644\u062b \u0627\u0644\u0623\u062e\u064a\u0631 \u0645\u0646 \u0633\u064a\u0646\u0627\u0621 \u0627\u0644\u0645\u0642\u0627\u0628\u0644 \u0644\u0645\u0635\u0631\u060c \u0648\u0642\u062f \u0643\u0627\u0646\u0648\u0627 \u0645\u0635\u0637\u0641\u064a\u0646 \u0644\u0644\u0635\u0644\u0627\u0629 \u0648\u0644\u0643\u0646 \u0642\u0628\u0644\u062a\u0647\u0645 \u0628\u0627\u062a\u062c\u0627\u0647 \u0627\u0644\u0634\u0631\u0642 \u0646\u062d\u0648 \u0641\u0644\u0633\u0637\u064a\u0646\u060c \u0648\u0644\u0645 \u0623\u0644\u0627\u062d\u0638 \u0648\u062c\u0648\u062f \u0625\u0645\u0627\u0645 \u0644\u0647\u0645 \u0648\u0642\u062f \u0643\u0627\u0646\u0648\u0627 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":20738,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[111],"tags":[],"class_list":{"0":"post-20737","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category--2016-2020"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts\/20737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/comments?post=20737"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts\/20737\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/media\/20738"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/media?parent=20737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/categories?post=20737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/tags?post=20737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}