{"id":20435,"date":"2025-03-23T10:00:24","date_gmt":"2025-03-23T10:00:24","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=20435"},"modified":"2025-04-28T15:30:27","modified_gmt":"2025-04-28T15:30:27","slug":"fgkjhgfg","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/it\/archives\/20435","title":{"rendered":"Visione del cloud nell&#039;ottobre 2018"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"20435\" class=\"elementor elementor-20435\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-24f764e9 e-flex e-con-boxed e-con e-parent\" data-id=\"24f764e9\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5455241c elementor-widget elementor-widget-text-editor\" data-id=\"5455241c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Ho avuto una visione in cui ero con un gruppo di persone e ho visto sopra di me un gruppo di nuvole che passavano velocemente da sinistra a destra e sopra di esse un altro gruppo di nuvole che passava velocemente da destra a sinistra in una notte di luna, ma non ho visto la luna, poi la scena nel cielo si \u00e8 trasformata in meteore che si muovevano in diverse direzioni in un modo che sembrava fuochi d&#039;artificio, quindi ho urlato inorridito alla scena e ho detto che Dio \u00e8 grande e che non c&#039;\u00e8 altro dio che Dio e ho continuato a ripeterlo e al resto delle persone non importava, e mi aspettavo che cadessero forti piogge e inondazioni, quindi ho provato a chiamare mia moglie e mio fratello per farli tornare a casa, ma non sono riuscito a contattarli, quindi la pioggia ha iniziato a cadere sotto forma di normale pioggia di media intensit\u00e0 mentre tornavo a casa.<\/h1><h1><strong>Interpretazione della visione in questo video<\/strong><\/h1><p><iframe title=\"Visione del cloud nell&#039;ottobre 2018\" width=\"800\" height=\"600\" src=\"https:\/\/www.youtube.com\/embed\/vrGHDWr79X8?list=PLGSQ8bPhLqKvbIK2NxQ1CoUA-dKyGIGlP\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0631\u0623\u064a\u062a \u0631\u0624\u064a\u0627 \u0628\u0623\u0646\u0646\u064a \u0643\u0646\u062a \u0645\u0639 \u0645\u062c\u0645\u0648\u0639\u0629 \u0645\u0646 \u0627\u0644\u0646\u0627\u0633 \u0648\u0631\u0623\u064a\u062a \u0641\u0648\u0642\u064a \u0645\u062c\u0645\u0648\u0639\u0629 \u0645\u0646 \u0627\u0644\u0633\u062d\u0628 \u062a\u0645\u0631 \u0633\u0631\u064a\u0639\u0627\u064b \u0645\u0646 \u0627\u0644\u064a\u0633\u0627\u0631 \u0625\u0644\u0649 \u0627\u0644\u064a\u0645\u064a\u0646 \u0648\u0641\u0648\u0642\u0647\u0627 \u0645\u062c\u0645\u0648\u0639\u0629 \u0623\u062e\u0631\u0649 \u0645\u0646 \u0627\u0644\u0633\u062d\u0628 \u062a\u0645\u0631 \u0633\u0631\u064a\u0639\u0627\u064b \u0645\u0646 \u0627\u0644\u064a\u0645\u064a\u0646 \u0625\u0644\u0649 \u0627\u0644\u064a\u0633\u0627\u0631 \u0641\u064a \u0644\u064a\u0644\u0647 \u0645\u0642\u0645\u0631\u0629 \u0648\u0644\u0643\u0646\u0646\u064a \u0644\u0645 \u0623\u0631\u0649 \u0642\u0645\u0631\u0627\u064b\u060c \u062b\u0645 \u062a\u062d\u0648\u0644\u062a \u0627\u0644\u0645\u0634\u0647\u062f \u0641\u064a \u0627\u0644\u0633\u0645\u0627\u0621 \u0625\u0644\u0649 \u0634\u0647\u0628 \u062a\u062a\u062d\u0631\u0643 \u0641\u064a \u0627\u062a\u062c\u0627\u0647\u0627\u062a \u0645\u062e\u062a\u0644\u0641\u0629 \u0641\u064a\u0645\u0627 \u064a\u0634\u0628\u0647 \u0627\u0644\u0623\u0644\u0639\u0627\u0628 \u0627\u0644\u0646\u0627\u0631\u064a\u0629\u060c \u0641\u0635\u0631\u062e\u062a \u0645\u0646 \u0647\u0648\u0644 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":20436,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[111],"tags":[],"class_list":{"0":"post-20435","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category--2016-2020"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts\/20435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/comments?post=20435"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/posts\/20435\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/media\/20436"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/media?parent=20435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/categories?post=20435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/it\/wp-json\/wp\/v2\/tags?post=20435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}