{"id":24157,"date":"2025-04-02T11:01:08","date_gmt":"2025-04-02T11:01:08","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=24157"},"modified":"2025-06-09T08:59:07","modified_gmt":"2025-06-09T08:59:07","slug":"j-3","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/hr\/archives\/24157","title":{"rendered":"Ljude \u0107e zadesiti godine obmane; u kojima \u0107e se vjerovati la\u017eljivcu, a istinoljubac nazivati la\u017eljivcem, izdajniku \u0107e se vjerovati, a pouzdani \u0107e se nazivati izdajnikom, a rabida \u0107e govoriti. Re\u010deno je: &quot;\u0160to je rabida?&quot; Rekao je: &quot;Glup \u010dovjek koji govori o prosta\u010dkim stvarima.&quot;"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":36270,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[114],"tags":[],"class_list":{"0":"post-24157","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-114"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/hr\/wp-json\/wp\/v2\/posts\/24157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/hr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/hr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/hr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/hr\/wp-json\/wp\/v2\/comments?post=24157"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/hr\/wp-json\/wp\/v2\/posts\/24157\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/hr\/wp-json\/wp\/v2\/media\/36270"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/hr\/wp-json\/wp\/v2\/media?parent=24157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/hr\/wp-json\/wp\/v2\/categories?post=24157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/hr\/wp-json\/wp\/v2\/tags?post=24157"}],"curies":[{"name":"radni list","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}