{"id":24890,"date":"2025-04-03T17:27:14","date_gmt":"2025-04-03T17:27:14","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=24890"},"modified":"2025-07-08T16:27:02","modified_gmt":"2025-07-08T16:27:02","slug":"ff","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/fr\/archives\/24890","title":{"rendered":"Message aux Fr\u00e8res musulmans"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"24890\" class=\"elementor elementor-24890\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c5aea7c e-flex e-con-boxed e-con e-parent\" data-id=\"1c5aea7c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-582358c5 elementor-widget elementor-widget-text-editor\" data-id=\"582358c5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><h1 class=\"x1gslohp\">\u00a0<\/h1><\/div><div class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">9 juin 2013<\/span><\/span><\/div><\/div><\/div><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Actions possibles pour ce poste\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><strong>Message aux Fr\u00e8res musulmans<\/strong><br class=\"html-br\" \/><br class=\"html-br\" \/><br class=\"html-br\" \/>J'ai toujours eu l'habitude de dire la v\u00e9rit\u00e9 et comme j'ai d\u00e9j\u00e0 envoy\u00e9 une lettre \u00e0 mes amis de la campagne Tamarod pour les confronter \u00e0 leurs erreurs, je dois vous confronter \u00e0 vos erreurs. Je connais beaucoup d'amis de votre groupe et je sais tr\u00e8s bien qu'aucun groupe ou mouvement n'est bon ou mauvais, et qu'il n'y a aucun mouvement politique dans le monde qui ait le droit absolu ou dont les d\u00e9cisions soient toujours correctes, il est possible que vos d\u00e9cisions soient parfois erron\u00e9es.<br class=\"html-br\" \/><br class=\"html-br\" \/>J'esp\u00e8re que vous accepterez \u00e0 bras ouverts ma critique de la politique de votre groupe, comme le Proph\u00e8te (paix et b\u00e9n\u00e9dictions d'Allah soient sur lui) et les califes Rashidun avaient l'habitude d'accepter les critiques de ceux qui leur \u00e9taient inf\u00e9rieurs et changeaient toujours leurs d\u00e9cisions \u00e0 la suite de ces critiques.<br class=\"html-br\" \/><br class=\"html-br\" \/>1- Les Fr\u00e8res musulmans jouissaient d'une grande popularit\u00e9 aupr\u00e8s du peuple avant la r\u00e9volution et jusqu'\u00e0 la d\u00e9mission de Moubarak. Vous devriez donc vous interroger sur les raisons pour lesquelles cette popularit\u00e9 a d\u00e9clin\u00e9 jour apr\u00e8s jour apr\u00e8s la d\u00e9mission jusqu'\u00e0 aujourd'hui.<br class=\"html-br\" \/>2- Il faut reconna\u00eetre que Tantawi a r\u00e9ussi \u00e0 r\u00e9duire votre popularit\u00e9. Il vous a app\u00e2t\u00e9 \u00e0 plusieurs reprises pendant son r\u00e8gne. Malheureusement, vous avez aval\u00e9 tous les app\u00e2ts qu'il vous a lanc\u00e9s, et chaque app\u00e2t a perdu votre popularit\u00e9 aupr\u00e8s des r\u00e9volutionnaires jusqu'\u00e0 ce qu'il n'y ait plus de confiance entre vous et eux aujourd'hui, et ce manque de confiance est d\u00fb \u00e0 vous, pas aux r\u00e9volutionnaires.<br class=\"html-br\" \/>3- Les accords ant\u00e9rieurs au r\u00e8gne de Morsi affectent toujours sa gestion du pays jusqu'\u00e0 aujourd'hui et vous comprenez bien ce que je veux dire, donc si vous pensez que les gens l'oublieront avec le temps, vous vous faites des illusions.<br class=\"html-br\" \/>4- Mon soutien au maintien de Morsi jusqu'\u00e0 la fin de son mandat ne signifie pas que je soutiens toutes ses politiques, mais parce que je suis convaincu que le renverser maintenant signifierait le retour des foulouls au pouvoir ou le retour du conseil militaire, et alors la r\u00e9volution aura grandement \u00e9chou\u00e9 et nous pourrions m\u00eame entrer dans une guerre civile dont les cons\u00e9quences ne sont connues que de Dieu Tout-Puissant Tout-Puissant.<br class=\"html-br\" \/>5- Parler de l'application de la charia est incontest\u00e9 parmi la plupart des \u00c9gyptiens, nous voulons tous appliquer la charia, mais ce que vous ne savez pas, c'est que la base de l'application des hudud est la justice, Dieu \u00e9tablira un \u00c9tat juste, m\u00eame s'il s'agit d'un infid\u00e8le, et n'\u00e9tablira pas un \u00c9tat injuste, m\u00eame s'il est musulman, alors gouvernez-vous avec justice avec les symboles de la corruption et ceux qui ont tu\u00e9 les r\u00e9volutionnaires dans tous les \u00e9v\u00e9nements pr\u00e9c\u00e9dents afin que les gens soient convaincus du s\u00e9rieux de votre appel \u00e0 appliquer la charia aux forts avant les faibles ?<br class=\"html-br\" \/>6- O\u00f9 en est le rapport de la commission d'enqu\u00eate pour gu\u00e9rir les c\u0153urs des familles des martyrs et des bless\u00e9s, tant que ceux qui ont tu\u00e9 les martyrs et bless\u00e9 les bless\u00e9s seront en libert\u00e9, la situation du pays continuera \u00e0 se d\u00e9t\u00e9riorer.<br class=\"html-br\" \/>7) Le Messager d'Allah (que la paix soit sur lui) a dit : \"\u00d4 peuple, ce qui a condamn\u00e9 ceux qui vous ont pr\u00e9c\u00e9d\u00e9s, c'est que si l'homme honorable volait, ils l'abandonnaient, et si l'homme faible volait, ils lui imposaient la limite. La justice a-t-elle \u00e9t\u00e9 appliqu\u00e9e \u00e0 tous les symboles de l'ancien r\u00e9gime pour que les gens aient le sentiment que la r\u00e9volution a r\u00e9ussi et s'est achev\u00e9e ? Ne me dites pas que le syst\u00e8me judiciaire en est la cause, car certains symboles de l'ancien r\u00e9gime n'ont pas encore \u00e9t\u00e9 traduits en justice et ne permettent \u00e0 personne de mentionner leurs noms, et vous savez ce que je veux dire.<br class=\"html-br\" \/>8- Le fait d'appartenir au mouvement dit de l'islam politique (et je ne reconnais pas ces \u00e9tiquettes) ne signifie pas que vous \u00eates infaillible ou que Dieu vous d\u00e9fendra et vaincra vos adversaires, mais vous devez prendre les moyens du succ\u00e8s et de la victoire et ne pas vous fier aux slogans, car les gens se m\u00e9fient maintenant de ceux qui lancent ces slogans, car les gens s'int\u00e9ressent maintenant aux actions plut\u00f4t qu'aux slogans.<br class=\"html-br\" \/>9- Le concept de la fin justifiant les moyens n'a pas sa place en ces temps o\u00f9 les m\u00e9dias exploitent les moindres erreurs et o\u00f9 les opposants applaudissent. Je vois que vous faites de la politique avec tous ses inconv\u00e9nients, et malheureusement, la politique avec ses mensonges, son hypocrisie et ses alliances avec les ennemis de la nation contredit les slogans islamiques que vous appeliez de vos v\u0153ux avant de gouverner le pays.<br class=\"html-br\" \/>10- Votre peur de retourner dans les centres de d\u00e9tention et de dissoudre le groupe rend vos pens\u00e9es dispers\u00e9es, vous obligeant \u00e0 accepter des d\u00e9cisions qui ne sont pas dans l'int\u00e9r\u00eat du pays mais en faveur du groupe.<br class=\"html-br\" \/><br class=\"html-br\" \/><strong>La solution \u00e0 mon humble avis<\/strong><br class=\"html-br\" \/>1- Vous voyagez sur une seule route comme si vous conduisiez un train vers l'ab\u00eeme, vous devez donc faire une pause et revoir vos erreurs pass\u00e9es et essayer d'y apporter des solutions radicales, mais reporter la solution des probl\u00e8mes avec la politique des analg\u00e9siques n'est pas un rem\u00e8de, mais plut\u00f4t une accumulation des probl\u00e8mes jusqu'\u00e0 ce qu'ils explosent \u00e0 un moment ou \u00e0 un autre.<br class=\"html-br\" \/>A l'\u00e9poque du Proph\u00e8te et de ses successeurs, il y avait diff\u00e9rentes sectes de juifs, de chr\u00e9tiens, d'hypocrites et autres, et le Proph\u00e8te et les califes Rashidun les ont contenues, mais je vois que vous ne contenez pas l'opposition, mais que vous ignorez leurs demandes ou que vous les contrariez par de nombreuses demandes, et ce n'est pas la bonne politique.<br class=\"html-br\" \/>3- L'\u00e9tat actuel de l'agitation en Egypte se poursuivra tout au long de votre r\u00e8gne, \u00e0 moins que vous ne changiez de politique. Si vous pensez que l'opposition se lassera, vous vous faites des illusions, tant que les probl\u00e8mes ne seront pas r\u00e9solus, l'agitation persistera.<br class=\"html-br\" \/>4- Il y a ceux qui attendent votre ent\u00eatement et votre \u00e9chec pour revenir au pouvoir, et malheureusement vos politiques jusqu'\u00e0 pr\u00e9sent les aident dans leurs plans, vous devez donc leur barrer la route pour revenir au pouvoir.<br class=\"html-br\" \/>5- L'id\u00e9e que vous \u00eates les gardiens de la r\u00e9volution et que les autres factions r\u00e9volutionnaires n'ont rien \u00e0 voir avec ce que vous faites est l'une des plus grandes erreurs que vous ayez commises.<br class=\"html-br\" \/><br class=\"html-br\" \/><br class=\"html-br\" \/>Je vous ai expliqu\u00e9 mes remarques, et j'esp\u00e8re que vous les comprenez bien, car votre succ\u00e8s dans la p\u00e9riode \u00e0 venir est le succ\u00e8s de la r\u00e9volution et votre \u00e9chec est l'\u00e9chec de la r\u00e9volution, et votre poursuite sur la m\u00eame voie et avec la m\u00eame politique vous nuira et nuira \u00e0 l'\u00c9gypte en fin de compte. Je sais que beaucoup d'entre vous aiment et craignent l'\u00c9gypte et sont sinc\u00e8res dans leur amour pour Dieu et la patrie, alors acceptez mes remarques avec beaucoup de patience, car notre objectif est le m\u00eame : le bien de la patrie.<br class=\"html-br\" \/><br class=\"html-br\" \/>Commandant Tamer Badr\u00a0<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>9 \u064a\u0648\u0646\u064a\u0648 2013 \u0631\u0633\u0627\u0644\u0629 \u0625\u0644\u0649 \u062c\u0645\u0627\u0639\u0629 \u0627\u0644\u0625\u062e\u0648\u0627\u0646 \u0627\u0644\u0645\u0633\u0644\u0645\u064a\u0646 \u0644\u0642\u062f \u062a\u0639\u0648\u062f\u062a \u062f\u0627\u0626\u0645\u0627 \u0623\u0646 \u0623\u0642\u0648\u0644 \u0627\u0644\u062d\u0642 \u0648\u0643\u0645\u0627 \u0648\u062c\u0647\u062a \u0631\u0633\u0627\u0644\u0629 \u0645\u0646 \u0642\u0628\u0644 \u0625\u0644\u0649 \u0623\u0635\u062f\u0642\u0627\u0626\u064a \u0641\u064a \u062d\u0645\u0644\u0629 \u062a\u0645\u0631\u062f \u0648\u0635\u0627\u0631\u062d\u062a\u0647\u0645 \u0628\u0623\u062e\u0637\u0627\u0626\u0647\u0645 \u0641\u0643\u0627\u0646 \u0644\u0632\u0645\u0627 \u0639\u0644\u064a \u0623\u0646 \u0623\u0635\u0627\u0631\u062d\u0643\u0645 \u0628\u0623\u062e\u0637\u0627\u0626\u0643\u0645 \u0648\u0623\u0646\u0627 \u0623\u0639\u0631\u0641 \u0627\u0644\u0643\u062b\u064a\u0631 \u0645\u0646 \u0627\u0644\u0623\u0635\u062f\u0642\u0627\u0621 \u0645\u0646 \u062c\u0645\u0627\u0639\u062a\u0643\u0645 \u0648\u0623\u0639\u0644\u0645 \u062a\u0645\u0627\u0645 \u0627\u0644\u0639\u0644\u0645 \u0623\u0646 \u0645\u0627 \u0645\u0646 \u062c\u0645\u0627\u0639\u0629 \u0623\u0648 \u062a\u064a\u0627\u0631 \u0645\u0646\u0647\u0645 \u0645\u0646 \u0647\u0648 \u0627\u0644\u0635\u0627\u0644\u062d \u0648\u0645\u0646\u0647\u0645 \u0645\u0646 \u0647\u0648 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":37946,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[117],"tags":[],"class_list":{"0":"post-24890","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-117"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts\/24890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/comments?post=24890"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts\/24890\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/media\/37946"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/media?parent=24890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/categories?post=24890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/tags?post=24890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}