{"id":22308,"date":"2025-03-28T19:55:10","date_gmt":"2025-03-28T19:55:10","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=22308"},"modified":"2025-04-17T06:28:09","modified_gmt":"2025-04-17T06:28:09","slug":"dfgsbgdf","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/fr\/archives\/22308","title":{"rendered":"Accusation de blasph\u00e8me"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"22308\" class=\"elementor elementor-22308\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-562af5c4 e-flex e-con-boxed e-con e-parent\" data-id=\"562af5c4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-126b1a33 elementor-widget elementor-widget-text-editor\" data-id=\"126b1a33\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Les pires coups sont ceux qui viennent de ceux que nous consid\u00e9rons comme nos amis les plus proches.<br class=\"html-br\" \/>En effet, dire la v\u00e9rit\u00e9 ne m\u2019a pas laiss\u00e9 un ami.<br class=\"html-br\" \/>Je ne me sens presque plus triste ou choqu\u00e9 lorsque je suis poignard\u00e9 par ceux que je consid\u00e9rais comme des amis proches.<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Les pires coups de poignard sont ceux qui viennent de ceux que nous consid\u00e9rons comme nos amis les plus proches. En fait, dire la v\u00e9rit\u00e9 ne m&#039;a laiss\u00e9 aucun ami. Je ne ressens presque plus de tristesse ni de choc lorsque je re\u00e7ois des coups de poignard de ceux que je consid\u00e9rais comme mes amis les plus proches.<\/p>","protected":false},"author":2,"featured_media":22309,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[121,113],"tags":[],"class_list":{"0":"post-22308","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-121","8":"category-113"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts\/22308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/comments?post=22308"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts\/22308\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/media\/22309"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/media?parent=22308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/categories?post=22308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/tags?post=22308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}