{"id":22299,"date":"2025-03-28T19:48:30","date_gmt":"2025-03-28T19:48:30","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=22299"},"modified":"2025-04-27T18:42:19","modified_gmt":"2025-04-27T18:42:19","slug":"gfdsghf","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/fr\/archives\/22299","title":{"rendered":"La vision du rejet de mon livre par Al-Azhar Les lettres attendues le 22 f\u00e9vrier 2020 se sont presque toutes r\u00e9alis\u00e9es le 23 mars 2020 apr\u00e8s le rejet de mon livre par Al-Azhar, pr\u00e8s d'un mois apr\u00e8s cette vision."},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"22299\" class=\"elementor elementor-22299\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-40ebe5cd e-flex e-con-boxed e-con e-parent\" data-id=\"40ebe5cd\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49d6bf41 elementor-widget elementor-widget-text-editor\" data-id=\"49d6bf41\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>14 avril 2020<\/h1><h1><br \/>La vision du rejet de mon livre par Al-Azhar Les lettres attendues le 22 f\u00e9vrier 2020 se sont presque toutes r\u00e9alis\u00e9es le 23 mars 2020 apr\u00e8s le rejet de mon livre par Al-Azhar, pr\u00e8s d'un mois apr\u00e8s cette vision.<br \/>Ce qui est important, c&#039;est que dans cette vision, je me demandais comment l&#039;employ\u00e9 d&#039;Al-Azhar allait m&#039;informer du rejet de mon livre sans en discuter avec moi. Mais, gloire \u00e0 Dieu, cette partie de la vision s&#039;est accomplie litt\u00e9ralement, sans ajout ni soustraction. De plus, comme je l&#039;ai vu dans la vision, l&#039;employ\u00e9 m&#039;a remis un papier \u00e0 signer, et voici ce qui s&#039;est r\u00e9ellement pass\u00e9.<br \/>Il y a une partie de cette vision que je n&#039;ai pas r\u00e9v\u00e9l\u00e9e au public \u00e0 l&#039;\u00e9poque\u00a0: la publication de l&#039;int\u00e9gralit\u00e9 du livre au format PDF. Cette partie n&#039;\u00e9tait pas publiable \u00e0 l&#039;\u00e9poque, je l&#039;ai donc gard\u00e9e pour moi jusqu&#039;\u00e0 ce que mon livre soit banni d&#039;Al-Azhar.<br \/>La vision s&#039;est r\u00e9alis\u00e9e d\u00e8s le d\u00e9but, et m\u00eame mon ami Hani Saeed m&#039;a consol\u00e9. Il reste la derni\u00e8re partie de la vision, qui contient d&#039;\u00e9tranges symboles que je n&#039;ai pas encore pu interpr\u00e9ter. Si la vision s&#039;est en grande partie r\u00e9alis\u00e9e, cette partie demeure. J&#039;esp\u00e8re que celui qui saura l&#039;interpr\u00e9ter me le dira.<br \/>La derni\u00e8re partie de la vision<br \/>Il y avait un kiosque \u00e0 haricots \u00e0 c\u00f4t\u00e9 de moi, alors j&#039;ai achet\u00e9 des frites dans un sac en plastique transparent. J&#039;ai commenc\u00e9 \u00e0 les manger seule, sans mon ami. J&#039;ai mang\u00e9 le premier paquet de frites dans le m\u00eame sac que les pommes de terre, jusqu&#039;\u00e0 ce que j&#039;arr\u00eate de manger le sac et que je ne mange que les frites jusqu&#039;\u00e0 \u00eatre rassasi\u00e9e avant d&#039;avoir fini la moiti\u00e9 du premier paquet. J&#039;ai d\u00e9cid\u00e9 de ramener le reste \u00e0 la maison.<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>14 \u0623\u0628\u0631\u064a\u0644 2020 \u0631\u0624\u064a\u0627 \u0631\u0641\u0636 \u0627\u0644\u0623\u0632\u0647\u0631 \u0644\u0643\u062a\u0627\u0628\u064a \u0627\u0644\u0631\u0633\u0627\u0626\u0644 \u0627\u0644\u0645\u0646\u062a\u0638\u0631\u0629 \u064a\u0648\u0645 22 \u0641\u0628\u0631\u0627\u064a\u0631 2020 \u062a\u0642\u0631\u064a\u0628\u0627 \u0643\u0644\u0647\u0627 \u062a\u062d\u0642\u0642\u062a \u064a\u0648\u0645 23 \u0645\u0627\u0631\u0633 2020 \u0628\u0639\u062f \u0623\u0646 \u0631\u0641\u0636 \u0627\u0644\u0623\u0632\u0647\u0631 \u0643\u062a\u0627\u0628\u064a \u0623\u064a \u0628\u0639\u062f \u0647\u0630\u0647 \u0627\u0644\u0631\u0624\u064a\u0627 \u0628\u0634\u0647\u0631 \u062a\u0642\u0631\u064a\u0628\u0627\u0627\u0644\u0645\u0647\u0645 \u0623\u0646\u0627 \u0641\u064a \u0647\u0630\u0647 \u0627\u0644\u0631\u0624\u064a\u0627 \u0643\u0646\u062a \u0645\u062a\u0639\u062c\u0628 \u0627\u0632\u0627\u064a \u0645\u0648\u0638\u0641 \u0627\u0644\u0623\u0632\u0647\u0631 \u0647\u064a\u0628\u0644\u063a\u0646\u064a \u0628\u0631\u0641\u0636 \u0627\u0644\u0623\u0632\u0647\u0631 \u0644\u0643\u062a\u0627\u0628\u064a \u062f\u0648\u0646 \u0645\u0646\u0627\u0642\u0634\u062a\u0647 \u0648\u0644\u0643\u0646 \u0633\u0628\u062d\u0627\u0646 \u0627\u0644\u0644\u0647 \u0641\u0647\u0630\u0627 \u0627\u0644\u062c\u0632\u0621 \u0645\u0646 \u0627\u0644\u0631\u0624\u064a\u0627 \u062a\u062d\u0642\u0642 \u062d\u0631\u0641\u064a\u0627 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":22300,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[113,111],"tags":[],"class_list":{"0":"post-22299","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-113","8":"category--2016-2020"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts\/22299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/comments?post=22299"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts\/22299\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/media\/22300"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/media?parent=22299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/categories?post=22299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/tags?post=22299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}