{"id":22163,"date":"2025-03-27T20:13:00","date_gmt":"2025-03-27T20:13:00","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=22163"},"modified":"2025-04-17T06:55:55","modified_gmt":"2025-04-17T06:55:55","slug":"cdc","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/fr\/archives\/22163","title":{"rendered":"Message aux amis et aux suiveurs"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"22163\" class=\"elementor elementor-22163\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-76fc7cdc e-flex e-con-boxed e-con e-parent\" data-id=\"76fc7cdc\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-534bc13f elementor-widget elementor-widget-text-editor\" data-id=\"534bc13f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><h1 class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">27 janvier 2020<\/span><\/span><\/h1><\/div><\/div><\/div><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Actions possibles pour ce poste\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">Le pire sentiment que vous puissiez ressentir est celui de savoir que de nombreuses personnes vous suivent, croient en vos id\u00e9es et lisent vos livres, mais que vous ne les connaissez pas et ne pouvez pas les atteindre parce que vous avez peur d'elles ou qu'elles ont peur de vous approcher en raison de vos id\u00e9es politiques ou religieuses qui diff\u00e8rent de celles du grand public.<br class=\"html-br\" \/>Il est dommage que vous ayez plus de 40 000 amis et suiveurs sur vos diff\u00e9rentes pages et que vous ne connaissiez personnellement que quelques dizaines d'entre eux<br class=\"html-br\" \/>Salutations \u00e0 tous ceux qui me suivent et sont convaincus de mes id\u00e9es mais ne les connaissent pas<br class=\"html-br\" \/>Je vous aime tous en Allah<br class=\"html-br\" \/>Mais une demande personnelle \u00e0 tous ceux qui ont lu mon livre Les lettres d'attente (que vous soyez convaincus ou non), merci de m'envoyer un message priv\u00e9 ou public, s'il n'y a pas de probl\u00e8me, en indiquant votre avis sur le livre en toute neutralit\u00e9, qu'il soit n\u00e9gatif ou positif, j'accepte les critiques mais je n'accepte pas les insultes.<br class=\"html-br\" \/>Note : La fille sur la photo est une jeune fille qui me suit, dont je ne connais pas le nom, mais elle fait partie de celles qui sont all\u00e9es au salon du livre pour acheter mes livres et qui ont re\u00e7u un livre en cadeau, alors je la salue.\u00a0<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>27 \u064a\u0646\u0627\u064a\u0631 2020 \u00a0 \u0623\u0633\u0648\u0623 \u0625\u062d\u0633\u0627\u0633 \u0645\u0645\u0643\u0646 \u062a\u0634\u0639\u0631 \u0628\u0647 \u0625\u0646\u0643 \u062a\u0643\u0648\u0646 \u0639\u0627\u0631\u0641 \u0627\u0646 \u0641\u064a \u0646\u0627\u0633 \u0643\u062a\u064a\u0631 \u0628\u064a\u062a\u0627\u0628\u0639\u0648\u0643 \u0648\u0645\u0624\u0645\u0646\u064a\u0646 \u0628\u0641\u0643\u0631\u0643 \u0648\u0628\u064a\u0642\u0631\u0623\u0648\u0627 \u0643\u062a\u0628\u0643 \u0648\u0627\u0646\u062a \u0644\u0627 \u062a\u0639\u0631\u0641\u0647\u0645 \u0648\u0644\u0627 \u062a\u0633\u062a\u0637\u064a\u0639 \u0627\u0644\u0648\u0635\u0648\u0644 \u0627\u0644\u064a\u0647\u0645 \u0628\u0633\u0628\u0628 \u062e\u0648\u0641\u0643 \u0639\u0644\u064a\u0647\u0645 \u0623\u0648 \u062e\u0648\u0641\u0647\u0645 \u0645\u0646 \u0627\u0644\u0625\u0642\u062a\u0631\u0627\u0628 \u0645\u0646\u0643 \u0628\u0633\u0628\u0628 \u0623\u0641\u0643\u0627\u0631\u0643 \u0627\u0644\u0633\u064a\u0627\u0633\u064a\u0629 \u0623\u0648 \u0627\u0644\u062f\u064a\u0646\u064a\u0629 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0639\u0646 \u0639\u0627\u0645\u0629 \u0627\u0644\u0646\u0627\u0633\u0647\u0630\u0627 \u0639\u064a\u0628 \u0627\u0646\u0643 \u064a\u0643\u0648\u0646 \u0639\u0646\u062f\u0643 \u0623\u0643\u062b\u0631 \u0645\u0646 \u0623\u0631\u0628\u0639\u064a\u0646 \u0623\u0644\u0641 \u0635\u062f\u064a\u0642 \u0648\u0645\u062a\u0627\u0628\u0639 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":22164,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[113],"tags":[],"class_list":{"0":"post-22163","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-113"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts\/22163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/comments?post=22163"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts\/22163\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/media\/22164"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/media?parent=22163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/categories?post=22163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/tags?post=22163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}