{"id":22125,"date":"2025-03-27T19:43:24","date_gmt":"2025-03-27T19:43:24","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=22125"},"modified":"2025-04-17T07:09:11","modified_gmt":"2025-04-17T07:09:11","slug":"yyreter","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/fr\/archives\/22125","title":{"rendered":"Salman Al-Farisi - Le chercheur de v\u00e9rit\u00e9"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"22125\" class=\"elementor elementor-22125\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7fcbd613 e-flex e-con-boxed e-con e-parent\" data-id=\"7fcbd613\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-454d8617 elementor-widget elementor-widget-text-editor\" data-id=\"454d8617\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><h1 class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">9 janvier 2020<\/span><\/span><\/h1><\/div><\/div><\/div><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Actions possibles pour ce poste\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><strong>Salman Al-Farisi - Le chercheur de v\u00e9rit\u00e9<\/strong><br class=\"html-br\" \/>Tout au long de la p\u00e9riode consacr\u00e9e \u00e0 l&#039;\u00e9criture de mon livre (Les Lettres Attendues) et jusqu&#039;\u00e0 aujourd&#039;hui, l&#039;histoire du noble compagnon Salman Al-Farsi n&#039;a jamais quitt\u00e9 mon esprit. Son histoire a \u00e9t\u00e9 pour moi une source d&#039;inspiration et un v\u00e9ritable exemple de patience et d&#039;effort dans la qu\u00eate de la v\u00e9rit\u00e9. Salman, qu&#039;Allah l&#039;agr\u00e9e, a v\u00e9cu entre le zoroastrisme, le christianisme et le juda\u00efsme avant l&#039;av\u00e8nement de l&#039;islam, et il a continu\u00e9 \u00e0 chercher la vraie religion jusqu&#039;\u00e0 ce qu&#039;Allah l&#039;y guide. Il n&#039;a pas soumis son esprit et son c\u0153ur aux traditions et croyances h\u00e9rit\u00e9es de sa patrie. S&#039;il avait adh\u00e9r\u00e9 jusqu&#039;\u00e0 sa mort, il n&#039;aurait pas \u00e9t\u00e9 parmi les compagnons du Proph\u00e8te (paix et b\u00e9n\u00e9dictions d&#039;Allah sur lui). Il n&#039;aurait pas \u00e9t\u00e9 guid\u00e9 vers l&#039;islam et serait mort dans son polyth\u00e9isme.<br class=\"html-br\" \/>Bien qu'il ait grandi en Perse au milieu du culte du feu, Salman le Persan \u00e9tait \u00e0 la recherche de la vraie religion et est parti \u00e0 la recherche de Dieu. Il n'\u00e9tait pas convaincu de cette religion, mais comme ses parents y \u00e9taient attach\u00e9s, il l'a embrass\u00e9e avec eux. Lorsque ses doutes sur sa religion et celle de sa famille se sont intensifi\u00e9s, Salman a quitt\u00e9 son pays, la Perse, et a \u00e9migr\u00e9 au Levant \u00e0 la recherche de la v\u00e9rit\u00e9 religieuse absolue. Il a rencontr\u00e9 des moines et des pr\u00eatres au Levant et, apr\u00e8s un long voyage, Salman est arriv\u00e9 comme esclave \u00e0 M\u00e9dine. Lorsqu'il a entendu parler du Proph\u00e8te (sur lui la paix), il l'a rencontr\u00e9 et s'est converti \u00e0 l'islam apr\u00e8s avoir \u00e9t\u00e9 convaincu de son message.<br class=\"html-br\" \/>Salman a grandi dans la descendance d'une famille aristocratique, vivant au paradis en Perse, et son p\u00e8re l'aimait tellement et le craignait tellement qu'il l'enfermait dans sa maison, et Salman avait progress\u00e9 dans le magiisme jusqu'\u00e0 devenir l'habitant du feu qui br\u00fble et ne le laisse pas s'\u00e9teindre pendant une heure.<br class=\"html-br\" \/>Un jour, son p\u00e8re lui demande de se rendre \u00e0 son domaine pour s'en occuper en raison de son emploi du temps charg\u00e9 et lui demande de ne pas \u00eatre en retard pour qu'il ne s'inqui\u00e8te pas. Sur le chemin du domaine, Salman passe devant une \u00e9glise o\u00f9 les gens prient, il entre et les admire et dit : \"Ceci - par Dieu - est mieux que la religion que nous pratiquons\". Il ne les quitte pas jusqu'au coucher du soleil.<br class=\"html-br\" \/>Salman est retourn\u00e9 voir son p\u00e8re et lui a racont\u00e9 ce qui s'\u00e9tait pass\u00e9. Il lui a dit qu'il \u00e9tait impressionn\u00e9 par cette religion et l'a encha\u00een\u00e9.<br class=\"html-br\" \/>Salman raconte : J'ai envoy\u00e9 des chr\u00e9tiens et je leur ai dit : \"Si un groupe de marchands du Levant vient \u00e0 vous, parlez-moi d'eux\". Ils le lui ont dit et il s'est enfui de la maison de son p\u00e8re vers le Levant.<br class=\"html-br\" \/>Lorsque celui-ci mourut, on lui recommanda d'aller voir un \u00e9v\u00eaque de Mossoul qui \u00e9tait dans le m\u00eame \u00e9tat de droiture et attendait la mission du Proph\u00e8te ; il alla donc le voir et resta avec lui pendant un certain temps. Lorsque celui-ci mourut, on lui recommanda d'aller voir un \u00e9v\u00eaque de Nusaybin, et l'affaire se r\u00e9p\u00e9ta jusqu'\u00e0 ce qu'il arrive \u00e0 un \u00e9v\u00eaque du peuple d'Amauria \u00e0 Rome, qui lui parla de l'\u00e9poque du Proph\u00e8te, qu'Allah le b\u00e9nisse et lui accorde la paix et les b\u00e9n\u00e9dictions. L'\u00e9v\u00eaque lui dit : \"Mon fils, par Dieu, je ne sais pas s'il reste quelqu'un qui soit dans la m\u00eame situation que nous, alors je t'ordonne de venir \u00e0 lui, mais le temps est venu pour un proph\u00e8te d'\u00eatre envoy\u00e9 du sanctuaire, dont l'\u00e9migration se fera entre deux libert\u00e9s vers une terre d\u00e9serte avec des palmiers, et il y aura en lui des signes qui ne seront pas cach\u00e9s, et entre ses \u00e9paules se trouve le sceau de la proph\u00e9tie, et il mangera un cadeau et ne mangera pas la charit\u00e9, alors si tu peux te rendre dans ce pays, fais-le.<br class=\"html-br\" \/>Il partit avec eux \u00e0 la recherche du proph\u00e8te de la fin des temps, mais en chemin, ils le vendirent \u00e0 un juif et l'amen\u00e8rent \u00e0 M\u00e9dine, o\u00f9 il reconnut \u00e0 ses palmiers qu'il s'agissait de la ville du Proph\u00e8te (sur lui la paix) telle que l'\u00e9v\u00eaque la lui avait d\u00e9crite.<br class=\"html-br\" \/>Salman raconte l'histoire de l'arriv\u00e9e du Proph\u00e8te \u00e0 M\u00e9dine : \"Allah a envoy\u00e9 son Proph\u00e8te (paix et salut sur lui) \u00e0 la Mecque sans me parler d'aucune de ses affaires, malgr\u00e9 mon esclavage, jusqu'\u00e0 ce que le Messager d'Allah (paix et salut sur lui) arrive \u00e0 Qibaa, alors que je travaillais pour mon ami dans un palmier, quand j'ai entendu la nouvelle de l'arriv\u00e9e du Proph\u00e8te, je suis descendu en disant : \"Quelle est cette nouvelle ?\" Mon ma\u00eetre leva la main et me donna un violent coup de poing en disant : \"Qu'est-ce que tu as, retourne \u00e0 ton travail ?\"<br class=\"html-br\" \/>Salman voulait tester les qualit\u00e9s du proph\u00e8te (sur lui la paix) dont l'\u00e9v\u00eaque lui avait parl\u00e9, \u00e0 savoir qu'il ne mange pas la charit\u00e9 et accepte les cadeaux, que l'anneau de la proph\u00e9tie se trouve entre ses \u00e9paules et d'autres signes. Il est donc all\u00e9 voir le proph\u00e8te (sur lui la paix) le soir et a pris de la nourriture avec lui en lui disant que cette nourriture \u00e9tait de la charit\u00e9, mais le proph\u00e8te a ordonn\u00e9 \u00e0 ses compagnons de manger et il n'a pas mang\u00e9, Salman a donc su qu'il s'agissait d'un des signes.<br class=\"html-br\" \/>Puis il retourna voir le proph\u00e8te (sur lui la paix), rassembla de la nourriture et lui dit que c'\u00e9tait un cadeau, et le proph\u00e8te (sur lui la paix) et ses compagnons mang\u00e8rent, de sorte qu'il sut qu'il s'agissait du deuxi\u00e8me signe.<br class=\"html-br\" \/>Salman a cherch\u00e9 l'anneau de la proph\u00e9tie et a dit : \"J'ai rencontr\u00e9 le Messager d'Allah, qu'Allah le b\u00e9nisse et lui accorde la paix, alors qu'il suivait un enterrement et qu'il \u00e9tait dans ses compagnons, je me suis tourn\u00e9 vers son dos pour voir si je pouvais voir l'anneau qui m'avait \u00e9t\u00e9 d\u00e9crit. Lorsqu'il me vit me retourner, il comprit que je m'enqu\u00e9rais de quelque chose qui m'avait \u00e9t\u00e9 d\u00e9crit ; il jeta donc sa robe sur son dos, et je regardai l'anneau et le reconnus ; je m'agenouillai donc pour l'embrasser et je pleurai\". Le Proph\u00e8te (sur lui la paix) demanda aux compagnons du Proph\u00e8te (sur lui la paix) de l'aider, et effectivement Salman fut lib\u00e9r\u00e9 et resta un compagnon du Proph\u00e8te (sur lui la paix), \u00e0 tel point que le Proph\u00e8te (sur lui la paix) dit : \"Salman est l'un des n\u00f4tres de la famille de la maison\".<br class=\"html-br\" \/>Le voyage de Salman vers la v\u00e9rit\u00e9 a \u00e9t\u00e9 long et difficile : il est pass\u00e9 du magiisme en Perse au christianisme au Levant, puis \u00e0 l'esclavage dans la p\u00e9ninsule arabique, jusqu'\u00e0 ce que Dieu tout-puissant le guide vers le Proph\u00e8te (Que la Paix soit sur lui) et l'islam.<br class=\"html-br\" \/>\u00d4 Dieu, unis-moi \u00e0 lui et \u00e0 ses compagnons, que Dieu les agr\u00e9e, dans le plus haut paradis.\u00a0<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>9 \u064a\u0646\u0627\u064a\u0631 2020 \u00a0 \u0633\u0644\u0645\u0627\u0646 \u0627\u0644\u0641\u0627\u0631\u0633\u064a \u0640 \u0627\u0644\u0628\u0627\u062d\u062b \u0639\u0646 \u0627\u0644\u062d\u0642\u064a\u0642\u0629\u0637\u0648\u0627\u0644 \u0627\u0644\u0641\u062a\u0631\u0629 \u0627\u0644\u062a\u064a \u0642\u0636\u064a\u062a\u0647\u0627 \u0641\u064a \u062a\u0623\u0644\u064a\u0641 \u0643\u062a\u0627\u0628\u064a (\u0627\u0644\u0631\u0633\u0627\u0626\u0644 \u0627\u0644\u0645\u0646\u062a\u0638\u0631\u0629) \u0648\u062d\u062a\u0649 \u0627\u0644\u0622\u0646 \u0643\u0627\u0646\u062a \u0642\u0635\u0629 \u0627\u0644\u0635\u062d\u0627\u0628\u064a \u0627\u0644\u062c\u0644\u064a\u0644 \u0633\u0644\u0645\u0627\u0646 \u0627\u0644\u0641\u0627\u0631\u0633\u064a \u0644\u0627 \u062a\u063a\u0627\u062f\u0631 \u0630\u0647\u0646\u064a \u0641\u0642\u062f \u0643\u0627\u0646\u062a \u0642\u0635\u062a\u0647 \u0645\u0635\u062f\u0631 \u0627\u0644\u0647\u0627\u0645 \u0644\u064a \u0648\u0645\u062b\u0627\u0644 \u062d\u0642\u064a\u0642\u064a \u0639\u0644\u0649 \u0627\u0644\u0635\u0628\u0631 \u0648\u0627\u0644\u062a\u0639\u0628 \u0641\u064a \u0633\u0628\u064a\u0644 \u0627\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u0627\u0644\u062d\u0642\u064a\u0642\u0629\u060c \u0641\u0642\u062f \u0639\u0627\u064a\u0634 \u0633\u0644\u0645\u0627\u0646 \u0631\u0636\u064a \u0627\u0644\u0644\u0647 \u0639\u0646\u0647 \u0627\u0644\u0645\u062c\u0648\u0633\u064a\u0629 \u0648\u0627\u0644\u0646\u0635\u0631\u0627\u0646\u064a\u0629 \u0648\u0627\u0644\u064a\u0647\u0648\u062f\u064a\u0629 \u0642\u0628\u064a\u0644 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":22126,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[113,118,184],"tags":[],"class_list":{"0":"post-22125","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-113","8":"category-118","9":"category-184"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts\/22125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/comments?post=22125"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts\/22125\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/media\/22126"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/media?parent=22125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/categories?post=22125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/tags?post=22125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}