{"id":21849,"date":"2025-03-27T10:45:34","date_gmt":"2025-03-27T10:45:34","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=21849"},"modified":"2025-04-20T10:04:01","modified_gmt":"2025-04-20T10:04:01","slug":"fghgfdf","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/fr\/archives\/21849","title":{"rendered":"Bataille du pont"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"21849\" class=\"elementor elementor-21849\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-168cbfe1 e-flex e-con-boxed e-con e-parent\" data-id=\"168cbfe1\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64d545a4 elementor-widget elementor-widget-text-editor\" data-id=\"64d545a4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><h1 class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\" aria-describedby=\"\u00abrap\u00bb\">4 d\u00e9cembre 2013<\/span><\/span><\/h1><\/div><\/div><\/div><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Actions possibles pour ce poste\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">Il existe d\u00e9sormais une faction politique qui, \u00e0 chaque fois que je la vois, me rappelle les musulmans lors de la bataille du Pont.<br class=\"html-br\" \/>Quand vous lirez cette bataille, vous conna\u00eetrez cette faction politique<br class=\"html-br\" \/><br class=\"html-br\" \/>L&#039;histoire militaire islamique nous offre de nombreux enseignements, n\u00e9cessaires et possibles \u00e0 retenir en toutes circonstances. M\u00eame les batailles perdues par les musulmans nous obligent \u00e0 nous arr\u00eater et \u00e0 examiner les raisons de cette d\u00e9faite. La plus c\u00e9l\u00e8bre de ces batailles est peut-\u00eatre celle du Pont, qui eut lieu le 23 Sha&#039;ban de l&#039;an 13 de l&#039;H\u00e9gire.<br class=\"html-br\" \/>Atmosph\u00e8re de pr\u00e9paration au combat<br class=\"html-br\" \/>Suite aux d\u00e9veloppements militaires sur le front face aux Romains, une grande partie de l&#039;arm\u00e9e fut red\u00e9ploy\u00e9e sur le front face \u00e0 ces derniers. Les Perses concentr\u00e8rent alors leurs efforts sur l&#039;\u00e9limination de la pr\u00e9sence islamique en Irak. Le commandant Muthanna ibn Haritha d\u00e9cida de rassembler l&#039;arm\u00e9e musulmane \u00e0 la fronti\u00e8re irakienne. Il alla rapidement pr\u00e9senter la situation au calife Abou Bakr al-Siddiq (qu&#039;Allah l&#039;agr\u00e9e), mais le trouva mourant. Il mourut peu apr\u00e8s et fut remplac\u00e9 par Omar ibn al-Khattab (qu&#039;Allah l&#039;agr\u00e9e). Muthanna lui pr\u00e9senta la situation militaire en Irak. Omar ibn al-Khattab avait de nombreuses t\u00e2ches devant lui apr\u00e8s son accession au califat. Cependant, il donna la priorit\u00e9 au djihad contre les Perses en Irak. Il appela le peuple \u00e0 mener le djihad contre les Perses. Cependant, la situation n&#039;\u00e9tait pas tout \u00e0 fait claire pour les musulmans pendant cette p\u00e9riode de transition entre les r\u00e8gnes de deux califes, et le peuple h\u00e9sita \u00e0 r\u00e9pondre \u00e0 cet appel. Apr\u00e8s de nombreuses tentatives, environ un millier d&#039;hommes r\u00e9pondirent. Il les rassembla et nomma Abou Ubayd al-Thaqafi \u00e0 leur commandement, les dirigeant vers l&#039;Irak. Selon l&#039;avis unanime des historiens, Abou Ubaid al-Thaqafi n&#039;\u00e9tait pas pleinement qualifi\u00e9 pour diriger, mais il \u00e9tait connu pour son courage, sa loyaut\u00e9 et sa pi\u00e9t\u00e9, \u00e0 tel point que son courage \u00e9tait un exemple parmi les Arabes de l&#039;\u00e9poque, un fait dont Omar ibn Al-Khattab, que Dieu l&#039;agr\u00e9e, \u00e9tait conscient. Cependant, durant cette p\u00e9riode difficile, il n&#039;eut d&#039;autre choix que de confier le commandement de l&#039;arm\u00e9e \u00e0 Abou Ubaid. D\u00e8s son entr\u00e9e en Irak, celui-ci organisa les rangs et, gr\u00e2ce \u00e0 Dieu et \u00e0 son courage et \u00e0 son audace, put reconqu\u00e9rir toutes les terres abandonn\u00e9es par les musulmans. Avec son arm\u00e9e, qui ne comptait pas plus de dix mille combattants, il remporta trois batailles majeures\u00a0: Al-Namariq, Al-Saqatiyah et Baqisyatha. Le calife Omar suivait de pr\u00e8s et directement les nouvelles d&#039;Abou Ubaid et \u00e9tait rassur\u00e9 de son \u00e9ligibilit\u00e9 \u00e0 diriger l&#039;arm\u00e9e apr\u00e8s les victoires qu&#039;il avait remport\u00e9es.<br class=\"html-br\" \/>La situation des Perses<br class=\"html-br\" \/>Ces victoires remport\u00e9es par les musulmans sous la conduite d&#039;Abou Oba\u00efd eurent un impact retentissant sur les Perses. Le front int\u00e9rieur perse fut profond\u00e9ment \u00e9branl\u00e9, \u00e0 tel point que les adversaires de Rostam se r\u00e9volt\u00e8rent contre lui, l&#039;accusant de n\u00e9gligence et d&#039;inaction dans la lutte contre les musulmans. Le moral commen\u00e7a \u00e0 s&#039;effondrer dans les rangs de l&#039;arm\u00e9e perse. Rostam dut agir pour enrayer la d\u00e9gradation sur le front int\u00e9rieur et, pour remporter une victoire sur l&#039;arm\u00e9e musulmane, remonter le moral de son arm\u00e9e. Il convoqua les plus hauts grad\u00e9s et convoqua le commandant Al-Jalinos, qui avait fui les combats contre les musulmans. Furieux, il le condamna \u00e0 mort avec sursis, le r\u00e9trogradant de commandant en chef \u00e0 commandant en chef adjoint. Il consulta ensuite les commandants sup\u00e9rieurs de ses arm\u00e9es sur les moyens de remporter une victoire sur les musulmans, ne serait-ce qu&#039;une seule fois, afin de remonter le moral des soldats perses, vaincus \u00e0 chaque rencontre. Rostam \u00e9tait astucieux\u00a0; il rencontra Al-Jalinos, l&#039;ancien commandant de l&#039;arm\u00e9e, et le consulta sur les forces et les faiblesses de l&#039;arm\u00e9e musulmane. Al-Jalinos lui expliqua qu&#039;un nombre important d&#039;hommes \u00e9tait inutile face \u00e0 l&#039;arm\u00e9e musulmane. Leur style de combat reposait sur des attaques \u00e9clair, ils excellaient dans les zones plates rappelant leur environnement d\u00e9sertique, et d&#039;autres facteurs que Rustum avait pris en compte et dont il avait tir\u00e9 profit pour pr\u00e9parer l&#039;arm\u00e9e.<br class=\"html-br\" \/>La premi\u00e8re mesure prise par Rostam fut de choisir un commandant fort pour l&#039;arm\u00e9e. Il choisit le plus habile et le plus intelligent des commandants perses, Dhu al-Hajib Bahman Jadhuyeh. C&#039;\u00e9tait l&#039;un des commandants perses les plus arrogants et les plus haineux envers les musulmans et les Arabes. On le surnommait Dhu al-Hajib car il avait l&#039;habitude de froncer ses \u00e9pais sourcils pour les relever par arrogance. Rostam lui confia le commandement de l&#039;arm\u00e9e, qui comptait plus de soixante-dix mille Perses. Il choisit \u00e9galement lui-m\u00eame les commandants des soldats et les h\u00e9ros de la cavalerie. Pour contrer la m\u00e9thode de combat \u00e9clair des musulmans, il \u00e9quipa l&#039;arm\u00e9e pour la premi\u00e8re fois d&#039;armes blind\u00e9es perses, notamment des \u00e9l\u00e9phants. Pour conf\u00e9rer une importance particuli\u00e8re \u00e0 cette arm\u00e9e blind\u00e9e, Rostam lui donna la grande banni\u00e8re perse, appel\u00e9e Darvin Kabyan, en peau de tigre. Cette banni\u00e8re n&#039;\u00e9tait arbor\u00e9e que par leurs rois lors des batailles d\u00e9cisives.<br class=\"html-br\" \/>Abou Oba\u00efd suivait les mouvements militaires perses gr\u00e2ce \u00e0 ses renseignements et re\u00e7ut des nouvelles de l&#039;immense arm\u00e9e que Rustam avait pr\u00e9par\u00e9e pour combattre l&#039;arm\u00e9e musulmane. Il se dirigea avec son arm\u00e9e vers une zone au nord d&#039;Al-Hirah appel\u00e9e \u00ab Qais Al-Natif \u00bb, et y campa avec son arm\u00e9e, attendant l&#039;arriv\u00e9e de l&#039;arm\u00e9e perse. Les Perses arriv\u00e8rent et se post\u00e8rent de l&#039;autre c\u00f4t\u00e9 de l&#039;Euphrate, les musulmans \u00e0 l&#039;ouest et les Perses \u00e0 l&#039;est, sous la conduite de Bahman Jadhuyeh. Entre les deux rives se trouvait un pont flottant que les Perses avaient construit \u00e0 l&#039;\u00e9poque pour la guerre. Les Perses \u00e9taient experts dans la construction de ces ponts. Bahman Jadhuyeh envoya un messager \u00e0 l&#039;arm\u00e9e musulmane pour lui dire : \u00ab Soit nous traversons vers vous, soit vous traversez vers nous. \u00bb<br class=\"html-br\" \/>Abou Ubaid d\u00e9sob\u00e9it aux conseils d&#039;Omar<br class=\"html-br\" \/>Omar ibn al-Khattab conseilla \u00e0 Abou &#039;Oba\u00efd avant qu&#039;il ne parte au combat : \u00ab Ne r\u00e9v\u00e8le pas tes secrets, car tu es ma\u00eetre de tes affaires jusqu&#039;\u00e0 ce qu&#039;ils soient r\u00e9v\u00e9l\u00e9s, et ne parle de rien avant d&#039;avoir consult\u00e9 les Compagnons du Messager d&#039;Allah (paix et b\u00e9n\u00e9dictions d&#039;Allah sur lui). \u00bb Il lui recommanda sp\u00e9cifiquement de s&#039;adresser \u00e0 Sa&#039;d ibn &#039;Oba\u00efd al-Ansari et Sulayt ibn Qays, deux des nobles Compagnons (qu&#039;Allah les agr\u00e9e tous). Abou &#039;Oba\u00efd commit la premi\u00e8re erreur en discutant et en consultant ses compagnons devant le messager persan. Il r\u00e9v\u00e9lait ainsi un secret et des questions d&#039;organisation militaire. Lorsque le message lui parvint, il devint furieux et dit : \u00ab Par Allah, je ne les laisserai pas traverser et dire que nous \u00e9tions des l\u00e2ches qui avons refus\u00e9 de les rencontrer. \u00bb Les Compagnons accept\u00e8rent de ne pas traverser et lui dirent : \u00ab Comment peux-tu traverser et couper ta ligne de retraite, avec l&#039;Euphrate derri\u00e8re toi ?! \u00bb Les musulmans et les peuples de la p\u00e9ninsule arabique \u00e9taient experts en guerre dans le d\u00e9sert. Ils y \u00e9tablissaient toujours une ligne de repli. En cas de d\u00e9faite, l&#039;arm\u00e9e pouvait y retourner sans \u00eatre compl\u00e8tement d\u00e9truite. Cependant, Abou Oba\u00efd insista sur son souhait de traverser. Ses compagnons lui rappel\u00e8rent les paroles d&#039;Omar ibn al-Khattab\u00a0: \u00ab\u00a0Consulte les compagnons du Messager d&#039;Allah (paix et b\u00e9n\u00e9dictions d&#039;Allah sur lui).\u00a0\u00bb Il dit\u00a0: \u00ab\u00a0Par Allah, nous ne serons pas des l\u00e2ches \u00e0 leurs yeux.\u00a0\u00bb Tout cela se d\u00e9roulait sous les yeux du messager persan, qui en profita pour attiser la col\u00e8re d&#039;Abou Oba\u00efd en disant\u00a0: \u00ab\u00a0Ils disent que vous \u00eates des l\u00e2ches et que vous ne traverserez jamais pour nous.\u00a0\u00bb Abou Oba\u00efd r\u00e9pondit\u00a0: \u00ab\u00a0Alors nous traverserons pour eux.\u00a0\u00bb Les soldats \u00e9cout\u00e8rent et ob\u00e9irent, et l&#039;arm\u00e9e musulmane commen\u00e7a \u00e0 traverser ce pont \u00e9troit pour atteindre l&#039;autre rive, o\u00f9 se trouvait l&#039;arm\u00e9e perse.<br class=\"html-br\" \/>Nous remarquons dans cette situation que l&#039;arm\u00e9e islamique est entr\u00e9e dans une zone confin\u00e9e entre le Nil, un petit fleuve affluent de l&#039;Euphrate, et l&#039;Euphrate. Les deux fleuves sont pleins d&#039;eau, et l&#039;arm\u00e9e perse bloque le reste de la zone. Si les musulmans p\u00e9n\u00e9traient dans cette zone, ils n&#039;auraient d&#039;autre choix que de combattre l&#039;arm\u00e9e perse. Les Perses, conscients de l&#039;importance de cet emplacement, ont donc d\u00e9gag\u00e9 un \u00e9troit espace pour que les musulmans puissent traverser jusqu&#039;\u00e0 eux. L&#039;arm\u00e9e islamique \u00e9tait regroup\u00e9e dans un espace tr\u00e8s restreint. Al-Muthanna ibn Haritha le vit et r\u00e9p\u00e9ta son conseil \u00e0 Abou Oba\u00efd : \u00ab Tu ne fais que nous pr\u00e9cipiter dans la destruction. \u00bb Abou Oba\u00efd maintint son avis. L&#039;arm\u00e9e islamique a effectivement p\u00e9n\u00e9tr\u00e9 dans cette zone. Les Perses avaient dix \u00e9l\u00e9phants, dont l&#039;\u00e9l\u00e9phant blanc, le plus c\u00e9l\u00e8bre et le plus grand des \u00e9l\u00e9phants perses en guerre. Tous les \u00e9l\u00e9phants le suivaient. S&#039;il avan\u00e7ait, ils avan\u00e7aient, et s&#039;il reculait, ils reculaient.<br class=\"html-br\" \/>La bataille<br class=\"html-br\" \/>La bataille s&#039;engagea et les arm\u00e9es perses, men\u00e9es par des \u00e9l\u00e9phants, avanc\u00e8rent vers l&#039;arm\u00e9e musulmane coinc\u00e9e entre l&#039;Euphrate et son affluent, le Nil. Les forces musulmanes recul\u00e8rent progressivement devant les \u00e9l\u00e9phants, mais derri\u00e8re elles se trouvaient deux fleuves, les for\u00e7ant \u00e0 attendre leur attaque. Le courage et la force des musulmans \u00e9taient exceptionnels et ils entr\u00e8rent en combat. Mais les chevaux, d\u00e8s qu&#039;ils aper\u00e7urent les \u00e9l\u00e9phants, prirent la fuite, ce qui emp\u00eacha les musulmans d&#039;avancer. Les chevaux revinrent et attaqu\u00e8rent l&#039;infanterie musulmane. Leurs tentatives pour forcer les chevaux \u00e0 avancer \u00e9chou\u00e8rent, faute d&#039;exp\u00e9rience face aux \u00e9l\u00e9phants. \u00c0 ce moment-l\u00e0, apr\u00e8s qu&#039;Abou &#039;Ubaid eut commis l&#039;erreur de r\u00e9v\u00e9ler le secret au messager persan, et commis une erreur en traversant contre l&#039;avis des compagnons du Messager de Dieu (que Dieu le b\u00e9nisse et lui accorde la paix), et commis une erreur en choisissant ce lieu pour la bataille, et apr\u00e8s toutes ces erreurs, il dut se retirer rapidement avec son arm\u00e9e du champ de bataille, comme Khalid ibn al-Walid l&#039;avait fait \u00e0 la bataille d&#039;al-Madhar, sachant qu&#039;il serait encercl\u00e9 par une arm\u00e9e venue du sud. Il se retira rapidement avec son arm\u00e9e jusqu&#039;\u00e0 rencontrer l&#039;arm\u00e9e d&#039;Andarzaghar \u00e0 l&#039;entr\u00e9e.<br class=\"html-br\" \/>Mais Abou Oba\u00efd \u00e9tait d\u00e9termin\u00e9 \u00e0 se battre et dit : \u00ab Je combattrai jusqu&#039;au bout. \u00bb Bien qu&#039;il s&#039;agisse d&#039;un acte de courage supr\u00eame de sa part, les guerres, tout comme elles reposent sur le courage, doivent \u00eatre men\u00e9es avec sagesse. Les \u00e9l\u00e9phants perses commenc\u00e8rent \u00e0 attaquer f\u00e9rocement les musulmans. Abou Oba\u00efd ordonna aux musulmans d&#039;abandonner leurs chevaux et de combattre les Perses \u00e0 pied. Les musulmans perdirent ainsi leur cavalerie et se retrouv\u00e8rent seuls face aux forces perses \u00e9quip\u00e9es de chevaux et d&#039;\u00e9l\u00e9phants. La bataille s&#039;intensifia et les musulmans n&#039;h\u00e9sit\u00e8rent pas \u00e0 se battre. Abou Oba\u00efd ibn Masoud al-Thaqafi s&#039;avan\u00e7a et dit : \u00ab Montrez-moi o\u00f9 tuer l&#039;\u00e9l\u00e9phant. \u00bb Il avait \u00e9galement dit : \u00ab Il sera tu\u00e9 par sa trompe. \u00bb Il s&#039;avan\u00e7a seul vers l&#039;\u00e9l\u00e9phant blanc, et ils lui dirent : \u00ab \u00d4 Abou Oba\u00efd, tu ne fais que te pr\u00e9cipiter dans la destruction, m\u00eame si tu es le commandant. \u00bb Il r\u00e9pondit : \u00ab Par Dieu, je ne le laisserai pas tranquille. Soit il me tue, soit je le tue. \u00bb Il se dirigea vers l&#039;\u00e9l\u00e9phant et coupa les ceintures qui portaient le commandant. Ce dernier tomba et fut tu\u00e9 par Abou Oba\u00efd ibn Masoud, mais l&#039;\u00e9l\u00e9phant \u00e9tait encore en vie, bien entra\u00een\u00e9 au combat. Abou Oba\u00efd entreprit de combattre ce puissant \u00e9l\u00e9phant, se dressant sur ses pattes arri\u00e8re et levant les pattes avant devant son visage. Cependant, Abou Oba\u00efd n&#039;h\u00e9sita pas \u00e0 se battre et \u00e0 tenter de le tuer. Lorsqu&#039;il comprit la difficult\u00e9 de la situation, il conseilla \u00e0 son entourage : \u00ab Si je meurs, le commandement de l&#039;arm\u00e9e reviendra \u00e0 un tel, puis \u00e0 un tel, puis \u00e0 un tel. \u00bb Il \u00e9num\u00e9ra les noms de ceux qui lui succ\u00e9deraient \u00e0 la t\u00eate de l&#039;arm\u00e9e. Ce fut \u00e9galement l&#039;une des erreurs d&#039;Abou Oba\u00efd, car le commandant de l&#039;arm\u00e9e doit se prot\u00e9ger, non par amour de la vie, mais par souci du bien-\u00eatre de son arm\u00e9e et de ses soldats dans de telles circonstances. Ce n&#039;est pas seulement une question de courage, car la mort du commandant brise le moral de l&#039;arm\u00e9e et bouleverse de nombreux \u00e9quilibres. Une autre erreur est qu&#039;Abou &#039;Oba\u00efd a recommand\u00e9 que l&#039;arm\u00e9e soit command\u00e9e apr\u00e8s lui par sept hommes de Thaqif, dont son fils, son fr\u00e8re et le huiti\u00e8me, Muthanna ibn Haritha. Il aurait \u00e9t\u00e9 plus appropri\u00e9 que le commandant soit Muthanna ou Sulayt ibn Qays imm\u00e9diatement apr\u00e8s lui, comme l&#039;a recommand\u00e9 Omar ibn al-Khattab, que Dieu l&#039;agr\u00e9e.<br class=\"html-br\" \/>Le martyre d&#039;Abou Ubaid et l&#039;accession d&#039;Al-Muthanna<br class=\"html-br\" \/>Abou Oba\u00efd continua son combat avec l&#039;\u00e9l\u00e9phant et tenta de lui couper la trompe, mais l&#039;\u00e9l\u00e9phant le surprit d&#039;un coup, le faisant tomber au sol. L&#039;\u00e9l\u00e9phant l&#039;attaqua et le pi\u00e9tina de ses pattes avant, le d\u00e9chiquetant. La situation fut difficile pour les musulmans lorsqu&#039;ils virent leur chef tu\u00e9 de cette fa\u00e7on horrible. Imm\u00e9diatement apr\u00e8s lui, le premier des sept prit le commandement de l&#039;arm\u00e9e et chargea \u00e0 cheval, se tuant et \u00e9tant tu\u00e9. Le deuxi\u00e8me et le troisi\u00e8me firent de m\u00eame, et ainsi de suite. Trois des fils d&#039;Abou Oba\u00efd ibn Massoud al-Thaqafi furent tu\u00e9s dans cette bataille. L&#039;un d&#039;eux \u00e9tait le commandant de l&#039;arm\u00e9e. Son fr\u00e8re, al-Hakam ibn Massoud al-Thaqafi, fut \u00e9galement tu\u00e9. Il \u00e9tait l&#039;un des commandants de l&#039;arm\u00e9e apr\u00e8s le martyre d&#039;Abou Oba\u00efd. Le commandement revint \u00e0 al-Muthanna ibn Haritha, et l&#039;affaire, comme nous le voyons, fut extr\u00eamement difficile, et les Perses lanc\u00e8rent une attaque f\u00e9roce contre les musulmans.<br class=\"html-br\" \/>\u00c0 ce moment-l\u00e0, des musulmans commenc\u00e8rent \u00e0 fuir en traversant le pont pour rejoindre l&#039;autre rive de l&#039;Euphrate. C&#039;\u00e9tait la premi\u00e8re fois depuis la conqu\u00eate perse que des musulmans fuyaient une bataille. Cette fuite, dans ce cas pr\u00e9cis, \u00e9tait l\u00e9gale et n&#039;\u00e9tait pas consid\u00e9r\u00e9e comme une fuite devant une avanc\u00e9e. On dit que fuir face \u00e0 une double force est permis. Que se passait-il alors lorsque l&#039;arm\u00e9e perse \u00e9tait six ou sept fois plus nombreuse que l&#039;arm\u00e9e musulmane\u00a0?! Mais l&#039;un des musulmans commit une autre grave erreur. Abdullah ibn Murthad al-Thaqafi alla couper le pont avec son \u00e9p\u00e9e, en disant\u00a0: \u00ab\u00a0Par Dieu, les musulmans ne fuiront pas la bataille\u00a0; combattez jusqu&#039;\u00e0 la mort pour ce que votre chef a fait.\u00a0\u00bb Les Perses reprirent le combat contre les musulmans, et la situation devint plus difficile. L&#039;homme qui avait coup\u00e9 le pont fut amen\u00e9 devant le commandant de l&#039;arm\u00e9e, Muthanna ibn Haritha. Muthanna le frappa et lui demanda\u00a0: \u00ab\u00a0Qu&#039;as-tu fait aux musulmans\u00a0?\u00a0\u00bb L&#039;homme r\u00e9pondit\u00a0: \u00ab\u00a0Je ne voulais pas que quiconque fuie la bataille.\u00a0\u00bb Le musulman r\u00e9pondit : \u00ab Ce n\u2019est pas une fuite. \u00bb<br class=\"html-br\" \/>Retrait ordonn\u00e9 \u00e0 travers le pont<br class=\"html-br\" \/>Al-Muthanna prit calmement la t\u00eate du reste de l&#039;arm\u00e9e musulmane apr\u00e8s les attaques perses f\u00e9roces et brutales. Il encouragea ses troupes en leur disant\u00a0: \u00ab\u00a0\u00d4 serviteurs d&#039;Allah, la victoire ou le paradis.\u00a0\u00bb Puis il appela les musulmans de l&#039;autre c\u00f4t\u00e9 \u00e0 r\u00e9parer le pont du mieux qu&#039;ils pouvaient. Des Perses, convertis \u00e0 l&#039;islam, \u00e9taient parmi les musulmans et capables de r\u00e9parer les ponts. Ils recommenc\u00e8rent donc \u00e0 r\u00e9parer le pont. Al-Muthanna entreprit l&#039;une des op\u00e9rations les plus difficiles\u00a0: un repli dans cet endroit \u00e9troit face aux forces perses violentes. Il fit venir les plus courageux des musulmans et les exhorta, sans les forcer, en disant\u00a0: \u00ab\u00a0Les plus courageux des musulmans se tiendront sur le pont pour le prot\u00e9ger.\u00a0\u00bb \u00c0 leur t\u00eate, Asim bin Amr Al-Tamimi, Zaid Al-Khail, Qais bin Sulayt, un compagnon du Messager de Dieu (paix et b\u00e9n\u00e9dictions d&#039;Allah sur lui), et notre ma\u00eetre Al-Muthanna bin Haritha, s&#039;avanc\u00e8rent pour prot\u00e9ger le pont. Ils se tenaient tous debout pour prot\u00e9ger l&#039;arm\u00e9e pendant la travers\u00e9e et pour garder le pont afin qu&#039;aucun Perse ne le coupe. Al-Muthanna bin Haritha dit \u00e0 l&#039;arm\u00e9e avec un calme \u00e9trange : \u00ab Traversez tranquillement et ne paniquez pas ; nous nous tiendrons devant vous, et par Dieu, nous ne quitterons pas cet endroit avant que le dernier d&#039;entre vous ne traverse. \u00bb Les musulmans commenc\u00e8rent \u00e0 se retirer un par un et combattirent jusqu&#039;au dernier moment. Le sang couvrait tout et les corps des musulmans, certains morts, d&#039;autres noy\u00e9s, s&#039;empilaient dans les deux fleuves. Le dernier martyr musulman sur le pont fut Suwaid ibn Qays, l&#039;un des compagnons du Proph\u00e8te (paix et b\u00e9n\u00e9dictions sur lui). Le dernier \u00e0 traverser le pont fut Al-Muthanna ibn Haritha. Il combattit jusqu&#039;au dernier moment et battit en retraite, les Perses devant lui. D\u00e8s qu&#039;il traversa le pont, il le coupa aux Perses, qui ne purent rejoindre les musulmans. Ces derniers firent demi-tour et atteignirent la rive occidentale de l&#039;Euphrate peu avant le coucher du soleil. Les Perses ne combattirent pas la nuit et abandonn\u00e8rent les musulmans. C&#039;\u00e9tait l&#039;occasion pour l&#039;arm\u00e9e musulmane de s&#039;\u00e9chapper en se retirant au plus profond du d\u00e9sert. Si elle \u00e9tait rest\u00e9e sur place, l&#039;arm\u00e9e perse aurait travers\u00e9 au matin et tu\u00e9 ceux qui \u00e9taient rest\u00e9s.<br class=\"html-br\" \/>Apr\u00e8s la bataille<br class=\"html-br\" \/>\u00c0 cette \u00e9poque, deux mille musulmans avaient fui, et certains poursuivirent leur fuite vers M\u00e9dine. Quatre mille musulmans tomb\u00e8rent en martyrs lors de cette bataille. Huit mille y particip\u00e8rent, dont quatre mille furent tu\u00e9s, martyrs au combat ou noy\u00e9s dans le fleuve. Parmi ces quatre mille, la majorit\u00e9 des habitants de Thaqeef et nombre de ceux qui furent t\u00e9moins de Badr, d&#039;Uhud et des combats contre le Messager de Dieu (paix et b\u00e9n\u00e9dictions d&#039;Allah sur lui). La situation \u00e9tait difficile pour les musulmans, et sans la gr\u00e2ce de Dieu Tout-Puissant et la nomination de Muthanna bin Haritha, aucun r\u00e9chapp\u00e9 n&#039;aurait pu \u00e9chapper \u00e0 ce pi\u00e8ge bien pr\u00e9par\u00e9 par les Perses. Muthanna poss\u00e9dait une comp\u00e9tence militaire in\u00e9gal\u00e9e, et c&#039;est l\u00e0 la valeur d&#039;un bon leadership. Abou &#039;Oba\u00efd bin Masoud \u00e9tait plein de courage, de foi et d&#039;audace. Il fut le premier \u00e0 \u00eatre mobilis\u00e9 et partit pour le djihad en pr\u00e9sence de nombreux Compagnons. Il s&#039;\u00e9tait mis en route devant eux et avait \u00e9t\u00e9 nomm\u00e9 commandant de l&#039;arm\u00e9e. Il s&#039;engagea dans la guerre avec un courage absolu et, pour l&#039;amour de Dieu, ne fut point bl\u00e2m\u00e9. Il s&#039;avan\u00e7a pour attaquer l&#039;\u00e9l\u00e9phant, sachant qu&#039;il serait tu\u00e9\u00a0; il recommanda donc le commandement \u00e0 son successeur et n&#039;h\u00e9sita pas \u00e0 combattre. Cependant, diriger une arm\u00e9e n&#039;est pas seulement une question de bravoure et de foi, mais aussi de grande habilet\u00e9 et de comp\u00e9tence militaire, \u00e0 tel point que certains juristes ont d\u00e9clar\u00e9\u00a0: \u00ab\u00a0S&#039;il y a deux chefs, dont l&#039;un a une position de foi mais ignore la valeur du leadership et de l&#039;\u00e9mirat, et l&#039;autre a atteint le niveau d&#039;immoralit\u00e9 mais est musulman et est capable de mener les guerres avec habilet\u00e9, alors il n&#039;y a rien de mal \u00e0 ce que cet immoral soit \u00e0 la t\u00eate de l&#039;arm\u00e9e, car il peut sauver toute l&#039;arm\u00e9e musulmane, tandis que l&#039;autre pourrait la mener \u00e0 la destruction malgr\u00e9 sa foi et son courage.\u00a0\u00bb<br class=\"html-br\" \/>La bataille du Pont eut lieu le 23 Chaban de l&#039;an 13 de l&#039;H\u00e9gire. Abou Oba\u00efd \u00e9tait arriv\u00e9 en Irak le 3 Chaban. Sa premi\u00e8re bataille eut lieu \u00e0 Namariq le 8 Chaban, puis \u00e0 Saqatiyah le 12 Chaban, puis \u00e0 Baqisyatha le 17 Chaban, et enfin cette bataille le 23 Chaban. Vingt jours apr\u00e8s l&#039;arriv\u00e9e d&#039;Abou Oba\u00efd et de son arm\u00e9e, les musulmans remport\u00e8rent trois batailles et furent vaincus lors d&#039;une bataille qui an\u00e9antit la moiti\u00e9 de l&#039;arm\u00e9e. Ceux qui rest\u00e8rent s&#039;enfuirent, et seuls deux mille combattants rest\u00e8rent avec Al-Muthanna. Al-Muthanna transmit la nouvelle \u00e0 M\u00e9dine avec Abdullah bin Zaid. \u00c0 son arriv\u00e9e, il trouva Omar bin Al-Khattab en chaire. Il lui confia l&#039;affaire, conscient de la difficult\u00e9 de la situation pour les musulmans. Omar pleura en chaire. Les musulmans devaient \u00eatre inform\u00e9s afin d&#039;\u00eatre mobilis\u00e9s pour aller \u00e0 nouveau aider les survivants de l&#039;arm\u00e9e en Irak. Apr\u00e8s avoir pleur\u00e9, il dit : \u00ab Que Dieu ait piti\u00e9 d&#039;Abou Ubaid ! S&#039;il n&#039;avait pas \u00e9t\u00e9 tu\u00e9 et s&#039;\u00e9tait retir\u00e9, nous aurions \u00e9t\u00e9 ses alli\u00e9s, mais Dieu a d\u00e9cr\u00e9t\u00e9 et ce qu&#039;Il veut, Il le fait. \u00bb Apr\u00e8s cela, ceux qui fuyaient la bataille arriv\u00e8rent \u00e0 M\u00e9dine, pleurant am\u00e8rement, disant : \u00ab Comment \u00e9chapper ?! Comment \u00e9chapper ?! \u00bb<br class=\"html-br\" \/>C&#039;\u00e9tait une honte et un d\u00e9shonneur pour les musulmans, car ils n&#039;avaient pas l&#039;habitude de fuir leurs ennemis auparavant. Cependant, Omar ibn al-Khattab (qu&#039;Allah l&#039;agr\u00e9e) les rassura et leur dit : \u00ab Je suis votre alli\u00e9, et ceci n&#039;est pas consid\u00e9r\u00e9 comme une fuite. \u00bb Omar continua de les motiver et de les encourager. Avec eux se trouvait Muadh al-Qari, l&#039;un des fuyards. Il dirigeait les musulmans dans les pri\u00e8res de Tarawih et, chaque fois qu&#039;il r\u00e9citait les versets sur la fuite, il pleurait en priant. Omar le rassura et lui dit : \u00ab Tu n&#039;es pas du nombre de ceux qui ont entendu ce verset. \u00bb<br class=\"html-br\" \/><br class=\"html-br\" \/><br class=\"html-br\" \/>Extrait du livre Unforgettable Days du major Tamer Badr\u00a0<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>4 \u062f\u064a\u0633\u0645\u0628\u0631 2013 \u00a0 \u0647\u0646\u0627\u0643 \u0641\u0635\u064a\u0644 \u0633\u064a\u0627\u0633\u064a \u0627\u0644\u0622\u0646 \u0643\u0644\u0645\u0627 \u0623\u0631\u0627\u0647 \u0623\u062a\u0630\u0643\u0631 \u0627\u0644\u0645\u0633\u0644\u0645\u0648\u0646 \u0641\u064a \u0645\u0639\u0631\u0643\u0629 \u0627\u0644\u062c\u0633\u0631\u0639\u0646\u062f\u0645\u0627 \u0633\u062a\u0642\u0631\u0624\u0648\u0646 \u0647\u0630\u0647 \u0627\u0644\u0645\u0639\u0631\u0643\u0629 \u0633\u062a\u0639\u0631\u0641\u0648\u0646 \u0647\u0630\u0627 \u0627\u0644\u0641\u0635\u064a\u0644 \u0627\u0644\u0633\u064a\u0627\u0633\u064a \u064a\u0642\u062f\u0645 \u0644\u0646\u0627 \u062a\u0627\u0631\u064a\u062e \u0627\u0644\u0639\u0633\u0643\u0631\u064a\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629 \u0643\u062b\u064a\u0631\u0627\u064b \u0645\u0646 \u0627\u0644\u062f\u0631\u0648\u0633 \u0627\u0644\u062a\u064a \u062a\u0628\u0642\u0649 \u0627\u0644\u0627\u0633\u062a\u0641\u0627\u062f\u0629 \u0645\u0646\u0647\u0627 \u0648\u0627\u062c\u0628\u0629 \u0648\u0645\u0645\u0643\u0646\u0629 \u0641\u064a \u0643\u0644 \u0648\u0642\u062a\u060c \u0648\u062d\u062a\u0649 \u062a\u0644\u0643 \u0627\u0644\u0645\u0639\u0627\u0631\u0643 \u0627\u0644\u062a\u064a \u062e\u0633\u0631 \u0641\u064a\u0647\u0627 \u0627\u0644\u0645\u0633\u0644\u0645\u0648\u0646 \u062a\u0633\u062a\u062f\u0639\u064a \u0627\u0644\u062a\u0648\u0642\u0641 \u0639\u0646\u062f\u0647\u0627 \u0648\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0623\u0633\u0628\u0627\u0628 \u0627\u0644\u062a\u064a \u0623\u062f\u062a \u0625\u0644\u0649 \u0627\u0644\u0647\u0632\u064a\u0645\u0629\u060c [&hellip;]<\/p>","protected":false},"author":2,"featured_media":21850,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[115],"tags":[],"class_list":{"0":"post-21849","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-115"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts\/21849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/comments?post=21849"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts\/21849\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/media\/21850"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/media?parent=21849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/categories?post=21849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/tags?post=21849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}