{"id":21114,"date":"2025-03-25T11:20:45","date_gmt":"2025-03-25T11:20:45","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=21114"},"modified":"2025-05-02T17:18:36","modified_gmt":"2025-05-02T17:18:36","slug":"refd","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/fr\/archives\/21114","title":{"rendered":"Vision de la Mosqu\u00e9e Blanche au Paradis le 31 mai 2022"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"21114\" class=\"elementor elementor-21114\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e530b30 e-flex e-con-boxed e-con e-parent\" data-id=\"1e530b30\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23641baf elementor-widget elementor-widget-text-editor\" data-id=\"23641baf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>J&#039;ai r\u00e9cemment particip\u00e9 \u00e0 la construction d&#039;une mosqu\u00e9e et j&#039;ai demand\u00e9 \u00e0 Dieu Tout-Puissant de la remplacer par un palais au paradis supr\u00eame. Aujourd&#039;hui, j&#039;ai eu une vision contenant des symboles que je souhaite interpr\u00e9ter, sachant qu&#039;il n&#039;y a ni maladies, ni m\u00e9dicaments, ni tentatives de meurtre, ni autres choses mat\u00e9rielles au paradis. Cependant, ces symboles dans la vision ont certainement une interpr\u00e9tation que je souhaite conna\u00eetre en la publiant avec vous. La vision est la suivante\u00a0:<br class=\"html-br\" \/>Je me suis aper\u00e7u que je me tenais devant une immense mosqu\u00e9e blanche au paradis. Je me suis rendu compte que cette mosqu\u00e9e m&#039;appartenait et qu&#039;elle avait \u00e9t\u00e9 construite sp\u00e9cialement pour moi, afin que je puisse participer \u00e0 la construction d&#039;une mosqu\u00e9e ici-bas, en r\u00e9ponse \u00e0 mes supplications. J&#039;y suis entr\u00e9 et j&#039;ai \u00e9t\u00e9 \u00e9merveill\u00e9 par la beaut\u00e9 de la mosqu\u00e9e, ses magnifiques pierres blanches entrecoup\u00e9es de magnifiques d\u00e9corations en bois brun. Je n&#039;avais jamais vu de mosqu\u00e9e aussi belle. La mosqu\u00e9e comportait plusieurs salles o\u00f9 priaient certains, et au milieu se trouvait une salle o\u00f9 l&#039;imam de la mosqu\u00e9e pouvait dormir. Il y avait aussi un endroit r\u00e9serv\u00e9 \u00e0 la distribution gratuite de m\u00e9dicaments. En sortant, deux femmes \u00e0 la peau fonc\u00e9e sont apparues \u00e0 c\u00f4t\u00e9 de moi. Je me suis rendu compte qu&#039;elles appartenaient aux gens de l&#039;Enfer. L&#039;une \u00e9tait h\u00e9sitante, l&#039;autre audacieuse. Je leur ai donc demand\u00e9 : \u00ab \u00cates-vous des gens de l&#039;Enfer ? \u00bb Elles ont acquiesc\u00e9 et, arriv\u00e9es au bout de la mosqu\u00e9e, j&#039;ai trouv\u00e9 une petite fille sur les marches. J&#039;avais peur pour elle \u00e0 cause des deux femmes, alors je la portai jusqu&#039;au seuil de la mosqu\u00e9e. Les deux femmes sortirent et soudain, elles surgirent. Elles brandissaient des \u00e9p\u00e9es et s&#039;appr\u00eataient \u00e0 se jeter sur la petite fille que je d\u00e9fendais avec l&#039;intention de la tuer. Mais j&#039;ai implor\u00e9 Dieu Tout-Puissant de nous prot\u00e9ger, moi et la petite fille. J&#039;ai commenc\u00e9 \u00e0 prier et \u00e0 r\u00e9p\u00e9ter plusieurs fois : \u00ab Il n&#039;y a de dieu que Toi, gloire \u00e0 Toi ! J&#039;\u00e9tais parmi les injustes \u00bb, pri\u00e8re de notre ma\u00eetre Jonas dans le ventre de la baleine. L&#039;\u00e9p\u00e9e tomba des mains de la jeune fille audacieuse, alors je la pris et la poignardai au ventre. Elle se transforma en poisson et mourut, tandis que l&#039;autre fille disparut.<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0643\u0646\u062a \u0642\u062f \u0634\u0627\u0631\u0643\u062a \u0642\u0631\u064a\u0628\u0627\u064b \u0641\u064a \u0627\u0646\u0634\u0627\u0621 \u0645\u0633\u062c\u062f \u0648\u062f\u0639\u0648\u062a \u0627\u0644\u0644\u0647 \u0633\u0628\u062d\u0627\u0646\u0647 \u0648\u062a\u0639\u0627\u0644\u064a \u0623\u0646 \u064a\u0628\u062f\u0644\u0646\u064a \u0628\u0647 \u0628\u0642\u0635\u0631 \u0641\u064a \u0627\u0644\u0641\u0631\u062f\u0648\u0633 \u0627\u0644\u0623\u0639\u0644\u0649 \u0641\u0631\u0623\u064a\u062a \u0627\u0644\u064a\u0648\u0645 \u062a\u0644\u0643 \u0627\u0644\u0631\u0624\u064a\u0627 \u0627\u0644\u062a\u064a \u064a\u0648\u062c\u062f \u0628\u0647\u0627 \u0628\u0639\u0636 \u0627\u0644\u0631\u0645\u0648\u0632 \u0627\u0644\u062a\u064a \u0627\u0631\u064a\u062f \u062a\u0641\u0633\u064a\u0631\u0647\u0627 \u0645\u0639 \u0627\u0644\u0639\u0644\u0645 \u0627\u0646\u0646\u064a \u0623\u0639\u0631\u0641 \u0623\u0646\u0647 \u0644\u0627 \u062a\u0648\u062c\u062f \u0623\u0645\u0631\u0627\u0636 \u0623\u0648 \u0623\u062f\u0648\u064a\u0647 \u0648\u0644\u0627 \u0645\u062d\u0627\u0648\u0644\u0627\u062a \u0642\u062a\u0644 \u0623\u0648 \u063a\u064a\u0631\u0647\u0627 \u0645\u0646 \u0623\u0645\u0648\u0631 \u0627\u0644\u062f\u0646\u064a\u0627 \u0641\u064a \u0627\u0644\u062c\u0646\u0629 \u0648\u0644\u0643\u0646\u0647\u0627 \u0631\u0645\u0648\u0632 \u0641\u064a \u0627\u0644\u0631\u0624\u064a\u0627 \u0648\u0628\u0627\u0644\u062a\u0623\u0643\u064a\u062f [&hellip;]<\/p>","protected":false},"author":2,"featured_media":21115,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[112],"tags":[],"class_list":{"0":"post-21114","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category--2021-"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts\/21114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/comments?post=21114"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts\/21114\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/media\/21115"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/media?parent=21114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/categories?post=21114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/tags?post=21114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}