{"id":20837,"date":"2025-03-24T11:59:22","date_gmt":"2025-03-24T11:59:22","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=20837"},"modified":"2025-04-27T18:58:09","modified_gmt":"2025-04-27T18:58:09","slug":"fdgfg","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/fr\/archives\/20837","title":{"rendered":"La vision de l&#039;Islam sur les gens apr\u00e8s avoir vu la lune se diviser avant la pri\u00e8re du Fajr le 16 f\u00e9vrier 2020"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"20837\" class=\"elementor elementor-20837\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34830f78 e-flex e-con-boxed e-con e-parent\" data-id=\"34830f78\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e111c3b elementor-widget elementor-widget-text-editor\" data-id=\"5e111c3b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Je crois que cette vision est directement li\u00e9e \u00e0 la vision que j\u2019ai eue avant-hier \u00e0 propos de la division de la lune le 14 f\u00e9vrier 2020.\u00a0<br class=\"html-br\" \/>La vision<br class=\"html-br\" \/>J&#039;ai vu des citoyens australiens s&#039;\u00eatre convertis \u00e0 l&#039;islam apr\u00e8s avoir assist\u00e9 au miracle de la division de la lune. Puis, j&#039;ai aper\u00e7u une jeune fille devant moi, probablement portugaise, qui voulait d\u00e9clarer sa conversion \u00e0 l&#039;islam apr\u00e8s avoir assist\u00e9 au miracle. Je lui ai donc parl\u00e9 en portugais et lui ai demand\u00e9 de r\u00e9p\u00e9ter apr\u00e8s moi (J&#039;atteste qu&#039;il n&#039;y a de dieu qu&#039;Allah et j&#039;atteste que Mahomet est le Messager d&#039;Allah) en portugais, tout en pleurant. Elle a donc r\u00e9p\u00e9t\u00e9 les deux t\u00e9moignages apr\u00e8s moi (sachant que je ne connaissais pas grand-chose au portugais).<br class=\"html-br\" \/>Puis la sc\u00e8ne s&#039;est d\u00e9plac\u00e9e : j&#039;\u00e9tais seul au sommet d&#039;un immeuble, en pleurs. Mon fr\u00e8re Tariq Badr s&#039;est approch\u00e9 de moi en pleurs, a pris du sable mouill\u00e9 du toit dans son poing et l&#039;a jet\u00e9 sur ma t\u00eate et mon corps \u00e0 plusieurs reprises en me disant : \u00ab Pourquoi as-tu fait \u00e7a ? \u00bb Alors j&#039;ai pris du sable mouill\u00e9 du toit dans mon poing et je l&#039;ai jet\u00e9 sur son visage et son corps d&#039;un coup.<\/h1><h1><strong>Interpr\u00e9tation de la vision dans cette vid\u00e9o<\/strong><\/h1><h1 data-wpview-marker=\"https%3A%2F%2Fwww.youtube.com%2Fwatch%3Fv%3DpWwnNv79JxA%26amp%3Blist%3DPLGSQ8bPhLqKvbIK2NxQ1CoUA-dKyGIGlP%26amp%3Bindex%3D70\">https:\/\/www.youtube.com\/watch?v=pWwnNv79JxA&amp;list=PLGSQ8bPhLqKvbIK2NxQ1CoUA-dKyGIGlP&amp;index=70<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0623\u0639\u062a\u0642\u062f \u0623\u0646 \u0647\u0630\u0647 \u0627\u0644\u0631\u0624\u064a\u0627 \u0644\u0647\u0627 \u0639\u0644\u0627\u0642\u0629 \u0645\u0628\u0627\u0634\u0631\u0629 \u0628\u0627\u0644\u0631\u0624\u064a\u0627 \u0627\u0644\u062a\u064a \u0631\u0623\u064a\u062a\u0647\u0627 \u0623\u0648\u0644 \u0623\u0645\u0633 \u0639\u0646 \u0627\u0646\u0634\u0642\u0627\u0642 \u0627\u0644\u0642\u0645\u0631 \u064a\u0648\u0645 14 \u0641\u0628\u0631\u0627\u064a\u0631 2020\u00a0\u0627\u0644\u0631\u0624\u064a\u0627\u0631\u0623\u064a\u062a \u0623\u0646 \u0645\u0648\u0627\u0637\u0646\u0648 \u0627\u0633\u062a\u0631\u0627\u0644\u064a\u0627 \u0642\u062f \u0623\u0633\u0644\u0645\u0648\u0627 \u0628\u0639\u062f \u0623\u0646 \u0631\u0623\u0648\u0627 \u0622\u064a\u0629 \u0627\u0646\u0634\u0642\u0627\u0642 \u0627\u0644\u0642\u0645\u0631 \u062b\u0645 \u0631\u0623\u064a\u062a \u0623\u0645\u0627\u0645\u064a \u0641\u062a\u0627\u0629 \u0623\u0639\u062a\u0642\u062f \u0623\u0646\u0647\u0627 \u0628\u0631\u062a\u063a\u0627\u0644\u064a\u0629 \u062a\u0642\u0641 \u0623\u0645\u0627\u0645\u064a \u0648\u062a\u0631\u064a\u062f \u0625\u0634\u0647\u0627\u0631 \u0625\u0633\u0644\u0627\u0645\u0647\u0627 \u0628\u0639\u062f \u0623\u0646 \u0631\u0623\u062a \u0622\u064a\u0629 \u0627\u0646\u0634\u0642\u0627\u0642 \u0627\u0644\u0642\u0645\u0631 \u0641\u062a\u062d\u062f\u062b\u062a \u0627\u0644\u064a\u0647\u0627 \u0628\u0627\u0644\u063a\u0629 \u0627\u0644\u0628\u0631\u062a\u063a\u0627\u0644\u064a\u0629 \u0648\u0642\u0644\u062a \u0644\u0647\u0627 \u0631\u062f\u062f\u064a [&hellip;]<\/p>","protected":false},"author":2,"featured_media":20838,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[111],"tags":[],"class_list":{"0":"post-20837","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category--2016-2020"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts\/20837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/comments?post=20837"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts\/20837\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/media\/20838"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/media?parent=20837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/categories?post=20837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/tags?post=20837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}