{"id":20781,"date":"2025-03-24T10:59:37","date_gmt":"2025-03-24T10:59:37","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=20781"},"modified":"2025-04-28T05:57:47","modified_gmt":"2025-04-28T05:57:47","slug":"khgf","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/fr\/archives\/20781","title":{"rendered":"Vision de la fille en pleurs le 29 ao\u00fbt 2019"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"20781\" class=\"elementor elementor-20781\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35ac5b5f e-flex e-con-boxed e-con e-parent\" data-id=\"35ac5b5f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-72694495 elementor-widget elementor-widget-text-editor\" data-id=\"72694495\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>J&#039;ai vu que j&#039;\u00e9tais sur le toit d&#039;une voiture de police anti-\u00e9meute, policier au milieu d&#039;un groupe de policiers lourdement arm\u00e9s. Une petite voiture de police avec le chef de patrouille roulait devant nous. C&#039;\u00e9tait dans une zone d\u00e9sertique. Le chef de patrouille s&#039;est arr\u00eat\u00e9 devant une fillette d&#039;une dizaine d&#039;ann\u00e9es. Je ne distinguais pas ses traits. Il l&#039;a frapp\u00e9e, l&#039;a abandonn\u00e9e et a continu\u00e9 son chemin. La fillette pleurait et j&#039;ai beaucoup pleur\u00e9, car elle pleurait \u00e0 cause de ce qui lui \u00e9tait arriv\u00e9. Je suis sorti de la voiture de police et je suis all\u00e9 vers la petite fille pendant que je pleurais. J&#039;ai commenc\u00e9 \u00e0 la consoler et \u00e0 la caresser. Je l&#039;ai emmen\u00e9e dans une \u00e9picerie qui \u00e9tait visiblement pauvre en produits, car il n&#039;y en avait pas beaucoup. Je crois que c&#039;\u00e9tait une petite \u00e9picerie b\u00e9douine. J&#039;ai dit \u00e0 la fillette d&#039;y acheter ce qu&#039;elle voulait. Elle a choisi trois choses dont je ne me souviens plus. \u00c0 ce moment-l\u00e0, j&#039;attendais la r\u00e9action des policiers apr\u00e8s cette situation, puis la vision a pris fin.<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0631\u0623\u064a\u062a \u0623\u0646\u0646\u064a \u0641\u0648\u0642 \u0633\u064a\u0627\u0631\u0629 \u0634\u0631\u0637\u0629 \u0644\u0645\u0643\u0627\u0641\u062d\u0629 \u0627\u0644\u0634\u063a\u0628 \u0648\u0643\u0646\u062a \u0641\u0631\u062f \u0634\u0631\u0637\u0629 \u0636\u0645\u0646 \u0645\u062c\u0645\u0648\u0639\u0629 \u0645\u0646 \u0623\u0641\u0631\u0627\u062f \u0627\u0644\u0634\u0631\u0637\u0629 \u0627\u0644\u0645\u062f\u062c\u062c\u064a\u0646 \u0628\u0627\u0644\u0633\u0644\u0627\u062d \u0648\u0643\u0627\u0646 \u064a\u0633\u064a\u0631 \u0623\u0645\u0627\u0645\u0646\u0627 \u0633\u064a\u0627\u0631\u0629 \u0634\u0631\u0637\u0629 \u0635\u063a\u064a\u0631\u0629 \u0628\u0647\u0627 \u0642\u0627\u0626\u062f \u0627\u0644\u062f\u0648\u0631\u064a\u0629 \u0648\u0643\u0627\u0646 \u0630\u0644\u0643 \u0641\u064a \u0645\u0646\u0637\u0642\u0629 \u0635\u062d\u0631\u0627\u0648\u064a\u0629\u060c \u0641\u062a\u0648\u0642\u0641 \u0642\u0627\u0626\u062f \u0627\u0644\u062f\u0648\u0631\u064a\u0629 \u0639\u0646\u062f \u0641\u062a\u0627\u0629 \u062a\u0628\u0644\u063a \u0627\u0644\u0639\u0627\u0634\u0631\u0629 \u0645\u0646 \u0639\u0645\u0631\u0647\u0627 \u062a\u0642\u0631\u064a\u0628\u0627\u064b \u0644\u0645 \u0623\u0645\u064a\u0632 \u0645\u0644\u0627\u0645\u062d \u0648\u062c\u0647\u0647\u0627 \u0641\u0636\u0631\u0628\u0647\u0627 \u0648\u062a\u0631\u0643\u0647\u0627 \u0648\u0623\u0643\u0645\u0644 \u0637\u0631\u064a\u0642\u0647 \u0641\u0628\u0643\u062a \u0627\u0644\u0641\u062a\u0627\u0647 \u0641\u0628\u0643\u064a\u062a \u0628\u0643\u0627\u0621 \u0634\u062f\u064a\u062f\u0627\u064b \u0644\u0628\u0643\u0627\u0626\u0647\u0627 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":20782,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[111],"tags":[],"class_list":{"0":"post-20781","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category--2016-2020"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts\/20781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/comments?post=20781"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts\/20781\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/media\/20782"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/media?parent=20781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/categories?post=20781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/tags?post=20781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}