{"id":20441,"date":"2025-03-23T10:14:18","date_gmt":"2025-03-23T10:14:18","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=20441"},"modified":"2025-04-28T15:29:51","modified_gmt":"2025-04-28T15:29:51","slug":"fyhgsdf","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/fr\/archives\/20441","title":{"rendered":"Une vision orne le Caire pour accueillir le Mahdi \u00e0 la mi-novembre 2018."},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"20441\" class=\"elementor elementor-20441\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d33b1d3 e-flex e-con-boxed e-con e-parent\" data-id=\"3d33b1d3\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64846c84 elementor-widget elementor-widget-text-editor\" data-id=\"64846c84\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>J&#039;ai vu les b\u00e2timents du Caire d\u00e9cor\u00e9s la nuit avec ce qui ressemblait \u00e0 des d\u00e9corations du Ramadan, et les gens ont commenc\u00e9 \u00e0 accrocher des d\u00e9corations en pr\u00e9vision de l&#039;apparition du Mahdi. Ils ne savaient pas qui \u00e9tait le Mahdi, mais ils savaient qu&#039;il appara\u00eetrait. J&#039;ai vu les gens au sommet d&#039;un des b\u00e2timents accrocher leurs derni\u00e8res d\u00e9corations, comme si Le Caire avait \u00e9t\u00e9 enti\u00e8rement d\u00e9cor\u00e9 par le lever du soleil, et que seule restait l&#039;apparition du Mahdi. Apr\u00e8s cela, je me suis r\u00e9veill\u00e9 \u00e0 l&#039;appel \u00e0 la pri\u00e8re de l&#039;aube.<br class=\"html-br\" \/><br class=\"html-br\" \/>\u00d4 Dieu, fais de cette vision une vision vraie et h\u00e2te l&#039;apparition du Mahdi bient\u00f4t et fais de nous parmi ses soldats et fais de nous parmi les troisi\u00e8mes martyrs de ses conqu\u00eates.<br class=\"html-br\" \/><br class=\"html-br\" \/><strong>mettre \u00e0 jour<\/strong><br class=\"html-br\" \/>Certains commentaires ont indiqu\u00e9 que la parure \u00e9tait mentionn\u00e9e dans le Coran non pas comme un signe de bonne nouvelle, mais plut\u00f4t comme un avertissement d\u2019un \u00e9v\u00e9nement qui allait se produire.<br class=\"html-br\" \/>(Jusqu&#039;\u00e0 ce que la terre ait rev\u00eatu sa parure et soit embellie, et que ses habitants croient avoir pouvoir sur elle, Notre ordre lui parvienne de nuit ou de jour, et Nous la rendons semblable \u00e0 une moisson, comme si elle n&#039;avait pas fleuri hier.)<br class=\"html-br\" \/>(Votre rendez-vous est le jour de l&#039;Ornement, et lorsque le peuple sera rassembl\u00e9 \u00e0 midi.)<br class=\"html-br\" \/>Que Dieu nous prot\u00e8ge tous<\/h1><h1><strong>Interpr\u00e9tation de la vision dans cette vid\u00e9o<\/strong><\/h1><p><iframe title=\"Une vision orne le Caire pour accueillir le Mahdi \u00e0 la mi-novembre 2018.\" width=\"800\" height=\"600\" src=\"https:\/\/www.youtube.com\/embed\/mJv5G0ToXVY?list=PLGSQ8bPhLqKvbIK2NxQ1CoUA-dKyGIGlP\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0631\u0623\u064a\u062a \u0623\u0646 \u0627\u0644\u0645\u0628\u0627\u0646\u0649 \u0641\u064a \u0627\u0644\u0642\u0627\u0647\u0631\u0629 \u062a\u062a\u0632\u064a\u0646 \u0644\u064a\u0644\u0627\u064b \u0628\u0645\u0627 \u064a\u0634\u0628\u0647 \u0632\u064a\u0646\u0629 \u0631\u0645\u0636\u0627\u0646 \u0648\u0623\u062e\u0630 \u0627\u0644\u0623\u0647\u0627\u0644\u0649 \u064a\u0639\u0644\u0642\u0648\u0646 \u0627\u0644\u0632\u064a\u0646\u0647 \u0625\u0633\u062a\u0639\u062f\u0627\u062f\u0627\u064b \u0644\u0638\u0647\u0648\u0631 \u0627\u0644\u0645\u0647\u062f\u064a \u0648\u0643\u0627\u0646 \u0627\u0644\u0646\u0627\u0633 \u0644\u0627 \u064a\u0639\u0631\u0641\u0648\u0646 \u0645\u0646 \u0647\u0648 \u0627\u0644\u0645\u0647\u062f\u064a \u0648\u0644\u0643\u0646\u0647\u0645 \u0643\u0627\u0646\u0648\u0627 \u064a\u0639\u0644\u0645\u0648\u0646 \u0623\u0646\u0647 \u0633\u064a\u0638\u0647\u0631 \u0648\u0634\u0627\u0647\u062f\u062a \u0641\u064a \u0623\u0639\u0644\u0649 \u0623\u062d\u062f \u0627\u0644\u0645\u0628\u0627\u0646\u064a \u0627\u0644\u0623\u0647\u0627\u0644\u0649 \u064a\u0639\u0644\u0642\u0648\u0646 \u0623\u062e\u0631 \u0632\u064a\u0646\u0647 \u0639\u0646\u062f\u0647\u0645 \u0648\u0643\u0623\u0646\u0647 \u0648\u0642\u062f \u0625\u0643\u062a\u0645\u0644\u062a \u0627\u0644\u0642\u0627\u0647\u0631\u0629 \u0641\u064a \u0627\u0644\u062a\u0632\u064a\u0646 \u0645\u0639 \u0627\u0644\u0634\u0631\u0648\u0642 \u0648\u0628\u0642\u0649 \u0638\u0647\u0648\u0631 \u0627\u0644\u0645\u0647\u062f\u064a \u0648\u0628\u0639\u062f \u0630\u0644\u0643 \u0625\u0633\u062a\u064a\u0642\u0638\u062a \u0639\u0644\u0649 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":20442,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[111],"tags":[],"class_list":{"0":"post-20441","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category--2016-2020"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts\/20441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/comments?post=20441"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts\/20441\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/media\/20442"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/media?parent=20441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/categories?post=20441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/tags?post=20441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}