{"id":20408,"date":"2025-03-23T09:12:33","date_gmt":"2025-03-23T09:12:33","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=20408"},"modified":"2025-04-26T19:12:31","modified_gmt":"2025-04-26T19:12:31","slug":"wtrge","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/fr\/archives\/20408","title":{"rendered":"Vision du Soleil, des Quatre Lunes et de V\u00e9nus en juin 2014"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"20408\" class=\"elementor elementor-20408\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-24874707 e-flex e-con-boxed e-con e-parent\" data-id=\"24874707\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6559fa38 elementor-widget elementor-widget-text-editor\" data-id=\"6559fa38\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>J&#039;ai vu le soleil et quatre lunes, dont l&#039;une portait l&#039;inscription \u00ab Il n&#039;y a de dieu que Dieu \u00bb, et les trois autres une inscription floue. J&#039;ai aper\u00e7u une plan\u00e8te tr\u00e8s brillante \u00e0 c\u00f4t\u00e9 d&#039;elles\u00a0: V\u00e9nus. J&#039;ai dit \u00e0 ma femme\u00a0: \u00ab\u00a0Regarde ce que je vois dans le ciel\u00a0\u00bb, sachant que j&#039;avais trouv\u00e9 cette image dans le ciel de jour.<\/h1><p><iframe title=\"Vision du Soleil, des Quatre Lunes et de V\u00e9nus en juin 2014\" width=\"800\" height=\"600\" src=\"https:\/\/www.youtube.com\/embed\/6Kkv6MhL-Lc?list=PLGSQ8bPhLqKvbIK2NxQ1CoUA-dKyGIGlP\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>J&#039;ai vu le soleil et quatre lunes, dont l&#039;une portait l&#039;inscription \u00ab Il n&#039;y a de dieu que Dieu \u00bb, et les trois autres une inscription floue. J&#039;ai aper\u00e7u une plan\u00e8te tr\u00e8s brillante \u00e0 c\u00f4t\u00e9 d&#039;elles\u00a0: V\u00e9nus. J&#039;ai dit \u00e0 ma femme\u00a0: \u00ab\u00a0Regarde ce que je vois dans le ciel\u00a0\u00bb, sachant que j&#039;avais trouv\u00e9 cette image dans le ciel de jour.<\/p>","protected":false},"author":2,"featured_media":20409,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[110],"tags":[],"class_list":{"0":"post-20408","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category--2011-2015"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts\/20408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/comments?post=20408"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/posts\/20408\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/media\/20409"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/media?parent=20408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/categories?post=20408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/fr\/wp-json\/wp\/v2\/tags?post=20408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}