{"id":20813,"date":"2025-03-24T11:34:07","date_gmt":"2025-03-24T11:34:07","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=20813"},"modified":"2025-04-28T05:50:29","modified_gmt":"2025-04-28T05:50:29","slug":"zxsdsdf","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/fa\/archives\/20813","title":{"rendered":"\u0631\u0624\u06cc\u0627\u06cc \u0634\u06cc\u062e \u0627\u062d\u0645\u062f \u0627\u0644\u0637\u06cc\u0628 \u0648 \u06a9\u062a\u0627\u0628 \u067e\u06cc\u0627\u0645\u200c\u0647\u0627\u06cc \u0645\u0648\u0631\u062f \u0627\u0646\u062a\u0638\u0627\u0631 \u062f\u0631 \u06f1\u06f3 \u0698\u0627\u0646\u0648\u06cc\u0647 \u06f2\u06f0\u06f2\u06f0"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"20813\" class=\"elementor elementor-20813\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78fe1cb e-flex e-con-boxed e-con e-parent\" data-id=\"78fe1cb\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-543c776c elementor-widget elementor-widget-text-editor\" data-id=\"543c776c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>\u0631\u0624\u06cc\u0627: \u0628\u0639\u062f \u0627\u0632 \u0627\u06cc\u0646\u06a9\u0647 \u062f\u0648 \u0628\u0627\u0631 \u0646\u0645\u0627\u0632 \u0627\u0633\u062a\u062e\u0627\u0631\u0647 \u062e\u0648\u0627\u0646\u062f\u0645 \u0648 \u0628\u0627\u0631\u0647\u0627 \u0627\u0632 \u062e\u062f\u0627\u0648\u0646\u062f \u062e\u0648\u0627\u0633\u062a\u0645 \u06a9\u0647 \u0645\u0631\u0627 \u0628\u0647 \u06a9\u062f\u0627\u0645 \u0631\u0627\u0647 \u0647\u062f\u0627\u06cc\u062a \u06a9\u0646\u062f\u061f \u0622\u06cc\u0627 \u0628\u0627\u06cc\u062f \u0628\u0647 \u0647\u0645\u06cc\u0646 \u0645\u0646\u0648\u0627\u0644 \u0627\u062f\u0627\u0645\u0647 \u062f\u0647\u0645 \u06cc\u0627 \u06a9\u062a\u0627\u0628\u0645 (\u0631\u0633\u0627\u0644\u0627\u062a \u0645\u0646\u062a\u0638\u0631) \u0631\u0627 \u0628\u0647 \u0627\u0644\u0627\u0632\u0647\u0631 \u0634\u0631\u06cc\u0641 \u0627\u0631\u0627\u0626\u0647 \u062f\u0647\u0645\u061f \u0628\u0639\u062f \u0627\u0632 \u0627\u06cc\u0646\u06a9\u0647 \u0631\u0648\u0632 \u0642\u0628\u0644 \u0645\u0642\u0627\u0644\u0647\u200c\u0627\u06cc \u0645\u0646\u062a\u0634\u0631 \u06a9\u0631\u062f\u0645 \u0648 \u0627\u0632 \u0645\u0631\u062f\u0645 \u062f\u0631 \u0645\u0648\u0631\u062f \u0627\u0631\u0627\u0626\u0647 \u06a9\u062a\u0627\u0628\u0645 \u0628\u0647 \u0627\u0644\u0627\u0632\u0647\u0631 \u0634\u0631\u06cc\u0641 \u0646\u0638\u0631\u062e\u0648\u0627\u0647\u06cc \u06a9\u0631\u062f\u0645\u060c \u0627\u06a9\u062b\u0631 \u0646\u0638\u0631\u0627\u062a \u0628\u0627 \u0646\u0638\u0631 \u0645\u0646 \u062f\u0631 \u0645\u0648\u0631\u062f \u0639\u062f\u0645 \u0627\u0631\u0627\u0626\u0647 \u06a9\u062a\u0627\u0628\u0645 \u0628\u0647 \u0627\u0644\u0627\u0632\u0647\u0631 \u0634\u0631\u06cc\u0641 \u0645\u0648\u0627\u0641\u0642 \u0628\u0648\u062f\u0646\u062f \u0632\u06cc\u0631\u0627 \u0622\u0646\u0647\u0627 \u0622\u0646 \u0631\u0627 \u0646\u0645\u06cc\u200c\u067e\u0630\u06cc\u0631\u0641\u062a\u0646\u062f.<br class=\"html-br\" \/><br class=\"html-br\" \/>\u0645\u0646 \u0642\u0635\u062f \u062f\u0627\u0634\u062a\u0645 \u0627\u0632 \u062f\u0631\u06af\u06cc\u0631\u06cc \u0628\u0627 \u0627\u0644\u0627\u0632\u0647\u0631 \u0634\u0631\u06cc\u0641 \u062e\u0648\u062f\u062f\u0627\u0631\u06cc \u06a9\u0646\u0645\u060c \u0627\u0645\u0627 \u0627\u06cc\u0646 \u0631\u0624\u06cc\u0627 \u0631\u0627 \u062f\u06cc\u062f\u0645. \u0627\u0645\u06cc\u062f\u0648\u0627\u0631\u0645 \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u0622\u0646 \u0631\u0627 \u062a\u0639\u0628\u06cc\u0631 \u06a9\u0646\u06cc\u062f\u060c \u0632\u06cc\u0631\u0627 \u062a\u0635\u0645\u06cc\u0645\u0627\u062a \u0633\u0631\u0646\u0648\u0634\u062a\u200c\u0633\u0627\u0632 \u0628\u0631\u0627\u06cc \u0645\u0646 \u0628\u0647 \u062a\u0639\u0628\u06cc\u0631 \u0622\u0646 \u0628\u0633\u062a\u06af\u06cc \u062f\u0627\u0631\u062f.<br class=\"html-br\" \/><br class=\"html-br\" \/>\u062e\u0648\u062f\u0645 \u0631\u0627 \u062f\u06cc\u062f\u0645 \u06a9\u0647 \u0627\u0632 \u0622\u067e\u0627\u0631\u062a\u0645\u0627\u0646 \u0645\u0627\u062f\u0631\u0645 \u062f\u0631 \u0645\u0646\u06cc\u0627\u0644 \u0627\u0644\u0631\u0648\u0636\u0647 \u0627\u0632 \u0637\u0628\u0642\u0647 \u0633\u0648\u0645 \u0628\u0647 \u0632\u0645\u06cc\u0646 \u067e\u0631\u06cc\u062f\u0645 \u0648 \u0641\u0642\u0637 \u0628\u0627 \u062f\u0648 \u067e\u0627\u06cc\u0645 \u0632\u0645\u06cc\u0646 \u0631\u0627 \u0644\u0645\u0633 \u06a9\u0631\u062f\u0645\u060c \u0628\u062f\u0648\u0646 \u0627\u06cc\u0646\u06a9\u0647 \u062a\u0645\u0627\u0645 \u0628\u062f\u0646\u0645 \u0628\u0647 \u0632\u0645\u06cc\u0646 \u0628\u062e\u0648\u0631\u062f \u0648 \u0647\u06cc\u0686 \u0627\u062a\u0641\u0627\u0642\u06cc \u0628\u0631\u0627\u06cc\u0645 \u0628\u06cc\u0641\u062a\u062f. \u0628\u0639\u062f \u0627\u0632 \u0622\u0646\u060c \u0631\u0627\u0647 \u0645\u06cc\u200c\u0631\u0641\u062a\u0645 \u0648 \u0645\u0631\u062f\u0645 \u0627\u0632 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u0634\u06af\u0641\u062a\u200c\u0632\u062f\u0647 \u0645\u06cc\u200c\u0634\u062f\u0646\u062f\u060c \u0628\u0627 \u0648\u062c\u0648\u062f \u0627\u06cc\u0646\u06a9\u0647 \u062f\u062e\u062a\u0631\u06cc \u0642\u0628\u0644 \u0627\u0632 \u0645\u0646 \u0627\u0632 \u0627\u0631\u062a\u0641\u0627\u0639 \u062a\u0646\u0647\u0627 \u0633\u0647 \u0645\u062a\u0631 \u067e\u0631\u06cc\u062f\u0647 \u0628\u0648\u062f \u0648 \u0645\u062a\u0639\u0627\u0642\u0628\u0627\u064b \u062f\u0631 \u0628\u06cc\u0645\u0627\u0631\u0633\u062a\u0627\u0646 \u0628\u0633\u062a\u0631\u06cc \u0634\u062f\u0647 \u0628\u0648\u062f.<br class=\"html-br\" \/>\u0627\u06cc\u0646 \u0635\u062d\u0646\u0647 \u0645\u0631\u0627 \u0646\u0632\u062f \u0634\u06cc\u062e \u0627\u062d\u0645\u062f \u0627\u0644\u0637\u06cc\u0628\u060c \u0627\u0645\u0627\u0645 \u0627\u0639\u0638\u0645 \u0627\u0644\u0627\u0632\u0647\u0631\u060c \u0628\u0631\u062f. \u0627\u0632 \u0627\u0648 \u067e\u0631\u0633\u06cc\u062f\u0645: \u00ab\u0622\u06cc\u0627 \u0627\u06af\u0631 \u0645\u0633\u0644\u0645\u0627\u0646\u0627\u0646 \u0622\u06cc\u0647 \u0633\u0648\u0631\u0647 \u0627\u062d\u0632\u0627\u0628 \u0631\u0627 \u06a9\u0647 \u0645\u06cc\u200c\u06af\u0648\u06cc\u062f: \u00ab\u0645\u062d\u0645\u062f \u067e\u062f\u0631 \u0647\u06cc\u0686 \u06cc\u06a9 \u0627\u0632 \u0645\u0631\u062f\u0627\u0646 \u0634\u0645\u0627 \u0646\u06cc\u0633\u062a\u060c \u0628\u0644\u06a9\u0647 \u0631\u0633\u0648\u0644 \u062e\u062f\u0627 \u0648 \u062e\u0627\u062a\u0645 \u067e\u06cc\u0627\u0645\u0628\u0631\u0627\u0646 \u0627\u0633\u062a\u00bb \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0639\u0646\u0627 \u062a\u0641\u0633\u06cc\u0631 \u06a9\u0646\u0646\u062f \u06a9\u0647 \u0686\u0648\u0646 \u0633\u0631\u0648\u0631 \u0645\u0627 \u0645\u062d\u0645\u062f \u0635\u0644\u06cc \u0627\u0644\u0644\u0647 \u0639\u0644\u06cc\u0647 \u0648 \u0622\u0644\u0647 \u062e\u0627\u062a\u0645 \u067e\u06cc\u0627\u0645\u0628\u0631\u0627\u0646 \u0627\u0633\u062a\u060c \u067e\u0633 \u062e\u0627\u062a\u0645 \u0631\u0633\u0648\u0644\u0627\u0646 \u0646\u06cc\u0632 \u0647\u0633\u062a\u060c \u0634\u0645\u0627 \u0631\u0627\u0636\u06cc \u0647\u0633\u062a\u06cc\u062f\u061f\u00bb \u0645\u0646 \u0686\u0646\u062f\u06cc\u0646 \u0645\u062f\u0631\u06a9 \u0628\u0631\u0627\u06cc \u062a\u0623\u06cc\u06cc\u062f \u0646\u0638\u0631 \u062e\u0648\u062f \u0628\u0647 \u0627\u0648 \u0627\u0631\u0627\u0626\u0647 \u062f\u0627\u062f\u0645 \u0648 \u0627\u0648 \u06af\u0641\u062a: \u00ab\u0628\u0627 \u0645\u062e\u0627\u0644\u0641 \u062e\u0648\u062f \u0628\u0647 \u062e\u0627\u0646\u0647 \u0645\u0646 \u0628\u06cc\u0627\u06cc\u06cc\u062f \u062a\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0648\u0631\u062f \u0628\u062d\u062b \u06a9\u0646\u06cc\u0645.\u00bb<br class=\"html-br\" \/>\u0645\u0646 \u0627\u0648 \u0631\u0627 \u067e\u0627\u0628\u0631\u0647\u0646\u0647 \u0631\u0647\u0627 \u06a9\u0631\u062f\u0645\u060c \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u06a9\u0641\u0634\u200c\u0647\u0627 \u0648 \u062c\u0648\u0631\u0627\u0628\u200c\u0647\u0627\u06cc\u0645 \u0631\u0648\u06cc \u06cc\u06a9 \u0645\u06cc\u0646\u06cc\u200c\u0628\u0648\u0633 \u0628\u0648\u062f. \u0633\u0648\u0627\u0631 \u0627\u062a\u0648\u0628\u0648\u0633 \u0634\u062f\u0645\u060c \u0622\u0646\u0647\u0627 \u0631\u0627 \u0628\u0631\u062f\u0627\u0634\u062a\u0645 \u0648 \u067e\u0648\u0634\u06cc\u062f\u0645 \u062a\u0627 \u0628\u0631\u0627\u06cc \u0645\u0644\u0627\u0642\u0627\u062a \u0628\u0627 \u0634\u06cc\u062e \u0627\u062d\u0645\u062f \u0627\u0644\u0637\u06cc\u0628 \u062f\u0631 \u062e\u0627\u0646\u0647\u200c\u0627\u0634 \u0622\u0645\u0627\u062f\u0647 \u0634\u0648\u0645. \u06cc\u0627\u062f\u0645 \u0646\u06cc\u0633\u062a \u06a9\u0647 \u0622\u06cc\u0627 \u06a9\u0641\u0634\u200c\u0647\u0627 \u0648 \u062c\u0648\u0631\u0627\u0628\u200c\u0647\u0627\u06cc\u0645 \u0631\u0627 \u0628\u0647 \u062e\u0627\u0637\u0631 \u0648\u0636\u0648 \u062f\u0631\u0622\u0648\u0631\u062f\u0645 \u06cc\u0627 \u0646\u0647.<br class=\"html-br\" \/>\u0631\u0624\u06cc\u0627 \u062a\u0645\u0627\u0645 \u0634\u062f\u060c \u0644\u0637\u0641\u0627\u064b \u0622\u0646 \u0631\u0627 \u062a\u0639\u0628\u06cc\u0631 \u06a9\u0646\u06cc\u062f. \u0622\u06cc\u0627 \u0642\u0631\u0627\u0631 \u0627\u0633\u062a \u0627\u0644\u0627\u0646 \u067e\u06cc\u0634 \u0634\u06cc\u062e \u0627\u062d\u0645\u062f \u0627\u0644\u0637\u06cc\u0628\u060c \u0627\u0645\u0627\u0645 \u0627\u0639\u0638\u0645 \u0627\u0644\u0627\u0632\u0647\u0631\u060c \u0628\u0631\u0648\u0645 \u0648 \u06a9\u062a\u0627\u0628\u0645 \u0631\u0627 \u0628\u0647 \u0627\u0648 \u0646\u0634\u0627\u0646 \u062f\u0647\u0645\u060c \u0647\u0631\u0686\u0646\u062f \u06a9\u0647 \u0646\u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u0645\u061f<\/h1><h1><strong>\u062a\u0641\u0633\u06cc\u0631 \u062e\u0648\u0627\u0628 \u062f\u0631 \u0627\u06cc\u0646 \u0648\u06cc\u062f\u06cc\u0648<\/strong><\/h1><p><iframe title=\"\u0631\u0624\u06cc\u0627\u06cc \u0634\u06cc\u062e \u0627\u062d\u0645\u062f \u0627\u0644\u0637\u06cc\u0628 \u0648 \u06a9\u062a\u0627\u0628 \u067e\u06cc\u0627\u0645\u200c\u0647\u0627\u06cc \u0645\u0648\u0631\u062f \u0627\u0646\u062a\u0638\u0627\u0631 \u062f\u0631 \u06f1\u06f3 \u0698\u0627\u0646\u0648\u06cc\u0647 \u06f2\u06f0\u06f2\u06f0\" width=\"800\" height=\"600\" src=\"https:\/\/www.youtube.com\/embed\/6U9RnAXkFJE?list=PLGSQ8bPhLqKvbIK2NxQ1CoUA-dKyGIGlP\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0627\u0644\u0631\u0624\u064a\u0627 \u0628\u0639\u062f \u0623\u0646 \u0635\u0644\u064a\u062a \u0645\u0631\u062a\u064a\u0646 \u0635\u0644\u0627\u0629 \u0627\u0633\u062a\u062e\u0627\u0631\u0629 \u0648\u062f\u0639\u0627\u0621 \u0645\u062a\u0643\u0631\u0631 \u0628\u0623\u0646 \u064a\u0647\u062f\u064a\u0646\u064a \u0627\u0644\u0644\u0647 \u0633\u0628\u062d\u0627\u0646\u0647 \u0648\u062a\u0639\u0627\u0644\u0649 \u0627\u0644\u0649 \u0623\u064a \u0627\u0644\u0637\u0631\u0642 \u0633\u0623\u062e\u062a\u0627\u0631\u061f \u0647\u0644 \u064a\u0633\u062a\u0645\u0631 \u0627\u0644\u0648\u0636\u0639 \u0639\u0644\u0649 \u0645\u0627 \u0647\u0648 \u0639\u0644\u064a\u0647 \u0623\u0645 \u0623\u0639\u0631\u0636 \u0643\u062a\u0627\u0628\u064a (\u0627\u0644\u0631\u0633\u0627\u0626\u0644 \u0627\u0644\u0645\u0646\u062a\u0638\u0631\u0629) \u0639\u0644\u0649 \u0627\u0644\u0623\u0632\u0647\u0631 \u0627\u0644\u0634\u0631\u064a\u0641\u060c \u0648\u0628\u0639\u062f \u0627\u0646 \u0646\u0634\u0631\u062a \u0645\u0642\u0627\u0644\u0627\u064b \u0641\u064a \u0627\u0644\u064a\u0648\u0645 \u0627\u0644\u0633\u0627\u0628\u0642 \u0623\u0633\u062a\u0634\u064a\u0631 \u0641\u064a\u0647 \u0627\u0644\u0646\u0627\u0633 \u0639\u0646 \u0631\u0623\u064a\u0647\u0645 \u0641\u064a \u0623\u0646 \u0623\u0639\u0631\u0636 \u0643\u062a\u0627\u0628\u064a \u0639\u0644\u0649 \u0627\u0644\u0623\u0632\u0647\u0631 \u0627\u0644\u0634\u0631\u064a\u0641 \u0643\u0627\u0646\u062a \u0645\u0639\u0638\u0645 \u0627\u0644\u0622\u0631\u0627\u0621 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":20814,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[111],"tags":[],"class_list":{"0":"post-20813","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category--2016-2020"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/fa\/wp-json\/wp\/v2\/posts\/20813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fa\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fa\/wp-json\/wp\/v2\/comments?post=20813"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/fa\/wp-json\/wp\/v2\/posts\/20813\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/fa\/wp-json\/wp\/v2\/media\/20814"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/fa\/wp-json\/wp\/v2\/media?parent=20813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/fa\/wp-json\/wp\/v2\/categories?post=20813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/fa\/wp-json\/wp\/v2\/tags?post=20813"}],"curies":[{"name":"\u0648\u0631\u062f\u067e\u0631\u0633","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}