{"id":22274,"date":"2025-03-28T19:22:27","date_gmt":"2025-03-28T19:22:27","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=22274"},"modified":"2025-04-13T09:07:19","modified_gmt":"2025-04-13T09:07:19","slug":"xsdsdsa","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/es\/archives\/22274","title":{"rendered":"Un mensaje para los que discuten sobre el contenido del libro sin leerlo"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"22274\" class=\"elementor elementor-22274\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef4e528 e-flex e-con-boxed e-con e-parent\" data-id=\"ef4e528\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-331008f3 elementor-widget elementor-widget-text-editor\" data-id=\"331008f3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\">\r\n<div class=\"x1iyjqo2\">\r\n<div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\">\r\n<div class=\"xu06os2 x1ok221b\">\r\n<div class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">29 de marzo de 2020<\/span><\/span><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"xqcrz7y x78zum5 x1qx5ct2 x1y1aw1k x1sxyh0 xwib8y2 xurb0ha xw4jnvo\">\r\n<div>\r\n<div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Medidas que pueden adoptarse para este puesto\">\r\n<div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\"><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">Para las personas que todav\u00eda vienen a m\u00ed y me insultan incluso despu\u00e9s de haber publicado el libro completo.<br class=\"html-br\" \/>Alguien vino a discutir conmigo, as\u00ed que le pregunt\u00e9: &quot;\u00bfHas le\u00eddo el libro completo o no?&quot;<br class=\"html-br\" \/>Me dijo: \u201cLe\u00ed sobre la divisi\u00f3n de la luna y la diferencia entre un mensajero y un profeta, pero no me convenci\u00f3 lo que dijiste y no termin\u00e9 el libro\u201d.<br class=\"html-br\" \/>De acuerdo, no estoy dispuesto a discutir con nadie que haya le\u00eddo partes del libro o extractos del mismo y quiera discutir conmigo sobre algunas partes del libro, no sobre el libro completo.<br class=\"html-br\" \/>Les aseguro que el libro se completa solo y que hay mucha evidencia en todos sus cap\u00edtulos que respalda mi opini\u00f3n, respaldada por el Cor\u00e1n y la Sunna. No es l\u00f3gico que alguien discuta conmigo sobre un punto del libro sin discutir el resto.<br class=\"html-br\" \/>Antes, sol\u00eda aceptar discusiones con muchos de ustedes por publicar peque\u00f1os fragmentos de mi libro. Sin embargo, ahora la situaci\u00f3n es diferente. He publicado el libro completo. No es l\u00f3gico que alguien discuta conmigo por un solo cap\u00edtulo o peque\u00f1as partes de mi libro.<br class=\"html-br\" \/>En general, he publicado mi libro completo, incluyendo mi opini\u00f3n al respecto, con base en el Cor\u00e1n y la Sunna. As\u00ed que, quien quiera enviarme sus comentarios sobre el libro completo, que me los env\u00ede.<br class=\"html-br\" \/>No impongo mi opini\u00f3n a ninguno de ustedes. Les present\u00e9 mi opini\u00f3n y la respuesta de Al-Azhar a mi libro.<br class=\"html-br\" \/>Para su informaci\u00f3n, Al-Azhar estudi\u00f3 mi libro completo durante dos meses y me envi\u00f3 sus notas para quien quiera leerlas. No se las ocult\u00e9, sino que las publiqu\u00e9 junto con mi respuesta.<br class=\"html-br\" \/>\u00c9stos fueron sus comentarios, carentes de cualquier vers\u00edculo cor\u00e1nico que niegue lo afirmado en mi libro.<br class=\"html-br\" \/>(\u00c9l menciona palabras del Cor\u00e1n y la Sunnah que giran en torno al conocimiento de lo invisible, luego procede con sus palabras de una manera gradual y organizada, en la que enfatiza que el hombre debe pensar en los asuntos de su religi\u00f3n de una manera moderna y cient\u00edfica, hasta que haya tenido \u00e9xito en esforzarse por imaginar los signos menores y mayores del D\u00eda de la Resurrecci\u00f3n de una manera precisa, cient\u00edfica y moderna. Intenta interpretar estos signos de una manera c\u00f3mica que lo aleja de la concepci\u00f3n isl\u00e1mica correcta de ellos.<br class=\"html-br\" \/>No se detuvo all\u00ed, sino que en este libro neg\u00f3 un asunto que la religi\u00f3n conoce por necesidad en el cap\u00edtulo de la creencia, al afirmar que Muhammad (que la paz y las bendiciones sean con \u00e9l) es el Sello de los Profetas, y no el Sello de los Mensajeros (p\u00e1g. 33 y siguientes). Cree que quienes niegan esto se encuentran en el mismo estado que los ignorantes que negaron la profec\u00eda de nuestro Maestro Muhammad (que la paz y las bendiciones sean con \u00e9l), y que un castigo doloroso aguarda a quienes creen que Muhammad (que la paz y las bendiciones sean con \u00e9l) es el Sello de los Mensajeros. Cita vers\u00edculos de la Sura Ad-Dukhan, del 1 al 15, y busca su propio beneficio interpretando los vers\u00edculos a su antojo. Esta idea maliciosa domina todo el libro, y contin\u00faa enfatiz\u00e1ndola desde el principio hasta el final de manera expl\u00edcita. \u00c9l cree en esto que es due\u00f1o de un nuevo llamado, y que todos deben creer en \u00e9l, y niega un asunto que se sabe de la religi\u00f3n por necesidad, que es que Muhammad, la paz y las bendiciones sean con \u00e9l, es el Sello de los Profetas y Mensajeros.<br class=\"html-br\" \/>Esta es la opini\u00f3n de Al-Azhar, y tienes mi libro completo. Quien quiera convencerse de la opini\u00f3n de Al-Azhar, que se convenza, y quien quiera convencerse de la m\u00eda, que se convenza.<br class=\"html-br\" \/>En definitiva, mi opini\u00f3n no contradice el Cor\u00e1n ni la Sunna. Quien quiera discutir conmigo, que traiga un vers\u00edculo o un hadiz que refute lo que he afirmado en mi libro. De lo contrario, no se agoten conmigo, pues he presentado mi opini\u00f3n y la he fundamentado con el Cor\u00e1n y la Sunna. Quien quiera presentar una opini\u00f3n que la contradiga, que presente una opini\u00f3n similar, respaldada por el Cor\u00e1n y la Sunna. No hace falta decir que contradigo el consenso de los eruditos, pues lo reconozco.<\/span><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>29 \u0645\u0627\u0631\u0633 2020 \u0628\u0627\u0644\u0646\u0633\u0628\u0629 \u0644\u0644\u0646\u0627\u0633 \u0627\u0644\u0644\u064a \u0644\u0633\u0647 \u0628\u062a\u062f\u062e\u0644 \u0639\u0646\u062f\u064a \u0648\u0628\u062a\u0634\u062a\u0645\u0646\u064a \u062d\u062a\u064a \u0628\u0639\u062f \u0627\u0646 \u0646\u0634\u0631\u062a \u0627\u0644\u0643\u062a\u0627\u0628 \u0643\u0627\u0645\u0644\u0627\u0648\u0627\u062d\u062f \u062f\u0627\u062e\u0644 \u0639\u0646\u062f\u064a \u0628\u064a\u062c\u0627\u062f\u0644\u0646\u064a \u0641\u0642\u0644\u062a \u0644\u0647 \u0623\u0646\u062a \u0642\u0631\u0623\u062a \u0627\u0644\u0643\u062a\u0627\u0628 \u0643\u0627\u0645\u0644\u0627 \u0623\u0645 \u0644\u0627 \u061f\u0641\u0642\u0627\u0644 \u0644\u064a \u0642\u0631\u0623\u062a \u0627\u0646\u0634\u0642\u0627\u0642 \u0627\u0644\u0642\u0645\u0631 \u0648\u0627\u0644\u0641\u0631\u0642 \u0628\u064a\u0646 \u0627\u0644\u0631\u0633\u0648\u0644 \u0648\u0627\u0644\u0646\u0628\u064a \u0648\u0644\u0645 \u0627\u0642\u062a\u0646\u0639 \u0628\u0643\u0644\u0627\u0645\u0643 \u0648\u0644\u0645 \u0627\u0643\u0645\u0644 \u0627\u0644\u0643\u062a\u0627\u0628\u0637\u064a\u0628 \u0623\u0646\u0627 \u0644\u064a\u0633 \u0639\u0646\u062f\u064a \u0627\u0633\u062a\u0639\u062f\u0627\u062f \u0644\u0644\u062c\u062f\u0627\u0644 \u0645\u0639 \u0623\u064a \u0634\u062e\u0635 \u0642\u0631\u0623 \u0623\u062c\u0632\u0627\u0621 \u0645\u0646 \u0627\u0644\u0643\u062a\u0627\u0628 \u0623\u0648 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":22275,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[121,113],"tags":[],"class_list":{"0":"post-22274","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-121","8":"category-113"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts\/22274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/comments?post=22274"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts\/22274\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/media\/22275"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/media?parent=22274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/categories?post=22274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/tags?post=22274"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}