{"id":22267,"date":"2025-03-28T19:14:23","date_gmt":"2025-03-28T19:14:23","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=22267"},"modified":"2025-04-17T06:47:00","modified_gmt":"2025-04-17T06:47:00","slug":"hgjgfj","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/es\/archives\/22267","title":{"rendered":"Esta es la interpretaci\u00f3n de mis visiones sobre mantener el libro descatalogado y donarlo"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"22267\" class=\"elementor elementor-22267\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6450eecd e-flex e-con-boxed e-con e-parent\" data-id=\"6450eecd\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dd16834 elementor-widget elementor-widget-text-editor\" data-id=\"dd16834\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><h1 class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\" style=\"text-align: right;\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">29 de marzo de 2020<\/span><\/span><\/h1><\/div><\/div><\/div><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Medidas que pueden adoptarse para este puesto\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><strong>Esta es la interpretaci\u00f3n de mis visiones sobre mantener el libro descatalogado y donarlo<\/strong><br class=\"html-br\" \/><br class=\"html-br\" \/>Las dos visiones que me contaron sobre el rechazo de Al-Azhar al libro \u201cLas cartas esperadas\u201d y la donaci\u00f3n del libro se han hecho realidad.<br class=\"html-br\" \/><br class=\"html-br\" \/><strong>No publiqu\u00e9 la primera visi\u00f3n completa en ese momento, ya que no mencion\u00e9 en ella que vi que publiqu\u00e9 el libro en PDF despu\u00e9s de que Al-Azhar rechazara mi libro.<\/strong><br class=\"html-br\" \/><br class=\"html-br\" \/>La primera visi\u00f3n, que fue una visi\u00f3n expl\u00edcita del rechazo de Al-Azhar a mi libro, Las cartas esperadas, fue el 22 de febrero de 2020.<br class=\"html-br\" \/>Mientras navegaba por Facebook en mi celular, me detuve en un video del programa de Omar Adeeb, donde mostraba una foto de la portada de mi libro. Lo criticaba y dec\u00eda a los espectadores que no todos los que escriben un libro deber\u00edan ser le\u00eddos. Era una noticia muy breve que hab\u00eda mostrado en su programa, as\u00ed que fui a la habitaci\u00f3n de mi esposa, Nahal, para que la viera.<br class=\"html-br\" \/>La escena me llev\u00f3 al Complejo de Investigaci\u00f3n Isl\u00e1mica afiliado a Al-Azhar, donde un empleado me inform\u00f3 que Al-Azhar hab\u00eda rechazado mi libro (Los Mensajes Esperados), me pidi\u00f3 que dejara de imprimirlo y me dio un papel para firmar. Me molest\u00e9 y escrib\u00ed en el papel (La carga de quien niegue al Mahdi recaer\u00e1 sobre tus hombros) y publiqu\u00e9 mi libro en PDF.<br class=\"html-br\" \/>La escena me llev\u00f3 a un lugar donde estaba sentado con un amigo que ley\u00f3 mi libro, Hani Saeed, y \u00e9l empez\u00f3 a consolarme por lo sucedido. Hab\u00eda un carrito de frijoles junto a m\u00ed, as\u00ed que compr\u00e9 unas papas fritas que estaban en una bolsa de pl\u00e1stico transparente. Empec\u00e9 a comer las papas fritas solo, sin mi amigo, mientras com\u00eda la primera bolsa de papas fritas en la misma bolsa de pl\u00e1stico que las papas, hasta que dej\u00e9 de comer la bolsa de pl\u00e1stico y com\u00ed solo las papas fritas hasta que me llen\u00e9 antes de terminarme la mitad de la primera bolsa. Decid\u00ed llevarme el resto a casa.<br class=\"html-br\" \/><br class=\"html-br\" \/><br class=\"html-br\" \/><strong>La segunda visi\u00f3n fue el 7 de marzo de 2020, dos d\u00edas despu\u00e9s del lanzamiento de la segunda edici\u00f3n de mi libro, el 5 de marzo de 2020.<\/strong><br class=\"html-br\" \/>El pez que aparece en \u00e9l simboliza mi libro, y lo don\u00e9 en caridad al final de la visi\u00f3n, despu\u00e9s de que se public\u00f3 la segunda edici\u00f3n del libro.<br class=\"html-br\" \/>Una visi\u00f3n de vender pescado crudo y luego donarlo como caridad el 7 de marzo de 2020<br class=\"html-br\" \/>Vi que ten\u00eda mercanc\u00eda de todo tipo de pescado crudo en el supermercado, sabiendo que tambi\u00e9n vend\u00edan otros productos. Entonces, puse otra cantidad de pescado crudo para que se vendiera con el resto del pescado que ten\u00eda, como si el due\u00f1o del supermercado fuera un intermediario entre el comprador y yo.<br class=\"html-br\" \/>Entonces ocurri\u00f3 algo que no recuerdo bien, relacionado con mi libro, Cartas de Espera. El due\u00f1o del supermercado me envi\u00f3 todas mis provisiones de pescado a casa, as\u00ed que decid\u00ed donarlas a caridad.<br class=\"html-br\" \/><br class=\"html-br\" \/><br class=\"html-br\" \/>Las dos visiones se hicieron realidad el 23 de marzo de 2020, cuando fui al Complejo de Investigaci\u00f3n Isl\u00e1mica y el empleado de investigaci\u00f3n me inform\u00f3 que Al-Azhar hab\u00eda rechazado mi libro y hab\u00eda prohibido su impresi\u00f3n.<br class=\"html-br\" \/><br class=\"html-br\" \/><br class=\"html-br\" \/>De acuerdo con ambas visiones, y sin dudarlo, me ofrec\u00ed a publicar el libro en formato PDF un d\u00eda despu\u00e9s del rechazo de Al-Azhar y sin esperar a que se agotara la segunda edici\u00f3n. Esto ocurri\u00f3 el 24 de marzo de 2020.<br class=\"html-br\" \/><br class=\"html-br\" \/><br class=\"html-br\" \/><strong>Nota<\/strong><br class=\"html-br\" \/>Las visiones no tienen nada que ver con el contenido del libro, sino con mi orden de publicarlo o regalarlo, o de presentarlo a Al-Azhar, o de informarme del rechazo de Al-Azhar. Las visiones no tienen nada que ver con el contenido del libro.<br class=\"html-br\" \/>La visi\u00f3n que me llev\u00f3 a terminar de escribir y publicar mi libro, Las Cartas Esperadas, fue la visi\u00f3n del libro y del verso: \u00abAs\u00ed que espera, son esperados\u00bb, el 17 de septiembre de 2019. Esa visi\u00f3n fue antes de terminar de escribir el libro y publicarlo a mediados de diciembre de 2019.<br class=\"html-br\" \/><br class=\"html-br\" \/><br class=\"html-br\" \/>(((((Las visiones no tienen relaci\u00f3n con el contenido del libro desde el interior))))<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>29 \u0645\u0627\u0631\u0633 2020 \u00a0 \u0647\u0630\u0627 \u062a\u0623\u0648\u064a\u0644 \u0631\u0624\u064a\u0627\u064a \u0628\u062e\u0635\u0648\u0635 \u0645\u0646\u0639 \u0627\u0644\u0643\u062a\u0627\u0628 \u0645\u0646 \u0627\u0644\u0637\u0628\u0639 \u0648\u0627\u0644\u062a\u0635\u062f\u0642 \u0628\u0647 \u0644\u0642\u062f \u062a\u062d\u0642\u0642 \u0627\u0644\u0631\u0624\u064a\u062a\u064a\u0646 \u0627\u0644\u062a\u064a \u0623\u062e\u0628\u0631\u062a\u0646\u0649 \u0628\u0631\u0641\u0636 \u0627\u0644\u0623\u0632\u0647\u0631 \u0644\u0643\u062a\u0627\u0628 \u0627\u0644\u0631\u0633\u0627\u0626\u0644 \u0627\u0644\u0645\u0646\u062a\u0638\u0631\u0629 \u0648\u0627\u0644\u062a\u0635\u062f\u0642 \u0628\u0627\u0644\u0643\u062a\u0627\u0628 \u0627\u0644\u0631\u0624\u064a\u0627 \u0627\u0644\u0623\u0648\u0644\u0649 \u0644\u0645 \u0623\u0646\u0634\u0631\u0647\u0627 \u0643\u0627\u0645\u0644\u0629 \u0648\u0642\u062a\u0647\u0627 \u062d\u064a\u062b \u0644\u0645 \u0623\u0630\u0643\u0631 \u0641\u064a\u0647\u0627 \u0623\u0646\u0646\u064a \u0631\u0623\u064a\u062a \u0641\u064a\u0647\u0627 \u0623\u0646\u0646\u064a \u0646\u0634\u0631\u062a \u0627\u0644\u0643\u062a\u0627\u0628 pdf \u0628\u0639\u062f \u0627\u0646 \u0631\u0641\u0636 \u0627\u0644\u0623\u0632\u0647\u0631 \u0643\u062a\u0627\u0628\u064a \u0627\u0644\u0631\u0624\u064a\u0627 \u0627\u0644\u0623\u0648\u0644\u0649 \u0648\u0647\u064a \u0631\u0624\u064a\u0627 \u0635\u0631\u064a\u062d\u0629 \u0628\u0631\u0641\u0636 \u0627\u0644\u0623\u0632\u0647\u0631 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":22268,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[113,111],"tags":[],"class_list":{"0":"post-22267","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-113","8":"category--2016-2020"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts\/22267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/comments?post=22267"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts\/22267\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/media\/22268"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/media?parent=22267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/categories?post=22267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/tags?post=22267"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}