{"id":22095,"date":"2025-03-27T19:17:13","date_gmt":"2025-03-27T19:17:13","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=22095"},"modified":"2025-04-17T07:16:50","modified_gmt":"2025-04-17T07:16:50","slug":"hsfh","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/es\/archives\/22095","title":{"rendered":"Quiero evidencia y prueba del Cor\u00e1n y la Sunnah \u00fanicamente para su creencia heredada de algunos eruditos de que nuestro Maestro Muhammad, la paz y las bendiciones sean con \u00e9l, es el Sello de los Mensajeros.\u00a0"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"22095\" class=\"elementor elementor-22095\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c2dbdd2 e-flex e-con-boxed e-con e-parent\" data-id=\"7c2dbdd2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2873c2b5 elementor-widget elementor-widget-text-editor\" data-id=\"2873c2b5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><h1 class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">1 de enero de 2020<\/span><\/span><\/h1><\/div><\/div><\/div><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Medidas que pueden adoptarse para este puesto\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">Y ellos pensaban, como t\u00fa pensabas, que Dios no resucitar\u00eda a nadie.<br class=\"html-br\" \/>Har\u00e9 un acuerdo contigo<br class=\"html-br\" \/>\u00bfQui\u00e9n me har\u00e1 cambiar de opini\u00f3n de que nuestro Maestro Muhammad (que la paz y las bendiciones de Allah sean con \u00e9l) no es el Sello de los Mensajeros y me guiar\u00e1 y me har\u00e1 volver en m\u00ed, como dices? Lo anunciar\u00e9 p\u00fablicamente y le agradecer\u00e9 delante de todos ustedes en un video.<br class=\"html-br\" \/><br class=\"html-br\" \/>Pero antes de eso, debe darme una prueba de que nuestro maestro Muhammad es el Sello de los Mensajeros.<br class=\"html-br\" \/>Para ahorrarle tiempo en preguntarle y responderle<br class=\"html-br\" \/>Las preguntas esperadas ya han sido respondidas, la m\u00e1s importante de las cuales es la confianza de los creyentes en que nuestro Maestro Muhammad (que la paz y las bendiciones sean con \u00e9l) es el Sello de los Mensajeros. Esta confianza se basa en dos pruebas:<br class=\"html-br\" \/>El hadiz que ha sido probado con evidencia que no es confiable porque uno de sus narradores (Al-Mukhtar bin Falfel) es un negador o uno veraz y tiene delirios (El mensaje y la profec\u00eda han sido cortados, por lo que no hay mensajero o profeta despu\u00e9s de m\u00ed), por lo que no hay necesidad de repetir la discusi\u00f3n de este hadiz y convencerme de ello.<br class=\"html-br\" \/><br class=\"html-br\" \/>La segunda pregunta es sobre el principio de Ibn Kathir (todo mensajero es un profeta, pero no todo profeta es un mensajero), que Ibn Kathir estableci\u00f3 bas\u00e1ndose en el hadiz de Al-Mukhtar bin Falfel, que fue transmitido por los eruditos musulmanes despu\u00e9s de ellos, y dijeron que el estatus de mensajero es superior al estatus de profeta.<br class=\"html-br\" \/>He demostrado con evidencia el error de esta regla en mi libro, y les he mencionado algunas de estas evidencias y les he explicado la diferencia entre un profeta y un mensajero, que no todo mensajero es profeta, y que el estatus de la profec\u00eda es superior al estatus de la mensajer\u00eda.<br class=\"html-br\" \/><br class=\"html-br\" \/>Si alguien tiene alguna otra evidencia del Cor\u00e1n y la Sunna de que nuestro Maestro Muhammad (que la paz y las bendiciones sean con \u00e9l) es el Sello de los Mensajeros, por favor, pres\u00e9ntamela, sabiendo que creo que nuestro Maestro Muhammad (que la paz y las bendiciones sean con \u00e9l) es el \u00fanico Sello de los Profetas, que la ley isl\u00e1mica es la ley definitiva hasta el D\u00eda del Juicio, y que la misi\u00f3n de los Mensajeros venideros es esforzarse por difundir la religi\u00f3n del Islam, interpretar los vers\u00edculos ambiguos del Cor\u00e1n y advertir sobre la aparici\u00f3n de la Se\u00f1al del Humo. No tendr\u00e1n la misi\u00f3n de reemplazar la ley isl\u00e1mica con otra ley.<br class=\"html-br\" \/>Tambi\u00e9n creo en el noble vers\u00edculo: \u201cMuhammad no es el padre de ninguno de tus hombres, sino el Mensajero de Dios y el Sello de los Profetas\u201d.<br class=\"html-br\" \/>Estoy de acuerdo con el Cor\u00e1n y el Hadiz en que nuestro Maestro Muhammad, la paz y las bendiciones sean con \u00e9l, es el Sello de los Profetas. As\u00ed que denme pruebas de que Dios Todopoderoso no enviar\u00e1 un mensajero y de que ustedes no repetir\u00e1n el error de quienes los precedieron: \u00abY que asumieron, como ustedes asumieron, que Dios no enviar\u00eda a nadie\u00bb.<br class=\"html-br\" \/>Se le permite mencionar, mencionar o buscar ayuda de cualquier erudito musulm\u00e1n, ya sea un amigo o alguien que conozca, para que me puedan proporcionar evidencia que me restablezca a donde estaba hace siete meses, tal como lo hizo usted, con una promesa de mi parte de anunciar mi error a todos ustedes en un video.<br class=\"html-br\" \/>Espero que discutas conmigo con argumentos y no con las repetidas acusaciones de que yo (encend\u00ed la discordia entre los musulmanes \u2013 el Anticristo o uno de sus seguidores \u2013 loco \u2013 equivocado \u2013 infiel \u2013 un demonio me susurr\u00f3 que te escribiera \u2013 qui\u00e9n eres t\u00fa para venir con algo contrario a lo que los eruditos musulmanes han acordado \u2013 etc. etc.) No hay necesidad de repetir esas acusaciones.<br class=\"html-br\" \/><br class=\"html-br\" \/>Quiero evidencia y prueba del Cor\u00e1n y la Sunnah \u00fanicamente para su creencia heredada de algunos eruditos de que nuestro Maestro Muhammad, la paz y las bendiciones sean con \u00e9l, es el Sello de los Mensajeros.\u00a0<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>1 \u064a\u0646\u0627\u064a\u0631 2020 \u00a0 \ufd3f\ufeed\u064e\ufe83\u064e\ufee7\u064e\u0651\ufeec\u064f\ufee2\u0652 \ufec7\u064e\ufee8\u064f\u0651\ufeee\ufe8d \ufedb\u064e\ufee4\u064e\ufe8e \ufec7\u064e\ufee8\u064e\ufee8\u0652\ufe98\u064f\ufee2\u0652 \ufe83\u064e\ufee5\u0652 \ufedf\u064e\ufee6\u0652 \ufef3\u064e\ufe92\u0652\ufecc\u064e\ufe9a\u064e \ufe8d\ufedf\ufee0\u064e\u0651\ufeea\u064f \ufe83\u064e\ufea3\u064e\ufeaa\u064b\ufe8d\ufd3e\u0633\u0623\u0628\u0631\u0645 \u0645\u0639\u0643\u0645 \u0627\u062a\u0641\u0627\u0642\u0645\u0646 \u0633\u064a\u064f\u063a\u064a\u0631 \u0627\u0639\u062a\u0642\u0627\u062f\u064a \u0628\u0623\u0646 \u0633\u064a\u062f\u0646\u0627 \u0645\u062d\u0645\u062f \ufdfa \u0644\u064a\u0633 \u062e\u0627\u062a\u0645 \u0627\u0644\u0645\u0631\u0633\u0644\u064a\u0646 \u0648\u0633\u064a\u0647\u062f\u064a\u0646\u064a \u0648\u0633\u064a\u0639\u064a\u062f\u0646\u064a \u0627\u0644\u0649 \u0631\u0634\u062f\u064a \u0643\u0645\u0627 \u062a\u0642\u0648\u0644\u0648\u0646 \u0633\u0623\u0639\u0644\u0646 \u0630\u0644\u0643 \u0639\u0644\u0649 \u0627\u0644\u0645\u0644\u0623 \u0648\u0633\u0623\u0634\u0643\u0631\u0647 \u0623\u0645\u0627\u0645\u0643\u0645 \u062c\u0645\u064a\u0639\u064b\u0627 \u0641\u064a \u0641\u064a\u062f\u064a\u0648 \u0645\u0635\u0648\u0631 \u0648\u0644\u0643\u0646 \u0642\u0628\u0644 \u0630\u0644\u0643 \u064a\u062c\u0628 \u0623\u0646 \u064a\u064b\u0639\u0637\u064a \u0644\u064a \u0627\u0644\u062d\u062c\u0629 \u0639\u0644\u0649 \u0623\u0646 \u0633\u064a\u062f\u0646\u0627 \u0645\u062d\u0645\u062f \u0647\u0648 \u062e\u0627\u062a\u0645 \u0627\u0644\u0645\u0631\u0633\u0644\u064a\u0646\u0648\u062d\u062a\u0649 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":22096,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[113],"tags":[],"class_list":{"0":"post-22095","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-113"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts\/22095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/comments?post=22095"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts\/22095\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/media\/22096"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/media?parent=22095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/categories?post=22095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/tags?post=22095"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}