{"id":22018,"date":"2025-03-27T13:03:33","date_gmt":"2025-03-27T13:03:33","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=22018"},"modified":"2025-04-17T07:56:58","modified_gmt":"2025-04-17T07:56:58","slug":"cvdsfvd","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/es\/archives\/22018","title":{"rendered":"Dedicatoria del libro &quot;Las cartas de espera&quot;"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"22018\" class=\"elementor elementor-22018\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ee68b47 e-flex e-con-boxed e-con e-parent\" data-id=\"7ee68b47\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ee422c6 elementor-widget elementor-widget-text-editor\" data-id=\"7ee422c6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><h1 class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">2 de diciembre de 2019<\/span><\/span><\/h1><\/div><\/div><\/div><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Medidas que pueden adoptarse para este puesto\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><div class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><div class=\"xqcrz7y x78zum5 x1qx5ct2 x1y1aw1k x1sxyh0 xwib8y2 xurb0ha xw4jnvo\"><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Medidas que pueden adoptarse para este puesto\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">He decidido dedicar mi pr\u00f3ximo libro, The Waiting Letters, a mi abuelo materno, el jeque Abdul Muttal Al-Saidi, a quien desear\u00eda que estuviera conmigo en este momento para apoyarme.<br class=\"html-br\" \/>El jeque Abdel Muttal Al-Saidi tuvo muchas batallas como resultado de sus opiniones y esfuerzos, y fue castigado m\u00e1s de una vez, incluyendo en 1937 cuando los alazharitas se rebelaron contra el jeque debido a sus opiniones. Se form\u00f3 un comit\u00e9 para juzgarlo. El jeque Mahmoud Shaltout, el jeque Al-Zankaloni y otros sugirieron que escribiera un memorando anunciando su retractaci\u00f3n de algunas de sus opiniones, y el jeque Abdel Muttal estuvo de acuerdo. El comit\u00e9 de juicio estuvo compuesto por: el jeque Muhammad Abdel Latif Al-Fahham, subsecretario de Al-Azhar; el jeque Abdel Majeed Al-Labban, jeque de la Facultad de Usul Al-Din; y el jeque Mamoun Al-Shinnawi, jeque de la Facultad de Sharia. El comit\u00e9 de juicio concluy\u00f3 que al jeque Abdel Muttal se le privar\u00eda de su ascenso durante cinco a\u00f1os y que ser\u00eda transferido de la docencia en la Facultad de Lengua \u00c1rabe al Departamento General de Tanta.<br class=\"html-br\" \/>El jeque Al-Saidi se apart\u00f3 del consenso de Al-Azhar sobre el tema de matar ap\u00f3statas, afirmando: \u00abNo puedo estar de acuerdo con esos r\u00edgidos jeques de Al-Azhar, pues traer\u00e9 sobre Al-Azhar lo que ellos traen con su rigidez\u00bb. A pesar de los ataques de los jeques de Al-Azhar, liderados por el jeque Issa Manoun, Al-Saidi se mantuvo firme en su \u00e9nfasis en la importancia de la libertad religiosa para todos. Abdel Muttal Al-Saidi cre\u00eda que la pena de muerte para un ap\u00f3stata solo deber\u00eda imponerse a un ap\u00f3stata asesino o a quien obligue a los musulmanes a abandonar su religi\u00f3n. Luchar aqu\u00ed es en defensa de la libertad. En cuanto a un ap\u00f3stata pac\u00edfico, no hay castigo para \u00e9l en este mundo, ya que la libertad religiosa est\u00e1 ligada al castigo mundano. Si hay castigo mundano por la creencia, entonces no hay libertad religiosa, y viceversa. Su apoyo a esto fue el vers\u00edculo cor\u00e1nico: \u00abNo hay compulsi\u00f3n en la religi\u00f3n\u00bb.<br class=\"html-br\" \/>Mi abuelo, el jeque Abdul Muttal Al-Saidi, afront\u00f3 muchos problemas debido a sus opiniones religiosas y, por ello, vi que era la persona m\u00e1s adecuada a quien deb\u00eda dedicar mi libro, Las cartas esperadas.\u00a0<\/span><\/h1><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>2 \u062f\u064a\u0633\u0645\u0628\u0631 2019 \u00a0\u00a0 \u0644\u0642\u062f \u0642\u0631\u0631\u062a \u0623\u0646 \u0623\u0647\u062f\u064a \u0643\u062a\u0627\u0628\u064a \u0627\u0644\u0642\u0627\u062f\u0645 \u0627\u0644\u0631\u0633\u0627\u0626\u0644 \u0627\u0644\u0645\u0646\u062a\u0638\u0631\u0629 \u0644\u062c\u062f\u064a \u0645\u0646 \u062c\u0647\u0629 \u0648\u0627\u0644\u062f\u062a\u064a \u0627\u0644\u0634\u064a\u062e \u0639\u0628\u062f \u0627\u0644\u0645\u062a\u0639\u0627\u0644 \u0627\u0644\u0635\u0639\u064a\u062f\u064a \u0627\u0644\u0630\u064a \u0643\u0646\u062a \u0623\u062a\u0645\u0646\u0649 \u0623\u0646 \u064a\u0643\u0648\u0646 \u0645\u0639\u064a \u0641\u064a \u0648\u0642\u062a\u0646\u0627 \u0627\u0644\u062d\u0627\u0644\u064a \u0644\u064a\u0633\u0627\u0646\u062f\u0646\u064a.\u0641\u0644\u0642\u062f \u0643\u0627\u0646 \u0644\u0644\u0634\u064a\u062e \u0639\u0628\u062f \u0627\u0644\u0645\u062a\u0639\u0627\u0644 \u0627\u0644\u0635\u0639\u064a\u062f\u064a \u0645\u0639\u0627\u0631\u0643 \u0639\u062f\u064a\u062f\u0629 \u0646\u062a\u064a\u062c\u0629 \u0627\u0631\u0627\u0621\u0647 \u0648\u0627\u062c\u062a\u0647\u0627\u062f\u0627\u062a\u0647 \u0648\u062a\u0645 \u0639\u0642\u0627\u0628\u0647 \u0623\u0643\u062b\u0631 \u0645\u0646 \u0645\u0631\u0629 \u0648\u0645\u0646\u0647\u0627 \u0643\u0627\u0646 \u0639\u0627\u0645 1937 \u062d\u064a\u0646\u0645\u0627 \u062b\u0627\u0631 \u0627\u0644\u0623\u0632\u0647\u0631\u064a\u0648\u0646 \u0636\u062f\u0651 \u0627\u0644\u0634\u064a\u062e \u0628\u0633\u0628\u0628 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":22019,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[113],"tags":[],"class_list":{"0":"post-22018","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-113"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts\/22018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/comments?post=22018"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts\/22018\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/media\/22019"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/media?parent=22018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/categories?post=22018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/tags?post=22018"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}