{"id":21943,"date":"2025-03-27T12:05:10","date_gmt":"2025-03-27T12:05:10","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=21943"},"modified":"2025-04-20T09:17:43","modified_gmt":"2025-04-20T09:17:43","slug":"fdgds","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/es\/archives\/21943","title":{"rendered":"Conquista de Italia"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"21943\" class=\"elementor elementor-21943\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36482d1 e-flex e-con-boxed e-con e-parent\" data-id=\"36482d1\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-187d66d1 elementor-widget elementor-widget-text-editor\" data-id=\"187d66d1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><h1 class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">27 de febrero de 2019<\/span><\/span><\/h1><\/div><\/div><\/div><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Medidas que pueden adoptarse para este puesto\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><strong>Conquista de Italia<\/strong><br class=\"html-br\" \/><br class=\"html-br\" \/>Los musulmanes invadieron la ciudad de C\u00e9sar dos veces y, lamentablemente, existe poca informaci\u00f3n en las fuentes isl\u00e1micas sobre estas invasiones y otras similares. Esto se debe a que la mayor\u00eda de estas invasiones fueron llevadas a cabo por muyahidines voluntarios, independientes de la autoridad del Califato. Esto ha impedido que los historiadores musulmanes conozcan la mayor\u00eda de estas haza\u00f1as y conquistas heroicas. La mayor parte de la informaci\u00f3n sobre estas invasiones proviene de fuentes europeas.<br class=\"html-br\" \/><br class=\"html-br\" \/>La esencia de esta gran epopeya reside en que los muyahidines voluntarios decidieron, tras consultarse entre ellos, invadir la ciudad de Roma. Presentaron la idea al gobierno de Sicilia y a su gobernador, Al-Fadl ibn Ja`far Al-Hamadhani. Este, a su vez, remiti\u00f3 el asunto al entonces pr\u00edncipe aglab\u00ed, Abu al-Abbas Muhammad ibn al-Aghlab. Este, atra\u00eddo por la idea, proporcion\u00f3 a los muyahidines gran cantidad de equipo, provisiones y hombres. La campa\u00f1a naval parti\u00f3 en el a\u00f1o 231 d. H. \/ 846 d. C. hacia las costas de Italia hasta llegar a la desembocadura del r\u00edo T\u00edber, donde se encuentra Roma. En aquel entonces, las murallas de Roma no abarcaban toda la ciudad antigua. En cambio, el distrito religioso, que albergaba las famosas iglesias de Pedro y Pablo, y un gran conjunto de templos, santuarios y tumbas antiguas, se encontraba extramuros. Hab\u00eda quedado desprotegido, pues los cristianos cre\u00edan que era un lugar sagrado protegido por el cielo. Los muyahidines atacaron ese distrito y se apoderaron de todos sus tesoros, indescriptibles. Luego sitiaron la ciudad de los C\u00e9sares, que estuvo a punto de caer. El papa Sergio estaba aterrorizado. El entonces papa de Roma, advertido de un ataque generalizado, envi\u00f3 mensajes de socorro a los reyes y pr\u00edncipes de Europa. El entonces emperador franco, Luis II, tom\u00f3 la iniciativa y envi\u00f3 una gran campa\u00f1a de sus soldados para rescatar Roma y sus iglesias. Debido a los desacuerdos surgidos entre los propios l\u00edderes de la campa\u00f1a musulmana, estos levantaron el asedio y regresaron a Sicilia cargados de bot\u00edn y prisioneros.<br class=\"html-br\" \/><br class=\"html-br\" \/>Este audaz intento de los muyahidines musulmanes revel\u00f3 la debilidad y fragilidad de las defensas de Roma, que anta\u00f1o fue la capital del mundo antiguo y el centro del cristianismo global. Los musulmanes decidieron volver a intentarlo hasta que se presentara la oportunidad. Esto ocurri\u00f3 en el a\u00f1o 256 d. H. \/ 870 d. C., con el firme apoyo del entonces pr\u00edncipe aglab\u00ed, Muhammad ibn Ahmad ibn al-Aghlab. Este pr\u00edncipe hab\u00eda logrado conquistar la isla de Malta un a\u00f1o antes, en el a\u00f1o 255 d. H. \/ 869 d. C. Sus ambiciones crecieron hasta alcanzar el honor de conquistar Roma. De hecho, las flotas de los muyahidines se encontraron con las flotas aglab\u00edes y continuaron por la misma ruta que en la campa\u00f1a anterior hasta llegar a la desembocadura del r\u00edo T\u00edber. El entonces papa de Roma, Le\u00f3n IV, tras haber aprendido la lecci\u00f3n de la invasi\u00f3n anterior, se apresur\u00f3 a solicitar las flotas de G\u00e9nova y N\u00e1poles para repeler la campa\u00f1a naval musulmana contra Roma. Una gran batalla naval estall\u00f3 entre ambos bandos cerca de las aguas del puerto de Ostia, en la que los musulmanes casi aplastaron a las flotas cristianas. De no haber sido por una violenta tormenta marina que azot\u00f3 Ostia, la lucha habr\u00eda cesado.<br class=\"html-br\" \/><br class=\"html-br\" \/>Esta poderosa tormenta no detuvo a los musulmanes, y a pesar de las grandes p\u00e9rdidas sufridas, insistieron en continuar la invasi\u00f3n y sitiaron la ciudad con la mayor fuerza hasta que estuvo a punto de caer. Esto impuls\u00f3 al papa Juan VIII, sucesor de Le\u00f3n IV, quien muri\u00f3 de dolor por los desastres a la cristiandad, a someterse a las condiciones de los musulmanes y pagarles un tributo anual de veinticinco mil mitzvales de plata. Esto tuvo un grave impacto en las naciones cristianas en general y en Europa en particular, pues \u00bfc\u00f3mo pod\u00eda el papa pagar tributo a los musulmanes? Pero esta es la verdad hist\u00f3rica establecida, indudable. Es algo que los enemigos han presenciado y escrito en sus libros, aunque les averg\u00fcence y les entristezca. Tambi\u00e9n es una de las escenas de orgullo, dignidad y hero\u00edsmo del pasado, que los musulmanes ahora necesitan conocer y aprovechar.<br class=\"html-br\" \/><br class=\"html-br\" \/>Por qu\u00e9 fuimos geniales<br class=\"html-br\" \/>El libro (Pa\u00edses inolvidables) de Tamer Badr\u00a0<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>27 \u0641\u0628\u0631\u0627\u064a\u0631 2019 \u00a0 \u0641\u062a\u0648\u062d \u0625\u064a\u0637\u0627\u0644\u064a\u0627 \u063a\u0632\u0627 \u0627\u0644\u0645\u0633\u0644\u0645\u0648\u0646 \u0645\u062f\u064a\u0646\u0629 \u0627\u0644\u0642\u064a\u0627\u0635\u0631\u0629 \u0645\u0631\u062a\u064a\u0646\u060c \u0648\u0644\u0644\u0623\u0633\u0641 \u0627\u0644\u0634\u062f\u064a\u062f \u0644\u0627 \u064a\u0648\u062c\u062f \u0641\u064a \u0627\u0644\u0645\u0631\u0627\u062c\u0639 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629 \u0623\u062e\u0628\u0627\u0631 \u0639\u0646 \u0647\u0630\u0647 \u0627\u0644\u063a\u0632\u0648\u0627\u062a \u0648\u0645\u062b\u0644\u0647\u0627 \u0625\u0644\u0627 \u0627\u0644\u0634\u064a\u0621 \u0627\u0644\u0642\u0644\u064a\u0644\u061b \u0630\u0644\u0643 \u0644\u0623\u0646 \u0645\u0639\u0638\u0645 \u0647\u0630\u0647 \u0627\u0644\u063a\u0632\u0648\u0627\u062a \u0643\u0627\u0646\u062a \u0628\u0648\u0627\u0633\u0637\u0629 \u0627\u0644\u0645\u062c\u0627\u0647\u062f\u064a\u0646 \u0627\u0644\u0645\u062a\u0637\u0648\u0639\u064a\u0646 \u0628\u0639\u064a\u062f\u0627\u064b \u0639\u0646 \u0633\u0644\u0637\u0629 \u0627\u0644\u062e\u0644\u0627\u0641\u0629\u060c \u0645\u0645\u0627 \u062c\u0639\u0644 \u0627\u0644\u0645\u0624\u0631\u062e\u064a\u0646 \u0627\u0644\u0645\u0633\u0644\u0645\u064a\u0646 \u0644\u0627 \u064a\u0639\u0631\u0641\u0648\u0646 \u0645\u0639\u0638\u0645 \u0647\u0630\u0647 \u0627\u0644\u0628\u0637\u0648\u0644\u0627\u062a \u0648\u0627\u0644\u0641\u062a\u0648\u062d\u0627\u062a\u060c \u0648\u0645\u0639\u0638\u0645 \u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0639\u0646 \u0647\u0630\u0647 \u0627\u0644\u063a\u0632\u0648\u0627\u062a \u0645\u0633\u062a\u0642\u0649 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":21944,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[115],"tags":[],"class_list":{"0":"post-21943","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-115"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts\/21943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/comments?post=21943"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts\/21943\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/media\/21944"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/media?parent=21943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/categories?post=21943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/tags?post=21943"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}