{"id":21156,"date":"2025-03-25T12:29:40","date_gmt":"2025-03-25T12:29:40","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=21156"},"modified":"2025-04-26T19:03:55","modified_gmt":"2025-04-26T19:03:55","slug":"dsfagg","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/es\/archives\/21156","title":{"rendered":"Si alguno de vosotros ve un sue\u00f1o que le agrada, entonces es de Dios; entonces que alabe a Dios por ello y lo cuente a otros."},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"21156\" class=\"elementor elementor-21156\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-40e237a0 e-flex e-con-boxed e-con e-parent\" data-id=\"40e237a0\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53949b61 elementor-widget elementor-widget-text-editor\" data-id=\"53949b61\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>El Profeta (que Dios le bendiga y le conceda paz) dijo: \u00abSi alguno de ustedes ve un sue\u00f1o que le agrada, es de Dios; que lo alabe y hable de \u00e9l. Pero si ve algo que le desagrada, es de Satan\u00e1s; que se proteja de su maldad y no se lo diga a nadie, pues no le har\u00e1 da\u00f1o\u00bb. Narrado por Al-Bujari.<br class=\"html-br\" \/><br class=\"html-br\" \/>Bueno, cuando una mujer me escribe diciendo que interpreta los sue\u00f1os y contradice el hadiz del Profeta, que Dios le bendiga y le conceda paz, y me dice (guarda estos sue\u00f1os para ti y no los muestres en Facebook ni hagas propaganda con ellos) y la gente me dice que te est\u00e1 aconsejando.<br class=\"html-br\" \/><br class=\"html-br\" \/>\u00bfDebo escuchar sus palabras o escuchar las palabras del Profeta (que Dios le bendiga y le conceda paz)?<br class=\"html-br\" \/><br class=\"html-br\" \/>Y luego no te escribo todas las visiones.<br class=\"html-br\" \/><br class=\"html-br\" \/>Solo escribo sobre las hermosas visiones en las que veo profetas, pero hay algunas visiones que contienen c\u00f3digos o enigmas, y quiero saber su interpretaci\u00f3n, as\u00ed que se las presento, y a trav\u00e9s de la interpretaci\u00f3n de la visi\u00f3n por parte de los int\u00e9rpretes, se me aclara el significado de lo que no entiendo en la visi\u00f3n.<br class=\"html-br\" \/><br class=\"html-br\" \/>No intento confiar en la interpretaci\u00f3n de una sola persona, sino que escucho a todos para resolver el misterio de cualquier visi\u00f3n que no entiendo.<br class=\"html-br\" \/><br class=\"html-br\" \/>Ya dije que hay personas mucho mejores que yo, y otras que tienen m\u00e1s visiones. Es decir, no estoy esperando una visi\u00f3n para cont\u00e1rsela, ni tengo un prop\u00f3sito espec\u00edfico al difundirla.<br class=\"html-br\" \/><br class=\"html-br\" \/>La cuesti\u00f3n es que necesito interpretar visiones que no entiendo.<br class=\"html-br\" \/><br class=\"html-br\" \/>\u00bfQu\u00e9 error comet\u00ed que hace que la gente no quiera que publique mis visiones en Facebook?<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0627\u0644\u0646\u0628\u064a \u0635\u0644 \u0627\u0644\u0644\u0647 \u0639\u0644\u064a\u0647 \u0648\u0633\u0644\u0645 \u0642\u0627\u0644 ( \u0625\u0650\u0630\u064e\u0627 \u0631\u064e\u0623\u064e\u0649 \u0623\u064e\u062d\u064e\u062f\u064f\u0643\u064f\u0645\u064f \u0627\u0644\u0631\u0651\u064f\u0624\u0652\u064a\u064e\u0627 \u064a\u064f\u062d\u0650\u0628\u0651\u064f\u0647\u064e\u0627 \u0641\u064e\u0625\u0650\u0646\u0651\u064e\u0647\u064e\u0627 \u0645\u0650\u0646\u064e \u0627\u0644\u0644\u0651\u064e\u0647\u0650 \u0641\u064e\u0644\u0652\u064a\u064e\u062d\u0652\u0645\u064e\u062f\u0650 \u0627\u0644\u0644\u0651\u064e\u0647\u064e \u0639\u064e\u0644\u064e\u064a\u0652\u0647\u064e\u0627 \u0648\u064e\u0644\u0652\u064a\u064f\u062d\u064e\u062f\u0651\u0650\u062b\u0652 \u0628\u0650\u0647\u064e\u0627 \u0648\u064e\u0625\u0650\u0630\u064e\u0627 \u0631\u064e\u0623\u064e\u0649 \u063a\u064e\u064a\u0652\u0631\u064e \u0630\u064e\u0644\u0650\u0643\u064e \u0645\u0650\u0645\u0651\u064e\u0627 \u064a\u064e\u0643\u0652\u0631\u064e\u0647\u064f \u0641\u064e\u0625\u0650\u0646\u0651\u064e\u0645\u064e\u0627 \u0647\u0650\u064a\u064e \u0645\u0650\u0646\u064e \u0627\u0644\u0634\u0651\u064e\u064a\u0652\u0637\u064e\u0627\u0646\u0650 \u0641\u064e\u0644\u0652\u064a\u064e\u0633\u0652\u062a\u064e\u0639\u0650\u0630\u0652 \u0645\u0650\u0646\u0652 \u0634\u064e\u0631\u0651\u0650\u0647\u064e\u0627 \u0648\u064e\u0644\u0627 \u064a\u064e\u0630\u0652\u0643\u064f\u0631\u0652\u0647\u064e\u0627 \u0644\u0650\u0623\u064e\u062d\u064e\u062f\u064d \u0641\u064e\u0625\u0650\u0646\u0651\u064e\u0647\u064e\u0627 \u0644\u064e\u0646\u0652 \u062a\u064e\u0636\u064f\u0631\u0651\u064e\u0647\u064f ) \u0631\u0648\u0627\u0647 \u0627\u0644\u0628\u062e\u0627\u0631\u064a \u0637\u064a\u0628 \u0644\u0645\u0627 \u062a\u0643\u062a\u0628 \u0644\u0649 \u0648\u0627\u062d\u062f\u0647 \u0628\u062a\u0642\u0648\u0644 \u0627\u0646\u0647\u0627 \u0645\u0641\u0633\u0631\u0629 \u0631\u0624\u0649 \u0648\u062a\u062e\u0627\u0644\u0641 \u062d\u062f\u064a\u062b \u0627\u0644\u0646\u0628\u064a \u0635\u0644 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":21157,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-21156","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-1"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts\/21156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/comments?post=21156"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts\/21156\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/media\/21157"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/media?parent=21156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/categories?post=21156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/tags?post=21156"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}