{"id":21153,"date":"2025-03-25T12:26:50","date_gmt":"2025-03-25T12:26:50","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=21153"},"modified":"2025-04-26T19:04:11","modified_gmt":"2025-04-26T19:04:11","slug":"dfsggfs","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/es\/archives\/21153","title":{"rendered":"La negaci\u00f3n de las visiones por parte de un amigo 24 de julio de 2018"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"21153\" class=\"elementor elementor-21153\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17204859 e-flex e-con-boxed e-con e-parent\" data-id=\"17204859\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12186654 elementor-widget elementor-widget-text-editor\" data-id=\"12186654\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Un amigo me recomend\u00f3 a un jeque que interpreta sue\u00f1os, as\u00ed que le cont\u00e9 el sue\u00f1o en el que vi a Mois\u00e9s, Job y Juan. Se asust\u00f3 y me dijo que era un sue\u00f1o de Satan\u00e1s para alejarme de mi religi\u00f3n.<br class=\"html-br\" \/>Le dije: \u201cEst\u00e1 bien, y las siete visiones en las que vi a nuestro maestro Muhammad, que Dios le bendiga y le conceda paz, y la visi\u00f3n en la que vi a nuestro maestro Jos\u00e9, y varias visiones en las que vi a nuestro maestro Jes\u00fas\u201d.<br class=\"html-br\" \/>Me dijo: \u00abEs imposible que sean ellos\u00bb. Me dijo: \u00abSoy jeque, im\u00e1n de una mezquita, y realizo todas mis oraciones en congregaci\u00f3n. Nunca lo he visto en ninguna visi\u00f3n. Llevo muchos a\u00f1os rezando a Dios para verlo solo una vez. Hay muchos jeques como yo que quieren ver al Profeta solo una vez. \u00a1Dime que viste a nuestro maestro Muhammad, Mois\u00e9s, Job, Juan, Jos\u00e9 y Jes\u00fas!\u00bb.<br class=\"html-br\" \/>Le dije: \u00abBueno, \u00bfcu\u00e1l es el prop\u00f3sito del diablo al hacerme esto?\u00bb. Me respondi\u00f3: \u00abPara que con el tiempo te pida cosas que te alejen de tu religi\u00f3n\u00bb.<br class=\"html-br\" \/>\u00c9sta es la opini\u00f3n de un jeque, y hay gente que comparte su opini\u00f3n, y hay otra gente que me dice que no existe ning\u00fan demonio que se haga pasar por profeta.<br class=\"html-br\" \/>Quiero saber si esta es una visi\u00f3n de Satan\u00e1s o del Anticristo. \u00bfCu\u00e1l es la segunda etapa y qu\u00e9 puede hacerme? \u00bfEs posible que todo lo que veo en las visiones sea una treta del Anticristo?<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0635\u062f\u064a\u0642 \u0631\u0634\u062d \u0644\u0649 \u0634\u064a\u062e \u0628\u064a\u0641\u0633\u0631 \u0631\u0624\u0649 \u0641\u062d\u0643\u064a\u062a \u0644\u0647 \u0639\u0644\u0649 \u0627\u0644\u0631\u0624\u064a\u0627 \u0627\u0644\u0644\u0649 \u0634\u0648\u0641\u062a \u0641\u064a\u0647\u0627 \u0633\u064a\u062f\u0646\u0627 \u0645\u0648\u0633\u0649 \u0648\u0627\u064a\u0648\u0628 \u0648\u064a\u062d\u064a\u0649 \u0641\u0627\u062a\u062e\u0636 \u0648\u0642\u0627\u0644 \u0644\u0649 \u062f\u0627 \u062d\u0644\u0645 \u0645\u0646 \u0639\u0646\u062f \u0627\u0644\u0634\u064a\u0637\u0627\u0646 \u0639\u0644\u0634\u0627\u0646 \u064a\u0628\u0639\u062f\u0643 \u0639\u0646 \u062f\u064a\u0646\u0643\u0641\u0642\u0644\u062a \u0644\u0647 \u0637\u064a\u0628 \u0648\u0627\u0644\u0633\u0628\u0639 \u0631\u0624\u0649 \u0627\u0644\u0644\u0649 \u0634\u0648\u0641\u062a \u0641\u064a\u0647\u0645 \u0633\u064a\u062f\u0646\u0627 \u0645\u062d\u0645\u062f \u0635\u0644 \u0627\u0644\u0644\u0647 \u0639\u0644\u064a\u0647 \u0648\u0633\u0644\u0645 \u0648\u0631\u0624\u064a\u0627 \u0634\u0648\u0641\u062a \u0641\u064a\u0647\u0627 \u0633\u064a\u062f\u0646\u0627 \u064a\u0648\u0633\u0641 \u0648\u0639\u062f\u0629 \u0631\u0624\u0649 \u0634\u0648\u0641\u062a \u0641\u064a\u0647\u0627 \u0633\u064a\u062f\u0646\u0627 \u0639\u064a\u0633\u0649\u0641\u0642\u0627\u0644 \u0644\u0649 \u0645\u0633\u062a\u062d\u064a\u0644 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":21154,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-21153","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-1"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts\/21153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/comments?post=21153"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts\/21153\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/media\/21154"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/media?parent=21153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/categories?post=21153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/tags?post=21153"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}