{"id":21094,"date":"2025-03-25T11:08:34","date_gmt":"2025-03-25T11:08:34","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=21094"},"modified":"2025-04-27T18:44:55","modified_gmt":"2025-04-27T18:44:55","slug":"gfshhg","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/es\/archives\/21094","title":{"rendered":"Una visi\u00f3n de soldados egipcios recitando Surat Al-Qamar el 5 de septiembre de 2020"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"21094\" class=\"elementor elementor-21094\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ff1d10c e-flex e-con-boxed e-con e-parent\" data-id=\"4ff1d10c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e6721ca elementor-widget elementor-widget-text-editor\" data-id=\"5e6721ca\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Vi dos filas de soldados egipcios con overoles de camuflaje de pie en dos filas ordenadas, alrededor de diez en n\u00famero, divididos en dos filas una detr\u00e1s de la otra, cada fila compuesta por cuatro o cinco individuos en cada fila, y frente a ellos hab\u00eda un soldado egipcio de pie frente a ellos, mir\u00e1ndolos, y todos estaban recitando al mismo tiempo los versos de tormento mencionados en Surat Al-Qamar, centr\u00e1ndose en el verso repetido en Surat Al-Qamar que ven\u00eda despu\u00e9s de cada tormento que Allah Todopoderoso infligi\u00f3 a las naciones anteriores: &quot;\u00bfC\u00f3mo fue entonces Mi castigo y Mis advertencias?&quot; La recitaci\u00f3n de los soldados de los versos de tormento en Surat Al-Qamar era similar a la de los concursantes que recitan el Sagrado Cor\u00e1n en una competencia de memorizaci\u00f3n del Cor\u00e1n de una manera muy excelente.<br class=\"html-br\" \/>La escena me tom\u00f3 como si estuviera mirando al cielo y sent\u00ed que estaba viendo a Dios Todopoderoso sentado en el trono y \u00c9l Todopoderoso dijo: \u201c\u00bfC\u00f3mo fue entonces Mi castigo y Mis advertencias?\u201d<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0631\u0623\u064a\u062a \u0635\u0641\u064a\u0646 \u0645\u0646 \u0627\u0644\u0639\u0633\u0643\u0631\u064a\u064a\u0646 \u0627\u0644\u0645\u0635\u0631\u064a\u064a\u0646 \u064a\u0644\u0628\u0633\u0648\u0646 \u0627\u0644\u0623\u0641\u0631\u0648\u0644 \u0627\u0644\u0645\u0645\u0648\u0647 \u0648\u064a\u0642\u0641\u0648\u0646 \u0641\u064a \u0635\u0641\u064a\u0646 \u0645\u0646\u062a\u0638\u0645\u064a\u0646 \u0639\u062f\u062f\u0647\u0645 \u062d\u0648\u0627\u0644\u064a \u0639\u0634\u0631\u0629 \u0645\u0646\u0642\u0633\u0645\u064a\u0646 \u0627\u0644\u0649 \u0635\u0641\u064a\u0646 \u0645\u062a\u062a\u0627\u0644\u064a\u0646 \u0648\u0631\u0627\u0621 \u0628\u0639\u0636\u0647\u0645 \u0627\u0644\u0628\u0639\u0636 \u0648\u0627\u0644\u0635\u0641\u064a\u0646 \u0643\u0644 \u0645\u0646\u0647\u0645\u0627 \u0645\u0643\u0648\u0646 \u0645\u0646 \u0623\u0631\u0628\u0639\u0629 \u0623\u0648 \u062e\u0645\u0633 \u0623\u0641\u0631\u0627\u062f \u0641\u064a \u0643\u0644 \u0635\u0641 \u0648\u0623\u0645\u0627\u0645\u0647\u0645 \u0639\u0633\u0643\u0631\u064a \u0645\u0635\u0631\u064a \u064a\u0642\u0641 \u0623\u0645\u0627\u0645\u0647\u0645 \u0648\u0645\u0648\u0627\u062c\u0647 \u0644\u0647\u0645 \u0648\u0643\u0644\u0647\u0645 \u064a\u062a\u0644\u0648\u0646 \u0641\u064a \u0630\u0627\u062a \u0627\u0644\u0648\u0642\u062a \u0622\u064a\u0627\u062a \u0627\u0644\u0639\u0630\u0627\u0628 \u0627\u0644\u0645\u0630\u0643\u0648\u0631\u0629 \u0641\u064a \u0633\u0648\u0631\u0629 \u0627\u0644\u0642\u0645\u0631 \u0645\u0639 \u0627\u0644\u062a\u0631\u0643\u064a\u0632 \u0639\u0644\u0649 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":21095,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[111],"tags":[],"class_list":{"0":"post-21094","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category--2016-2020"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts\/21094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/comments?post=21094"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts\/21094\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/media\/21095"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/media?parent=21094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/categories?post=21094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/tags?post=21094"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}