{"id":20438,"date":"2025-03-23T10:08:25","date_gmt":"2025-03-23T10:08:25","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=20438"},"modified":"2025-04-28T15:30:10","modified_gmt":"2025-04-28T15:30:10","slug":"heyd","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/es\/archives\/20438","title":{"rendered":"Visi\u00f3n de Jes\u00fas, la paz sea con \u00e9l, en octubre de 2018"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"20438\" class=\"elementor elementor-20438\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ca7d819 e-flex e-con-boxed e-con e-parent\" data-id=\"6ca7d819\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-403b3a12 elementor-widget elementor-widget-text-editor\" data-id=\"403b3a12\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Vi que estaba en Palestina durante la gran batalla \u00e9pica de la liberaci\u00f3n musulmana del Levante. La guerra era muy intensa y yo participaba en ella y observaba todos sus acontecimientos. Uno de los musulmanes, exhausto por la guerra, me dijo: &quot;\u00bfPor qu\u00e9 todo esto? Nuestro Maestro Jes\u00fas, la paz sea con \u00e9l, descender\u00e1 pronto y pondr\u00e1 fin a todo esto&quot;. As\u00ed que lo mir\u00e9 y le dije: &quot;Para que pueda dedicarse a la llamada&quot;.<br class=\"html-br\" \/>Entonces la escena me llev\u00f3 a la llegada de nuestro maestro Jes\u00fas, la paz sea con \u00e9l, a Jerusal\u00e9n, y comenc\u00e9 a correr hacia \u00e9l hasta que lo alcanc\u00e9 y lo abrac\u00e9 mientras lloraba intensamente, y \u00e9l tambi\u00e9n me abraz\u00f3, pero no lloraba.<br class=\"html-br\" \/>Me despert\u00e9 del sue\u00f1o llorando incontrolablemente.<br class=\"html-br\" \/><br class=\"html-br\" \/>\u00c9sta es la misi\u00f3n de los musulmanes que entend\u00ed a partir de esta visi\u00f3n y debo transmitirla a ustedes.<br class=\"html-br\" \/><br class=\"html-br\" \/>((Liberar el Levante para que nuestro maestro Jes\u00fas, la paz sea con \u00e9l, pueda dedicarse a la predicaci\u00f3n))<\/h1><h1>Interpretaci\u00f3n de la visi\u00f3n en este v\u00eddeo<\/h1><p><iframe title=\"Una visi\u00f3n del descenso de Jes\u00fas, la paz sea con \u00e9l, en octubre de 2018\" width=\"800\" height=\"600\" src=\"https:\/\/www.youtube.com\/embed\/IERYjs8g7gs?list=PLGSQ8bPhLqKvbIK2NxQ1CoUA-dKyGIGlP\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0631\u0623\u064a\u062a \u0623\u0646\u0646\u0649 \u0628\u0641\u0644\u0633\u0637\u064a\u0646 \u0623\u062b\u0646\u0627\u0621 \u0627\u0644\u0645\u0644\u062d\u0645\u0629 \u0627\u0644\u0643\u0628\u0631\u0649 \u0623\u062b\u0646\u0627\u0621 \u062a\u062d\u0631\u064a\u0631 \u0627\u0644\u0645\u0633\u0644\u0645\u064a\u0646 \u0644\u0644\u0634\u0627\u0645 \u0648\u0642\u062f \u0643\u0627\u0646\u062a \u0627\u0644\u062d\u0631\u0628 \u0634\u062f\u064a\u062f\u0647 \u062c\u062f\u0627 \u0648\u0642\u062f \u0643\u0646\u062a \u0645\u0634\u0627\u0631\u0643 \u0641\u064a \u0647\u0630\u0647 \u0627\u0644\u062d\u0631\u0628 \u0648\u0623\u0634\u0627\u0647\u062f \u062c\u0645\u064a\u0639 \u0623\u062d\u062f\u0627\u062b\u0647\u0627 \u0641\u0642\u0627\u0644 \u0644\u064a \u0623\u062d\u062f \u0627\u0644\u0645\u0633\u0644\u0645\u064a\u0646 \u0627\u0644\u0630\u064a\u0646 \u0623\u0646\u0647\u0643\u062a\u0647 \u0627\u0644\u062d\u0631\u0628 \u0644\u0645\u0627\u0630\u0627 \u0643\u0644 \u0647\u0630\u0627 \u0648\u0633\u064a\u062f\u0646\u0627 \u0639\u064a\u0633\u0649 \u0639\u0644\u064a\u0647 \u0627\u0644\u0633\u0644\u0627\u0645 \u0633\u064a\u0646\u0632\u0644 \u0642\u0631\u064a\u0628\u0627\u064b \u0648\u0633\u064a\u064f\u0646\u0647\u064a \u0643\u0644 \u0647\u0630\u0627 \u0641\u0646\u0638\u0631\u062a \u0627\u0644\u064a\u0647 \u0648\u0642\u0644\u062a \u0644\u0647 (\u062d\u062a\u064a \u064a\u062a\u0641\u0631\u063a \u0644\u0644\u062f\u0639\u0648\u0629)\u0628\u0639\u062f \u0630\u0644\u0643 \u0625\u0646\u062a\u0642\u0644 \u0628\u064a \u0627\u0644\u0645\u0634\u0647\u062f \u0628\u0648\u0635\u0648\u0644 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":20439,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[111],"tags":[],"class_list":{"0":"post-20438","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category--2016-2020"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts\/20438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/comments?post=20438"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/posts\/20438\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/media\/20439"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/media?parent=20438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/categories?post=20438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/es\/wp-json\/wp\/v2\/tags?post=20438"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}