{"id":26456,"date":"2025-04-09T10:21:46","date_gmt":"2025-04-09T10:21:46","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=26456"},"modified":"2025-07-03T14:50:07","modified_gmt":"2025-07-03T14:50:07","slug":"5-165","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/de\/archives\/26456","title":{"rendered":"Ich erkl\u00e4re, dass ich mich den Demonstrationen vom Freitag \u201eDas Land ist der Stolz\u201c anschlie\u00dfe und im Namen Gottes, des Vaterlandes und um der Wahrheit willen k\u00e4mpfe."},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"26456\" class=\"elementor elementor-26456\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3388f7c e-flex e-con-boxed e-con e-parent\" data-id=\"3388f7c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-33b687d0 elementor-widget elementor-widget-text-editor\" data-id=\"33b687d0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><h1 class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">15. April 2016<\/span><\/span><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"xzpqnlu xjm9jq1 x6ikm8r x10wlt62 x10l6tqk x1i1rx1s\">\u00a0<\/span><\/span><\/h1><\/div><\/div><\/div><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Ma\u00dfnahmen, die f\u00fcr diese Stelle ergriffen werden k\u00f6nnen\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">Ich habe Gott geschworen, f\u00fcr seine Sache zu k\u00e4mpfen, und der beste Dschihad besteht darin, in Gegenwart eines ungerechten Herrschers die Wahrheit zu sagen.<br class=\"html-br\" \/>Ich habe euch versprochen, dass ich auf der Erde bei euch sein werde, wenn ihr euch f\u00fcr ein Ziel zusammenschlie\u00dft. Und nun habt ihr euch vereint und die Zeit ist gekommen, mein Versprechen an euch zu erf\u00fcllen.<br class=\"html-br\" \/>Deshalb erkl\u00e4re ich, dass ich mich an den Demonstrationen zum Freitag des Landes der Ehre beteilige und f\u00fcr Gott, f\u00fcr das Vaterland und f\u00fcr die Wahrheit k\u00e4mpfe. Ich werde bei euch sein, denn ihr seid meine Lieben und meine Br\u00fcder, und ich werde euch nicht im Stich lassen.<br class=\"html-br\" \/>Ich bin jetzt mit dir auf Mustafa Mahmouds Reise<br class=\"html-br\" \/><br class=\"html-br\" \/>Ich entschuldige mich bei meiner Familie, dass ich sie unter diesen Umst\u00e4nden zur\u00fcckgelassen habe, und w\u00fcnsche ihnen viel Erfolg.<br class=\"html-br\" \/><br class=\"html-br\" \/>Gott der Allm\u00e4chtige sagte: \u201eSprich: Wenn euch eure V\u00e4ter, eure S\u00f6hne, eure Br\u00fcder, eure Frauen, eure Verwandten, euer erworbener Reichtum, euer Handel, dessen Niedergang ihr f\u00fcrchtet, und eure Wohnst\u00e4tten, an denen ihr Freude habt, lieber sind als Gott und sein Gesandter und das Streben nach seiner Sache, dann wartet, bis Gott seine Entscheidung trifft. Und Gott weist dem Volk der Trotzigen nicht den Weg.\u201c Die Wahrheit Gottes des Allm\u00e4chtigen.<br class=\"html-br\" \/><br class=\"html-br\" \/>Ich bezeuge, dass es keinen Gott au\u00dfer Allah gibt und ich bezeuge, dass Muhammad der Gesandte Allahs ist.<br class=\"html-br\" \/><br class=\"html-br\" \/>Tamer Badr<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>15 \u0623\u0628\u0631\u064a\u0644 2016 \u0644\u0642\u062f \u0639\u0627\u0647\u062f\u062a \u0627\u0644\u0644\u0647 \u0639\u0644\u0649 \u0627\u0644\u062c\u0647\u0627\u062f \u0641\u064a \u0633\u0628\u064a\u0644\u0647 \u0641\u062e\u064a\u0631 \u0627\u0644\u062c\u0647\u0627\u062f \u0647\u0648 \u0643\u0644\u0645\u0629 \u062d\u0642 \u0639\u0646\u062f \u0633\u0644\u0637\u0627\u0646 \u062c\u0627\u0626\u0631 \u0648\u0644\u0642\u062f \u0639\u0627\u0647\u062f\u062a\u0643\u0645 \u0623\u0646 \u0623\u0643\u0648\u0646 \u0645\u0639\u0643\u0645 \u0639\u0644\u0649 \u0627\u0644\u0623\u0631\u0636 \u0639\u0646\u062f \u0625\u062a\u062d\u0627\u062f\u0643\u0645 \u0639\u0644\u0649 \u0623\u0647\u062f\u0627\u0641 \u0648\u0627\u062d\u062f\u0629 \u0648\u0647\u0627 \u0623\u0646\u062a\u0645 \u0642\u062f \u0625\u062a\u062d\u062f\u062a\u0645 \u0648\u0642\u062f \u062d\u0627\u0646 \u0627\u0644\u0648\u0642\u062a \u0628\u0627\u0644\u0648\u0641\u0627\u0621 \u0628\u0639\u0647\u062f\u064a \u0644\u0643\u0645 \u0644\u0630\u0644\u0643 \u0641\u0625\u0646\u0646\u064a \u0623\u0639\u0644\u0646 \u0625\u0646\u0636\u0645\u0627\u0645\u064a \u0625\u0644\u0649 \u0645\u0638\u0627\u0647\u0631\u0627\u062a \u062c\u0645\u0639\u0629 \u0627\u0644\u0623\u0631\u0636 \u0647\u064a \u0627\u0644\u0639\u0631\u0636 \u0645\u062c\u0627\u0647\u062f\u0627\u064b \u0641\u064a \u0633\u0628\u064a\u0644 \u0627\u0644\u0644\u0644\u0647 \u0648\u0641\u064a [&hellip;]<\/p>","protected":false},"author":2,"featured_media":36988,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[117,118],"tags":[],"class_list":{"0":"post-26456","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-117","8":"category-118"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts\/26456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/comments?post=26456"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts\/26456\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/media\/36988"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/media?parent=26456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/categories?post=26456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/tags?post=26456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}