{"id":26073,"date":"2025-04-06T14:41:27","date_gmt":"2025-04-06T14:41:27","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=26073"},"modified":"2025-07-04T11:28:11","modified_gmt":"2025-07-04T11:28:11","slug":"5-108","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/de\/archives\/26073","title":{"rendered":"Ich respektiere Unterschiede, aber ich respektiere keine Beleidigungen und keinen Verrat."},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"26073\" class=\"elementor elementor-26073\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5cdd87bf e-flex e-con-boxed e-con e-parent\" data-id=\"5cdd87bf\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-59885d59 elementor-widget elementor-widget-text-editor\" data-id=\"59885d59\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><div class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">4. Januar 2015<\/span><\/span><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"xzpqnlu xjm9jq1 x6ikm8r x10wlt62 x10l6tqk x1i1rx1s\">\u00a0<\/span><\/span><\/div><\/div><\/div><\/div><div class=\"xqcrz7y x78zum5 x1qx5ct2 x1y1aw1k x1sxyh0 xwib8y2 xurb0ha xw4jnvo\"><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Ma\u00dfnahmen, die f\u00fcr diese Stelle ergriffen werden k\u00f6nnen\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><\/div><div class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">Ich habe dar\u00fcber nachgedacht, die Kommentare f\u00fcr Nicht-Freunde auf diesem Konto wegen der gegen mich gerichteten Beleidigungen zu schlie\u00dfen, aber nach einigem Nachdenken habe ich beschlossen, die Kommentare weiterhin f\u00fcr alle zu \u00f6ffnen, damit ich denen, die mich respektieren und lieben, nicht die M\u00f6glichkeit nehme, ihre Meinung auf meiner Seite zu ver\u00f6ffentlichen, und ich schlage ihnen nicht die T\u00fcr vor der Nase zu, damit sie mir nicht schreiben k\u00f6nnen. Nur f\u00fcr sie werde ich den Verrat und die Beleidigungen ertragen, die von denen gegen mich gerichtet werden, die mich hassen und verraten, in der Hoffnung, dass ich als Gegenleistung f\u00fcr ihre falschen Anschuldigungen gegen mich gute Taten erlange, und in der Hoffnung, dass sie eines Tages zur Wahrheit gef\u00fchrt werden und die Wahrheit \u00fcber meine Position erfahren<br class=\"html-br\" \/>Was diejenigen betrifft, die mich beleidigen, habe ich keine andere Wahl, als sie zu blockieren, obwohl ich diese Funktion hasse. Pers\u00f6nlich respektiere ich Unterschiede, aber ich respektiere keine Beleidigungen und keinen Verrat.<\/span><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>4 \u064a\u0646\u0627\u064a\u0631 2015\u00a0\u00a0\u0623\u0646\u0627 \u0641\u0643\u0631\u062a \u0641\u064a \u063a\u0644\u0642 \u0627\u0644\u062a\u0639\u0644\u064a\u0642\u0627\u062a \u0644\u063a\u064a\u0631 \u0627\u0644\u0623\u0635\u062f\u0642\u0627\u0621 \u0639\u0644\u0649 \u062d\u0633\u0627\u0628\u064a \u0647\u0630\u0627 \u0628\u0633\u0628\u0628 \u0627\u0644\u0634\u062a\u0627\u0626\u0645 \u0627\u0644\u062a\u064a \u062a\u064f\u0648\u062c\u0647 \u0625\u0644\u064a \u0648\u0644\u0643\u0646 \u0628\u0639\u062f \u062a\u0641\u0643\u064a\u0631 \u0641\u0642\u062f \u0642\u0631\u0631\u062a \u0623\u0646 \u0627\u0633\u062a\u0645\u0631 \u0641\u064a \u0641\u062a\u062d \u0627\u0644\u062a\u0639\u0644\u064a\u0642\u0627\u062a \u0644\u0644\u0643\u0644 \u062d\u062a\u0649 \u0644\u0627 \u0623\u062d\u0631\u0645 \u0645\u0646 \u0627\u062d\u062a\u0631\u0645\u0646\u064a \u0648\u0623\u062d\u0628\u0646\u064a \u0641\u064a \u0648\u0636\u0639 \u0622\u0631\u0627\u0621\u0647 \u0639\u0644\u0649 \u0635\u0641\u062d\u062a\u064a \u0648\u0623\u0644\u0627 \u0623\u063a\u0644\u0642 \u0627\u0644\u0628\u0627\u0628 \u0623\u0645\u0627\u0645\u0647 \u0641\u0644\u0627 \u064a\u0633\u062a\u0637\u064a\u0639 \u0623\u0646 \u064a\u0643\u062a\u0628 \u0625\u0644\u064a \u0648\u0645\u0646 \u0623\u062c\u0644\u0647\u0645 \u0641\u0642\u0637 \u0633\u0623\u062a\u062d\u0645\u0644 \u0627\u0644\u062a\u062e\u0648\u064a\u0646 \u0648\u0627\u0644\u0625\u0647\u0627\u0646\u0627\u062a \u0627\u0644\u062a\u064a [&hellip;]<\/p>","protected":false},"author":2,"featured_media":37183,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[121,117],"tags":[],"class_list":{"0":"post-26073","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-121","8":"category-117"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts\/26073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/comments?post=26073"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts\/26073\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/media\/37183"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/media?parent=26073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/categories?post=26073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/tags?post=26073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}