{"id":25565,"date":"2025-04-05T17:20:17","date_gmt":"2025-04-05T17:20:17","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=25565"},"modified":"2025-07-08T07:36:43","modified_gmt":"2025-07-08T07:36:43","slug":"h-102","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/de\/archives\/25565","title":{"rendered":"Ich bitte alle meine Freunde, einen ruhigen Dialog fernab von jeglichem Fanatismus zu f\u00fchren und meine Anwesenheit zu respektieren."},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"25565\" class=\"elementor elementor-25565\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-758a449c e-flex e-con-boxed e-con e-parent\" data-id=\"758a449c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9c0b25e elementor-widget elementor-widget-text-editor\" data-id=\"9c0b25e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><h1 class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">6. M\u00e4rz 2014<\/span><\/span><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"xzpqnlu xjm9jq1 x6ikm8r x10wlt62 x10l6tqk x1i1rx1s\">\u00a0<\/span><\/span><\/h1><\/div><\/div><\/div><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Ma\u00dfnahmen, die f\u00fcr diese Stelle ergriffen werden k\u00f6nnen\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">Ich habe Freunde aus allen Gesellschaftsschichten, was zu Diskussionen \u00fcber meine Artikel f\u00fchrt, die \u00fcber einen respektvollen, zivilisierten Dialog hinausgehen und sich in einen Austausch von Beleidigungen und Anschuldigungen gegen beide Parteien verwandeln.<br class=\"html-br\" \/><br class=\"html-br\" \/>Es ist f\u00fcr mich nicht sinnvoll, eine Seite zu erstellen, auf der ich Freunde aus einer bestimmten Gruppe akzeptiere, und eine andere Seite zu erstellen, auf der ich Freunde aus einer anderen Gruppe akzeptiere.<br class=\"html-br\" \/><br class=\"html-br\" \/>Alle Anschuldigungen wiederholen sich und sind nichts Neues, aber ich sage, dass jeder der Revolution Unrecht getan hat, und ich hoffe, dass wir nach vorne schauen, anstatt zu streiten, was nichts bringen wird.<br class=\"html-br\" \/><br class=\"html-br\" \/>Ich bitte alle meine Freunde, einen ruhigen Dialog zu f\u00fchren, fernab von jeglichem Fanatismus. Ich bitte euch, meine Anwesenheit zu respektieren und mich vor Freunden nicht in Verlegenheit zu bringen. Wenn ihr euch gegenseitig beleidigen wollt, hoffe ich, dass dies au\u00dferhalb meiner Seite geschieht.<br class=\"html-br\" \/><br class=\"html-br\" \/>Allah \u00e4ndert den Zustand eines Volkes nicht, bis es sein eigenes Wesen \u00e4ndert.<br class=\"html-br\" \/><br class=\"html-br\" \/>O Gott, vereinige unser Wort und unterst\u00fctze unsere Revolution<br class=\"html-br\" \/><br class=\"html-br\" \/>Major Tamer Badr<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>6. M\u00e4rz 2014 Ich habe Freunde aus allen politischen Lagern, was zu Diskussionen \u00fcber meine Artikel f\u00fchrt, die von einem respektvollen, zivilisierten Dialog abweichen und sich in einen Austausch von Beleidigungen und Anschuldigungen gegen beide Seiten verwandeln. Es ist unsinnig f\u00fcr mich, eine Seite zu erstellen, auf der ich Freunde der einen und eine andere Seite, auf der ich Freunde der anderen Fraktion empfange. Alle Anschuldigungen wiederholen sich und sind nichts Neues, aber ich sage alles [\u2026]<\/p>","protected":false},"author":2,"featured_media":37597,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[117],"tags":[],"class_list":{"0":"post-25565","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-117"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts\/25565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/comments?post=25565"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts\/25565\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/media\/37597"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/media?parent=25565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/categories?post=25565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/tags?post=25565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}