{"id":25457,"date":"2025-04-05T14:29:45","date_gmt":"2025-04-05T14:29:45","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=25457"},"modified":"2025-06-10T10:39:56","modified_gmt":"2025-06-10T10:39:56","slug":"g-86","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/de\/archives\/25457","title":{"rendered":"Generationenkonflikt"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"25457\" class=\"elementor elementor-25457\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a514878 e-flex e-con-boxed e-con e-parent\" data-id=\"1a514878\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4e830a93 elementor-widget elementor-widget-text-editor\" data-id=\"4e830a93\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><h1 class=\"x1gslohp\">\u00a0<\/h1><\/div><div class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">15. Januar 2014<\/span><\/span><\/div><\/div><\/div><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Ma\u00dfnahmen, die f\u00fcr diese Stelle ergriffen werden k\u00f6nnen\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><strong>Generationenkonflikt<\/strong><br class=\"html-br\" \/><br class=\"html-br\" \/>Es ist der Konflikt zwischen einer Generation, die in der Zeit der Sklaverei aufwuchs, und einer Generation, die aus der Sklaverei befreit werden will.<br class=\"html-br\" \/>Die Geschichte der Kinder Israels ist daf\u00fcr ein gutes Beispiel.<br class=\"html-br\" \/><br class=\"html-br\" \/>Nachdem Gott die Kinder Israels vor dem Pharao gerettet hatte, sagten sie zu Moses: \u201eMach uns einen Gott wie diesen.\u201c Dies geschah, obwohl sie die Wunder gesehen hatten, mit denen Gott sie unterst\u00fctzt hatte. Doch sie wurden schnell ungl\u00e4ubig und weigerten sich sogar zu glauben, bevor sie Gott \u00f6ffentlich sahen. Also lie\u00df Gott sie sterben und sandte einen Blitz auf sie. Dann flehte Moses (Friede sei mit ihm) seinen Herrn an, sein Volk wiederzubeleben, und Gott erh\u00f6rte ihn \u2013 zur Ehre Moses.<br class=\"html-br\" \/><br class=\"html-br\" \/>Gott schickte ihnen Manna und Wachteln. Manna ist eine Pflanze mit einer honig\u00e4hnlichen Fl\u00fcssigkeit, und Wachteln sind eine Vogelart, die t\u00e4glich zu ihnen kam. Aufgrund ihrer Unwissenheit und ihres Mangels an Wissen baten sie statt um Manna und Wachteln um das Gem\u00fcse, Gurken, Knoblauch, Linsen und Zwiebeln, das sie w\u00e4hrend ihrer Sklaverei in \u00c4gypten gegessen hatten.<br class=\"html-br\" \/><br class=\"html-br\" \/>Gott hatte ihnen Pal\u00e4stina als ihr Land zugeschrieben. Als Gott ihnen befahl, zu k\u00e4mpfen, bis sie das Heilige Land (Pal\u00e4stina) erreichten, weigerten sie sich und sagten zu Moses: \u201eGeht, ihr und euer Herr, und k\u00e4mpft. Wir bleiben hier!\u201c Also verbot Gott es ihnen vierzig Jahre lang.<br class=\"html-br\" \/><br class=\"html-br\" \/>Ja, der allm\u00e4chtige Gott hat dieser Generation den Zutritt nach Pal\u00e4stina verboten. Diese Generation wuchs in der Sklaverei der Pharaonen auf und nicht in der Freiheit. Sie hatten das Recht, 40 Jahre lang auf der Erde umherzuwandern, bis eine neue Generation in Freiheit, Gottesliebe, Siegeswillen und dem Betreten Pal\u00e4stinas erzogen wurde.<br class=\"html-br\" \/><br class=\"html-br\" \/>Und hier stehen wir nun zwischen einer Generation, die in der \u00c4ra der Sklaverei bleiben will, und einer Generation, die Freiheit und die Befreiung von Al-Aqsa will.<br class=\"html-br\" \/>Wird Gott es so einrichten, dass wir zu dieser Generation geh\u00f6ren, die aus der Sklaverei befreit wird und die gefangene Al-Aqsa-Moschee befreit?<br class=\"html-br\" \/><br class=\"html-br\" \/>Major Tamer Badr\u00a0<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>15 \u064a\u0646\u0627\u064a\u0631 2014 \u0635\u0631\u0627\u0639 \u0627\u0644\u0623\u062c\u064a\u0627\u0644 \u0625\u0646\u0647 \u0627\u0644\u0635\u0631\u0627\u0639 \u0628\u064a\u0646 \u062c\u064a\u0644 \u0646\u0634\u0623 \u0641\u064a \u0632\u0645\u0646 \u0627\u0644\u0639\u0628\u0648\u062f\u064a\u0629 \u0648\u062c\u064a\u0644 \u064a\u0631\u064a\u062f \u0627\u0644\u062a\u062d\u0631\u0631 \u0645\u0646 \u0627\u0644\u0639\u0628\u0648\u062f\u064a\u0629 \u0648\u0641\u064a \u0642\u0635\u0629 \u0628\u0646\u064a \u0625\u0633\u0631\u0627\u0626\u064a\u0644 \u062e\u064a\u0631 \u0645\u062b\u0627\u0644 \u0639\u0644\u0649 \u0630\u0644\u0643 \u0641\u0628\u0639\u062f \u0623\u0646 \u0623\u0646\u062c\u0649 \u0627\u0644\u0644\u0647 \u0628\u0646\u064a \u0625\u0633\u0631\u0627\u0626\u064a\u0644 \u0645\u0646 \u0641\u0631\u0639\u0648\u0646 \u0642\u0627\u0644\u0648\u0627 \u0644\u0645\u0648\u0633\u0649 \u0627\u062c\u0639\u0644 \u0644\u0646\u0627 \u0625\u0644\u0647\u0627 \u0645\u062b\u0644 \u0647\u0630\u0627 \u0627\u0644\u0622\u0644\u0647\u0629 &#8230;.\u0630\u0644\u0643 \u0628\u0627\u0644\u0631\u063a\u0645 \u0645\u0646 \u0625\u0646\u0647\u0645 \u0631\u0623\u0648\u0627 \u0627\u0644\u0645\u0639\u062c\u0632\u0627\u062a \u0627\u0644\u062a\u064a \u0623\u064a\u062f\u0647\u0645 \u0627\u0644\u0644\u0647 \u0628\u0647\u0627 \u0648 \u0644\u0643\u0646 \u0645\u0627 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":36472,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[183,117],"tags":[],"class_list":{"0":"post-25457","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-183","8":"category-117"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts\/25457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/comments?post=25457"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts\/25457\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/media\/36472"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/media?parent=25457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/categories?post=25457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/tags?post=25457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}