{"id":21877,"date":"2025-03-27T11:08:01","date_gmt":"2025-03-27T11:08:01","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=21877"},"modified":"2025-04-20T09:45:18","modified_gmt":"2025-04-20T09:45:18","slug":"ghfghh","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/de\/archives\/21877","title":{"rendered":"Der Fall von Sevilla"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"21877\" class=\"elementor elementor-21877\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7069da1c e-flex e-con-boxed e-con e-parent\" data-id=\"7069da1c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2416b690 elementor-widget elementor-widget-text-editor\" data-id=\"2416b690\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><h1 class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">17. September 2014<\/span><\/span><\/h1><\/div><\/div><\/div><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Ma\u00dfnahmen, die f\u00fcr diese Stelle ergriffen werden k\u00f6nnen\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">Der Fall von Sevilla<br class=\"html-br\" \/><br class=\"html-br\" \/>Die Geschichte wiederholt sich bei uns immer wieder, und leider sind wir eine Nation, die die Geschichte nicht liest, um daraus Nutzen zu ziehen, und am Ende begehen wir dieselben Fehler wie diejenigen, die vor uns kamen. Wer sich nicht an die Vergangenheit erinnert, ist dazu verdammt, sie zu wiederholen, und leider wiederholen wir die Fehler der Vergangenheit und verb\u00fcnden uns mit unseren Feinden, um uns gegenseitig zu vernichten.<br class=\"html-br\" \/><br class=\"html-br\" \/>Dies ist die Geschichte des Untergangs Sevillas, der ein wiederkehrendes Beispiel f\u00fcr den Untergang der \u00fcbrigen andalusischen St\u00e4dte ist und leider auch ein wiederkehrendes Beispiel f\u00fcr unsere heutige Realit\u00e4t.<br class=\"html-br\" \/><br class=\"html-br\" \/>Der Fall von C\u00f3rdoba, der gr\u00f6\u00dften Hochburg des Islam in Andalusien im Jahr 633 n. Chr. \/ 1236 n. Chr., war der Anfang vom Ende des v\u00f6lligen Zusammenbruchs Andalusiens. Die Bev\u00f6lkerung Sevillas erkannte nach dem Fall der Almohaden, dass sie externen Schutz brauchte, da sie sich nicht mehr auf sich selbst verlassen konnte. Sie schworen ihre Treue zu Prinz Abu Zakariya al-Hafsi, dem F\u00fcrsten der Hafsiden in Tunesien, der nach dem Fall der Almohaden gegl\u00e4nzt hatte. Die vom Hafsidenprinzen nach Sevilla geschickten M\u00e4nner misshandelten die Bev\u00f6lkerung jedoch und zeigten Korruption, sodass die Bev\u00f6lkerung Sevillas gezwungen war, sie zu vertreiben und begann, sich auf sich selbst zu verlassen. Sie annullierten einen dem\u00fctigenden Vertrag, der zwischen ihnen und dem christlichen K\u00f6nig von Kastilien, Ferdinand III., geschlossen worden war, und t\u00f6teten Ibn al-Jadd, den Autor des Projekts des oben genannten Vertrags und Unterst\u00fctzer der Politik der Dem\u00fctigung der Christen.<br class=\"html-br\" \/>Dies war ein Vorbote vom Ende Sevillas, doch die Stadt hatte die Unterst\u00fctzung des Islam von au\u00dfen verloren und erkl\u00e4rte durch den Vertragsbruch Kastilien den Krieg, f\u00fcr den sie aufgrund ihrer Umst\u00e4nde nicht reif war.<br class=\"html-br\" \/>Im Jahr 644 n. Chr. \/ 1246 n. Chr. begann die christliche Bewegung gegen Sevilla. Die Kreuzfahrer eroberten in diesem Jahr die Garnison von Sevilla mit Hilfe von Ibn al-Ahmar, K\u00f6nig von Granada. Dieser hatte seinen Vertrag mit Ferdinand abgeschlossen, in dem dieser Argona abtrat und al-Hajjar, die Festung Jabir und die L\u00e4ndereien der Frantira verkaufte. Er bekannte sich zum Gehorsam gegen\u00fcber dem K\u00f6nig von Kastilien und verpflichtete sich, ihm einen j\u00e4hrlichen Tribut von 150.000 Maravedis (spanische W\u00e4hrung) zu zahlen und ihn in seinen Kriegen gegen seine muslimischen Feinde zu unterst\u00fctzen.<br class=\"html-br\" \/>Im folgenden Jahr, 645 n. Chr. \/ 1247 n. Chr., r\u00fcckten die christlichen Armeen erneut nach Sevilla vor und eroberten dank der Intervention von Ibn al-Ahmar Dutzende islamischer St\u00e4dte. Sevilla wurde von christlichen Bataillonen und dem Bataillon des Muslims Ibn al-Ahmar belagert und von allen Seiten umzingelt. Sie alle beteiligten sich an der Vertreibung der Bev\u00f6lkerung und der Unterdr\u00fcckung des Islam. Vielleicht war die Pr\u00e4senz eines islamischen Kampfbanners, das die belagerten Muslime sehen konnten, der schwerste Schlag, den die weinenden Augen und Herzen der tapferen Bev\u00f6lkerung Sevillas erlitten!!<br class=\"html-br\" \/>Die ehrenwerten Einwohner Sevillas hielten etwa ein Jahr lang stand und wehrten die von Ibn al-Ahmar unterst\u00fctzte Belagerung der Christen ab. Es gelang ihnen, die Christen mehr als einmal in einen Hinterhalt zu locken und sie mehr als einmal zu besiegen.<br class=\"html-br\" \/>W\u00e4hrend der Belagerung versuchten sie vergeblich, Hilfe aus Marokko zu erhalten. Die Christen erhielten weiterhin Hilfe, bis es ihnen gelang, die Versorgung der belagerten Muslime in Sevilla zu unterbinden. Die Lebensmittelvorr\u00e4te gingen zur Neige, und die Hungersnot breitete sich in der ersch\u00f6pften Stadt aus!<br class=\"html-br\" \/>Und es war Gottes Wille, und die Muslime von Sevilla verlie\u00dfen ihre Stadt gem\u00e4\u00df den Vertragsbedingungen im Jahr 647 AH \/ 1248 n. Chr. Sie flohen in andere islamische spanische St\u00e4dte, die bald darauf fielen!!<br class=\"html-br\" \/><br class=\"html-br\" \/>Aus dem Buch &quot;Unforgettable Countries&quot; von Major Tamer Badr\u00a0<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>17 \u0633\u0628\u062a\u0645\u0628\u0631 2014 \u00a0 \u0633\u0642\u0648\u0637 \u0623\u0634\u0628\u064a\u0644\u064a\u0629 \u0627\u0644\u062a\u0627\u0631\u064a\u062e \u064a\u062a\u0643\u0631\u0631 \u062f\u0627\u0626\u0645\u0627 \u0645\u0639\u0646\u0627 \u0648\u0644\u0644\u0623\u0633\u0641 \u0646\u062d\u0646 \u0623\u0645\u0629 \u0644\u0627 \u062a\u0642\u0631\u0623 \u0627\u0644\u062a\u0627\u0631\u064a\u062e \u062d\u062a\u0649 \u062a\u0633\u062a\u0641\u064a\u062f \u0645\u0646\u0647 \u0648\u0641\u064a \u0627\u0644\u0646\u0647\u0627\u064a\u0629 \u0646\u0642\u0639 \u0641\u064a \u0646\u0641\u0633 \u0623\u062e\u0637\u0627\u0621 \u0645\u0646 \u0633\u0628\u0642\u0648\u0646\u0627 \u0641\u0647\u0624\u0644\u0627\u0621 \u0627\u0644\u0630\u064a\u0646 \u0644\u0627 \u064a\u062a\u0630\u0643\u0631\u0648\u0646 \u0627\u0644\u0645\u0627\u0636\u064a \u0645\u062d\u0643\u0648\u0645 \u0639\u0644\u064a\u0647\u0645 \u0628\u0625\u0639\u0627\u062f\u062a\u0647 \u0648\u0644\u0644\u0623\u0633\u0641 \u0646\u062d\u0646 \u0646\u0643\u0631\u0631 \u0623\u062e\u0637\u0627\u0621 \u0627\u0644\u0645\u0627\u0636\u064a \u0648\u0646\u062a\u062d\u0627\u0644\u0641 \u0645\u0639 \u0623\u0639\u062f\u0627\u0626\u0646\u0627 \u0644\u0646\u0642\u0636\u064a \u0639\u0644\u0649 \u0628\u0639\u0636\u0646\u0627 \u0627\u0644\u0628\u0639\u0636 \u0647\u0630\u0647 \u0642\u0635\u0629 \u0633\u0642\u0648\u0637 \u0623\u0634\u0628\u064a\u0644\u064a\u0629 \u0648\u0647\u064a \u0645\u062b\u0627\u0644 \u0645\u062a\u0643\u0631\u0631 \u0644\u0633\u0642\u0648\u0637 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":21878,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[115],"tags":[],"class_list":{"0":"post-21877","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-115"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts\/21877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/comments?post=21877"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts\/21877\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/media\/21878"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/media?parent=21877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/categories?post=21877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/tags?post=21877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}