{"id":21426,"date":"2025-03-26T11:00:26","date_gmt":"2025-03-26T11:00:26","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=21426"},"modified":"2025-04-17T12:37:31","modified_gmt":"2025-04-17T12:37:31","slug":"dsfgdfg","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/de\/archives\/21426","title":{"rendered":"Die Gestaltung und Bemalung der Prophetenmoschee ist jetzt ein Zeichen der Stunde"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"21426\" class=\"elementor elementor-21426\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-25084731 e-flex e-con-boxed e-con e-parent\" data-id=\"25084731\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35568d86 elementor-widget elementor-widget-text-editor\" data-id=\"35568d86\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><h1 class=\"x1gslohp\">\u00a0<\/h1><\/div><div class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">3. Oktober 2013<\/span><\/span><\/div><\/div><\/div><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"Ma\u00dfnahmen, die f\u00fcr diese Stelle ergriffen werden k\u00f6nnen\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><strong>Makkah Clock Tower ist eines der Zeichen der Stunde<\/strong><br class=\"html-br\" \/><strong>Die Gestaltung und Bemalung der Prophetenmoschee ist jetzt ein Zeichen der Stunde<\/strong><br class=\"html-br\" \/><br class=\"html-br\" \/>1- Die H\u00f6he des Geb\u00e4udes auf dem Berg Abu Qubais in Mekka<br class=\"html-br\" \/><br class=\"html-br\" \/>Im bekannten Hadith Gabriels fragte der Prophet (Friede und Segen seien auf ihm) den Propheten (Allahs Segen und Friede seien auf ihm) nach der Stunde. Dieser sagte: \u201eErz\u00e4hl mir von ihren Zeichen.\u201c Er (Friede und Segen seien auf ihm) antwortete: \u201eDass die Sklavin ihre Herrin geb\u00e4ren wird und dass du barf\u00fc\u00dfige, nackte und mittellose Hirten sehen wirst, die im Bau hoher Geb\u00e4ude wetteifern.\u201c \u00dcberliefert von Muslim.<br class=\"html-br\" \/><br class=\"html-br\" \/>Auf die Autorit\u00e4t von Abd al-Razzaq, auf die Autorit\u00e4t von Muammar, auf die Autorit\u00e4t von Yazid ibn Abi Ziyad, auf die Autorit\u00e4t von Mujahid, auf die Autorit\u00e4t von Abdullah ibn Amr, der sagte: \u201eWenn Sie ein Geb\u00e4ude in Richtung Abu Qubays aufsteigen sehen und Wasser im Tal flie\u00dft, dann seien Sie auf der Hut.\u201c<br class=\"html-br\" \/>Erz\u00e4hlt von Ibn Abi Shaybah in Al-Musannaf: Ghundar berichtete uns, gest\u00fctzt auf Shu\u2019bah, Ya\u2019la ibn Ata\u2019 und seinen Vater, dass dieser sagte: \u201eIch hielt die Z\u00fcgel von Abdullah ibn Amrs Reittier, als er sagte: \u201eWas werdet ihr tun, wenn ihr die Kaaba zerst\u00f6rt und keinen Stein auf dem anderen lasst?\u201c Sie sagten: \u201eUnd wir sind Muslime?\u201c Er sagte: \u201eUnd ihr seid Muslime.\u201c Er sagte: \u201eWas dann?\u201c Er sagte: \u201eDann wird sie besser wiederaufgebaut, als sie war. Wenn ihr also Mekka voller Ungl\u00fcck seht und die Geb\u00e4ude bis zu den Berggipfeln ragen seht, dann wisst, dass die Sache zu euch gekommen ist.\u201c<br class=\"html-br\" \/>Und sein Ausspruch: \u201eUnd das Wasser floss im Tal\u201c, bedeutet, dass gro\u00dfe Gr\u00e4ben gegraben und gegraben wurden, wie Brunnen, die durch Kan\u00e4le miteinander verbunden sind. Und Gott wei\u00df es am besten, es handelt sich um die riesigen Tunnel, die ein Netzwerk zwischen den Bergen Mekkas bildeten, oder um die Gr\u00e4ben f\u00fcr die Kanalisation, Elektrizit\u00e4t und Klimaanlagen, die aus weiten Entfernungen herangef\u00fchrt wurden. Dies ist die Bedeutung seines Ausspruchs: \u201eUnd das Wasser floss im Tal\u201c.<br class=\"html-br\" \/>Al-Azraqi berichtete in seinem Buch \u201eAkhbar Makkah\u201c unter Berufung auf Yusuf ibn Mahak, dass dieser sagte: \u201eIch sa\u00df mit Abdullah ibn Amr ibn al-As (m\u00f6ge Gott mit ihnen beiden zufrieden sein) in einer Ecke der Heiligen Moschee, als er ein Haus mit Blick auf Abu Qubays betrachtete. Er sagte: Ist das der Fall? Ich sagte: Ja.\u201c Er sagte: \u201eWenn du siehst, wie sich die H\u00e4user \u00fcber ihre Holzb\u00f6den erheben und Fl\u00fcsse aus ihren T\u00e4lern sprudeln, dann ist die Sache nahe.\u201c<br class=\"html-br\" \/>Abdul Razzaq, auf die Autorit\u00e4t von Muammar, auf die Autorit\u00e4t von Yazid bin Abi Ziyad, auf die Autorit\u00e4t von Mujahid, auf die Autorit\u00e4t von Abdullah bin Amr, der sagte: \u201eWenn Sie ein Geb\u00e4ude in Richtung Abu Qubais sehen und Wasser im Tal flie\u00dft, dann seien Sie vorsichtig.\u201c<br class=\"html-br\" \/><br class=\"html-br\" \/>Abu Qubays ist ein Berg \u00f6stlich der Gro\u00dfen Moschee. Er ist etwa 420 Meter hoch. Man sagt, er erhielt seinen Namen, weil ein Mann namens Abu Qubays als erster dort baute. Er stammte aus dem Stamm der Jurhum und hie\u00df \u201eAbu Qubays ibn Salih\u201c. Er floh auf den Berg, weshalb der Berg nach ihm benannt wurde.<br class=\"html-br\" \/><br class=\"html-br\" \/>Zur Aufnahme einer Uhr f\u00fcr die Mekka-Zeit wurde ein Turm mit einer H\u00f6he von 595 Metern errichtet. Damit \u00fcbertrifft er die H\u00f6he des Berges Abu Qubais um etwa 135 Meter.<br class=\"html-br\" \/><br class=\"html-br\" \/><br class=\"html-br\" \/>2- Die Prophetenmoschee (Der Wei\u00dfe Palast)<br class=\"html-br\" \/><br class=\"html-br\" \/>Ahmad berichtete in seinem Musnad und Al-Hakim in Al-Mustadrak, dass der Gesandte Allahs (Allahs Segen und Frieden auf ihm) sich an die Menschen wandte und sagte: Der Tag der Erl\u00f6sung, und was ist der Tag der Erl\u00f6sung? Dreimal. Es wurde gesagt: O Gesandter Allahs, was ist der Tag der Erl\u00f6sung? Er sagte: Der Antichrist wird kommen und Uhud besteigen, dann wird er auf die Stadt blicken und zu seinen Gef\u00e4hrten sagen: Seht ihr diesen wei\u00dfen Palast nicht? Ist dies die Moschee von Ahmad? Dann wird er in die Stadt kommen und an jeder Stelle, an der er vorbeigeht, einen Engel finden, der seine H\u00e4nde ausstreckt. Dann wird er zum Scho\u00df der Klippe kommen und den S\u00e4ulengang der Stadt dreimal ersch\u00fcttern, und es wird kein Heuchler \u00fcbrig bleiben, Mann oder Frau, lobenswerter Mann oder Frau, ohne dass er zu ihm hinausgeht, und die Stadt wird gerettet sein, und dies ist der Tag der Erl\u00f6sung. Ein stichhaltiger Hadith gem\u00e4\u00df den Kriterien der Muslime.<br class=\"html-br\" \/>Betrachten Sie die Form der Prophetenmoschee, Sie werden feststellen, dass sie tats\u00e4chlich einem wei\u00dfen Palast gleicht. Als der Prophet \u2013 Gott segne ihn und schenke ihm Frieden \u2013 diese Worte sprach, war seine Moschee aus Lehmziegeln gebaut, ihr Dach aus Palmwedeln und ihre S\u00e4ulen aus Palmst\u00e4mmen. Gepriesen sei Gott, wer die Moschee heute sieht, wird sie wie einen wei\u00dfen Palast erscheinen sehen.<br class=\"html-br\" \/><br class=\"html-br\" \/>Wir stehen dann an der Schwelle zu den gro\u00dfen Zeichen der Stunde, einschlie\u00dflich des Erscheinens des Antichristen und anderer gro\u00dfer Ereignisse.<br class=\"html-br\" \/>Wir bitten den allm\u00e4chtigen Gott, uns standhaft zu machen und uns den Sieg zu gew\u00e4hren.<br class=\"html-br\" \/><br class=\"html-br\" \/>Major Tamer Badr\u00a0<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u00a0 3 \u0623\u0643\u062a\u0648\u0628\u0631 2013\u00a0 \u0628\u0631\u062c \u0627\u0644\u0633\u0627\u0639\u0629 \u0628\u0645\u0643\u0629 \u0645\u0646 \u0639\u0644\u0627\u0645\u0627\u062a \u0627\u0644\u0633\u0627\u0639\u0629\u062a\u0635\u0645\u064a\u0645 \u0648\u0637\u0644\u0627\u0621 \u0627\u0644\u0645\u0633\u062c\u062f \u0627\u0644\u0646\u0628\u0648\u064a \u0627\u0644\u0622\u0646 \u0645\u0646 \u0639\u0644\u0627\u0645\u0627\u062a \u0627\u0644\u0633\u0627\u0639\u0629 1 &#8211; \u0627\u0631\u062a\u0641\u0627\u0639 \u0627\u0644\u0628\u0646\u064a\u0627\u0646 \u0627\u0639\u0644\u0649 \u062c\u0628\u0644 \u0627\u0628\u064a \u0642\u0628\u064a\u0633 \u0628\u0645\u0643\u0629 \u0641\u0641\u064a \u062d\u062f\u064a\u062b \u062c\u0628\u0631\u064a\u0644 \u0627\u0644\u0645\u0639\u0631\u0648\u0641 \u0639\u0646\u062f\u0645\u0627 \u0633\u0623\u0644 \u0627\u0644\u0646\u0628\u064a\u0651\u064e \u0635\u0644\u0649 \u0627\u0644\u0644\u0647 \u0639\u0644\u064a\u0647 \u0648\u0633\u0644\u0645 \u0639\u0646 \u0627\u0644\u0633\u0627\u0639\u0629 \u0648\u0642\u0627\u0644: \u0623\u062e\u0628\u0631\u0646\u064a \u0639\u0646 \u0623\u0645\u0627\u0631\u062a\u0647\u0627. \u0641\u0642\u0627\u0644 \u0635\u0644\u0649 \u0627\u0644\u0644\u0647 \u0639\u0644\u064a\u0647 \u0648\u0633\u0644\u0645: \u0623\u0646 \u062a\u0644\u062f \u0627\u0644\u0623\u0645\u0629 \u0631\u0628\u062a\u0647\u0627\u060c \u0648\u0623\u0646 \u062a\u0631\u0649 \u0627\u0644\u062d\u0641\u0627\u0629 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":21427,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[114],"tags":[],"class_list":{"0":"post-21426","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-114"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts\/21426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/comments?post=21426"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts\/21426\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/media\/21427"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/media?parent=21426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/categories?post=21426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/tags?post=21426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}