{"id":21138,"date":"2025-03-25T12:08:04","date_gmt":"2025-03-25T12:08:04","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=21138"},"modified":"2025-05-02T17:14:11","modified_gmt":"2025-05-02T17:14:11","slug":"ghkgh","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/de\/archives\/21138","title":{"rendered":"Vision des Mahdi, der w\u00e4hrend des Gebets belagert wird, 2. Juli 2023"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"21138\" class=\"elementor elementor-21138\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ac7451e e-flex e-con-boxed e-con e-parent\" data-id=\"5ac7451e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4bf6c04d elementor-widget elementor-widget-text-editor\" data-id=\"4bf6c04d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Ich sah den Mahdi und eine Gruppe von Menschen unter einer der neuen Br\u00fccken. Ich konnte nicht genau sagen, wo sie war. Unter der Br\u00fccke war ein leerer Platz ohne Moschee. Als zum Gebet unter der Br\u00fccke gerufen wurde, z\u00f6gerte der Mahdi, der Imam f\u00fcr dieses Gebet zu sein, aber er trat vor und wurde zum Imam. Er wusste, dass er der Mahdi war, aber er verriet es niemandem, der bei ihm war, und behielt dieses Geheimnis f\u00fcr sich.<br class=\"html-br\" \/>In der ersten Rak&#039;ah rezitierte Al-Mahdi die Al-Fatiha und dann die letzten beiden Verse der Surat Al-Baqarah: \u201eDer Gesandte glaubte an das, was ihm von seinem Herrn offenbart wurde, und die Gl\u00e4ubigen auch. Sie alle glaubten an Allah, seine Engel, seine B\u00fccher und seine Gesandten. Wir machen keinen Unterschied zwischen seinen Gesandten, und sie sagen: \u201aWir h\u00f6ren und wir gehorchen. Verzeihe, unser Herr, und zu Dir ist die letzte Heimsuchung.\u2018 (285) Allah belastet keine Seele \u00fcber ihre Kr\u00e4fte hinaus. Ihr wird zuteil, was sie verdient hat, und sie wird zuf\u00fcgen, was sie begangen hat. Unser Herr, keine Seele wird f\u00fcr ihre S\u00fcnden bestraft. Erhebe dich von uns, wenn wir vergessen oder einen Fehler machen, unser Herr, und erlege uns keine Last auf, wie du sie denen vor uns auferlegt hast. Unser Herr, und erlege uns nichts auf, was wir nicht tragen k\u00f6nnen. Vergib uns und vergib uns und sei uns gn\u00e4dig. Du bist unser Besch\u00fctzer, so gib uns Sieg \u00fcber das ungl\u00e4ubige Volk. (286)<br class=\"html-br\" \/>W\u00e4hrend des Mahdi-Gebets erschienen zahlreiche Soldaten und umringten den Mahdi und die ihn begleitenden Gl\u00e4ubigen. Sie wussten, dass der Mahdi unter den Betenden war, aber sie wussten nicht genau, wer der Mahdi war. Sie wollten wissen, wer der Mahdi war, doch der Mahdi wollte sich weder den ihn begleitenden Gl\u00e4ubigen noch den ihn umgebenden Soldaten und seinen Begleitern zu erkennen geben.<br class=\"html-br\" \/>Die Soldaten durchsuchten die Gl\u00e4ubigen und terrorisierten sie. Eine Gruppe von Gl\u00e4ubigen f\u00fcrchtete sich vor dem Vorgehen der Soldaten und verlie\u00df den Ort noch w\u00e4hrend des Gebets. Etwa die H\u00e4lfte der Gl\u00e4ubigen oder weniger blieb beim Gebet mit dem Mahdi. W\u00e4hrend der Mahdi im ersten Taschahhud sa\u00df, streckte ein Offizier der ersten Reihe von Gl\u00e4ubigen die Hand zum H\u00e4ndesch\u00fctteln entgegen, damit auch sie sich die Hand gaben. Er tat dies, damit sie wussten, wer der Mahdi war. Dann ging er zum Mahdi und streckte ihm w\u00e4hrend des ersten Taschahhud die Hand zum H\u00e4ndesch\u00fctteln entgegen. Der Mahdi streckte seine Hand aus und sch\u00fcttelte sie, da er z\u00f6gerte, jemandem w\u00e4hrend des Gebets die Hand zu sch\u00fctteln. Der Offizier erkannte ihn jedoch nicht, und der Mahdi beendete sein Gebet. Dann sagte der Offizier zu den Soldaten, die bei ihm waren: \u201eIch m\u00f6chte die Namen aller Gl\u00e4ubigen, wenn sie ihr Gebet beendet haben.\u201c Der Mahdi hatte Angst, dass sie ihn erkennen w\u00fcrden.<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0631\u0623\u064a\u062a \u0627\u0644\u0645\u0647\u062f\u064a \u0648\u0645\u062c\u0645\u0648\u0639\u0629 \u0645\u0646 \u0627\u0644\u0646\u0627\u0633 \u062a\u062d\u062a \u0625\u062d\u062f\u0649 \u0627\u0644\u0643\u0628\u0627\u0631\u064a \u0627\u0644\u062c\u062f\u064a\u062f\u0629 \u0648\u0644\u0645 \u0623\u0645\u064a\u0632 \u0645\u0643\u0627\u0646\u0647\u0627 \u0628\u0627\u0644\u0636\u0628\u0637 \u0648\u0642\u062f \u0643\u0627\u0646\u062a \u0633\u0627\u062d\u0629 \u062e\u0627\u0644\u064a\u0629 \u062a\u062d\u062a \u0627\u0644\u0643\u0648\u0628\u0631\u064a \u0644\u0627 \u064a\u0648\u062c\u062f \u0628\u0647\u0627 \u0645\u0633\u062c\u062f \u0648\u0639\u0646\u062f \u0625\u0642\u0627\u0645\u0629 \u0627\u0644\u0635\u0644\u0627\u0629 \u062a\u062d\u062a \u0627\u0644\u0643\u0648\u0628\u0631\u064a \u062a\u0631\u062f\u062f \u0627\u0644\u0645\u0647\u062f\u064a \u0641\u064a \u0623\u0646 \u064a\u0643\u0648\u0646 \u0627\u0644\u0625\u0645\u0627\u0645 \u0641\u064a \u062a\u0644\u0643 \u0627\u0644\u0635\u0644\u0627\u0629 \u0648\u0644\u0643\u0646\u0647 \u062a\u0642\u062f\u0645 \u0648\u0623\u0635\u0628\u062d \u0627\u0644\u0625\u0645\u0627\u0645 \u0648\u0642\u062f \u0643\u0627\u0646 \u064a\u0639\u0631\u0641 \u0623\u0646\u0647 \u0647\u0648 \u0627\u0644\u0645\u0647\u062f\u064a \u0648\u0644\u0643\u0646\u0647 \u0644\u0645 \u064a\u062e\u0628\u0631 \u0623\u062d\u062f \u0645\u0645\u0646 \u0645\u0639\u0647 \u0648\u0643\u062a\u0645 \u0647\u0630\u0627 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":21139,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[112],"tags":[],"class_list":{"0":"post-21138","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category--2021-"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts\/21138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/comments?post=21138"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts\/21138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/media\/21139"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/media?parent=21138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/categories?post=21138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/tags?post=21138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}